{"id":91287,"date":"2020-06-10T11:33:02","date_gmt":"2020-06-10T11:33:02","guid":{"rendered":"https:\/\/raed.academy\/?p=91287"},"modified":"2020-06-10T18:23:30","modified_gmt":"2020-06-10T18:23:30","slug":"patrimoni-en-linia","status":"publish","type":"post","link":"https:\/\/raed.academy\/ca\/patrimoni-en-linia\/","title":{"rendered":"Patrimoni en l\u00ednia"},"content":{"rendered":"<p><a href=\"https:\/\/raed.academy\/ca\/academics\/dr-ignacio-buqueras-bach\/\" target=\"_blank\" rel=\"noopener noreferrer\"><em><strong>Ignacio Buqueras<\/strong><\/em><\/a><br \/>\n<em>Acad\u00e8mic de n\u00famero de la Reial Acad\u00e8mia de Doctors de Espa\u00f1a<\/em><br \/>\n<em>Acad\u00e8mic de n\u00famero de la Reial Acad\u00e8mia Europea de Doctors-Barcelona 1914 (RAED)<\/em><\/p>\n<p><span class=\"tlid-translation translation\" lang=\"ca\"><strong>Ignacio Buqueras<\/strong>, acad\u00e8mic de n\u00famero de la <strong>Reial Acad\u00e8mia de Doctors d&#8217;Espanya<\/strong>, president d&#8217;honor de la <strong>Fundaci\u00f3 Independent<\/strong> i acad\u00e8mic numerari de la <strong>Reial Acad\u00e8mia Europea de Doctors-Barcelona 1914<\/strong> (RAED), remet a la comunitat acad\u00e8mica la reprogramaci\u00f3 i activitats virtuals de l&#8217;<strong>Associaci\u00f3 per a la Difusi\u00f3 i Promoci\u00f3 del Patrimoni Espanyol<\/strong>, una entitat impulsada i liderada per ell mateix, amb motiu de les restriccions que han imposat les autoritats des de la declaraci\u00f3 de l&#8217;estat d&#8217;alarma a causa de la pand\u00e8mia pel coronavirus causant de la Covid-19.<\/span><\/p>\n<p>Amb l&#8217;objectiu de facilitar un millor coneixement del patrimoni mundial reconegut per la <strong>Unesco<\/strong> a Espanya, col\u00b7laborar en la seva conservaci\u00f3 i ajudar en la seva difusi\u00f3, l&#8217;Associaci\u00f3 posa a disposici\u00f3 de tots els ciutadans els seus serveis i activitats, recordant que Espanya \u00e9s el tercer pa\u00eds del m\u00f3n amb m\u00e9s reconeixements i que aquest any se celebra el XXXV Aniversari de les cinc primeres declaracions. Buqueras convida per aquest motiu a tots els interessats a visitar el web de l&#8217;entitat (<strong>www.adiprope.org<\/strong>) i proposa col\u00b7laborar amb la iniciativa sumant-se als <strong>Amics del Patrimoni<\/strong>.<\/p>\n<div id=\"attachment_70966\" style=\"width: 422px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-70966\" class=\"wp-image-70966 size-full\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2019\/04\/alhambra-granada-patrimonio-Espa\u00f1a-dstNtc.jpeg\" alt=\"Alhambra de Granada, patrimoni d'Espanya\" width=\"412\" height=\"250\" aria-describedby=\"caption-attachment-70966\" data-attachment-id=\"70966\" data-permalink=\"https:\/\/raed.academy\/un-patrimonio-compartido\/alhambra-granada-patrimonio-espana-dstntc\/\" data-orig-file=\"https:\/\/raed.academy\/wp-content\/uploads\/2019\/04\/alhambra-granada-patrimonio-Espa\u00f1a-dstNtc.jpeg\" data-orig-size=\"412,250\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Alhambra de Granada patrimonio de Espa\u00f1a\" data-image-description=\"\" data-medium-file=\"https:\/\/raed.academy\/wp-content\/uploads\/2019\/04\/alhambra-granada-patrimonio-Espa\u00f1a-dstNtc.jpeg\" data-large-file=\"https:\/\/raed.academy\/wp-content\/uploads\/2019\/04\/alhambra-granada-patrimonio-Espa\u00f1a-dstNtc.jpeg\" \/><p id=\"caption-attachment-70966\" class=\"wp-caption-text\">Alhambra de Granada, patrimoni d&#8217;Espanya<\/p><\/div>\n<p>Entre les activitats que ofereix l&#8217;Associaci\u00f3 per a la Difusi\u00f3 i Promoci\u00f3 del Patrimoni Espanyol destaquen el cap\u00edtol dedicat al Patrimoni Mundial a Catalunya del llibre sobre tot el Patrimoni espanyol que ha editat l&#8217;associaci\u00f3, ara publicat al web; la confer\u00e8ncia que en aquest mateix sentit va pronunciar <strong>Jos\u00e9 Manuel Almuzara<\/strong>, arquitecte i president de l&#8217;<strong>Associaci\u00f3 pro Beatificaci\u00f3 d&#8217;Antoni Gaud\u00ed<\/strong>, que es pot trobar al canal de YouTube de l&#8217;entitat, o el cap\u00edtol dedicat a la Comunitat de Madrid, tamb\u00e9 disponible online .<\/p>\n<p>En aquest canal tamb\u00e9 estan disponibles la confer\u00e8ncia del periodista <strong>Rafael N\u00fa\u00f1ez<\/strong> sobre <strong>&#8220;Madrid, Patrimonio del Renacimiento espa\u00f1ol&#8221;<\/strong>, la confer\u00e8ncia en l\u00ednia que va pronunciar el director general de Patrimoni Cultural de l&#8217;<strong>Ajuntament de Madrid<\/strong>, <strong>Luis Lafuente<\/strong>, amb el t\u00edtol <strong>&#8220;El Paseo del Prado y el Buen Retiro. Un Paisaje de las Artes y las Ciencias&#8221;<\/strong> o la de <strong>Mar\u00eda Rosa Su\u00e1rez-Incl\u00e1n<\/strong>, directiva d&#8217;Associaci\u00f3 per a la Difusi\u00f3 i Promoci\u00f3 del Patrimoni Espanyol, sobre la<strong> &#8220;Candidatura de Madrid a Patrimonio Mundial&#8221;<\/strong>. Per poder seguir i participar de les properes confer\u00e8ncies online \u00e9s necessari registrar-se al canal.<\/p>\n<p>Destacat impulsor d&#8217;iniciatives nascudes des de la societat civil, Buqueras ha liderat iniciatives de gran calat com la <strong>Confederaci\u00f3 Espanyola d&#8217;Organitzacions de Gent Gran<\/strong> o l&#8217;<strong>Associaci\u00f3 per a la Racionalitzaci\u00f3 dels Horaris Espanyols<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ignacio Buqueras Acad\u00e8mic de n\u00famero de la Reial Acad\u00e8mia de Doctors de Espa\u00f1a Acad\u00e8mic de n\u00famero de la Reial Acad\u00e8mia Europea de Doctors-Barcelona 1914 (RAED) Ignacio Buqueras, acad\u00e8mic de n\u00famero de la Reial Acad\u00e8mia de Doctors d&#8217;Espanya, president d&#8217;honor de la Fundaci\u00f3 Independent i acad\u00e8mic numerari de la Reial Acad\u00e8mia Europea de Doctors-Barcelona 1914 (RAED), [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":70967,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[268,275],"tags":[],"class_list":["post-91287","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coronavirus-des-del-coneixement","category-educacio-etica-i-valors","et-has-post-format-content","et_post_format-et-post-format-standard"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Patrimoni en l\u00ednia - Reial Acad\u00e8mia Europea de Doctors<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/raed.academy\/ca\/patrimoni-en-linia\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Patrimoni en l\u00ednia - Reial Acad\u00e8mia Europea de Doctors\" \/>\n<meta property=\"og:description\" content=\"Ignacio Buqueras Acad\u00e8mic de n\u00famero de la Reial Acad\u00e8mia de Doctors de Espa\u00f1a Acad\u00e8mic de n\u00famero de la Reial Acad\u00e8mia Europea de Doctors-Barcelona 1914 (RAED) Ignacio Buqueras, acad\u00e8mic de n\u00famero de la Reial Acad\u00e8mia de Doctors d&#8217;Espanya, president d&#8217;honor de la Fundaci\u00f3 Independent i acad\u00e8mic numerari de la Reial Acad\u00e8mia Europea de Doctors-Barcelona 1914 (RAED), [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/raed.academy\/ca\/patrimoni-en-linia\/\" \/>\n<meta property=\"og:site_name\" content=\"Reial Acad\u00e8mia Europea de Doctors\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/fb.me\/raed.academy\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-10T11:33:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-10T18:23:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/raed.academy\/wp-content\/uploads\/2019\/04\/alhambra-granada-patrimonio-Espa\u00f1a-dstNtc.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"412\" \/>\n\t<meta property=\"og:image:height\" content=\"250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"RAED\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@raedacademy\" \/>\n<meta name=\"twitter:site\" content=\"@raedacademy\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"RAED\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/patrimoni-en-linia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/patrimoni-en-linia\\\/\"},\"author\":{\"name\":\"RAED\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/person\\\/5a755da80d1d979fd66ba745c8702927\"},\"headline\":\"Patrimoni en l\u00ednia\",\"datePublished\":\"2020-06-10T11:33:02+00:00\",\"dateModified\":\"2020-06-10T18:23:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/patrimoni-en-linia\\\/\"},\"wordCount\":483,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/patrimoni-en-linia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/alhambra-granada-patrimonio-Espa\u00f1a-dstNtc.jpeg\",\"articleSection\":[\"Coronavirus des del coneixement\",\"Educaci\u00f3, \u00e8tica i valors\"],\"inLanguage\":\"ca-ES\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/raed.academy\\\/ca\\\/patrimoni-en-linia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/patrimoni-en-linia\\\/\",\"url\":\"https:\\\/\\\/raed.academy\\\/ca\\\/patrimoni-en-linia\\\/\",\"name\":\"Patrimoni en l\u00ednia - Reial Acad\u00e8mia Europea de Doctors\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/patrimoni-en-linia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/patrimoni-en-linia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/alhambra-granada-patrimonio-Espa\u00f1a-dstNtc.jpeg\",\"datePublished\":\"2020-06-10T11:33:02+00:00\",\"dateModified\":\"2020-06-10T18:23:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/patrimoni-en-linia\\\/#breadcrumb\"},\"inLanguage\":\"ca-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/raed.academy\\\/ca\\\/patrimoni-en-linia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/patrimoni-en-linia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/alhambra-granada-patrimonio-Espa\u00f1a-dstNtc.jpeg\",\"contentUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/alhambra-granada-patrimonio-Espa\u00f1a-dstNtc.jpeg\",\"width\":412,\"height\":250,\"caption\":\"Alhambra de Granada patrimonio de Espa\u00f1a\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/patrimoni-en-linia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/raed.academy\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Patrimoni en l\u00ednia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/raed.academy\\\/ca\\\/\",\"name\":\"Reial Acad\u00e8mia Europea de Doctors\",\"description\":\"Corporaci\u00f3n de derecho p\u00fablico de car\u00e1cter cient\u00edfico, t\u00e9cnico y art\u00edstico, que tiene por objeto la investigaci\u00f3n, el estudio, el fomento y la extensi\u00f3n del conocimiento en su sentido m\u00e1s amplio\",\"publisher\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/raed.academy\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#organization\",\"name\":\"Real Academia Europea de Doctores\",\"url\":\"https:\\\/\\\/raed.academy\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/cropped-logo_raed.png\",\"contentUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/cropped-logo_raed.png\",\"width\":512,\"height\":512,\"caption\":\"Real Academia Europea de Doctores\"},\"image\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/fb.me\\\/raed.academy\",\"https:\\\/\\\/x.com\\\/raedacademy\",\"https:\\\/\\\/www.instagram.com\\\/raed.academy\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCUYQwW2KrdirNWihxMDObwg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/person\\\/5a755da80d1d979fd66ba745c8702927\",\"name\":\"RAED\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g\",\"caption\":\"RAED\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Patrimoni en l\u00ednia - Reial Acad\u00e8mia Europea de Doctors","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/raed.academy\/ca\/patrimoni-en-linia\/","og_locale":"ca_ES","og_type":"article","og_title":"Patrimoni en l\u00ednia - Reial Acad\u00e8mia Europea de Doctors","og_description":"Ignacio Buqueras Acad\u00e8mic de n\u00famero de la Reial Acad\u00e8mia de Doctors de Espa\u00f1a Acad\u00e8mic de n\u00famero de la Reial Acad\u00e8mia Europea de Doctors-Barcelona 1914 (RAED) Ignacio Buqueras, acad\u00e8mic de n\u00famero de la Reial Acad\u00e8mia de Doctors d&#8217;Espanya, president d&#8217;honor de la Fundaci\u00f3 Independent i acad\u00e8mic numerari de la Reial Acad\u00e8mia Europea de Doctors-Barcelona 1914 (RAED), [&hellip;]","og_url":"https:\/\/raed.academy\/ca\/patrimoni-en-linia\/","og_site_name":"Reial Acad\u00e8mia Europea de Doctors","article_publisher":"http:\/\/fb.me\/raed.academy","article_published_time":"2020-06-10T11:33:02+00:00","article_modified_time":"2020-06-10T18:23:30+00:00","og_image":[{"width":412,"height":250,"url":"https:\/\/raed.academy\/wp-content\/uploads\/2019\/04\/alhambra-granada-patrimonio-Espa\u00f1a-dstNtc.jpeg","type":"image\/jpeg"}],"author":"RAED","twitter_card":"summary_large_image","twitter_creator":"@raedacademy","twitter_site":"@raedacademy","twitter_misc":{"Written by":"RAED","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/raed.academy\/ca\/patrimoni-en-linia\/#article","isPartOf":{"@id":"https:\/\/raed.academy\/ca\/patrimoni-en-linia\/"},"author":{"name":"RAED","@id":"https:\/\/raed.academy\/ca\/#\/schema\/person\/5a755da80d1d979fd66ba745c8702927"},"headline":"Patrimoni en l\u00ednia","datePublished":"2020-06-10T11:33:02+00:00","dateModified":"2020-06-10T18:23:30+00:00","mainEntityOfPage":{"@id":"https:\/\/raed.academy\/ca\/patrimoni-en-linia\/"},"wordCount":483,"commentCount":0,"publisher":{"@id":"https:\/\/raed.academy\/ca\/#organization"},"image":{"@id":"https:\/\/raed.academy\/ca\/patrimoni-en-linia\/#primaryimage"},"thumbnailUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2019\/04\/alhambra-granada-patrimonio-Espa\u00f1a-dstNtc.jpeg","articleSection":["Coronavirus des del coneixement","Educaci\u00f3, \u00e8tica i valors"],"inLanguage":"ca-ES","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/raed.academy\/ca\/patrimoni-en-linia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/raed.academy\/ca\/patrimoni-en-linia\/","url":"https:\/\/raed.academy\/ca\/patrimoni-en-linia\/","name":"Patrimoni en l\u00ednia - Reial Acad\u00e8mia Europea de Doctors","isPartOf":{"@id":"https:\/\/raed.academy\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/raed.academy\/ca\/patrimoni-en-linia\/#primaryimage"},"image":{"@id":"https:\/\/raed.academy\/ca\/patrimoni-en-linia\/#primaryimage"},"thumbnailUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2019\/04\/alhambra-granada-patrimonio-Espa\u00f1a-dstNtc.jpeg","datePublished":"2020-06-10T11:33:02+00:00","dateModified":"2020-06-10T18:23:30+00:00","breadcrumb":{"@id":"https:\/\/raed.academy\/ca\/patrimoni-en-linia\/#breadcrumb"},"inLanguage":"ca-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/raed.academy\/ca\/patrimoni-en-linia\/"]}]},{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/raed.academy\/ca\/patrimoni-en-linia\/#primaryimage","url":"https:\/\/raed.academy\/wp-content\/uploads\/2019\/04\/alhambra-granada-patrimonio-Espa\u00f1a-dstNtc.jpeg","contentUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2019\/04\/alhambra-granada-patrimonio-Espa\u00f1a-dstNtc.jpeg","width":412,"height":250,"caption":"Alhambra de Granada patrimonio de Espa\u00f1a"},{"@type":"BreadcrumbList","@id":"https:\/\/raed.academy\/ca\/patrimoni-en-linia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/raed.academy\/ca\/"},{"@type":"ListItem","position":2,"name":"Patrimoni en l\u00ednia"}]},{"@type":"WebSite","@id":"https:\/\/raed.academy\/ca\/#website","url":"https:\/\/raed.academy\/ca\/","name":"Reial Acad\u00e8mia Europea de Doctors","description":"Corporaci\u00f3n de derecho p\u00fablico de car\u00e1cter cient\u00edfico, t\u00e9cnico y art\u00edstico, que tiene por objeto la investigaci\u00f3n, el estudio, el fomento y la extensi\u00f3n del conocimiento en su sentido m\u00e1s amplio","publisher":{"@id":"https:\/\/raed.academy\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/raed.academy\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca-ES"},{"@type":"Organization","@id":"https:\/\/raed.academy\/ca\/#organization","name":"Real Academia Europea de Doctores","url":"https:\/\/raed.academy\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/raed.academy\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/raed.academy\/wp-content\/uploads\/2017\/01\/cropped-logo_raed.png","contentUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2017\/01\/cropped-logo_raed.png","width":512,"height":512,"caption":"Real Academia Europea de Doctores"},"image":{"@id":"https:\/\/raed.academy\/ca\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/fb.me\/raed.academy","https:\/\/x.com\/raedacademy","https:\/\/www.instagram.com\/raed.academy\/","https:\/\/www.youtube.com\/channel\/UCUYQwW2KrdirNWihxMDObwg"]},{"@type":"Person","@id":"https:\/\/raed.academy\/ca\/#\/schema\/person\/5a755da80d1d979fd66ba745c8702927","name":"RAED","image":{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g","caption":"RAED"}}]}},"_links":{"self":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/posts\/91287","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/comments?post=91287"}],"version-history":[{"count":0,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/posts\/91287\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/media\/70967"}],"wp:attachment":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/media?parent=91287"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/categories?post=91287"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/tags?post=91287"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}