{"id":90875,"date":"2020-06-01T10:28:41","date_gmt":"2020-06-01T10:28:41","guid":{"rendered":"https:\/\/raed.academy\/?p=90875"},"modified":"2020-06-06T13:15:04","modified_gmt":"2020-06-06T13:15:04","slug":"imatges-del-confinament-luis-pons","status":"publish","type":"post","link":"https:\/\/raed.academy\/ca\/imatges-del-confinament-luis-pons\/","title":{"rendered":"Imatges del confinament"},"content":{"rendered":"<p><a href=\"https:\/\/raed.academy\/ca\/academics\/dr-luis-pons-puiggros\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong><em>Luis Pons<\/em><\/strong><\/a><br \/>\n<em>Acad\u00e8mico corresponent de la Reial Acad\u00e8mia Europea de Doctors-Barcelona 1914 (RAED)<\/em><\/p>\n<p><span class=\"tlid-translation translation\" lang=\"ca\"><strong>Luis Pons<\/strong>, acad\u00e8mic corresponent de la <strong>Reial Acad\u00e8mia Europea de Doctors-Barcelona 1914<\/strong> (RAED), torna a compartir amb els acad\u00e8mics i amics de la instituci\u00f3 la seva passi\u00f3 per la fotografia presentant la nova s\u00e8rie de instant\u00e0nies, aquest cop captades en una situaci\u00f3 diferent i \u00fanica: el confinament provocat per la pand\u00e8mia de la Covid-19. &#8220;La fotografia des del confinament s&#8217;em presenta com un mite d&#8217;<strong>Ulisses<\/strong>, per\u00f2 a l&#8217;inrev\u00e9s. A Ulisses, li suposava un conflicte que el seu cos estigu\u00e9s viatjant mentre que el seu esperit encara seguia a casa. En aquest per\u00edode, el cos del fot\u00f2graf no s&#8217;ha mogut de casa, i en canvi el seu esperit, s\u00ed que ha recorregut gaireb\u00e9 tota la zona metropolitana de Barcelona&#8221;, assenyala l&#8217;acad\u00e8mic en la presentaci\u00f3 d&#8217;aquesta s\u00e8rie d&#8217;instant\u00e0nies.<\/span><\/p>\n<p>Aquesta s\u00e8rie de fotografies tracta d&#8217;aportar una visi\u00f3 a vista d&#8217;ocell de la ciutat de Barcelona, \u200b\u200bi voltants, des del domicili del fot\u00f2graf confinat. &#8220;La ciutat de Barcelona ofereix facetes que sorprenen. Al cel no se li pot confinar i tamb\u00e9 s&#8217;amplia el seu l\u00edmit amb els equips fotogr\u00e0fics. El material que s&#8217;ha utilitzat, s&#8217;ha dedicat per dos apartats, les aus en vol usant teleobjectiu i r\u00e0fegues a alta velocitat, i la contemplaci\u00f3 tranquil\u00b7la dels paisatges amb gran angular. Les aus ja presents (gavines de tot tipus, t\u00f3rtores, cotorres de Cramer, falciots, etc.), se&#8217;ls afegeixen una major mobilitat d&#8217;aus com rapinyaires (xoriguer i falc\u00f3 pelegr\u00ed), \u00e0necs de diferents tipus i agrons, entre elles les reals i la imperial o purp\u00farea&#8221;, explica l&#8217;acad\u00e8mic.<\/p>\n<p>Pons certifica amb la seva c\u00e0mera com la reducci\u00f3 de contaminaci\u00f3 per la disminuci\u00f3 de l&#8217;activitat ha deixat uns cels di\u00fcrns i nocturns d&#8217;aire molt net. &#8220;Les postes de sol i nuvolositats di\u00fcrnes i nocturnes, juntament amb la lluna i els planetes, aix\u00ed com les estrelles, sorprenen. La visibilitat de persones, s&#8217;ha evitat per respectar el dret a la intimitat. S&#8217;han seleccionat preferentment els fons borrosos i que destaquen el tema de la imatge. Per\u00f2 la col\u00b7lecci\u00f3 d&#8217;imatges realitzada, pot presentar inter\u00e8s dins d&#8217;unes d\u00e8cades&#8221;, conclou.<\/p>\n<h3><a href=\"https:\/\/photos.app.goo.gl\/HvKxnfD8nVVv8o3M6\" target=\"_blank\" rel=\"noopener noreferrer\">Veure totes les fotografies en alta qualitat<\/a><\/h3>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-90875 gallery-columns-3 gallery-size-full'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"675\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2020\/06\/fotos-Luis-Pons-4.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/raed.academy\/wp-content\/uploads\/2020\/06\/fotos-Luis-Pons-4.jpg 900w, https:\/\/raed.academy\/wp-content\/uploads\/2020\/06\/fotos-Luis-Pons-4-768x576.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"675\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2020\/06\/fotos-Luis-Pons-5.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/raed.academy\/wp-content\/uploads\/2020\/06\/fotos-Luis-Pons-5.jpg 900w, https:\/\/raed.academy\/wp-content\/uploads\/2020\/06\/fotos-Luis-Pons-5-768x576.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"675\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2020\/05\/fotos-Luis-Pons-8.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/raed.academy\/wp-content\/uploads\/2020\/05\/fotos-Luis-Pons-8.jpg 900w, https:\/\/raed.academy\/wp-content\/uploads\/2020\/05\/fotos-Luis-Pons-8-768x576.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"950\" height=\"712\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2020\/05\/fotos-Luis-Pons-9.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/raed.academy\/wp-content\/uploads\/2020\/05\/fotos-Luis-Pons-9.jpg 950w, https:\/\/raed.academy\/wp-content\/uploads\/2020\/05\/fotos-Luis-Pons-9-768x576.jpg 768w\" sizes=\"(max-width: 950px) 100vw, 950px\" \/>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"950\" height=\"712\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2020\/05\/fotos-Luis-Pons-10.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/raed.academy\/wp-content\/uploads\/2020\/05\/fotos-Luis-Pons-10.jpg 950w, https:\/\/raed.academy\/wp-content\/uploads\/2020\/05\/fotos-Luis-Pons-10-768x576.jpg 768w\" sizes=\"(max-width: 950px) 100vw, 950px\" \/>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"950\" height=\"712\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2020\/05\/fotos-Luis-Pons-11.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/raed.academy\/wp-content\/uploads\/2020\/05\/fotos-Luis-Pons-11.jpg 950w, https:\/\/raed.academy\/wp-content\/uploads\/2020\/05\/fotos-Luis-Pons-11-768x576.jpg 768w\" sizes=\"(max-width: 950px) 100vw, 950px\" \/>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2020\/05\/fotos-Luis-Pons-12.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/raed.academy\/wp-content\/uploads\/2020\/05\/fotos-Luis-Pons-12.jpg 1000w, https:\/\/raed.academy\/wp-content\/uploads\/2020\/05\/fotos-Luis-Pons-12-768x576.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"675\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2020\/05\/fotos-Luis-Pons-14.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/raed.academy\/wp-content\/uploads\/2020\/05\/fotos-Luis-Pons-14.jpg 900w, https:\/\/raed.academy\/wp-content\/uploads\/2020\/05\/fotos-Luis-Pons-14-768x576.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"950\" height=\"713\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2020\/05\/fotos-Luis-Pons-15.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/raed.academy\/wp-content\/uploads\/2020\/05\/fotos-Luis-Pons-15.jpg 950w, https:\/\/raed.academy\/wp-content\/uploads\/2020\/05\/fotos-Luis-Pons-15-768x576.jpg 768w\" sizes=\"(max-width: 950px) 100vw, 950px\" \/>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"970\" height=\"728\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2020\/05\/fotos-Luis-Pons-16.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/raed.academy\/wp-content\/uploads\/2020\/05\/fotos-Luis-Pons-16.jpg 970w, https:\/\/raed.academy\/wp-content\/uploads\/2020\/05\/fotos-Luis-Pons-16-768x576.jpg 768w\" sizes=\"(max-width: 970px) 100vw, 970px\" \/>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"675\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2020\/05\/fotos-Luis-Pons-19.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/raed.academy\/wp-content\/uploads\/2020\/05\/fotos-Luis-Pons-19.jpg 900w, https:\/\/raed.academy\/wp-content\/uploads\/2020\/05\/fotos-Luis-Pons-19-768x576.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"930\" height=\"698\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2020\/05\/fotos-Luis-Pons-20.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/raed.academy\/wp-content\/uploads\/2020\/05\/fotos-Luis-Pons-20.jpg 930w, https:\/\/raed.academy\/wp-content\/uploads\/2020\/05\/fotos-Luis-Pons-20-768x576.jpg 768w\" sizes=\"(max-width: 930px) 100vw, 930px\" \/>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"675\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2020\/05\/fotos-Luis-Pons-21.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/raed.academy\/wp-content\/uploads\/2020\/05\/fotos-Luis-Pons-21.jpg 900w, https:\/\/raed.academy\/wp-content\/uploads\/2020\/05\/fotos-Luis-Pons-21-768x576.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"870\" height=\"653\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2020\/05\/fotos-Luis-Pons-22.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/raed.academy\/wp-content\/uploads\/2020\/05\/fotos-Luis-Pons-22.jpg 870w, https:\/\/raed.academy\/wp-content\/uploads\/2020\/05\/fotos-Luis-Pons-22-768x576.jpg 768w\" sizes=\"(max-width: 870px) 100vw, 870px\" \/>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"675\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2020\/05\/fotos-Luis-Pons-23.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/raed.academy\/wp-content\/uploads\/2020\/05\/fotos-Luis-Pons-23.jpg 900w, https:\/\/raed.academy\/wp-content\/uploads\/2020\/05\/fotos-Luis-Pons-23-768x576.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Luis Pons Acad\u00e8mico corresponent de la Reial Acad\u00e8mia Europea de Doctors-Barcelona 1914 (RAED) Luis Pons, acad\u00e8mic corresponent de la Reial Acad\u00e8mia Europea de Doctors-Barcelona 1914 (RAED), torna a compartir amb els acad\u00e8mics i amics de la instituci\u00f3 la seva passi\u00f3 per la fotografia presentant la nova s\u00e8rie de instant\u00e0nies, aquest cop captades en una situaci\u00f3 [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":91094,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[268,275],"tags":[],"class_list":["post-90875","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coronavirus-des-del-coneixement","category-educacio-etica-i-valors","et-has-post-format-content","et_post_format-et-post-format-standard"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Imatges del confinament - Reial Acad\u00e8mia Europea de Doctors<\/title>\n<meta name=\"description\" content=\"Luis Pons presenta la seva nova s\u00e8rie d&#039;instant\u00e0nies, aquest cop captades en una situaci\u00f3 diferent i \u00fanica: el confinament per la pand\u00e8mia de la Covid-19\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/raed.academy\/ca\/imatges-del-confinament-luis-pons\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Imatges del confinament - Reial Acad\u00e8mia Europea de Doctors\" \/>\n<meta property=\"og:description\" content=\"Luis Pons presenta la seva nova s\u00e8rie d&#039;instant\u00e0nies, aquest cop captades en una situaci\u00f3 diferent i \u00fanica: el confinament per la pand\u00e8mia de la Covid-19\" \/>\n<meta property=\"og:url\" content=\"https:\/\/raed.academy\/ca\/imatges-del-confinament-luis-pons\/\" \/>\n<meta property=\"og:site_name\" content=\"Reial Acad\u00e8mia Europea de Doctors\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/fb.me\/raed.academy\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-01T10:28:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-06T13:15:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/raed.academy\/wp-content\/uploads\/2020\/06\/fotos-Luis-Pons-13-dst.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"420\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"RAED\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@raedacademy\" \/>\n<meta name=\"twitter:site\" content=\"@raedacademy\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"RAED\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/imatges-del-confinament-luis-pons\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/imatges-del-confinament-luis-pons\\\/\"},\"author\":{\"name\":\"RAED\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/person\\\/5a755da80d1d979fd66ba745c8702927\"},\"headline\":\"Imatges del confinament\",\"datePublished\":\"2020-06-01T10:28:41+00:00\",\"dateModified\":\"2020-06-06T13:15:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/imatges-del-confinament-luis-pons\\\/\"},\"wordCount\":414,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/imatges-del-confinament-luis-pons\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/fotos-Luis-Pons-13-dst.jpg\",\"articleSection\":[\"Coronavirus des del coneixement\",\"Educaci\u00f3, \u00e8tica i valors\"],\"inLanguage\":\"ca-ES\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/raed.academy\\\/ca\\\/imatges-del-confinament-luis-pons\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/imatges-del-confinament-luis-pons\\\/\",\"url\":\"https:\\\/\\\/raed.academy\\\/ca\\\/imatges-del-confinament-luis-pons\\\/\",\"name\":\"Imatges del confinament - Reial Acad\u00e8mia Europea de Doctors\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/imatges-del-confinament-luis-pons\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/imatges-del-confinament-luis-pons\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/fotos-Luis-Pons-13-dst.jpg\",\"datePublished\":\"2020-06-01T10:28:41+00:00\",\"dateModified\":\"2020-06-06T13:15:04+00:00\",\"description\":\"Luis Pons presenta la seva nova s\u00e8rie d'instant\u00e0nies, aquest cop captades en una situaci\u00f3 diferent i \u00fanica: el confinament per la pand\u00e8mia de la Covid-19\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/imatges-del-confinament-luis-pons\\\/#breadcrumb\"},\"inLanguage\":\"ca-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/raed.academy\\\/ca\\\/imatges-del-confinament-luis-pons\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/imatges-del-confinament-luis-pons\\\/#primaryimage\",\"url\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/fotos-Luis-Pons-13-dst.jpg\",\"contentUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/fotos-Luis-Pons-13-dst.jpg\",\"width\":1000,\"height\":420},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/imatges-del-confinament-luis-pons\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/raed.academy\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Imatges del confinament\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/raed.academy\\\/ca\\\/\",\"name\":\"Reial Acad\u00e8mia Europea de Doctors\",\"description\":\"Corporaci\u00f3n de derecho p\u00fablico de car\u00e1cter cient\u00edfico, t\u00e9cnico y art\u00edstico, que tiene por objeto la investigaci\u00f3n, el estudio, el fomento y la extensi\u00f3n del conocimiento en su sentido m\u00e1s amplio\",\"publisher\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/raed.academy\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#organization\",\"name\":\"Real Academia Europea de Doctores\",\"url\":\"https:\\\/\\\/raed.academy\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/cropped-logo_raed.png\",\"contentUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/cropped-logo_raed.png\",\"width\":512,\"height\":512,\"caption\":\"Real Academia Europea de Doctores\"},\"image\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/fb.me\\\/raed.academy\",\"https:\\\/\\\/x.com\\\/raedacademy\",\"https:\\\/\\\/www.instagram.com\\\/raed.academy\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCUYQwW2KrdirNWihxMDObwg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/person\\\/5a755da80d1d979fd66ba745c8702927\",\"name\":\"RAED\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g\",\"caption\":\"RAED\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Imatges del confinament - Reial Acad\u00e8mia Europea de Doctors","description":"Luis Pons presenta la seva nova s\u00e8rie d'instant\u00e0nies, aquest cop captades en una situaci\u00f3 diferent i \u00fanica: el confinament per la pand\u00e8mia de la Covid-19","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/raed.academy\/ca\/imatges-del-confinament-luis-pons\/","og_locale":"ca_ES","og_type":"article","og_title":"Imatges del confinament - Reial Acad\u00e8mia Europea de Doctors","og_description":"Luis Pons presenta la seva nova s\u00e8rie d'instant\u00e0nies, aquest cop captades en una situaci\u00f3 diferent i \u00fanica: el confinament per la pand\u00e8mia de la Covid-19","og_url":"https:\/\/raed.academy\/ca\/imatges-del-confinament-luis-pons\/","og_site_name":"Reial Acad\u00e8mia Europea de Doctors","article_publisher":"http:\/\/fb.me\/raed.academy","article_published_time":"2020-06-01T10:28:41+00:00","article_modified_time":"2020-06-06T13:15:04+00:00","og_image":[{"width":1000,"height":420,"url":"https:\/\/raed.academy\/wp-content\/uploads\/2020\/06\/fotos-Luis-Pons-13-dst.jpg","type":"image\/jpeg"}],"author":"RAED","twitter_card":"summary_large_image","twitter_creator":"@raedacademy","twitter_site":"@raedacademy","twitter_misc":{"Written by":"RAED","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/raed.academy\/ca\/imatges-del-confinament-luis-pons\/#article","isPartOf":{"@id":"https:\/\/raed.academy\/ca\/imatges-del-confinament-luis-pons\/"},"author":{"name":"RAED","@id":"https:\/\/raed.academy\/ca\/#\/schema\/person\/5a755da80d1d979fd66ba745c8702927"},"headline":"Imatges del confinament","datePublished":"2020-06-01T10:28:41+00:00","dateModified":"2020-06-06T13:15:04+00:00","mainEntityOfPage":{"@id":"https:\/\/raed.academy\/ca\/imatges-del-confinament-luis-pons\/"},"wordCount":414,"commentCount":0,"publisher":{"@id":"https:\/\/raed.academy\/ca\/#organization"},"image":{"@id":"https:\/\/raed.academy\/ca\/imatges-del-confinament-luis-pons\/#primaryimage"},"thumbnailUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2020\/06\/fotos-Luis-Pons-13-dst.jpg","articleSection":["Coronavirus des del coneixement","Educaci\u00f3, \u00e8tica i valors"],"inLanguage":"ca-ES","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/raed.academy\/ca\/imatges-del-confinament-luis-pons\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/raed.academy\/ca\/imatges-del-confinament-luis-pons\/","url":"https:\/\/raed.academy\/ca\/imatges-del-confinament-luis-pons\/","name":"Imatges del confinament - Reial Acad\u00e8mia Europea de Doctors","isPartOf":{"@id":"https:\/\/raed.academy\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/raed.academy\/ca\/imatges-del-confinament-luis-pons\/#primaryimage"},"image":{"@id":"https:\/\/raed.academy\/ca\/imatges-del-confinament-luis-pons\/#primaryimage"},"thumbnailUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2020\/06\/fotos-Luis-Pons-13-dst.jpg","datePublished":"2020-06-01T10:28:41+00:00","dateModified":"2020-06-06T13:15:04+00:00","description":"Luis Pons presenta la seva nova s\u00e8rie d'instant\u00e0nies, aquest cop captades en una situaci\u00f3 diferent i \u00fanica: el confinament per la pand\u00e8mia de la Covid-19","breadcrumb":{"@id":"https:\/\/raed.academy\/ca\/imatges-del-confinament-luis-pons\/#breadcrumb"},"inLanguage":"ca-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/raed.academy\/ca\/imatges-del-confinament-luis-pons\/"]}]},{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/raed.academy\/ca\/imatges-del-confinament-luis-pons\/#primaryimage","url":"https:\/\/raed.academy\/wp-content\/uploads\/2020\/06\/fotos-Luis-Pons-13-dst.jpg","contentUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2020\/06\/fotos-Luis-Pons-13-dst.jpg","width":1000,"height":420},{"@type":"BreadcrumbList","@id":"https:\/\/raed.academy\/ca\/imatges-del-confinament-luis-pons\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/raed.academy\/ca\/"},{"@type":"ListItem","position":2,"name":"Imatges del confinament"}]},{"@type":"WebSite","@id":"https:\/\/raed.academy\/ca\/#website","url":"https:\/\/raed.academy\/ca\/","name":"Reial Acad\u00e8mia Europea de Doctors","description":"Corporaci\u00f3n de derecho p\u00fablico de car\u00e1cter cient\u00edfico, t\u00e9cnico y art\u00edstico, que tiene por objeto la investigaci\u00f3n, el estudio, el fomento y la extensi\u00f3n del conocimiento en su sentido m\u00e1s amplio","publisher":{"@id":"https:\/\/raed.academy\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/raed.academy\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca-ES"},{"@type":"Organization","@id":"https:\/\/raed.academy\/ca\/#organization","name":"Real Academia Europea de Doctores","url":"https:\/\/raed.academy\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/raed.academy\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/raed.academy\/wp-content\/uploads\/2017\/01\/cropped-logo_raed.png","contentUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2017\/01\/cropped-logo_raed.png","width":512,"height":512,"caption":"Real Academia Europea de Doctores"},"image":{"@id":"https:\/\/raed.academy\/ca\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/fb.me\/raed.academy","https:\/\/x.com\/raedacademy","https:\/\/www.instagram.com\/raed.academy\/","https:\/\/www.youtube.com\/channel\/UCUYQwW2KrdirNWihxMDObwg"]},{"@type":"Person","@id":"https:\/\/raed.academy\/ca\/#\/schema\/person\/5a755da80d1d979fd66ba745c8702927","name":"RAED","image":{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g","caption":"RAED"}}]}},"_links":{"self":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/posts\/90875","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/comments?post=90875"}],"version-history":[{"count":0,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/posts\/90875\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/media\/91094"}],"wp:attachment":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/media?parent=90875"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/categories?post=90875"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/tags?post=90875"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}