{"id":87086,"date":"2020-02-13T21:46:17","date_gmt":"2020-02-13T21:46:17","guid":{"rendered":"https:\/\/raed.academy\/?p=87086"},"modified":"2020-02-14T09:20:37","modified_gmt":"2020-02-14T09:20:37","slug":"la-malaltia-a-la-prehistoria-balear","status":"publish","type":"post","link":"https:\/\/raed.academy\/ca\/la-malaltia-a-la-prehistoria-balear\/","title":{"rendered":"La malaltia a la prehist\u00f2ria balear"},"content":{"rendered":"<h2>Daniel Turb\u00f3n publica un detallat estudi sobre els cranis d&#8217;una necr\u00f2polis talai\u00f2tica de Mallorca<\/h2>\n<div id=\"attachment_86935\" style=\"width: 230px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-86935\" class=\"wp-image-86935\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2020\/02\/Daniel-Turbon.jpg\" alt=\"Dr. Daniel Turb\u00f3n\" width=\"220\" height=\"329\" aria-describedby=\"caption-attachment-86935\" data-attachment-id=\"86935\" data-permalink=\"https:\/\/raed.academy\/la-enfermedad-en-la-prehistoria-balear-daniel-turbon\/daniel-turbon-3\/\" data-orig-file=\"https:\/\/raed.academy\/wp-content\/uploads\/2020\/02\/Daniel-Turbon.jpg\" data-orig-size=\"270,404\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Daniel-Turbon\" data-image-description=\"\" data-medium-file=\"https:\/\/raed.academy\/wp-content\/uploads\/2020\/02\/Daniel-Turbon.jpg\" data-large-file=\"https:\/\/raed.academy\/wp-content\/uploads\/2020\/02\/Daniel-Turbon.jpg\" \/><p id=\"caption-attachment-86935\" class=\"wp-caption-text\">Dr. Daniel Turb\u00f3n<\/p><\/div>\n<p><a href=\"https:\/\/raed.academy\/ca\/academics\/dr-daniel-turbon-borrega\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Daniel Turb\u00f3n<\/strong><\/a>, catedr\u00e0tic em\u00e8rit d&#8217;Antropologia F\u00edsica de la <a href=\"http:\/\/www.ub.edu\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Universitat de Barcelona<\/strong><\/a> i acad\u00e8mic de n\u00famero de la <strong>Reial Acad\u00e8mia Europea de Doctors-Barcelona 1914<\/strong> (RAED), ha publicat a l&#8217;\u00faltim n\u00famero de la revista <strong>&#8220;Pyrenae&#8221;<\/strong>, referent de la Prehist\u00f2ria i la Hist\u00f2ria Antiga de la Mediterr\u00e0nia occidental, l&#8217;estudi <strong>&#8220;Paleopatolog\u00eda craneal de la necr\u00f3polis talay\u00f3tica de Son Real (Mallorca)&#8221;<\/strong>, que ha fet al costat dels reconeguts especialistes en Paleoantropologia <strong>Dom\u00e8nec Campillo<\/strong>, cient\u00edfic de reconegut prestigi internacional al camp de l&#8217;estudi de les malalties antigues, i <strong>Miguel Botella<\/strong>, catedr\u00e0tic d&#8217;Antropologia F\u00edsica de la <a href=\"http:\/\/www.ugr.es\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Universitat de Granada<\/strong><\/a>. En aquest treball s&#8217;estudien nou casos in\u00e8dits de patologia cranial d&#8217;aquesta necr\u00f2polis que daten dels segles VII al II abans de la nostra era.<\/p>\n<p>El nou material s&#8217;afegeix als casos anteriorment documentats per Campillo el 1977 i el 2007 i documenta un cas de neopl\u00e0sia maligna o histiocitosis, malalties escassament provades en aquest per\u00edode. D&#8217;altra banda, es recullen en dues taules tots els casos descrits de patologia cranial d&#8217;aquesta necr\u00f2polis bale\u00e0rica. Els investigadors pretenen oferir aix\u00ed un panorama de conjunt, a m\u00e9s de la seva discussi\u00f3, d&#8217;inter\u00e8s tant per als especialistes com per al p\u00fablic en general. Destaca tant l&#8217;elevat percentatge d&#8217;erosions cranials superades pels individus com l&#8217;elevat \u00edndex d&#8217;intervenci\u00f3 humana als cranis mitjan\u00e7ant trepanacions.<\/p>\n<div id=\"attachment_86938\" style=\"width: 560px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-86938\" class=\"wp-image-86938 size-full\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2020\/02\/Paleopatologia-craneal-de-la-necropolis-talayotica-de-Son-Real-Mallorca.jpg\" alt=\"Son Real 28-2. Neoplasia maligna, posible histiocitosis.\" width=\"550\" height=\"419\" aria-describedby=\"caption-attachment-86938\" data-attachment-id=\"86938\" data-permalink=\"https:\/\/raed.academy\/la-enfermedad-en-la-prehistoria-balear-daniel-turbon\/paleopatologia-craneal-de-la-necropolis-talayotica-de-son-real-mallorca\/\" data-orig-file=\"https:\/\/raed.academy\/wp-content\/uploads\/2020\/02\/Paleopatologia-craneal-de-la-necropolis-talayotica-de-Son-Real-Mallorca.jpg\" data-orig-size=\"550,419\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Paleopatologia-craneal-de-la-necropolis-talayotica-de Son-Real-Mallorca\" data-image-description=\"\" data-medium-file=\"https:\/\/raed.academy\/wp-content\/uploads\/2020\/02\/Paleopatologia-craneal-de-la-necropolis-talayotica-de-Son-Real-Mallorca.jpg\" data-large-file=\"https:\/\/raed.academy\/wp-content\/uploads\/2020\/02\/Paleopatologia-craneal-de-la-necropolis-talayotica-de-Son-Real-Mallorca.jpg\" \/><p id=\"caption-attachment-86938\" class=\"wp-caption-text\">Son Real 28-2. Neopl\u00e0sia maligna, possible histiocitosis.<\/p><\/div>\n<p>&#8220;De les lesions paleopatol\u00f2giques aportades al present article algunes ja havien estat descrites per Campillo; altres afeccions s\u00f3n in\u00e8dites i no registrades a Son Real fins avui. Per exemple, una lesi\u00f3 metast\u00e0tica que tamb\u00e9 podria ser una histiocitosis. A m\u00e9s, hi ha un cas d&#8217;otitis amb erosi\u00f3 del conducte auditiu extern, un traumatisme cranial; diverses erosions cranials, una d&#8217;elles per traumatisme, una altra amb sobreinfecci\u00f3 posttraum\u00e0tica, causant una sinusitis, aix\u00ed com diverses afeccions mandibulars, com ara un cas d&#8217;artropatia degenerativa en ambd\u00f3s c\u00f2ndils mandibulars amb reacci\u00f3 exostosant; un quist radicular; oste\u00eftis amb reabsorci\u00f3 i variants poc freq\u00fcents a les dents. Aquesta necr\u00f2polis \u00e9s el m\u00e9s important conjunt d&#8217;enterraments, pel nombre de tombes i pel 8% de trepanacions registrades a la Mediterr\u00e0nia occidental. Aquest percentatge \u00e9s el m\u00e9s alt conegut per l&#8217;Occident europeu d&#8217;aquesta \u00e8poca fins ara descrit&#8221;, destaca l&#8217;estudi a les seves conclusions.<\/p>\n<p>Turb\u00f3n \u00e9s coordinador del <strong>Grup d&#8217;Innovaci\u00f3 Docent de Biologia i Cultura<\/strong> de la Universitat de Barcelona. Com a investigador ha liderat 16 projectes, set d&#8217;ells de biologia molecular. Actualment investiga l&#8217;origen del creixement i desenvolupament humans. Ha publicat 241 treballs cient\u00edfics i \u00e9s autor, entre d&#8217;altres, de llibres de refer\u00e8ncia com ara <strong>&#8220;La evoluci\u00f3n hu\u00admana&#8221;<\/strong> (Ariel, 2006) i <strong>&#8220;Darwin y el mono&#8221;<\/strong> (Sello Editorial, 2009).<\/p>\n<h3><a href=\"http:\/\/www.pyrenae.com\/home\/index.php?option=com_k2&amp;view=item&amp;id=338:paleopatologia-craneal-de-la-necropolis-talayotica-de-son-real-mallorca&amp;Itemid=268&amp;lang=es\" target=\"_blank\" rel=\"noopener noreferrer\">Article a Pyrenae<\/a><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Daniel Turb\u00f3n publica un detallat estudi sobre els cranis d&#8217;una necr\u00f2polis talai\u00f2tica de Mallorca Daniel Turb\u00f3n, catedr\u00e0tic em\u00e8rit d&#8217;Antropologia F\u00edsica de la Universitat de Barcelona i acad\u00e8mic de n\u00famero de la Reial Acad\u00e8mia Europea de Doctors-Barcelona 1914 (RAED), ha publicat a l&#8217;\u00faltim n\u00famero de la revista &#8220;Pyrenae&#8221;, referent de la Prehist\u00f2ria i la Hist\u00f2ria Antiga [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":86933,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[247],"tags":[],"class_list":["post-87086","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-antropologia-ca","et-has-post-format-content","et_post_format-et-post-format-standard"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La malaltia a la prehist\u00f2ria balear - Reial Acad\u00e8mia Europea de Doctors<\/title>\n<meta name=\"description\" content=\"Daniel Turb\u00f3n publica un detallat estudi sobre els cranis d&#039;una necr\u00f2polis talai\u00f2tica de Mallorca\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/raed.academy\/ca\/la-malaltia-a-la-prehistoria-balear\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La malaltia a la prehist\u00f2ria balear - Reial Acad\u00e8mia Europea de Doctors\" \/>\n<meta property=\"og:description\" content=\"Daniel Turb\u00f3n publica un detallat estudi sobre els cranis d&#039;una necr\u00f2polis talai\u00f2tica de Mallorca\" \/>\n<meta property=\"og:url\" content=\"https:\/\/raed.academy\/ca\/la-malaltia-a-la-prehistoria-balear\/\" \/>\n<meta property=\"og:site_name\" content=\"Reial Acad\u00e8mia Europea de Doctors\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/fb.me\/raed.academy\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-13T21:46:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-14T09:20:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/raed.academy\/wp-content\/uploads\/2020\/02\/Crane-trepanation-dst.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"420\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"RAED\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@raedacademy\" \/>\n<meta name=\"twitter:site\" content=\"@raedacademy\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"RAED\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/la-malaltia-a-la-prehistoria-balear\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/la-malaltia-a-la-prehistoria-balear\\\/\"},\"author\":{\"name\":\"RAED\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/person\\\/5a755da80d1d979fd66ba745c8702927\"},\"headline\":\"La malaltia a la prehist\u00f2ria balear\",\"datePublished\":\"2020-02-13T21:46:17+00:00\",\"dateModified\":\"2020-02-14T09:20:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/la-malaltia-a-la-prehistoria-balear\\\/\"},\"wordCount\":534,\"publisher\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/la-malaltia-a-la-prehistoria-balear\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Crane-trepanation-dst.jpg\",\"articleSection\":[\"Antropologia\"],\"inLanguage\":\"ca-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/la-malaltia-a-la-prehistoria-balear\\\/\",\"url\":\"https:\\\/\\\/raed.academy\\\/ca\\\/la-malaltia-a-la-prehistoria-balear\\\/\",\"name\":\"La malaltia a la prehist\u00f2ria balear - Reial Acad\u00e8mia Europea de Doctors\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/la-malaltia-a-la-prehistoria-balear\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/la-malaltia-a-la-prehistoria-balear\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Crane-trepanation-dst.jpg\",\"datePublished\":\"2020-02-13T21:46:17+00:00\",\"dateModified\":\"2020-02-14T09:20:37+00:00\",\"description\":\"Daniel Turb\u00f3n publica un detallat estudi sobre els cranis d'una necr\u00f2polis talai\u00f2tica de Mallorca\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/la-malaltia-a-la-prehistoria-balear\\\/#breadcrumb\"},\"inLanguage\":\"ca-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/raed.academy\\\/ca\\\/la-malaltia-a-la-prehistoria-balear\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/la-malaltia-a-la-prehistoria-balear\\\/#primaryimage\",\"url\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Crane-trepanation-dst.jpg\",\"contentUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Crane-trepanation-dst.jpg\",\"width\":1000,\"height\":420},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/la-malaltia-a-la-prehistoria-balear\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/raed.academy\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La malaltia a la prehist\u00f2ria balear\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/raed.academy\\\/ca\\\/\",\"name\":\"Reial Acad\u00e8mia Europea de Doctors\",\"description\":\"Corporaci\u00f3n de derecho p\u00fablico de car\u00e1cter cient\u00edfico, t\u00e9cnico y art\u00edstico, que tiene por objeto la investigaci\u00f3n, el estudio, el fomento y la extensi\u00f3n del conocimiento en su sentido m\u00e1s amplio\",\"publisher\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/raed.academy\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#organization\",\"name\":\"Real Academia Europea de Doctores\",\"url\":\"https:\\\/\\\/raed.academy\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/cropped-logo_raed.png\",\"contentUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/cropped-logo_raed.png\",\"width\":512,\"height\":512,\"caption\":\"Real Academia Europea de Doctores\"},\"image\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/fb.me\\\/raed.academy\",\"https:\\\/\\\/x.com\\\/raedacademy\",\"https:\\\/\\\/www.instagram.com\\\/raed.academy\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCUYQwW2KrdirNWihxMDObwg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/person\\\/5a755da80d1d979fd66ba745c8702927\",\"name\":\"RAED\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g\",\"caption\":\"RAED\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La malaltia a la prehist\u00f2ria balear - Reial Acad\u00e8mia Europea de Doctors","description":"Daniel Turb\u00f3n publica un detallat estudi sobre els cranis d'una necr\u00f2polis talai\u00f2tica de Mallorca","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/raed.academy\/ca\/la-malaltia-a-la-prehistoria-balear\/","og_locale":"ca_ES","og_type":"article","og_title":"La malaltia a la prehist\u00f2ria balear - Reial Acad\u00e8mia Europea de Doctors","og_description":"Daniel Turb\u00f3n publica un detallat estudi sobre els cranis d'una necr\u00f2polis talai\u00f2tica de Mallorca","og_url":"https:\/\/raed.academy\/ca\/la-malaltia-a-la-prehistoria-balear\/","og_site_name":"Reial Acad\u00e8mia Europea de Doctors","article_publisher":"http:\/\/fb.me\/raed.academy","article_published_time":"2020-02-13T21:46:17+00:00","article_modified_time":"2020-02-14T09:20:37+00:00","og_image":[{"width":1000,"height":420,"url":"https:\/\/raed.academy\/wp-content\/uploads\/2020\/02\/Crane-trepanation-dst.jpg","type":"image\/jpeg"}],"author":"RAED","twitter_card":"summary_large_image","twitter_creator":"@raedacademy","twitter_site":"@raedacademy","twitter_misc":{"Written by":"RAED","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/raed.academy\/ca\/la-malaltia-a-la-prehistoria-balear\/#article","isPartOf":{"@id":"https:\/\/raed.academy\/ca\/la-malaltia-a-la-prehistoria-balear\/"},"author":{"name":"RAED","@id":"https:\/\/raed.academy\/ca\/#\/schema\/person\/5a755da80d1d979fd66ba745c8702927"},"headline":"La malaltia a la prehist\u00f2ria balear","datePublished":"2020-02-13T21:46:17+00:00","dateModified":"2020-02-14T09:20:37+00:00","mainEntityOfPage":{"@id":"https:\/\/raed.academy\/ca\/la-malaltia-a-la-prehistoria-balear\/"},"wordCount":534,"publisher":{"@id":"https:\/\/raed.academy\/ca\/#organization"},"image":{"@id":"https:\/\/raed.academy\/ca\/la-malaltia-a-la-prehistoria-balear\/#primaryimage"},"thumbnailUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2020\/02\/Crane-trepanation-dst.jpg","articleSection":["Antropologia"],"inLanguage":"ca-ES"},{"@type":"WebPage","@id":"https:\/\/raed.academy\/ca\/la-malaltia-a-la-prehistoria-balear\/","url":"https:\/\/raed.academy\/ca\/la-malaltia-a-la-prehistoria-balear\/","name":"La malaltia a la prehist\u00f2ria balear - Reial Acad\u00e8mia Europea de Doctors","isPartOf":{"@id":"https:\/\/raed.academy\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/raed.academy\/ca\/la-malaltia-a-la-prehistoria-balear\/#primaryimage"},"image":{"@id":"https:\/\/raed.academy\/ca\/la-malaltia-a-la-prehistoria-balear\/#primaryimage"},"thumbnailUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2020\/02\/Crane-trepanation-dst.jpg","datePublished":"2020-02-13T21:46:17+00:00","dateModified":"2020-02-14T09:20:37+00:00","description":"Daniel Turb\u00f3n publica un detallat estudi sobre els cranis d'una necr\u00f2polis talai\u00f2tica de Mallorca","breadcrumb":{"@id":"https:\/\/raed.academy\/ca\/la-malaltia-a-la-prehistoria-balear\/#breadcrumb"},"inLanguage":"ca-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/raed.academy\/ca\/la-malaltia-a-la-prehistoria-balear\/"]}]},{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/raed.academy\/ca\/la-malaltia-a-la-prehistoria-balear\/#primaryimage","url":"https:\/\/raed.academy\/wp-content\/uploads\/2020\/02\/Crane-trepanation-dst.jpg","contentUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2020\/02\/Crane-trepanation-dst.jpg","width":1000,"height":420},{"@type":"BreadcrumbList","@id":"https:\/\/raed.academy\/ca\/la-malaltia-a-la-prehistoria-balear\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/raed.academy\/ca\/"},{"@type":"ListItem","position":2,"name":"La malaltia a la prehist\u00f2ria balear"}]},{"@type":"WebSite","@id":"https:\/\/raed.academy\/ca\/#website","url":"https:\/\/raed.academy\/ca\/","name":"Reial Acad\u00e8mia Europea de Doctors","description":"Corporaci\u00f3n de derecho p\u00fablico de car\u00e1cter cient\u00edfico, t\u00e9cnico y art\u00edstico, que tiene por objeto la investigaci\u00f3n, el estudio, el fomento y la extensi\u00f3n del conocimiento en su sentido m\u00e1s amplio","publisher":{"@id":"https:\/\/raed.academy\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/raed.academy\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca-ES"},{"@type":"Organization","@id":"https:\/\/raed.academy\/ca\/#organization","name":"Real Academia Europea de Doctores","url":"https:\/\/raed.academy\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/raed.academy\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/raed.academy\/wp-content\/uploads\/2017\/01\/cropped-logo_raed.png","contentUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2017\/01\/cropped-logo_raed.png","width":512,"height":512,"caption":"Real Academia Europea de Doctores"},"image":{"@id":"https:\/\/raed.academy\/ca\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/fb.me\/raed.academy","https:\/\/x.com\/raedacademy","https:\/\/www.instagram.com\/raed.academy\/","https:\/\/www.youtube.com\/channel\/UCUYQwW2KrdirNWihxMDObwg"]},{"@type":"Person","@id":"https:\/\/raed.academy\/ca\/#\/schema\/person\/5a755da80d1d979fd66ba745c8702927","name":"RAED","image":{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g","caption":"RAED"}}]}},"_links":{"self":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/posts\/87086","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/comments?post=87086"}],"version-history":[{"count":0,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/posts\/87086\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/media\/86933"}],"wp:attachment":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/media?parent=87086"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/categories?post=87086"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/tags?post=87086"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}