{"id":68907,"date":"2019-03-20T23:31:54","date_gmt":"2019-03-20T23:31:54","guid":{"rendered":"https:\/\/raed.academy\/?p=68907"},"modified":"2019-03-22T11:56:36","modified_gmt":"2019-03-22T11:56:36","slug":"acer-biomaterials-grafe-ingres-josep-maria-guilemany-raed","status":"publish","type":"post","link":"https:\/\/raed.academy\/ca\/acer-biomaterials-grafe-ingres-josep-maria-guilemany-raed\/","title":{"rendered":"De l&#8217;acer als biomaterials i al graf\u00e8"},"content":{"rendered":"<h2>Josep Maria Guilemany, art\u00edfex de la creaci\u00f3 del Departament de Ci\u00e8ncia dels Materials de la Universitat de Barcelona, \u200b\u200bingressa com a acad\u00e8mic<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-68817\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2019\/03\/acto-ingreso-RAED-Josep-Maria-Guilemany-9.jpg\" alt=\"Dr. Josep Maria Guilemany\" width=\"310\" height=\"465\" \/><a href=\"https:\/\/raed.academy\/ca\/academics\/dr-josep-maria-guilemany-casadamon\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Josep Maria Guilemany<\/strong><\/a>, doctor en Ci\u00e8ncies Qu\u00edmiques i catedr\u00e0tic de Ci\u00e8ncia dels Materials i Enginyeria Metal\u00b7l\u00fargica a la <a href=\"http:\/\/www.ub.edu\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Universitat de Barcelona<\/strong><\/a>, \u200b\u200bva ingressar com a acad\u00e8mic de n\u00famero de la <strong>Reial Acad\u00e8mia Europea de Doctors-Barcelona 1914<\/strong> (RAED) durant una cerim\u00f2nia que es va celebrar el passat 19 de mar\u00e7 a la Sala d&#8217;Actes de <a href=\"http:\/\/www.foment.com\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Foment del Treball Nacional<\/strong><\/a>, seu de la RAED. El recipiendari va llegir el discurs d&#8217;ingr\u00e9s <strong>&#8220;De la belleza de los materiales a las artes y las tecnolog\u00edas avanzadas para la sociedad innovadora del siglo XXI&#8221;<\/strong>. Li va respondre en nom de la Reial Corporaci\u00f3 l&#8217;acad\u00e8mic de n\u00famero i rector de la <a href=\"http:\/\/www.uic.es\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Universitat Internacional de Catalunya<\/strong><\/a> <a href=\"https:\/\/raed.academy\/ca\/academics\/dr-javier-gil-mur\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Javier Gil<\/strong><\/a>.<\/p>\n<p>Al seu treball, el nou acad\u00e8mic, art\u00edfex de la creaci\u00f3 del Departament de Ci\u00e8ncia dels Materials i Enginyeria Metal\u00b7l\u00fargica de la Universitat de Barcelona i el seu director, fa una completa descripci\u00f3 dels materials que es fan servir avui dia per les m\u00e9s diverses funcions, des de l&#8217;amplitud de mires que li atorguen les seves gaireb\u00e9 quatre d\u00e8cades dedicades al m\u00f3n de l&#8217;empresa i la doc\u00e8ncia. En aquest sentit, incideix en la import\u00e0ncia cabdal que adquireix a Espanya la producci\u00f3 i manipulaci\u00f3 de molts d&#8217;aquests materials.<\/p>\n<p>&#8220;Que els materials s\u00f3n imprescindibles a la societat actual resulta evident, ja que n&#8217;hi ha prou amb nom\u00e9s mirar al nostre voltant i adonar-nos que vivim en un m\u00f3n envoltat de materials. En efecte, escrit est\u00e0 que una part important de l&#8217;avan\u00e7 econ\u00f2mic i t\u00e8cnic-social d&#8217;un pa\u00eds dep\u00e8n del seu nivell en Enginyeria de Materials, juntament amb el desenvolupament de les seves capacitats energ\u00e8tiques i de les Ci\u00e8ncies de la Informaci\u00f3&#8221;, inicia Guilemany la seva reflexi\u00f3.<\/p>\n<p>Despr\u00e9s de repassar i enumerar les caracter\u00edstiques de materials cl\u00e0ssics i fonamentals en el desenvolupament i particularment en l&#8217;\u00e8poca industrial, com l&#8217;acer i les foses, aliatges lleugers, els superaliatges, els cer\u00e0mics, els superconductors i els pol\u00edmers, el nou acad\u00e8mic incideix en els nous materials estrat\u00e8gics com ara els biomaterials, els materials per a la generaci\u00f3 d&#8217;energies alternatives, els materials per a l&#8217;esport, l&#8217;oci i la ind\u00fastria 4.0. Sense deixar d&#8217;apuntar els reptes de la societat innovadora del segle XXI.<\/p>\n<div class=\"subtituloIz\" style=\"width: 400px;\"><span>\u201c<\/span>En efecte, escrit est\u00e0 que una part important de l&#8217;avan\u00e7 econ\u00f2mic i t\u00e8cnic-social d&#8217;un pa\u00eds dep\u00e8n del seu nivell en Enginyeria de Materials, juntament amb el desenvolupament de les seves capacitats energ\u00e8tiques i de les Ci\u00e8ncies de la Informaci\u00f3&#8221;<\/div>\n<p>&#8220;Al llarg dels \u00faltims cinquanta anys s&#8217;ha treballat en l&#8217;obtenci\u00f3 i processat dels materials estructurals tradicionals, en el coneixement i interpretaci\u00f3 de la seva estructura en estat s\u00f2lid i comprensi\u00f3 de les seves propietats per a una aplicaci\u00f3 en noves fronteres de la tecnologia. Comunament els materials met\u00e0l\u00b7lics han ocupat el centre de gravetat i dels seus coneixements profunds sobre la base cient\u00edfica se&#8217;ls ha caracteritzat i constru\u00eft un m\u00f3n sorprenent de materials en els quals, avui dia, met\u00e0l\u00b7lics, cer\u00e0mics, pol\u00edmers i els seus compostos conjuguen i competeixen dins del seus abast respectiu i limitacions en les aplicacions tecnol\u00f2giques m\u00e9s avan\u00e7ades. Estem vinculats a materials superconductors, noves classes de materials semiconductors i magn\u00e8tics, materials per a aplicacions m\u00e8diques en escales micro i manom\u00e8triques, materials per a la generaci\u00f3 de noves fonts d&#8217;energia alternativa, materials amb aplicacions biomim\u00e8tiques que tracten de reproduir pell humana, m\u00fasculs, ossos, fins i tot es diu neurones. Aquestes s\u00f3n algunes de les noves fronteres en el nostre m\u00f3n i la Ci\u00e8ncia i Enginyeria dels Materials ocupa el centre de gravetat d&#8217;aquesta r\u00e0pida i imparable evoluci\u00f3&#8221;, assegura.<\/p>\n<h3><a href=\"https:\/\/raed.academy\/\/wp-content\/uploads\/publicaciones\/discursos-ingreso\/Discurso-ingreso-Josep-Maria-Guilemany-De-la-belleza-de-los-materiales-a-las-artes-compr.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Discurs d&#8217;ingr\u00e9s<\/a><\/h3>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 25%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-68907 gallery-columns-4 gallery-size-medium'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/raed.academy\/wp-content\/uploads\/2019\/03\/acto-ingreso-RAED-Josep-Maria-Guilemany-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"850\" height=\"567\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2019\/03\/acto-ingreso-RAED-Josep-Maria-Guilemany-2.jpg\" class=\"attachment-medium size-medium\" alt=\"Acte d&#039;ingr\u00e9s a la RAED del Dr. Josep Maria Guilemany\" srcset=\"https:\/\/raed.academy\/wp-content\/uploads\/2019\/03\/acto-ingreso-RAED-Josep-Maria-Guilemany-2.jpg 850w, https:\/\/raed.academy\/wp-content\/uploads\/2019\/03\/acto-ingreso-RAED-Josep-Maria-Guilemany-2-768x512.jpg 768w\" sizes=\"(max-width: 850px) 100vw, 850px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/raed.academy\/wp-content\/uploads\/2019\/03\/acto-ingreso-RAED-Josep-Maria-Guilemany-3.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"950\" height=\"634\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2019\/03\/acto-ingreso-RAED-Josep-Maria-Guilemany-3.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/raed.academy\/wp-content\/uploads\/2019\/03\/acto-ingreso-RAED-Josep-Maria-Guilemany-3.jpg 950w, https:\/\/raed.academy\/wp-content\/uploads\/2019\/03\/acto-ingreso-RAED-Josep-Maria-Guilemany-3-768x513.jpg 768w\" sizes=\"(max-width: 950px) 100vw, 950px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/raed.academy\/wp-content\/uploads\/2019\/03\/acto-ingreso-RAED-Josep-Maria-Guilemany-4.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"850\" height=\"567\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2019\/03\/acto-ingreso-RAED-Josep-Maria-Guilemany-4.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/raed.academy\/wp-content\/uploads\/2019\/03\/acto-ingreso-RAED-Josep-Maria-Guilemany-4.jpg 850w, https:\/\/raed.academy\/wp-content\/uploads\/2019\/03\/acto-ingreso-RAED-Josep-Maria-Guilemany-4-768x512.jpg 768w\" sizes=\"(max-width: 850px) 100vw, 850px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/raed.academy\/wp-content\/uploads\/2019\/03\/acto-ingreso-RAED-Josep-Maria-Guilemany-5.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"850\" height=\"567\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2019\/03\/acto-ingreso-RAED-Josep-Maria-Guilemany-5.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/raed.academy\/wp-content\/uploads\/2019\/03\/acto-ingreso-RAED-Josep-Maria-Guilemany-5.jpg 850w, https:\/\/raed.academy\/wp-content\/uploads\/2019\/03\/acto-ingreso-RAED-Josep-Maria-Guilemany-5-768x512.jpg 768w\" sizes=\"(max-width: 850px) 100vw, 850px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/raed.academy\/wp-content\/uploads\/2019\/03\/acto-ingreso-RAED-Josep-Maria-Guilemany-6.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"850\" height=\"567\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2019\/03\/acto-ingreso-RAED-Josep-Maria-Guilemany-6.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/raed.academy\/wp-content\/uploads\/2019\/03\/acto-ingreso-RAED-Josep-Maria-Guilemany-6.jpg 850w, https:\/\/raed.academy\/wp-content\/uploads\/2019\/03\/acto-ingreso-RAED-Josep-Maria-Guilemany-6-768x512.jpg 768w\" sizes=\"(max-width: 850px) 100vw, 850px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/raed.academy\/wp-content\/uploads\/2019\/03\/acto-ingreso-RAED-Josep-Maria-Guilemany-7.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"950\" height=\"634\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2019\/03\/acto-ingreso-RAED-Josep-Maria-Guilemany-7.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/raed.academy\/wp-content\/uploads\/2019\/03\/acto-ingreso-RAED-Josep-Maria-Guilemany-7.jpg 950w, https:\/\/raed.academy\/wp-content\/uploads\/2019\/03\/acto-ingreso-RAED-Josep-Maria-Guilemany-7-768x513.jpg 768w\" sizes=\"(max-width: 950px) 100vw, 950px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/raed.academy\/wp-content\/uploads\/2019\/03\/acto-ingreso-RAED-Josep-Maria-Guilemany-8.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"850\" height=\"567\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2019\/03\/acto-ingreso-RAED-Josep-Maria-Guilemany-8.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/raed.academy\/wp-content\/uploads\/2019\/03\/acto-ingreso-RAED-Josep-Maria-Guilemany-8.jpg 850w, https:\/\/raed.academy\/wp-content\/uploads\/2019\/03\/acto-ingreso-RAED-Josep-Maria-Guilemany-8-768x512.jpg 768w\" sizes=\"(max-width: 850px) 100vw, 850px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/raed.academy\/wp-content\/uploads\/2019\/03\/acto-ingreso-RAED-Josep-Maria-Guilemany-11.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"950\" height=\"634\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2019\/03\/acto-ingreso-RAED-Josep-Maria-Guilemany-11.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/raed.academy\/wp-content\/uploads\/2019\/03\/acto-ingreso-RAED-Josep-Maria-Guilemany-11.jpg 950w, https:\/\/raed.academy\/wp-content\/uploads\/2019\/03\/acto-ingreso-RAED-Josep-Maria-Guilemany-11-768x513.jpg 768w\" sizes=\"(max-width: 950px) 100vw, 950px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/raed.academy\/wp-content\/uploads\/2019\/03\/acto-ingreso-RAED-Josep-Maria-Guilemany-12.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1050\" height=\"701\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2019\/03\/acto-ingreso-RAED-Josep-Maria-Guilemany-12.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/raed.academy\/wp-content\/uploads\/2019\/03\/acto-ingreso-RAED-Josep-Maria-Guilemany-12.jpg 1050w, https:\/\/raed.academy\/wp-content\/uploads\/2019\/03\/acto-ingreso-RAED-Josep-Maria-Guilemany-12-768x513.jpg 768w\" sizes=\"(max-width: 1050px) 100vw, 1050px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/raed.academy\/wp-content\/uploads\/2019\/03\/acto-ingreso-RAED-Josep-Maria-Guilemany-13.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"850\" height=\"567\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2019\/03\/acto-ingreso-RAED-Josep-Maria-Guilemany-13.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/raed.academy\/wp-content\/uploads\/2019\/03\/acto-ingreso-RAED-Josep-Maria-Guilemany-13.jpg 850w, https:\/\/raed.academy\/wp-content\/uploads\/2019\/03\/acto-ingreso-RAED-Josep-Maria-Guilemany-13-768x512.jpg 768w\" sizes=\"(max-width: 850px) 100vw, 850px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/raed.academy\/wp-content\/uploads\/2019\/03\/acto-ingreso-RAED-Josep-Maria-Guilemany-15.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"950\" height=\"634\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2019\/03\/acto-ingreso-RAED-Josep-Maria-Guilemany-15.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/raed.academy\/wp-content\/uploads\/2019\/03\/acto-ingreso-RAED-Josep-Maria-Guilemany-15.jpg 950w, https:\/\/raed.academy\/wp-content\/uploads\/2019\/03\/acto-ingreso-RAED-Josep-Maria-Guilemany-15-768x513.jpg 768w\" sizes=\"(max-width: 950px) 100vw, 950px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/raed.academy\/wp-content\/uploads\/2019\/03\/acto-ingreso-RAED-Josep-Maria-Guilemany-16.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1070\" height=\"714\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2019\/03\/acto-ingreso-RAED-Josep-Maria-Guilemany-16.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/raed.academy\/wp-content\/uploads\/2019\/03\/acto-ingreso-RAED-Josep-Maria-Guilemany-16.jpg 1070w, https:\/\/raed.academy\/wp-content\/uploads\/2019\/03\/acto-ingreso-RAED-Josep-Maria-Guilemany-16-768x512.jpg 768w\" sizes=\"(max-width: 1070px) 100vw, 1070px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Josep Maria Guilemany, art\u00edfex de la creaci\u00f3 del Departament de Ci\u00e8ncia dels Materials de la Universitat de Barcelona, \u200b\u200bingressa com a acad\u00e8mic Josep Maria Guilemany, doctor en Ci\u00e8ncies Qu\u00edmiques i catedr\u00e0tic de Ci\u00e8ncia dels Materials i Enginyeria Metal\u00b7l\u00fargica a la Universitat de Barcelona, \u200b\u200bva ingressar com a acad\u00e8mic de n\u00famero de la Reial Acad\u00e8mia Europea [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":69125,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[72],"tags":[],"class_list":["post-68907","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized-ca","et-has-post-format-content","et_post_format-et-post-format-standard"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>De l&#039;acer als biomaterials i al graf\u00e8 - Reial Acad\u00e8mia Europea de Doctors<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/raed.academy\/ca\/acer-biomaterials-grafe-ingres-josep-maria-guilemany-raed\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"De l&#039;acer als biomaterials i al graf\u00e8 - Reial Acad\u00e8mia Europea de Doctors\" \/>\n<meta property=\"og:description\" content=\"Josep Maria Guilemany, art\u00edfex de la creaci\u00f3 del Departament de Ci\u00e8ncia dels Materials de la Universitat de Barcelona, \u200b\u200bingressa com a acad\u00e8mic Josep Maria Guilemany, doctor en Ci\u00e8ncies Qu\u00edmiques i catedr\u00e0tic de Ci\u00e8ncia dels Materials i Enginyeria Metal\u00b7l\u00fargica a la Universitat de Barcelona, \u200b\u200bva ingressar com a acad\u00e8mic de n\u00famero de la Reial Acad\u00e8mia Europea [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/raed.academy\/ca\/acer-biomaterials-grafe-ingres-josep-maria-guilemany-raed\/\" \/>\n<meta property=\"og:site_name\" content=\"Reial Acad\u00e8mia Europea de Doctors\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/fb.me\/raed.academy\" \/>\n<meta property=\"article:published_time\" content=\"2019-03-20T23:31:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-03-22T11:56:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/raed.academy\/wp-content\/uploads\/2019\/03\/materiales-dstNtc.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"970\" \/>\n\t<meta property=\"og:image:height\" content=\"333\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"RAED\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@raedacademy\" \/>\n<meta name=\"twitter:site\" content=\"@raedacademy\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"RAED\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/acer-biomaterials-grafe-ingres-josep-maria-guilemany-raed\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/acer-biomaterials-grafe-ingres-josep-maria-guilemany-raed\\\/\"},\"author\":{\"name\":\"RAED\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/person\\\/5a755da80d1d979fd66ba745c8702927\"},\"headline\":\"De l&#8217;acer als biomaterials i al graf\u00e8\",\"datePublished\":\"2019-03-20T23:31:54+00:00\",\"dateModified\":\"2019-03-22T11:56:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/acer-biomaterials-grafe-ingres-josep-maria-guilemany-raed\\\/\"},\"wordCount\":705,\"publisher\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/acer-biomaterials-grafe-ingres-josep-maria-guilemany-raed\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/materiales-dstNtc.jpg\",\"articleSection\":[\"Uncategorized @ca\"],\"inLanguage\":\"ca-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/acer-biomaterials-grafe-ingres-josep-maria-guilemany-raed\\\/\",\"url\":\"https:\\\/\\\/raed.academy\\\/ca\\\/acer-biomaterials-grafe-ingres-josep-maria-guilemany-raed\\\/\",\"name\":\"De l'acer als biomaterials i al graf\u00e8 - Reial Acad\u00e8mia Europea de Doctors\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/acer-biomaterials-grafe-ingres-josep-maria-guilemany-raed\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/acer-biomaterials-grafe-ingres-josep-maria-guilemany-raed\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/materiales-dstNtc.jpg\",\"datePublished\":\"2019-03-20T23:31:54+00:00\",\"dateModified\":\"2019-03-22T11:56:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/acer-biomaterials-grafe-ingres-josep-maria-guilemany-raed\\\/#breadcrumb\"},\"inLanguage\":\"ca-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/raed.academy\\\/ca\\\/acer-biomaterials-grafe-ingres-josep-maria-guilemany-raed\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/acer-biomaterials-grafe-ingres-josep-maria-guilemany-raed\\\/#primaryimage\",\"url\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/materiales-dstNtc.jpg\",\"contentUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/materiales-dstNtc.jpg\",\"width\":970,\"height\":333,\"caption\":\"nanotubos de dioxido de-titanio\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/acer-biomaterials-grafe-ingres-josep-maria-guilemany-raed\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/raed.academy\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"De l&#8217;acer als biomaterials i al graf\u00e8\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/raed.academy\\\/ca\\\/\",\"name\":\"Reial Acad\u00e8mia Europea de Doctors\",\"description\":\"Corporaci\u00f3n de derecho p\u00fablico de car\u00e1cter cient\u00edfico, t\u00e9cnico y art\u00edstico, que tiene por objeto la investigaci\u00f3n, el estudio, el fomento y la extensi\u00f3n del conocimiento en su sentido m\u00e1s amplio\",\"publisher\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/raed.academy\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#organization\",\"name\":\"Real Academia Europea de Doctores\",\"url\":\"https:\\\/\\\/raed.academy\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/cropped-logo_raed.png\",\"contentUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/cropped-logo_raed.png\",\"width\":512,\"height\":512,\"caption\":\"Real Academia Europea de Doctores\"},\"image\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/fb.me\\\/raed.academy\",\"https:\\\/\\\/x.com\\\/raedacademy\",\"https:\\\/\\\/www.instagram.com\\\/raed.academy\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCUYQwW2KrdirNWihxMDObwg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/person\\\/5a755da80d1d979fd66ba745c8702927\",\"name\":\"RAED\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g\",\"caption\":\"RAED\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"De l'acer als biomaterials i al graf\u00e8 - Reial Acad\u00e8mia Europea de Doctors","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/raed.academy\/ca\/acer-biomaterials-grafe-ingres-josep-maria-guilemany-raed\/","og_locale":"ca_ES","og_type":"article","og_title":"De l'acer als biomaterials i al graf\u00e8 - Reial Acad\u00e8mia Europea de Doctors","og_description":"Josep Maria Guilemany, art\u00edfex de la creaci\u00f3 del Departament de Ci\u00e8ncia dels Materials de la Universitat de Barcelona, \u200b\u200bingressa com a acad\u00e8mic Josep Maria Guilemany, doctor en Ci\u00e8ncies Qu\u00edmiques i catedr\u00e0tic de Ci\u00e8ncia dels Materials i Enginyeria Metal\u00b7l\u00fargica a la Universitat de Barcelona, \u200b\u200bva ingressar com a acad\u00e8mic de n\u00famero de la Reial Acad\u00e8mia Europea [&hellip;]","og_url":"https:\/\/raed.academy\/ca\/acer-biomaterials-grafe-ingres-josep-maria-guilemany-raed\/","og_site_name":"Reial Acad\u00e8mia Europea de Doctors","article_publisher":"http:\/\/fb.me\/raed.academy","article_published_time":"2019-03-20T23:31:54+00:00","article_modified_time":"2019-03-22T11:56:36+00:00","og_image":[{"width":970,"height":333,"url":"https:\/\/raed.academy\/wp-content\/uploads\/2019\/03\/materiales-dstNtc.jpg","type":"image\/jpeg"}],"author":"RAED","twitter_card":"summary_large_image","twitter_creator":"@raedacademy","twitter_site":"@raedacademy","twitter_misc":{"Written by":"RAED","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/raed.academy\/ca\/acer-biomaterials-grafe-ingres-josep-maria-guilemany-raed\/#article","isPartOf":{"@id":"https:\/\/raed.academy\/ca\/acer-biomaterials-grafe-ingres-josep-maria-guilemany-raed\/"},"author":{"name":"RAED","@id":"https:\/\/raed.academy\/ca\/#\/schema\/person\/5a755da80d1d979fd66ba745c8702927"},"headline":"De l&#8217;acer als biomaterials i al graf\u00e8","datePublished":"2019-03-20T23:31:54+00:00","dateModified":"2019-03-22T11:56:36+00:00","mainEntityOfPage":{"@id":"https:\/\/raed.academy\/ca\/acer-biomaterials-grafe-ingres-josep-maria-guilemany-raed\/"},"wordCount":705,"publisher":{"@id":"https:\/\/raed.academy\/ca\/#organization"},"image":{"@id":"https:\/\/raed.academy\/ca\/acer-biomaterials-grafe-ingres-josep-maria-guilemany-raed\/#primaryimage"},"thumbnailUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2019\/03\/materiales-dstNtc.jpg","articleSection":["Uncategorized @ca"],"inLanguage":"ca-ES"},{"@type":"WebPage","@id":"https:\/\/raed.academy\/ca\/acer-biomaterials-grafe-ingres-josep-maria-guilemany-raed\/","url":"https:\/\/raed.academy\/ca\/acer-biomaterials-grafe-ingres-josep-maria-guilemany-raed\/","name":"De l'acer als biomaterials i al graf\u00e8 - Reial Acad\u00e8mia Europea de Doctors","isPartOf":{"@id":"https:\/\/raed.academy\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/raed.academy\/ca\/acer-biomaterials-grafe-ingres-josep-maria-guilemany-raed\/#primaryimage"},"image":{"@id":"https:\/\/raed.academy\/ca\/acer-biomaterials-grafe-ingres-josep-maria-guilemany-raed\/#primaryimage"},"thumbnailUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2019\/03\/materiales-dstNtc.jpg","datePublished":"2019-03-20T23:31:54+00:00","dateModified":"2019-03-22T11:56:36+00:00","breadcrumb":{"@id":"https:\/\/raed.academy\/ca\/acer-biomaterials-grafe-ingres-josep-maria-guilemany-raed\/#breadcrumb"},"inLanguage":"ca-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/raed.academy\/ca\/acer-biomaterials-grafe-ingres-josep-maria-guilemany-raed\/"]}]},{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/raed.academy\/ca\/acer-biomaterials-grafe-ingres-josep-maria-guilemany-raed\/#primaryimage","url":"https:\/\/raed.academy\/wp-content\/uploads\/2019\/03\/materiales-dstNtc.jpg","contentUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2019\/03\/materiales-dstNtc.jpg","width":970,"height":333,"caption":"nanotubos de dioxido de-titanio"},{"@type":"BreadcrumbList","@id":"https:\/\/raed.academy\/ca\/acer-biomaterials-grafe-ingres-josep-maria-guilemany-raed\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/raed.academy\/ca\/"},{"@type":"ListItem","position":2,"name":"De l&#8217;acer als biomaterials i al graf\u00e8"}]},{"@type":"WebSite","@id":"https:\/\/raed.academy\/ca\/#website","url":"https:\/\/raed.academy\/ca\/","name":"Reial Acad\u00e8mia Europea de Doctors","description":"Corporaci\u00f3n de derecho p\u00fablico de car\u00e1cter cient\u00edfico, t\u00e9cnico y art\u00edstico, que tiene por objeto la investigaci\u00f3n, el estudio, el fomento y la extensi\u00f3n del conocimiento en su sentido m\u00e1s amplio","publisher":{"@id":"https:\/\/raed.academy\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/raed.academy\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca-ES"},{"@type":"Organization","@id":"https:\/\/raed.academy\/ca\/#organization","name":"Real Academia Europea de Doctores","url":"https:\/\/raed.academy\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/raed.academy\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/raed.academy\/wp-content\/uploads\/2017\/01\/cropped-logo_raed.png","contentUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2017\/01\/cropped-logo_raed.png","width":512,"height":512,"caption":"Real Academia Europea de Doctores"},"image":{"@id":"https:\/\/raed.academy\/ca\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/fb.me\/raed.academy","https:\/\/x.com\/raedacademy","https:\/\/www.instagram.com\/raed.academy\/","https:\/\/www.youtube.com\/channel\/UCUYQwW2KrdirNWihxMDObwg"]},{"@type":"Person","@id":"https:\/\/raed.academy\/ca\/#\/schema\/person\/5a755da80d1d979fd66ba745c8702927","name":"RAED","image":{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g","caption":"RAED"}}]}},"_links":{"self":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/posts\/68907","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/comments?post=68907"}],"version-history":[{"count":0,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/posts\/68907\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/media\/69125"}],"wp:attachment":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/media?parent=68907"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/categories?post=68907"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/tags?post=68907"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}