{"id":68627,"date":"2019-03-14T15:36:15","date_gmt":"2019-03-14T15:36:15","guid":{"rendered":"https:\/\/raed.academy\/?p=68627"},"modified":"2019-03-15T18:33:44","modified_gmt":"2019-03-15T18:33:44","slug":"de-ladulteri-a-les-parelles-de-fet","status":"publish","type":"post","link":"https:\/\/raed.academy\/ca\/de-ladulteri-a-les-parelles-de-fet\/","title":{"rendered":"De l&#8217;adulteri a les parelles de fet"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-47823 jetpack-lazy-image jetpack-lazy-image--handled alignleft\" src=\"https:\/\/i1.wp.com\/raed.academy\/wp-content\/uploads\/2018\/07\/Dr-Enrique-Lecumberri-ponencia-IV-acto-internacional.jpg?resize=549%2C366&amp;ssl=1\" sizes=\"(max-width: 549px) 100vw, 549px\" srcset=\"https:\/\/i1.wp.com\/raed.academy\/wp-content\/uploads\/2018\/07\/Dr-Enrique-Lecumberri-ponencia-IV-acto-internacional.jpg?w=800&amp;ssl=1 800w, https:\/\/i1.wp.com\/raed.academy\/wp-content\/uploads\/2018\/07\/Dr-Enrique-Lecumberri-ponencia-IV-acto-internacional.jpg?resize=768%2C512&amp;ssl=1 768w\" alt=\"Dr. Enrique Lecumberri\" width=\"549\" height=\"366\" aria-describedby=\"caption-attachment-47823\" data-attachment-id=\"47823\" data-permalink=\"https:\/\/raed.academy\/iv-acto-internacional\/dr-enrique-lecumberri-ponencia-iv-acto-internacional\/\" data-orig-file=\"https:\/\/i1.wp.com\/raed.academy\/wp-content\/uploads\/2018\/07\/Dr-Enrique-Lecumberri-ponencia-IV-acto-internacional.jpg?fit=800%2C533&amp;ssl=1\" data-orig-size=\"800,533\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;6.3&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS M50&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1531420390&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;45&quot;,&quot;iso&quot;:&quot;6400&quot;,&quot;shutter_speed&quot;:&quot;0.02&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Dr. Enrique Lecumberri ponencia IV acto internacional\" data-image-description=\"&lt;p&gt;Foto RAED&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/i1.wp.com\/raed.academy\/wp-content\/uploads\/2018\/07\/Dr-Enrique-Lecumberri-ponencia-IV-acto-internacional.jpg?fit=800%2C533&amp;ssl=1\" data-large-file=\"https:\/\/i1.wp.com\/raed.academy\/wp-content\/uploads\/2018\/07\/Dr-Enrique-Lecumberri-ponencia-IV-acto-internacional.jpg?fit=800%2C533&amp;ssl=1\" data-recalc-dims=\"1\" data-lazy-loaded=\"1\" \/><a href=\"https:\/\/raed.academy\/ca\/academics\/dr-enrique-lecumberri-marti\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Enrique Lecumberri<\/strong><\/a>, exmagistrat del <strong>Tribunal Suprem<\/strong> i acad\u00e8mic d&#8217;honor de la<strong> Reial Acad\u00e8mia Europea de Doctors-Barcelona 1914<\/strong> (RAED), va presentar al <strong>IV Acte Internacional-Congr\u00e9s Europeu d&#8217;Investigacions Interdisciplin\u00e0ries<\/strong> de la RAED, que es va celebrar el passat mes de juliol a diverses capitals de la Mediterr\u00e0nia, el treball<strong> &#8220;Del adulterio y amancebamiento a las parejas de hecho&#8221;<\/strong>, on repassa de forma succinta les figures jur\u00eddiques que han portat a la legislaci\u00f3 espanyola de ser una de les m\u00e9s conservadores a alinear-se amb les actuals legislacions europees.<\/p>\n<p>En aquest mateix sentit, tant els articles del codi penal referits a aquesta mat\u00e8ria com el que recull el dret civil a la majoria de Comunitats Aut\u00f2nomes al respecte entronca d&#8217;alguna manera amb les penes i drets que va recon\u00e8ixer la Rep\u00fablica Espanyola fins al 1939. &#8220;A Espanya, si exceptuem al Codi Penal republic\u00e0, sempre va ser penalitzat el delicte d&#8217;adulteri fins a la llei de 26 de maig de 1978, promulgada sota el Govern d&#8217;<strong>Adolfo Su\u00e1rez<\/strong>, \u00e9s a dir, <img loading=\"lazy\" decoding=\"async\" class=\"img-mrg-superior jetpack-lazy-image jetpack-lazy-image--handled alignright wp-image-68542\" src=\"https:\/\/i0.wp.com\/raed.academy\/wp-content\/uploads\/2019\/03\/Pareja-de-Hecho-dstNtc.jpg?resize=321%2C167&amp;ssl=1\" alt=\"\" width=\"321\" height=\"167\" data-attachment-id=\"68542\" data-permalink=\"https:\/\/raed.academy\/del-adulterio-a-las-parejas-de-hecho\/pareja-de-hecho-dstntc\/\" data-orig-file=\"https:\/\/i0.wp.com\/raed.academy\/wp-content\/uploads\/2019\/03\/Pareja-de-Hecho-dstNtc.jpg?fit=380%2C198&amp;ssl=1\" data-orig-size=\"380,198\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Pareja-de-Hecho-dstNtc\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/raed.academy\/wp-content\/uploads\/2019\/03\/Pareja-de-Hecho-dstNtc.jpg?fit=380%2C198&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/raed.academy\/wp-content\/uploads\/2019\/03\/Pareja-de-Hecho-dstNtc.jpg?fit=380%2C198&amp;ssl=1\" data-recalc-dims=\"1\" data-lazy-loaded=\"1\" \/>uns mesos abans de la promulgaci\u00f3 i publicaci\u00f3 de la <strong>Constituci\u00f3 Espanyola<\/strong> de 27 de desembre del 1978 i uns mesos abans de l&#8217;aprovaci\u00f3 de la llei de reforma pol\u00edtica de 4 de gener del 1977&#8243;, recorda l&#8217;acad\u00e8mic.<\/p>\n<p>Quan al reconeixement de les parelles de fet, Lecumberri recorda que va ser Catalunya la primera Comunitat Aut\u00f2noma que va aprovar una llei al respecte el 1998. &#8220;El desig del legislador per regular les parelles de fet va ser precisament posar fi a aquelles relacions extra-conjugals que d&#8217;acord amb la legislaci\u00f3 espanyola no es consideraven matrimonis&#8221;, especifica. Avui dia, una \u00e0mplia majoria social espanyola accepta i comparteix la legislaci\u00f3 actual en aquestes mat\u00e8ries.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Enrique Lecumberri, exmagistrat del Tribunal Suprem i acad\u00e8mic d&#8217;honor de la Reial Acad\u00e8mia Europea de Doctors-Barcelona 1914 (RAED), va presentar al IV Acte Internacional-Congr\u00e9s Europeu d&#8217;Investigacions Interdisciplin\u00e0ries de la RAED, que es va celebrar el passat mes de juliol a diverses capitals de la Mediterr\u00e0nia, el treball &#8220;Del adulterio y amancebamiento a las parejas de [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":68543,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[225],"tags":[],"class_list":["post-68627","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dret","et-has-post-format-content","et_post_format-et-post-format-standard"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>De l&#039;adulteri a les parelles de fet - Reial Acad\u00e8mia Europea de Doctors<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/raed.academy\/ca\/de-ladulteri-a-les-parelles-de-fet\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"De l&#039;adulteri a les parelles de fet - Reial Acad\u00e8mia Europea de Doctors\" \/>\n<meta property=\"og:description\" content=\"Enrique Lecumberri, exmagistrat del Tribunal Suprem i acad\u00e8mic d&#8217;honor de la Reial Acad\u00e8mia Europea de Doctors-Barcelona 1914 (RAED), va presentar al IV Acte Internacional-Congr\u00e9s Europeu d&#8217;Investigacions Interdisciplin\u00e0ries de la RAED, que es va celebrar el passat mes de juliol a diverses capitals de la Mediterr\u00e0nia, el treball &#8220;Del adulterio y amancebamiento a las parejas de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/raed.academy\/ca\/de-ladulteri-a-les-parelles-de-fet\/\" \/>\n<meta property=\"og:site_name\" content=\"Reial Acad\u00e8mia Europea de Doctors\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/fb.me\/raed.academy\" \/>\n<meta property=\"article:published_time\" content=\"2019-03-14T15:36:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-03-15T18:33:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/raed.academy\/wp-content\/uploads\/2019\/03\/Pareja-de-Hecho-dstNtc.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"380\" \/>\n\t<meta property=\"og:image:height\" content=\"198\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"RAED\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@raedacademy\" \/>\n<meta name=\"twitter:site\" content=\"@raedacademy\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"RAED\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/de-ladulteri-a-les-parelles-de-fet\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/de-ladulteri-a-les-parelles-de-fet\\\/\"},\"author\":{\"name\":\"RAED\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/person\\\/5a755da80d1d979fd66ba745c8702927\"},\"headline\":\"De l&#8217;adulteri a les parelles de fet\",\"datePublished\":\"2019-03-14T15:36:15+00:00\",\"dateModified\":\"2019-03-15T18:33:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/de-ladulteri-a-les-parelles-de-fet\\\/\"},\"wordCount\":299,\"publisher\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/de-ladulteri-a-les-parelles-de-fet\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/Pareja-de-Hecho-dstNtc.jpg\",\"articleSection\":[\"Dret\"],\"inLanguage\":\"ca-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/de-ladulteri-a-les-parelles-de-fet\\\/\",\"url\":\"https:\\\/\\\/raed.academy\\\/ca\\\/de-ladulteri-a-les-parelles-de-fet\\\/\",\"name\":\"De l'adulteri a les parelles de fet - Reial Acad\u00e8mia Europea de Doctors\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/de-ladulteri-a-les-parelles-de-fet\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/de-ladulteri-a-les-parelles-de-fet\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/Pareja-de-Hecho-dstNtc.jpg\",\"datePublished\":\"2019-03-14T15:36:15+00:00\",\"dateModified\":\"2019-03-15T18:33:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/de-ladulteri-a-les-parelles-de-fet\\\/#breadcrumb\"},\"inLanguage\":\"ca-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/raed.academy\\\/ca\\\/de-ladulteri-a-les-parelles-de-fet\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/de-ladulteri-a-les-parelles-de-fet\\\/#primaryimage\",\"url\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/Pareja-de-Hecho-dstNtc.jpg\",\"contentUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/Pareja-de-Hecho-dstNtc.jpg\",\"width\":380,\"height\":198},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/de-ladulteri-a-les-parelles-de-fet\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/raed.academy\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"De l&#8217;adulteri a les parelles de fet\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/raed.academy\\\/ca\\\/\",\"name\":\"Reial Acad\u00e8mia Europea de Doctors\",\"description\":\"Corporaci\u00f3n de derecho p\u00fablico de car\u00e1cter cient\u00edfico, t\u00e9cnico y art\u00edstico, que tiene por objeto la investigaci\u00f3n, el estudio, el fomento y la extensi\u00f3n del conocimiento en su sentido m\u00e1s amplio\",\"publisher\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/raed.academy\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#organization\",\"name\":\"Real Academia Europea de Doctores\",\"url\":\"https:\\\/\\\/raed.academy\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/cropped-logo_raed.png\",\"contentUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/cropped-logo_raed.png\",\"width\":512,\"height\":512,\"caption\":\"Real Academia Europea de Doctores\"},\"image\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/fb.me\\\/raed.academy\",\"https:\\\/\\\/x.com\\\/raedacademy\",\"https:\\\/\\\/www.instagram.com\\\/raed.academy\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCUYQwW2KrdirNWihxMDObwg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/person\\\/5a755da80d1d979fd66ba745c8702927\",\"name\":\"RAED\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g\",\"caption\":\"RAED\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"De l'adulteri a les parelles de fet - Reial Acad\u00e8mia Europea de Doctors","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/raed.academy\/ca\/de-ladulteri-a-les-parelles-de-fet\/","og_locale":"ca_ES","og_type":"article","og_title":"De l'adulteri a les parelles de fet - Reial Acad\u00e8mia Europea de Doctors","og_description":"Enrique Lecumberri, exmagistrat del Tribunal Suprem i acad\u00e8mic d&#8217;honor de la Reial Acad\u00e8mia Europea de Doctors-Barcelona 1914 (RAED), va presentar al IV Acte Internacional-Congr\u00e9s Europeu d&#8217;Investigacions Interdisciplin\u00e0ries de la RAED, que es va celebrar el passat mes de juliol a diverses capitals de la Mediterr\u00e0nia, el treball &#8220;Del adulterio y amancebamiento a las parejas de [&hellip;]","og_url":"https:\/\/raed.academy\/ca\/de-ladulteri-a-les-parelles-de-fet\/","og_site_name":"Reial Acad\u00e8mia Europea de Doctors","article_publisher":"http:\/\/fb.me\/raed.academy","article_published_time":"2019-03-14T15:36:15+00:00","article_modified_time":"2019-03-15T18:33:44+00:00","og_image":[{"width":380,"height":198,"url":"https:\/\/raed.academy\/wp-content\/uploads\/2019\/03\/Pareja-de-Hecho-dstNtc.jpg","type":"image\/jpeg"}],"author":"RAED","twitter_card":"summary_large_image","twitter_creator":"@raedacademy","twitter_site":"@raedacademy","twitter_misc":{"Written by":"RAED","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/raed.academy\/ca\/de-ladulteri-a-les-parelles-de-fet\/#article","isPartOf":{"@id":"https:\/\/raed.academy\/ca\/de-ladulteri-a-les-parelles-de-fet\/"},"author":{"name":"RAED","@id":"https:\/\/raed.academy\/ca\/#\/schema\/person\/5a755da80d1d979fd66ba745c8702927"},"headline":"De l&#8217;adulteri a les parelles de fet","datePublished":"2019-03-14T15:36:15+00:00","dateModified":"2019-03-15T18:33:44+00:00","mainEntityOfPage":{"@id":"https:\/\/raed.academy\/ca\/de-ladulteri-a-les-parelles-de-fet\/"},"wordCount":299,"publisher":{"@id":"https:\/\/raed.academy\/ca\/#organization"},"image":{"@id":"https:\/\/raed.academy\/ca\/de-ladulteri-a-les-parelles-de-fet\/#primaryimage"},"thumbnailUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2019\/03\/Pareja-de-Hecho-dstNtc.jpg","articleSection":["Dret"],"inLanguage":"ca-ES"},{"@type":"WebPage","@id":"https:\/\/raed.academy\/ca\/de-ladulteri-a-les-parelles-de-fet\/","url":"https:\/\/raed.academy\/ca\/de-ladulteri-a-les-parelles-de-fet\/","name":"De l'adulteri a les parelles de fet - Reial Acad\u00e8mia Europea de Doctors","isPartOf":{"@id":"https:\/\/raed.academy\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/raed.academy\/ca\/de-ladulteri-a-les-parelles-de-fet\/#primaryimage"},"image":{"@id":"https:\/\/raed.academy\/ca\/de-ladulteri-a-les-parelles-de-fet\/#primaryimage"},"thumbnailUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2019\/03\/Pareja-de-Hecho-dstNtc.jpg","datePublished":"2019-03-14T15:36:15+00:00","dateModified":"2019-03-15T18:33:44+00:00","breadcrumb":{"@id":"https:\/\/raed.academy\/ca\/de-ladulteri-a-les-parelles-de-fet\/#breadcrumb"},"inLanguage":"ca-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/raed.academy\/ca\/de-ladulteri-a-les-parelles-de-fet\/"]}]},{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/raed.academy\/ca\/de-ladulteri-a-les-parelles-de-fet\/#primaryimage","url":"https:\/\/raed.academy\/wp-content\/uploads\/2019\/03\/Pareja-de-Hecho-dstNtc.jpg","contentUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2019\/03\/Pareja-de-Hecho-dstNtc.jpg","width":380,"height":198},{"@type":"BreadcrumbList","@id":"https:\/\/raed.academy\/ca\/de-ladulteri-a-les-parelles-de-fet\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/raed.academy\/ca\/"},{"@type":"ListItem","position":2,"name":"De l&#8217;adulteri a les parelles de fet"}]},{"@type":"WebSite","@id":"https:\/\/raed.academy\/ca\/#website","url":"https:\/\/raed.academy\/ca\/","name":"Reial Acad\u00e8mia Europea de Doctors","description":"Corporaci\u00f3n de derecho p\u00fablico de car\u00e1cter cient\u00edfico, t\u00e9cnico y art\u00edstico, que tiene por objeto la investigaci\u00f3n, el estudio, el fomento y la extensi\u00f3n del conocimiento en su sentido m\u00e1s amplio","publisher":{"@id":"https:\/\/raed.academy\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/raed.academy\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca-ES"},{"@type":"Organization","@id":"https:\/\/raed.academy\/ca\/#organization","name":"Real Academia Europea de Doctores","url":"https:\/\/raed.academy\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/raed.academy\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/raed.academy\/wp-content\/uploads\/2017\/01\/cropped-logo_raed.png","contentUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2017\/01\/cropped-logo_raed.png","width":512,"height":512,"caption":"Real Academia Europea de Doctores"},"image":{"@id":"https:\/\/raed.academy\/ca\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/fb.me\/raed.academy","https:\/\/x.com\/raedacademy","https:\/\/www.instagram.com\/raed.academy\/","https:\/\/www.youtube.com\/channel\/UCUYQwW2KrdirNWihxMDObwg"]},{"@type":"Person","@id":"https:\/\/raed.academy\/ca\/#\/schema\/person\/5a755da80d1d979fd66ba745c8702927","name":"RAED","image":{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g","caption":"RAED"}}]}},"_links":{"self":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/posts\/68627","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/comments?post=68627"}],"version-history":[{"count":0,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/posts\/68627\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/media\/68543"}],"wp:attachment":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/media?parent=68627"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/categories?post=68627"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/tags?post=68627"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}