{"id":65736,"date":"2019-01-30T20:30:44","date_gmt":"2019-01-30T20:30:44","guid":{"rendered":"https:\/\/raed.academy\/?p=65736"},"modified":"2019-01-31T16:50:10","modified_gmt":"2019-01-31T16:50:10","slug":"ingres-raed-joan-massons","status":"publish","type":"post","link":"https:\/\/raed.academy\/ca\/ingres-raed-joan-massons\/","title":{"rendered":"R\u00e0tios que no diuen la veritat"},"content":{"rendered":"<h2>Joan Massons, professor d&#8217;ESADE i reconegut assessor financer, ingressa com a acad\u00e8mic de n\u00famero de la RAED<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-65463\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2019\/01\/ratios-dstNtc.jpg\" alt=\"\" width=\"450\" height=\"296\" \/><a href=\"https:\/\/raed.academy\/ca\/academics\/dr-joan-massons-rabassa\/\" target=\"_blank\" rel=\"noopener\"><strong>Joan Massons<\/strong><\/a>, doctor en Administraci\u00f3 i Direcci\u00f3 d&#8217;Empreses, professor de Finances i Planificaci\u00f3 Financera de l&#8217;Escola de Negocis <a href=\"http:\/\/www.esade.edu\" target=\"_blank\" rel=\"noopener\"><strong>ESADE<\/strong><\/a> i reconegut assessor financer, va ingressar com a acad\u00e8mic de n\u00famero de la <strong>Reial Acad\u00e8mia Europea de Doctors-Barcelona 1914<\/strong> (RAED) durant una cerim\u00f2nia que es va celebrar el passat 29 de gener al Sal\u00f3 d&#8217;Actes de <a href=\"http:\/\/www.foment.com\" target=\"_blank\" rel=\"noopener\"><strong>Foment del Treball Nacional<\/strong><\/a>, seu de la RAED. El recipiendari va llegir el discurs d&#8217;ingr\u00e9s <strong>&#8220;Paradigmas financieros en tela de juicio&#8221;<\/strong>. Li va respondre en nom de la Reial Corporaci\u00f3 l&#8217;acad\u00e8mic de n\u00famero <a href=\"https:\/\/raed.academy\/ca\/academics\/dr-jose-maria-gay-de-liebana-saludas\/\" target=\"_blank\" rel=\"noopener\"><strong>Jos\u00e9 Mar\u00eda Gay de Li\u00e9bana<\/strong><\/a>.<\/p>\n<p>En el seu treball, el nou acad\u00e8mic q\u00fcestiona i invalida d&#8217;una forma raonada alguns dels indicadors de refer\u00e8ncia en l&#8217;an\u00e0lisi i l&#8217;auditoria empresarial com l&#8217;ebitda, la r\u00e0tio ROCE, les r\u00e0tios ebitda\/inter\u00e8s o ebitda\/vendes, la taxa de creixement autosostenible (SGR) o l&#8217;\u00edndex WACC, tradu\u00eft habitualment com a cost mitj\u00e0 ponderat dels recursos financers. Amb exemples concrets i did\u00e0ctics, l&#8217;estudi\u00f3s desmunta el rigor d&#8217;aquests mecanismes tan habituals com -considera- enganyosos.<\/p>\n<p>&#8220;Fa quatre anys vaig presentar al <strong>Col\u00b7legi de Titulars Mercantils<\/strong>, avui ref\u00f3s amb el <a href=\"https:\/\/economistas.es\" target=\"_blank\" rel=\"noopener\"><strong>Col\u00b7legi d&#8217;Economistes<\/strong><\/a>, una confer\u00e8ncia titulada <strong>&#8220;Ratios que mienten&#8221;<\/strong>. En ella, exposava la meva cr\u00edtica a determinats indicadors econ\u00f2mics tot esperant la reacci\u00f3 i resposta dels experts en economia empresarial all\u00e0 presents. Vaig trobar assentiment un\u00e0nime a les meves cr\u00edtiques i les veus que aquest dia es van expressar ho van fer per manifestar que el recel cap a determinats indicadors econ\u00f2mics no era nou, per\u00f2 que molts professionals es resignaven a emprar r\u00e0tios dubtosos, perqu\u00e8 en cas contrari podien ser criticats per no emprar totes les eines al seu abast&#8221;, argumenta l&#8217;autor en la presentaci\u00f3 del seu estudi.<\/p>\n<p>Per a Massons, els indicadors i models d&#8217;an\u00e0lisi de l&#8217;economia empresarial analitzats &#8220;no diuen absolutament res sobre la salut i solidesa de l&#8217;empresa. No nom\u00e9s aix\u00f2, en algun cas fins i tot poden dir exactament el contrari del que realment est\u00e0 passant a una empresa&#8221;, assenyala.<\/p>\n<h3><a href=\"https:\/\/raed.academy\/wp-content\/uploads\/2019\/01\/discurso-ingreso-Joan-Massons-Rabassa-Paradigmas-Financieros-comp.pdf\" target=\"_blank\" rel=\"noopener\">Discurs d&#8217;ingr\u00e9s<\/a><\/h3>\n<p>&nbsp;<\/p>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 25%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-65736 gallery-columns-4 gallery-size-medium'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/raed.academy\/wp-content\/uploads\/2019\/01\/ingreso-RAED-Joan-Massons-Rabassa-10.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"850\" height=\"567\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2019\/01\/ingreso-RAED-Joan-Massons-Rabassa-10.jpg\" class=\"attachment-medium size-medium\" alt=\"Dr. Joan Massons i Rabassa\" srcset=\"https:\/\/raed.academy\/wp-content\/uploads\/2019\/01\/ingreso-RAED-Joan-Massons-Rabassa-10.jpg 850w, https:\/\/raed.academy\/wp-content\/uploads\/2019\/01\/ingreso-RAED-Joan-Massons-Rabassa-10-768x512.jpg 768w\" sizes=\"(max-width: 850px) 100vw, 850px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/raed.academy\/wp-content\/uploads\/2019\/01\/ingreso-RAED-Joan-Massons-Rabassa-29.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"850\" height=\"567\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2019\/01\/ingreso-RAED-Joan-Massons-Rabassa-29.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/raed.academy\/wp-content\/uploads\/2019\/01\/ingreso-RAED-Joan-Massons-Rabassa-29.jpg 850w, https:\/\/raed.academy\/wp-content\/uploads\/2019\/01\/ingreso-RAED-Joan-Massons-Rabassa-29-768x512.jpg 768w\" sizes=\"(max-width: 850px) 100vw, 850px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/raed.academy\/wp-content\/uploads\/2019\/01\/ingreso-RAED-Joan-Massons-Rabassa-28.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"850\" height=\"567\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2019\/01\/ingreso-RAED-Joan-Massons-Rabassa-28.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/raed.academy\/wp-content\/uploads\/2019\/01\/ingreso-RAED-Joan-Massons-Rabassa-28.jpg 850w, https:\/\/raed.academy\/wp-content\/uploads\/2019\/01\/ingreso-RAED-Joan-Massons-Rabassa-28-768x512.jpg 768w\" sizes=\"(max-width: 850px) 100vw, 850px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/raed.academy\/wp-content\/uploads\/2019\/01\/ingreso-RAED-Joan-Massons-Rabassa-39.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"850\" height=\"567\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2019\/01\/ingreso-RAED-Joan-Massons-Rabassa-39.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/raed.academy\/wp-content\/uploads\/2019\/01\/ingreso-RAED-Joan-Massons-Rabassa-39.jpg 850w, https:\/\/raed.academy\/wp-content\/uploads\/2019\/01\/ingreso-RAED-Joan-Massons-Rabassa-39-768x512.jpg 768w\" sizes=\"(max-width: 850px) 100vw, 850px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/raed.academy\/wp-content\/uploads\/2019\/01\/ingreso-RAED-Joan-Massons-Rabassa-42.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"850\" height=\"567\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2019\/01\/ingreso-RAED-Joan-Massons-Rabassa-42.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/raed.academy\/wp-content\/uploads\/2019\/01\/ingreso-RAED-Joan-Massons-Rabassa-42.jpg 850w, https:\/\/raed.academy\/wp-content\/uploads\/2019\/01\/ingreso-RAED-Joan-Massons-Rabassa-42-768x512.jpg 768w\" sizes=\"(max-width: 850px) 100vw, 850px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/raed.academy\/wp-content\/uploads\/2019\/01\/ingreso-RAED-Joan-Massons-Rabassa-52.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"850\" height=\"567\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2019\/01\/ingreso-RAED-Joan-Massons-Rabassa-52.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/raed.academy\/wp-content\/uploads\/2019\/01\/ingreso-RAED-Joan-Massons-Rabassa-52.jpg 850w, https:\/\/raed.academy\/wp-content\/uploads\/2019\/01\/ingreso-RAED-Joan-Massons-Rabassa-52-768x512.jpg 768w\" sizes=\"(max-width: 850px) 100vw, 850px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/raed.academy\/wp-content\/uploads\/2019\/01\/ingreso-RAED-Joan-Massons-Rabassa-56.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"970\" height=\"647\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2019\/01\/ingreso-RAED-Joan-Massons-Rabassa-56.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/raed.academy\/wp-content\/uploads\/2019\/01\/ingreso-RAED-Joan-Massons-Rabassa-56.jpg 970w, https:\/\/raed.academy\/wp-content\/uploads\/2019\/01\/ingreso-RAED-Joan-Massons-Rabassa-56-768x512.jpg 768w\" sizes=\"(max-width: 970px) 100vw, 970px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/raed.academy\/wp-content\/uploads\/2019\/01\/ingreso-RAED-Joan-Massons-Rabassa-60.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"930\" height=\"621\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2019\/01\/ingreso-RAED-Joan-Massons-Rabassa-60.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/raed.academy\/wp-content\/uploads\/2019\/01\/ingreso-RAED-Joan-Massons-Rabassa-60.jpg 930w, https:\/\/raed.academy\/wp-content\/uploads\/2019\/01\/ingreso-RAED-Joan-Massons-Rabassa-60-768x513.jpg 768w\" sizes=\"(max-width: 930px) 100vw, 930px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/raed.academy\/wp-content\/uploads\/2019\/01\/ingreso-RAED-Joan-Massons-Rabassa-61.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"850\" height=\"567\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2019\/01\/ingreso-RAED-Joan-Massons-Rabassa-61.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/raed.academy\/wp-content\/uploads\/2019\/01\/ingreso-RAED-Joan-Massons-Rabassa-61.jpg 850w, https:\/\/raed.academy\/wp-content\/uploads\/2019\/01\/ingreso-RAED-Joan-Massons-Rabassa-61-768x512.jpg 768w\" sizes=\"(max-width: 850px) 100vw, 850px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/raed.academy\/wp-content\/uploads\/2019\/01\/ingreso-RAED-Joan-Massons-Rabassa-63.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1100\" height=\"733\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2019\/01\/ingreso-RAED-Joan-Massons-Rabassa-63.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/raed.academy\/wp-content\/uploads\/2019\/01\/ingreso-RAED-Joan-Massons-Rabassa-63.jpg 1100w, https:\/\/raed.academy\/wp-content\/uploads\/2019\/01\/ingreso-RAED-Joan-Massons-Rabassa-63-768x512.jpg 768w, https:\/\/raed.academy\/wp-content\/uploads\/2019\/01\/ingreso-RAED-Joan-Massons-Rabassa-63-1080x720.jpg 1080w\" sizes=\"(max-width: 1100px) 100vw, 1100px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/raed.academy\/wp-content\/uploads\/2019\/01\/ingreso-RAED-Joan-Massons-Rabassa-65.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"850\" height=\"567\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2019\/01\/ingreso-RAED-Joan-Massons-Rabassa-65.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/raed.academy\/wp-content\/uploads\/2019\/01\/ingreso-RAED-Joan-Massons-Rabassa-65.jpg 850w, https:\/\/raed.academy\/wp-content\/uploads\/2019\/01\/ingreso-RAED-Joan-Massons-Rabassa-65-768x512.jpg 768w\" sizes=\"(max-width: 850px) 100vw, 850px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/raed.academy\/wp-content\/uploads\/2019\/01\/ingreso-RAED-Joan-Massons-Rabassa-69.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"850\" height=\"567\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2019\/01\/ingreso-RAED-Joan-Massons-Rabassa-69.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/raed.academy\/wp-content\/uploads\/2019\/01\/ingreso-RAED-Joan-Massons-Rabassa-69.jpg 850w, https:\/\/raed.academy\/wp-content\/uploads\/2019\/01\/ingreso-RAED-Joan-Massons-Rabassa-69-768x512.jpg 768w\" sizes=\"(max-width: 850px) 100vw, 850px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/raed.academy\/wp-content\/uploads\/2019\/01\/ingreso-RAED-Joan-Massons-Rabassa-73.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"850\" height=\"567\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2019\/01\/ingreso-RAED-Joan-Massons-Rabassa-73.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/raed.academy\/wp-content\/uploads\/2019\/01\/ingreso-RAED-Joan-Massons-Rabassa-73.jpg 850w, https:\/\/raed.academy\/wp-content\/uploads\/2019\/01\/ingreso-RAED-Joan-Massons-Rabassa-73-768x512.jpg 768w\" sizes=\"(max-width: 850px) 100vw, 850px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/raed.academy\/wp-content\/uploads\/2019\/01\/ingreso-RAED-Joan-Massons-Rabassa-76.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"850\" height=\"567\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2019\/01\/ingreso-RAED-Joan-Massons-Rabassa-76.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/raed.academy\/wp-content\/uploads\/2019\/01\/ingreso-RAED-Joan-Massons-Rabassa-76.jpg 850w, https:\/\/raed.academy\/wp-content\/uploads\/2019\/01\/ingreso-RAED-Joan-Massons-Rabassa-76-768x512.jpg 768w\" sizes=\"(max-width: 850px) 100vw, 850px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/raed.academy\/wp-content\/uploads\/2019\/01\/ingreso-RAED-Joan-Massons-Rabassa-77.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"970\" height=\"647\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2019\/01\/ingreso-RAED-Joan-Massons-Rabassa-77.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/raed.academy\/wp-content\/uploads\/2019\/01\/ingreso-RAED-Joan-Massons-Rabassa-77.jpg 970w, https:\/\/raed.academy\/wp-content\/uploads\/2019\/01\/ingreso-RAED-Joan-Massons-Rabassa-77-768x512.jpg 768w\" sizes=\"(max-width: 970px) 100vw, 970px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/raed.academy\/wp-content\/uploads\/2019\/01\/ingreso-RAED-Joan-Massons-Rabassa-80.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"667\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2019\/01\/ingreso-RAED-Joan-Massons-Rabassa-80.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/raed.academy\/wp-content\/uploads\/2019\/01\/ingreso-RAED-Joan-Massons-Rabassa-80.jpg 1000w, https:\/\/raed.academy\/wp-content\/uploads\/2019\/01\/ingreso-RAED-Joan-Massons-Rabassa-80-768x512.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Joan Massons, professor d&#8217;ESADE i reconegut assessor financer, ingressa com a acad\u00e8mic de n\u00famero de la RAED Joan Massons, doctor en Administraci\u00f3 i Direcci\u00f3 d&#8217;Empreses, professor de Finances i Planificaci\u00f3 Financera de l&#8217;Escola de Negocis ESADE i reconegut assessor financer, va ingressar com a acad\u00e8mic de n\u00famero de la Reial Acad\u00e8mia Europea de Doctors-Barcelona 1914 [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":65464,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[233],"tags":[475],"class_list":["post-65736","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economiques-i-empresarials","tag-ingressos-academics","et-has-post-format-content","et_post_format-et-post-format-standard"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>R\u00e0tios que no diuen la veritat - Reial Acad\u00e8mia Europea de Doctors<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/raed.academy\/ca\/ingres-raed-joan-massons\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"R\u00e0tios que no diuen la veritat - Reial Acad\u00e8mia Europea de Doctors\" \/>\n<meta property=\"og:description\" content=\"Joan Massons, professor d&#8217;ESADE i reconegut assessor financer, ingressa com a acad\u00e8mic de n\u00famero de la RAED Joan Massons, doctor en Administraci\u00f3 i Direcci\u00f3 d&#8217;Empreses, professor de Finances i Planificaci\u00f3 Financera de l&#8217;Escola de Negocis ESADE i reconegut assessor financer, va ingressar com a acad\u00e8mic de n\u00famero de la Reial Acad\u00e8mia Europea de Doctors-Barcelona 1914 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/raed.academy\/ca\/ingres-raed-joan-massons\/\" \/>\n<meta property=\"og:site_name\" content=\"Reial Acad\u00e8mia Europea de Doctors\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/fb.me\/raed.academy\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-30T20:30:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-01-31T16:50:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/raed.academy\/wp-content\/uploads\/2019\/01\/ratios-dstNtc.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"550\" \/>\n\t<meta property=\"og:image:height\" content=\"362\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"RAED\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@raedacademy\" \/>\n<meta name=\"twitter:site\" content=\"@raedacademy\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"RAED\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/ingres-raed-joan-massons\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/ingres-raed-joan-massons\\\/\"},\"author\":{\"name\":\"RAED\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/person\\\/5a755da80d1d979fd66ba745c8702927\"},\"headline\":\"R\u00e0tios que no diuen la veritat\",\"datePublished\":\"2019-01-30T20:30:44+00:00\",\"dateModified\":\"2019-01-31T16:50:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/ingres-raed-joan-massons\\\/\"},\"wordCount\":408,\"publisher\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/ingres-raed-joan-massons\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/ratios-dstNtc.jpg\",\"keywords\":[\"Ingressos acad\u00e8mics\"],\"articleSection\":[\"Econ\u00f2miques i Empresarials\"],\"inLanguage\":\"ca-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/ingres-raed-joan-massons\\\/\",\"url\":\"https:\\\/\\\/raed.academy\\\/ca\\\/ingres-raed-joan-massons\\\/\",\"name\":\"R\u00e0tios que no diuen la veritat - Reial Acad\u00e8mia Europea de Doctors\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/ingres-raed-joan-massons\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/ingres-raed-joan-massons\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/ratios-dstNtc.jpg\",\"datePublished\":\"2019-01-30T20:30:44+00:00\",\"dateModified\":\"2019-01-31T16:50:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/ingres-raed-joan-massons\\\/#breadcrumb\"},\"inLanguage\":\"ca-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/raed.academy\\\/ca\\\/ingres-raed-joan-massons\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/ingres-raed-joan-massons\\\/#primaryimage\",\"url\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/ratios-dstNtc.jpg\",\"contentUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/ratios-dstNtc.jpg\",\"width\":550,\"height\":362},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/ingres-raed-joan-massons\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/raed.academy\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"R\u00e0tios que no diuen la veritat\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/raed.academy\\\/ca\\\/\",\"name\":\"Reial Acad\u00e8mia Europea de Doctors\",\"description\":\"Corporaci\u00f3n de derecho p\u00fablico de car\u00e1cter cient\u00edfico, t\u00e9cnico y art\u00edstico, que tiene por objeto la investigaci\u00f3n, el estudio, el fomento y la extensi\u00f3n del conocimiento en su sentido m\u00e1s amplio\",\"publisher\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/raed.academy\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#organization\",\"name\":\"Real Academia Europea de Doctores\",\"url\":\"https:\\\/\\\/raed.academy\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/cropped-logo_raed.png\",\"contentUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/cropped-logo_raed.png\",\"width\":512,\"height\":512,\"caption\":\"Real Academia Europea de Doctores\"},\"image\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/fb.me\\\/raed.academy\",\"https:\\\/\\\/x.com\\\/raedacademy\",\"https:\\\/\\\/www.instagram.com\\\/raed.academy\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCUYQwW2KrdirNWihxMDObwg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/person\\\/5a755da80d1d979fd66ba745c8702927\",\"name\":\"RAED\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g\",\"caption\":\"RAED\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"R\u00e0tios que no diuen la veritat - Reial Acad\u00e8mia Europea de Doctors","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/raed.academy\/ca\/ingres-raed-joan-massons\/","og_locale":"ca_ES","og_type":"article","og_title":"R\u00e0tios que no diuen la veritat - Reial Acad\u00e8mia Europea de Doctors","og_description":"Joan Massons, professor d&#8217;ESADE i reconegut assessor financer, ingressa com a acad\u00e8mic de n\u00famero de la RAED Joan Massons, doctor en Administraci\u00f3 i Direcci\u00f3 d&#8217;Empreses, professor de Finances i Planificaci\u00f3 Financera de l&#8217;Escola de Negocis ESADE i reconegut assessor financer, va ingressar com a acad\u00e8mic de n\u00famero de la Reial Acad\u00e8mia Europea de Doctors-Barcelona 1914 [&hellip;]","og_url":"https:\/\/raed.academy\/ca\/ingres-raed-joan-massons\/","og_site_name":"Reial Acad\u00e8mia Europea de Doctors","article_publisher":"http:\/\/fb.me\/raed.academy","article_published_time":"2019-01-30T20:30:44+00:00","article_modified_time":"2019-01-31T16:50:10+00:00","og_image":[{"width":550,"height":362,"url":"https:\/\/raed.academy\/wp-content\/uploads\/2019\/01\/ratios-dstNtc.jpg","type":"image\/jpeg"}],"author":"RAED","twitter_card":"summary_large_image","twitter_creator":"@raedacademy","twitter_site":"@raedacademy","twitter_misc":{"Written by":"RAED","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/raed.academy\/ca\/ingres-raed-joan-massons\/#article","isPartOf":{"@id":"https:\/\/raed.academy\/ca\/ingres-raed-joan-massons\/"},"author":{"name":"RAED","@id":"https:\/\/raed.academy\/ca\/#\/schema\/person\/5a755da80d1d979fd66ba745c8702927"},"headline":"R\u00e0tios que no diuen la veritat","datePublished":"2019-01-30T20:30:44+00:00","dateModified":"2019-01-31T16:50:10+00:00","mainEntityOfPage":{"@id":"https:\/\/raed.academy\/ca\/ingres-raed-joan-massons\/"},"wordCount":408,"publisher":{"@id":"https:\/\/raed.academy\/ca\/#organization"},"image":{"@id":"https:\/\/raed.academy\/ca\/ingres-raed-joan-massons\/#primaryimage"},"thumbnailUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2019\/01\/ratios-dstNtc.jpg","keywords":["Ingressos acad\u00e8mics"],"articleSection":["Econ\u00f2miques i Empresarials"],"inLanguage":"ca-ES"},{"@type":"WebPage","@id":"https:\/\/raed.academy\/ca\/ingres-raed-joan-massons\/","url":"https:\/\/raed.academy\/ca\/ingres-raed-joan-massons\/","name":"R\u00e0tios que no diuen la veritat - Reial Acad\u00e8mia Europea de Doctors","isPartOf":{"@id":"https:\/\/raed.academy\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/raed.academy\/ca\/ingres-raed-joan-massons\/#primaryimage"},"image":{"@id":"https:\/\/raed.academy\/ca\/ingres-raed-joan-massons\/#primaryimage"},"thumbnailUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2019\/01\/ratios-dstNtc.jpg","datePublished":"2019-01-30T20:30:44+00:00","dateModified":"2019-01-31T16:50:10+00:00","breadcrumb":{"@id":"https:\/\/raed.academy\/ca\/ingres-raed-joan-massons\/#breadcrumb"},"inLanguage":"ca-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/raed.academy\/ca\/ingres-raed-joan-massons\/"]}]},{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/raed.academy\/ca\/ingres-raed-joan-massons\/#primaryimage","url":"https:\/\/raed.academy\/wp-content\/uploads\/2019\/01\/ratios-dstNtc.jpg","contentUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2019\/01\/ratios-dstNtc.jpg","width":550,"height":362},{"@type":"BreadcrumbList","@id":"https:\/\/raed.academy\/ca\/ingres-raed-joan-massons\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/raed.academy\/ca\/"},{"@type":"ListItem","position":2,"name":"R\u00e0tios que no diuen la veritat"}]},{"@type":"WebSite","@id":"https:\/\/raed.academy\/ca\/#website","url":"https:\/\/raed.academy\/ca\/","name":"Reial Acad\u00e8mia Europea de Doctors","description":"Corporaci\u00f3n de derecho p\u00fablico de car\u00e1cter cient\u00edfico, t\u00e9cnico y art\u00edstico, que tiene por objeto la investigaci\u00f3n, el estudio, el fomento y la extensi\u00f3n del conocimiento en su sentido m\u00e1s amplio","publisher":{"@id":"https:\/\/raed.academy\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/raed.academy\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca-ES"},{"@type":"Organization","@id":"https:\/\/raed.academy\/ca\/#organization","name":"Real Academia Europea de Doctores","url":"https:\/\/raed.academy\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/raed.academy\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/raed.academy\/wp-content\/uploads\/2017\/01\/cropped-logo_raed.png","contentUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2017\/01\/cropped-logo_raed.png","width":512,"height":512,"caption":"Real Academia Europea de Doctores"},"image":{"@id":"https:\/\/raed.academy\/ca\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/fb.me\/raed.academy","https:\/\/x.com\/raedacademy","https:\/\/www.instagram.com\/raed.academy\/","https:\/\/www.youtube.com\/channel\/UCUYQwW2KrdirNWihxMDObwg"]},{"@type":"Person","@id":"https:\/\/raed.academy\/ca\/#\/schema\/person\/5a755da80d1d979fd66ba745c8702927","name":"RAED","image":{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g","caption":"RAED"}}]}},"_links":{"self":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/posts\/65736","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/comments?post=65736"}],"version-history":[{"count":0,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/posts\/65736\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/media\/65464"}],"wp:attachment":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/media?parent=65736"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/categories?post=65736"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/tags?post=65736"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}