{"id":188762,"date":"2026-08-11T19:47:30","date_gmt":"2026-08-11T19:47:30","guid":{"rendered":"https:\/\/raed.academy\/?p=188762"},"modified":"2026-08-12T12:47:38","modified_gmt":"2026-08-12T12:47:38","slug":"la-vigencia-de-la-constitucio-2","status":"publish","type":"post","link":"https:\/\/raed.academy\/ca\/la-vigencia-de-la-constitucio-2\/","title":{"rendered":"La vig\u00e8ncia de la Constituci\u00f3"},"content":{"rendered":"<div id=\"attachment_185784\" style=\"width: 510px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-185784\" class=\"wp-image-185784 size-full\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2026\/05\/Daniel-Berzosa-Lopez-2-imgcp-1.67.webp\" sizes=\"(max-width: 500px) 100vw, 500px\" srcset=\"https:\/\/raed.academy\/wp-content\/uploads\/2026\/05\/Daniel-Berzosa-Lopez-2-imgcp-1.67.webp 500w, https:\/\/raed.academy\/wp-content\/uploads\/2026\/05\/Daniel-Berzosa-Lopez-2-imgcp-1.67-440x264.webp 440w\" alt=\"Daniel Berzosa\" width=\"500\" height=\"300\" aria-describedby=\"caption-attachment-185784\" \/><p id=\"caption-attachment-185784\" class=\"wp-caption-text\">Dr. Daniel Berzosa<\/p><\/div>\n<p><a href=\"https:\/\/raed.academy\/ca\/academics\/dr-daniel-berzosa-lopez\/\" target=\"_blank\" rel=\"noopener\"><em><strong>Daniel Berzosa<\/strong><\/em><\/a>, professor de\u00a0Dret\u00a0Constitucional i\u00a0Drets\u00a0Fonamentals\u00a0de\u00a0<strong>Cunef\u00a0Universitat<\/strong>, de l&#8217;<strong>Institut d&#8217;Estudis Borsaris<\/strong> i de l&#8217;<strong>Institut d&#8217;Empresa-Law &amp; Business School<\/strong>, membre de l&#8217;<strong>Acad\u00e8mia Global<\/strong> i del <strong>Consell Cient\u00edfic<\/strong> del col\u00b7lectiu internacional <strong>Citizens pro Europe<\/strong> i acad\u00e8mic de n\u00famero i membre de la <strong>Junta de Govern<\/strong> de la <strong>Reial Acad\u00e8mia Europea de Doctors<\/strong> (RAED), va presentar el passat 15 de juliol als <strong>Cursos d&#8217;Estiu<\/strong> que la <strong>Universitat Complutense de Madrid<\/strong> va celebrar a San Lorenzo de El Escorial sota el t\u00edtol <strong>&#8220;La Constituci\u00f3n de 1978, \u00bfen cuidados intensivos o ya en paliativos?&#8221;<\/strong>, la confer\u00e8ncia inaugural <strong>&#8220;La Constituci\u00f3n espa\u00f1ola de 1978, \u00bfsigue vigente?&#8221;<\/strong>, en la que va defensar la plena legitimitat de la Carta Magna, no nom\u00e9s com a text formal, sin\u00f3 com a norma efectiva que limita i ordena el poder. A la cita van participar d&#8217;altres destacats representants de l&#8217;\u00e0mbit judicial, acad\u00e8mic, pol\u00edtic i period\u00edstic. Dirigit per<strong> Manuel Almenar<\/strong>, magistrat de la <strong>Sala Primera<\/strong> del <strong>Tribunal Suprem<\/strong>, la trobada va comptar amb el patrocini de la <strong>Fundaci\u00f3 per a la Magistratura<\/strong> i de <strong>Telef\u00f3nica<\/strong>. D&#8217;altra banda, l&#8217;expert jurista va reflexionar sobre la recent reforma del <strong>Codi Penal<\/strong> en relaci\u00f3 amb la consideraci\u00f3 que tenen les inj\u00faries a la Corona en el programa <strong>&#8220;Audiencia abierta&#8221;<\/strong> de<strong> Televisi\u00f3 Espanyola<\/strong> em\u00e8s el passat 18 de juliol.<\/p>\n<p>L&#8217;expert va afirmar que la vig\u00e8ncia de la <strong>Constituci\u00f3<\/strong> no es mesura per la seva simple pres\u00e8ncia al <strong>Butllet\u00ed Oficial de l&#8217;Estat<\/strong>, sin\u00f3 per la seva capacitat de governar realment el poder i de ser aplicada cada dia. En aquest sentit va rec\u00f3rrer a la classificaci\u00f3 de <strong>Karl Loewenstein<\/strong>, que distingeix entre constitucions normatives, nominals o sem\u00e0ntiques per determinar que l&#8217;espanyola del 1978 continua sent normativa gr\u00e0cies a la tasca quotidiana dels jutges, que descriu com els arcbotants invisibles de l&#8217;Estat de dret. Berzosa va tra\u00e7ar la traject\u00f2ria del constitucionalisme des d&#8217;<strong>Arist\u00f2til<\/strong> i <strong>Domicio Ulpiano<\/strong> fins a <strong>John Locke<\/strong>, <strong>Montesquieu<\/strong>, <strong>Alexander Hamilton<\/strong> i <strong>James Madison<\/strong>, subratllant que el text del 1978 va n\u00e9ixer del consens entre antics enemics, no de la imposici\u00f3 d&#8217;un vencedor. I va destacar com centre suss articles 1 i 2: Espanya com a Estat social i democr\u00e0tic de dret, la sobirania popular i la unitat de la naci\u00f3 compatible amb l&#8217;autonomia de les nacionalitats i regions.<\/p>\n<p>Berzosa, per\u00f2, va recon\u00e8ixer tensions i erosions al present, generades en bona mesura per la vulneraci\u00f3 de la separaci\u00f3 de poders, com la polititzaci\u00f3 del <strong>Consell General del Poder Judicial<\/strong>, l&#8217;\u00fas excessiu del decret llei, les friccions del model territorial i certes derives interpretatives. Tot i aix\u00f2, va considerar que la Constituci\u00f3 ha superat amb \u00e8xit les crisis m\u00e9s greus de les \u00faltimes d\u00e8cades i que el seu assoliment m\u00e9s gran \u00e9s la normalitat dels drets fonamentals i la subjecci\u00f3 del poder a la llei. La vig\u00e8ncia d&#8217;una Carta Magna, va acabar, no \u00e9s irreversible, dep\u00e8n de la fidelitat de jutges, institucions i ciutadans. I va assegurar que mentre es mantingui la convicci\u00f3 que el poder s&#8217;ha de sotmetre al dret, la Constituci\u00f3 continuar\u00e0 respirant.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-93780 alignright\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2020\/09\/Constitucion-espanola-dstNtc.jpg\" sizes=\"(max-width: 500px) 100vw, 500px\" srcset=\"https:\/\/raed.academy\/wp-content\/uploads\/2020\/09\/Constitucion-espanola-dstNtc.jpg 500w, https:\/\/raed.academy\/wp-content\/uploads\/2020\/09\/Constitucion-espanola-dstNtc-440x264.jpg 440w\" alt=\"\" width=\"500\" height=\"300\" \/>A Televisi\u00f3 Espanyola, d&#8217;altra banda, l&#8217;acad\u00e8mic va explicar la reforma que elimina el tipus penal espec\u00edfic d&#8217;inj\u00faries a la Corona, tot i que no s&#8217;elimina la protecci\u00f3 al dret a l&#8217;honor, la intimitat o la mateixa imatge de qualsevol membre de la fam\u00edlia reial, prioritzant la llibertat d&#8217;expressi\u00f3. &#8220;El que permet la reforma \u00e9s equiparar la llei per a tothom, la qual cosa no significa la desprotecci\u00f3 a la Corona. El <strong>Tribunal Europeu dels Drets Humans<\/strong> ja havia dictaminat que a una democr\u00e0cia constitucional no hauria d&#8217;establir-se cap altra difer\u00e8ncia&#8221;, va assenyalar l&#8217;expert jurista.<\/p>\n<p>Berzosa \u00e9s membre de la <strong>Societat de Diplom\u00e0cia i Ci\u00e8ncies Pol\u00edtiques dels Estats Units<\/strong>, coordinador de l&#8217;<strong>Observatori Internacional de la Regulaci\u00f3 de les Entitats del Sector P\u00fablic<\/strong> de la <strong>Universitat de Santiago de Compostel\u00b7la<\/strong>, membre dels comit\u00e8s organitzadors dels congressos del <strong>World Law Congress<\/strong> de Cartagena de Indias 2021 i Madrid 2019 i autor de llibres i articles cient\u00edfics publicats en revistes de prestigi. \u00c9s aix\u00ed mateix un reconegut divulgador de temes legals i ci\u00e8ncies pol\u00edtiques en els principals mitjans de comunicaci\u00f3 espanyols.<\/p>\n<h2 dir=\"auto\"><em><a href=\"https:\/\/www.danielberzosa.com\/wp-content\/uploads\/2026\/07\/Vigencia-de-la-CE78_vf.pdf\" target=\"_blank\" rel=\"noopener\">Llegiu l&#8217;article<\/a><\/em><\/h2>\n<p><iframe loading=\"lazy\" title=\"Injurias a la Corona\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/4byh_WibL98?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Daniel Berzosa defensa la plena legitimitat de la Carta Magna, no nom\u00e9s com a text formal, sin\u00f3 com a norma efectiva que limita i ordena el poder, a la confer\u00e8ncia &#8220;La Constituci\u00f3 espanyola de 1978, segueix vigent?&#8221;<\/p>\n","protected":false},"author":12,"featured_media":93781,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[350,225,509,242,404,487],"tags":[],"class_list":["post-188762","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencies-politiques","category-dret","category-dret-penal","category-categ-historia","category-historia-nacional-ca","category-monarquia-ca","et-has-post-format-content","et_post_format-et-post-format-standard"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La vig\u00e8ncia de la Constituci\u00f3 - Reial Acad\u00e8mia Europea de Doctors<\/title>\n<meta name=\"description\" content=\"Daniel Berzosa defensa la plena legitimitat de la Carta Magna, no nom\u00e9s com a text formal, sin\u00f3 com a norma efectiva que limita i ordena el poder, a la confer\u00e8ncia &quot;La Constituci\u00f3 espanyola de 1978, segueix vigent?&quot;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/raed.academy\/ca\/la-vigencia-de-la-constitucio-2\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La vig\u00e8ncia de la Constituci\u00f3 - Reial Acad\u00e8mia Europea de Doctors\" \/>\n<meta property=\"og:description\" content=\"Daniel Berzosa defensa la plena legitimitat de la Carta Magna, no nom\u00e9s com a text formal, sin\u00f3 com a norma efectiva que limita i ordena el poder, a la confer\u00e8ncia &quot;La Constituci\u00f3 espanyola de 1978, segueix vigent?&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/raed.academy\/ca\/la-vigencia-de-la-constitucio-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Reial Acad\u00e8mia Europea de Doctors\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/fb.me\/raed.academy\" \/>\n<meta property=\"article:published_time\" content=\"2026-08-11T19:47:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-12T12:47:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/raed.academy\/wp-content\/uploads\/2020\/09\/Constitucion-espanola-dstNtc.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"RAED\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@raedacademy\" \/>\n<meta name=\"twitter:site\" content=\"@raedacademy\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"RAED\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/la-vigencia-de-la-constitucio-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/la-vigencia-de-la-constitucio-2\\\/\"},\"author\":{\"name\":\"RAED\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/person\\\/5a755da80d1d979fd66ba745c8702927\"},\"headline\":\"La vig\u00e8ncia de la Constituci\u00f3\",\"datePublished\":\"2026-08-11T19:47:30+00:00\",\"dateModified\":\"2026-08-12T12:47:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/la-vigencia-de-la-constitucio-2\\\/\"},\"wordCount\":775,\"publisher\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/la-vigencia-de-la-constitucio-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Constitucion-espanola-dstNtc.jpg\",\"articleSection\":[\"Ci\u00e8ncies pol\u00edtiques\",\"Dret\",\"Dret Penal\",\"Hist\u00f2ria\",\"Hist\u00f2ria nacional\",\"Monarquia\"],\"inLanguage\":\"ca-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/la-vigencia-de-la-constitucio-2\\\/\",\"url\":\"https:\\\/\\\/raed.academy\\\/ca\\\/la-vigencia-de-la-constitucio-2\\\/\",\"name\":\"La vig\u00e8ncia de la Constituci\u00f3 - Reial Acad\u00e8mia Europea de Doctors\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/la-vigencia-de-la-constitucio-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/la-vigencia-de-la-constitucio-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Constitucion-espanola-dstNtc.jpg\",\"datePublished\":\"2026-08-11T19:47:30+00:00\",\"dateModified\":\"2026-08-12T12:47:38+00:00\",\"description\":\"Daniel Berzosa defensa la plena legitimitat de la Carta Magna, no nom\u00e9s com a text formal, sin\u00f3 com a norma efectiva que limita i ordena el poder, a la confer\u00e8ncia \\\"La Constituci\u00f3 espanyola de 1978, segueix vigent?\\\"\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/la-vigencia-de-la-constitucio-2\\\/#breadcrumb\"},\"inLanguage\":\"ca-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/raed.academy\\\/ca\\\/la-vigencia-de-la-constitucio-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/la-vigencia-de-la-constitucio-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Constitucion-espanola-dstNtc.jpg\",\"contentUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Constitucion-espanola-dstNtc.jpg\",\"width\":500,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/la-vigencia-de-la-constitucio-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/raed.academy\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La vig\u00e8ncia de la Constituci\u00f3\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/raed.academy\\\/ca\\\/\",\"name\":\"Reial Acad\u00e8mia Europea de Doctors\",\"description\":\"Corporaci\u00f3n de derecho p\u00fablico de car\u00e1cter cient\u00edfico, t\u00e9cnico y art\u00edstico, que tiene por objeto la investigaci\u00f3n, el estudio, el fomento y la extensi\u00f3n del conocimiento en su sentido m\u00e1s amplio\",\"publisher\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/raed.academy\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#organization\",\"name\":\"Real Academia Europea de Doctores\",\"url\":\"https:\\\/\\\/raed.academy\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/cropped-logo_raed.png\",\"contentUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/cropped-logo_raed.png\",\"width\":512,\"height\":512,\"caption\":\"Real Academia Europea de Doctores\"},\"image\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/fb.me\\\/raed.academy\",\"https:\\\/\\\/x.com\\\/raedacademy\",\"https:\\\/\\\/www.instagram.com\\\/raed.academy\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCUYQwW2KrdirNWihxMDObwg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/person\\\/5a755da80d1d979fd66ba745c8702927\",\"name\":\"RAED\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g\",\"caption\":\"RAED\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La vig\u00e8ncia de la Constituci\u00f3 - Reial Acad\u00e8mia Europea de Doctors","description":"Daniel Berzosa defensa la plena legitimitat de la Carta Magna, no nom\u00e9s com a text formal, sin\u00f3 com a norma efectiva que limita i ordena el poder, a la confer\u00e8ncia \"La Constituci\u00f3 espanyola de 1978, segueix vigent?\"","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/raed.academy\/ca\/la-vigencia-de-la-constitucio-2\/","og_locale":"ca_ES","og_type":"article","og_title":"La vig\u00e8ncia de la Constituci\u00f3 - Reial Acad\u00e8mia Europea de Doctors","og_description":"Daniel Berzosa defensa la plena legitimitat de la Carta Magna, no nom\u00e9s com a text formal, sin\u00f3 com a norma efectiva que limita i ordena el poder, a la confer\u00e8ncia \"La Constituci\u00f3 espanyola de 1978, segueix vigent?\"","og_url":"https:\/\/raed.academy\/ca\/la-vigencia-de-la-constitucio-2\/","og_site_name":"Reial Acad\u00e8mia Europea de Doctors","article_publisher":"http:\/\/fb.me\/raed.academy","article_published_time":"2026-08-11T19:47:30+00:00","article_modified_time":"2026-08-12T12:47:38+00:00","og_image":[{"width":500,"height":300,"url":"https:\/\/raed.academy\/wp-content\/uploads\/2020\/09\/Constitucion-espanola-dstNtc.jpg","type":"image\/jpeg"}],"author":"RAED","twitter_card":"summary_large_image","twitter_creator":"@raedacademy","twitter_site":"@raedacademy","twitter_misc":{"Written by":"RAED","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/raed.academy\/ca\/la-vigencia-de-la-constitucio-2\/#article","isPartOf":{"@id":"https:\/\/raed.academy\/ca\/la-vigencia-de-la-constitucio-2\/"},"author":{"name":"RAED","@id":"https:\/\/raed.academy\/ca\/#\/schema\/person\/5a755da80d1d979fd66ba745c8702927"},"headline":"La vig\u00e8ncia de la Constituci\u00f3","datePublished":"2026-08-11T19:47:30+00:00","dateModified":"2026-08-12T12:47:38+00:00","mainEntityOfPage":{"@id":"https:\/\/raed.academy\/ca\/la-vigencia-de-la-constitucio-2\/"},"wordCount":775,"publisher":{"@id":"https:\/\/raed.academy\/ca\/#organization"},"image":{"@id":"https:\/\/raed.academy\/ca\/la-vigencia-de-la-constitucio-2\/#primaryimage"},"thumbnailUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2020\/09\/Constitucion-espanola-dstNtc.jpg","articleSection":["Ci\u00e8ncies pol\u00edtiques","Dret","Dret Penal","Hist\u00f2ria","Hist\u00f2ria nacional","Monarquia"],"inLanguage":"ca-ES"},{"@type":"WebPage","@id":"https:\/\/raed.academy\/ca\/la-vigencia-de-la-constitucio-2\/","url":"https:\/\/raed.academy\/ca\/la-vigencia-de-la-constitucio-2\/","name":"La vig\u00e8ncia de la Constituci\u00f3 - Reial Acad\u00e8mia Europea de Doctors","isPartOf":{"@id":"https:\/\/raed.academy\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/raed.academy\/ca\/la-vigencia-de-la-constitucio-2\/#primaryimage"},"image":{"@id":"https:\/\/raed.academy\/ca\/la-vigencia-de-la-constitucio-2\/#primaryimage"},"thumbnailUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2020\/09\/Constitucion-espanola-dstNtc.jpg","datePublished":"2026-08-11T19:47:30+00:00","dateModified":"2026-08-12T12:47:38+00:00","description":"Daniel Berzosa defensa la plena legitimitat de la Carta Magna, no nom\u00e9s com a text formal, sin\u00f3 com a norma efectiva que limita i ordena el poder, a la confer\u00e8ncia \"La Constituci\u00f3 espanyola de 1978, segueix vigent?\"","breadcrumb":{"@id":"https:\/\/raed.academy\/ca\/la-vigencia-de-la-constitucio-2\/#breadcrumb"},"inLanguage":"ca-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/raed.academy\/ca\/la-vigencia-de-la-constitucio-2\/"]}]},{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/raed.academy\/ca\/la-vigencia-de-la-constitucio-2\/#primaryimage","url":"https:\/\/raed.academy\/wp-content\/uploads\/2020\/09\/Constitucion-espanola-dstNtc.jpg","contentUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2020\/09\/Constitucion-espanola-dstNtc.jpg","width":500,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/raed.academy\/ca\/la-vigencia-de-la-constitucio-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/raed.academy\/ca\/"},{"@type":"ListItem","position":2,"name":"La vig\u00e8ncia de la Constituci\u00f3"}]},{"@type":"WebSite","@id":"https:\/\/raed.academy\/ca\/#website","url":"https:\/\/raed.academy\/ca\/","name":"Reial Acad\u00e8mia Europea de Doctors","description":"Corporaci\u00f3n de derecho p\u00fablico de car\u00e1cter cient\u00edfico, t\u00e9cnico y art\u00edstico, que tiene por objeto la investigaci\u00f3n, el estudio, el fomento y la extensi\u00f3n del conocimiento en su sentido m\u00e1s amplio","publisher":{"@id":"https:\/\/raed.academy\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/raed.academy\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca-ES"},{"@type":"Organization","@id":"https:\/\/raed.academy\/ca\/#organization","name":"Real Academia Europea de Doctores","url":"https:\/\/raed.academy\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/raed.academy\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/raed.academy\/wp-content\/uploads\/2017\/01\/cropped-logo_raed.png","contentUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2017\/01\/cropped-logo_raed.png","width":512,"height":512,"caption":"Real Academia Europea de Doctores"},"image":{"@id":"https:\/\/raed.academy\/ca\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/fb.me\/raed.academy","https:\/\/x.com\/raedacademy","https:\/\/www.instagram.com\/raed.academy\/","https:\/\/www.youtube.com\/channel\/UCUYQwW2KrdirNWihxMDObwg"]},{"@type":"Person","@id":"https:\/\/raed.academy\/ca\/#\/schema\/person\/5a755da80d1d979fd66ba745c8702927","name":"RAED","image":{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g","caption":"RAED"}}]}},"_links":{"self":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/posts\/188762","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/comments?post=188762"}],"version-history":[{"count":3,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/posts\/188762\/revisions"}],"predecessor-version":[{"id":188802,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/posts\/188762\/revisions\/188802"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/media\/93781"}],"wp:attachment":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/media?parent=188762"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/categories?post=188762"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/tags?post=188762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}