{"id":165115,"date":"2025-06-16T09:39:23","date_gmt":"2025-06-16T09:39:23","guid":{"rendered":"https:\/\/raed.academy\/?p=165115"},"modified":"2025-06-16T09:39:23","modified_gmt":"2025-06-16T09:39:23","slug":"daristotil-a-ulisses-i-daltres-referents-universals","status":"publish","type":"post","link":"https:\/\/raed.academy\/ca\/daristotil-a-ulisses-i-daltres-referents-universals\/","title":{"rendered":"D&#8217;Arist\u00f2til a Ulisses i d&#8217;altres referents universals"},"content":{"rendered":"<div id=\"attachment_144449\" style=\"width: 510px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-144449\" class=\"wp-image-144449 size-full\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2014\/07\/Joaquin-Callabed-dstNtc.jpg\" alt=\"Dr. Joaqu\u00edn Callabed\" width=\"500\" height=\"300\" srcset=\"https:\/\/raed.academy\/wp-content\/uploads\/2014\/07\/Joaquin-Callabed-dstNtc.jpg 500w, https:\/\/raed.academy\/wp-content\/uploads\/2014\/07\/Joaquin-Callabed-dstNtc-440x264.jpg 440w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><p id=\"caption-attachment-144449\" class=\"wp-caption-text\">Dr. Joaqu\u00edn Callabed<\/p><\/div>\n<p><a href=\"https:\/\/raed.academy\/ca\/academics\/dr-joaquin-callabed-carracedo\/\" target=\"_blank\" rel=\"noopener\"><em><strong>Joaqu\u00edn Callabed<\/strong><\/em><\/a>, president del <strong>Club de\u00a0Pediatria\u00a0Social<\/strong>, acad\u00e8mic corresponent de la <strong>Reial Acad\u00e8mia de\u00a0Medicina\u00a0de\u00a0Catalunya<\/strong>\u00a0i de la <strong>Reial Acad\u00e8mia de\u00a0Farm\u00e0cia\u00a0de\u00a0Catalunya<\/strong>\u00a0i acad\u00e8mic numerari i vicepresident de la\u00a0Secci\u00f3\u00a0de\u00a0Ci\u00e8ncies\u00a0de la\u00a0Salut\u00a0de la <strong>Reial Acad\u00e8mia Europea de\u00a0Doctors\u00a0<\/strong>(RAED), repr\u00e8n les seves reflexions sobre els autors de l&#8217;Antiga Gr\u00e8cia i l&#8217;actualitat de la cultura cl\u00e0ssica als articles <strong>&#8220;<span class=\"TextRun SCXW230926259 BCX0\" lang=\"ES-ES\" xml:lang=\"ES-ES\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW230926259 BCX0\">El Liceo creado por Arist\u00f3teles&#8221;<\/span><\/span><\/strong><span class=\"TextRun SCXW230926259 BCX0\" lang=\"ES-ES\" xml:lang=\"ES-ES\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW230926259 BCX0\">, <\/span><\/span><strong><span class=\"TextRun SCXW230926259 BCX0\" lang=\"ES-ES\" xml:lang=\"ES-ES\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW230926259 BCX0\">&#8220;<\/span><\/span><span class=\"TextRun SCXW230926259 BCX0\" lang=\"ES-ES\" xml:lang=\"ES-ES\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW230926259 BCX0\">Tales de Mileto, uno de los siete sabios de Grecia&#8221;<\/span><\/span><\/strong><span class=\"TextRun SCXW230926259 BCX0\" lang=\"ES-ES\" xml:lang=\"ES-ES\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW230926259 BCX0\">,<\/span><\/span><strong><span class=\"TextRun SCXW230926259 BCX0\" lang=\"ES-ES\" xml:lang=\"ES-ES\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW230926259 BCX0\"> &#8220;El gran siglo de Pis\u00edstrato&#8221;<\/span><\/span><\/strong><span class=\"TextRun SCXW230926259 BCX0\" lang=\"ES-ES\" xml:lang=\"ES-ES\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW230926259 BCX0\">,<\/span><\/span><strong><span class=\"TextRun SCXW230926259 BCX0\" lang=\"ES-ES\" xml:lang=\"ES-ES\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW230926259 BCX0\"> &#8220;La educaci\u00f3n infantil en la Antigua Grecia&#8221;<\/span><\/span><\/strong><span class=\"TextRun SCXW230926259 BCX0\" lang=\"ES-ES\" xml:lang=\"ES-ES\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW230926259 BCX0\">,<\/span><\/span><strong><span class=\"TextRun SCXW230926259 BCX0\" lang=\"ES-ES\" xml:lang=\"ES-ES\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW230926259 BCX0\"> &#8220;Her\u00e1clito de \u00c9feso y el fuego&#8221;<\/span><\/span><\/strong><span class=\"TextRun SCXW230926259 BCX0\" lang=\"ES-ES\" xml:lang=\"ES-ES\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW230926259 BCX0\"> i<\/span><\/span> <strong><span class=\"TextRun SCXW230926259 BCX0\" lang=\"ES-ES\" xml:lang=\"ES-ES\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW230926259 BCX0\">&#8220;Ulises, s\u00edmbolo de la aventura humana&#8221;<\/span><\/span><\/strong>, publicats entre aquests mesos de maig i juny a la secci\u00f3 <strong>&#8220;Lectores expertos&#8221;<\/strong> de l&#8217;edici\u00f3 digital del diari <strong>&#8220;La Vanguardia&#8221;<\/strong>, de la comunitat de lectors de la qual forma part activa.<\/p>\n<p>A <em>&#8220;El Liceu creado por Arist\u00f3teles&#8221;<\/em>, Callabed es refereix al llegendari espai situat en les proximitats del temple d&#8217;<strong>Apol\u00b7lo Lici<\/strong>, dins de les muralles d&#8217;Atenes, on <strong>Arist\u00f2til<\/strong> impartia els seus ensenyaments, tradicionalment passejant amb els seus deixebles pel jard\u00ed o per algun p\u00f2rtic cobert. Per aix\u00f2 l&#8217;escola filos\u00f2fica d&#8217;Arist\u00f2til se la coneix com l&#8217;escola del Liceu, o tamb\u00e9, com l&#8217;escola peripat\u00e8tica. &#8220;Al Liceu, Arist\u00f2til va dictar les lli\u00e7ons que constituiran despr\u00e9s la major part de la seva obra conservada. L&#8217;escola sempre va tenir una orientaci\u00f3 emp\u00edrica, en oposici\u00f3 a l&#8217;Acad\u00e8mia d&#8217;Atenes, molt m\u00e9s especulativa. Aquesta orientaci\u00f3 emp\u00edrica s&#8217;accentua quan <strong>Teofrast<\/strong> n&#8217;assumeix la direcci\u00f3. Al testament d&#8217;Arist\u00f2til es parla de la infraestructura del Liceu, que comptava amb jard\u00ed, el passeig, biblioteca i d&#8217;altres peces&#8221;, explica.<\/p>\n<p>D&#8217;altra banda, en <em>&#8220;Tales de Mileto, uno de los siete sabios de Grecia&#8221;<\/em>, l&#8217;expert recupera la figura d&#8217;aquest fil\u00f2sof, matem\u00e0tic, ge\u00f2metra, f\u00edsic i legislador grec que va definir l&#8217;aigua com el principi originari de la natura i va fundar l&#8217;Escola J\u00f2nica de Milet. &#8220;<strong>Tales de Milet<\/strong> \u00e9s reconegut per trencar amb l\u2019\u00fas de la mitologia per explicar el m\u00f3n i l&#8217;univers, canviant-lo per explicacions naturals mitjan\u00e7ant teories i hip\u00f2tesis naturalistes que utilitzen la ra\u00f3 (logos), per la qual cosa \u00e9s considerat l&#8217;iniciador de l&#8217;especulaci\u00f3 cient\u00edfica i filos\u00f2fica grega i occidental&#8221;, assenyala.<\/p>\n<p>A <em>&#8220;El gran siglo de Pis\u00edstrato&#8221;<\/em>, l&#8217;acad\u00e8mic presenta el personatge que ha estat considerat el prototip dels tirans grecs despr\u00e9s d&#8217;exercir un r\u00e8gim amb m\u00e0 de ferro i grans \u00e8xits pol\u00edtics a Atenes al segle VI aC &#8220;El segle de <strong>Pis\u00edstrat<\/strong> a l&#8217;Antiga Gr\u00e8cia \u00e9s un dels grans de la hist\u00f2ria. Se li ha considerat el prototip dels tirans grecs, la pol\u00edtica dels quals evoca els d\u00e8spotes il\u00b7lustrats del segle XVIII. Va exercir la dictadura a Atenes entre 561 i 528 aC amb dues interrupcions&#8221;, recorda.<\/p>\n<p>El president del Club de Pediatria Social dedica &#8220;La educaci\u00f3n infantil en la Antigua Grecia&#8221; a analitzar els diferents models educatius a aquest per\u00edode cl\u00e0ssic. &#8220;A Atenes, el pare tenia dret a acceptar el nen nounat o exposar-lo, \u00e9s a dir, abandonar-lo, sense preocupar-se si seria acollit o moriria com els petits cadells. A Esparta nom\u00e9s la Comunitat dels Iguals podia decidir sense consultar amb els pares, si el nounat era prou robust per arribar a ser un espart\u00e0 o b\u00e9 calia llan\u00e7ar-lo a l\u2019avenc del B\u00e0rat, que era un clot profund on es llan\u00e7aven els condemnats a mort&#8221;, inicia la seva explicaci\u00f3.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-123506 alignleft\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2022\/10\/partenon-antigua-Grecia-licencia-pixabay.com-no-atrib.webp\" sizes=\"(max-width: 600px) 100vw, 600px\" srcset=\"https:\/\/raed.academy\/wp-content\/uploads\/2022\/10\/partenon-antigua-Grecia-licencia-pixabay.com-no-atrib.webp 600w, https:\/\/raed.academy\/wp-content\/uploads\/2022\/10\/partenon-antigua-Grecia-licencia-pixabay.com-no-atrib-440x264.webp 440w\" alt=\"Parten\u00f3n de la antigua Grecia\" width=\"600\" height=\"360\" aria-describedby=\"caption-attachment-123506\" \/>A <em>&#8220;Her\u00e1clito de \u00c9feso i el fuego&#8221;<\/em>, el &#8216;lector expert&#8217; aborda la figura i l&#8217;obra d&#8217;un dels primers fil\u00f2sofs presocr\u00e0tics que va provar d&#8217;identificar la primera causa de creaci\u00f3 del m\u00f3n. &#8220;Va ser un dels primers fil\u00f2sofs que va voler explicar la primera causa de la creaci\u00f3 del m\u00f3n. Per aix\u00f2, va rebutjar anteriors opinions com la de Tales de Milet, que considerava que era l&#8217;aigua, o la d&#8217;<strong>Anaximandre<\/strong>, que considerava que era l&#8217;aire. Per contra, va considerar <strong>Her\u00e0clit d&#8217;Efes<\/strong> que el foc n&#8217;\u00e9s la causa primera&#8221;, detalla.<\/p>\n<p>Finalment, a <em>&#8220;Ulises, s\u00edmbolo de la aventura humana&#8221;<\/em>, Callabed fa refer\u00e8ncia a un dels protagonistes principals de la guerra de Troia i un dels grans herois dels grecs que han passat a la hist\u00f2ria i s\u00f3n de refer\u00e8ncia comuna encara avui dia. &#8220;Caracteritza a <strong>Ulisses<\/strong> la seva humanitat. Els seus companys s\u00f3n amics i s\u00fabdits i li obeeixen perqu\u00e8 veuen en ell un esperit superior capa\u00e7 de superar totes les dificultats. Ulisses considera que la intel\u00b7lig\u00e8ncia i l&#8217;enginy poden imposar-se sempre, tant si es troba amb la maga <strong>Circe<\/strong>, a l&#8217;antre del ciclop o llan\u00e7at per la tempesta a les riberes dels feacios sap respondre adequadament: valor, reflexi\u00f3 i ast\u00facia s\u00f3n les seves armes preferides. La deessa <strong>Atena<\/strong> no deixa mai de protegir-lo, salvant-lo de perills i apareixent d\u2019una forma o l&#8217;altra per guiar-lo enmig de dificultats&#8221;, narra.<\/p>\n<p><a href=\"https:\/\/www.lavanguardia.com\/participacion\/red-lectores\/20250519\/10684879\/liceo-creado-aristoteles.html\" target=\"_blank\" rel=\"noopener\"><strong>Llegiu &#8220;<span class=\"TextRun SCXW230926259 BCX0\" lang=\"ES-ES\" xml:lang=\"ES-ES\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW230926259 BCX0\">El Liceo creado por Arist\u00f3teles&#8221;<\/span><\/span><\/strong><\/a><span class=\"TextRun SCXW230926259 BCX0\" lang=\"ES-ES\" xml:lang=\"ES-ES\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW230926259 BCX0\"><br \/>\n<\/span><\/span><a href=\"https:\/\/www.lavanguardia.com\/participacion\/red-lectores\/20250529\/10728013\/tales-mileto-siete-sabios-grecia.html\" target=\"_blank\" rel=\"noopener\"><strong><span class=\"TextRun SCXW230926259 BCX0\" lang=\"ES-ES\" xml:lang=\"ES-ES\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW230926259 BCX0\">Llegiu &#8220;<\/span><\/span><span class=\"TextRun SCXW230926259 BCX0\" lang=\"ES-ES\" xml:lang=\"ES-ES\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW230926259 BCX0\">Tales de Mileto, uno de los siete sabios de Grecia&#8221;<\/span><\/span><\/strong><\/a><span class=\"TextRun SCXW230926259 BCX0\" lang=\"ES-ES\" xml:lang=\"ES-ES\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW230926259 BCX0\"><br \/>\n<\/span><\/span><a href=\"https:\/\/www.lavanguardia.com\/participacion\/red-lectores\/20250530\/10733508\/gran-siglo-pisistrato.html\" target=\"_blank\" rel=\"noopener\"><strong><span class=\"TextRun SCXW230926259 BCX0\" lang=\"ES-ES\" xml:lang=\"ES-ES\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW230926259 BCX0\">Llegiu &#8220;El gran siglo de Pis\u00edstrato&#8221;<\/span><\/span><\/strong><\/a><span class=\"TextRun SCXW230926259 BCX0\" lang=\"ES-ES\" xml:lang=\"ES-ES\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW230926259 BCX0\"><br \/>\n<\/span><\/span><a href=\"https:\/\/www.lavanguardia.com\/participacion\/red-lectores\/20250602\/10736594\/educacion-infantil-antigua-grecia.html\" target=\"_blank\" rel=\"noopener\"><strong><span class=\"TextRun SCXW230926259 BCX0\" lang=\"ES-ES\" xml:lang=\"ES-ES\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW230926259 BCX0\">Llegiu &#8220;La educaci\u00f3n infantil en la Antigua Grecia&#8221;<\/span><\/span><\/strong><\/a><span class=\"TextRun SCXW230926259 BCX0\" lang=\"ES-ES\" xml:lang=\"ES-ES\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW230926259 BCX0\"><br \/>\n<\/span><\/span><strong><span class=\"TextRun SCXW230926259 BCX0\" lang=\"ES-ES\" xml:lang=\"ES-ES\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW230926259 BCX0\"><a href=\"https:\/\/www.lavanguardia.com\/participacion\/red-lectores\/20250609\/10760663\/heraclito-efeso-fuego.html\" target=\"_blank\" rel=\"noopener\">Llegiu &#8220;Her\u00e1clito de \u00c9feso y el fuego&#8221;<\/a><br \/>\n<\/span><\/span><\/strong><a href=\"https:\/\/www.lavanguardia.com\/participacion\/red-lectores\/20250610\/10768267\/ulises-simbolo-aventura-humana.html\" target=\"_blank\" rel=\"noopener\"><strong><span class=\"TextRun SCXW230926259 BCX0\" lang=\"ES-ES\" xml:lang=\"ES-ES\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW230926259 BCX0\">Llegiu &#8220;Ulises, s\u00edmbolo de la aventura humana&#8221;<\/span><\/span><\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Joaqu\u00edn Callabed repr\u00e8n les seves reflexions sobre els autors de l&#8217;Antiga Gr\u00e8cia i l&#8217;actualitat de la cultura cl\u00e0ssica als seus \u00faltims articles &#8220;El Liceo creado por Arist\u00f3teles&#8221;, &#8220;Tales de Mileto, uno de los siete sabios de Grecia&#8221;, &#8220;El gran siglo de Pis\u00edstrato&#8221;, &#8230;<\/p>\n","protected":false},"author":12,"featured_media":123507,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[229,350,496,242,401,439],"tags":[],"class_list":["post-165115","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-art","category-ciencies-politiques","category-educacio-etica-i-valors-ca","category-categ-historia","category-historia-de-lart-i-patrimoni-cultural","category-literatura-ca","et-has-post-format-content","et_post_format-et-post-format-standard"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>D&#039;Arist\u00f2til a Ulisses i d&#039;altres referents universals - Reial Acad\u00e8mia Europea de Doctors<\/title>\n<meta name=\"description\" content=\"Joaqu\u00edn Callabed repr\u00e8n les seves reflexions sobre els autors de l&#039;Antiga Gr\u00e8cia i l&#039;actualitat de la cultura cl\u00e0ssica als seus \u00faltims articles\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/raed.academy\/ca\/daristotil-a-ulisses-i-daltres-referents-universals\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D&#039;Arist\u00f2til a Ulisses i d&#039;altres referents universals - Reial Acad\u00e8mia Europea de Doctors\" \/>\n<meta property=\"og:description\" content=\"Joaqu\u00edn Callabed repr\u00e8n les seves reflexions sobre els autors de l&#039;Antiga Gr\u00e8cia i l&#039;actualitat de la cultura cl\u00e0ssica als seus \u00faltims articles\" \/>\n<meta property=\"og:url\" content=\"https:\/\/raed.academy\/ca\/daristotil-a-ulisses-i-daltres-referents-universals\/\" \/>\n<meta property=\"og:site_name\" content=\"Reial Acad\u00e8mia Europea de Doctors\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/fb.me\/raed.academy\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-16T09:39:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/raed.academy\/wp-content\/uploads\/2022\/10\/partenon-antigua-Grecia-licencia-pixabay.com-no-atrib.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"RAED\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@raedacademy\" \/>\n<meta name=\"twitter:site\" content=\"@raedacademy\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"RAED\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/daristotil-a-ulisses-i-daltres-referents-universals\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/daristotil-a-ulisses-i-daltres-referents-universals\\\/\"},\"author\":{\"name\":\"RAED\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/person\\\/5a755da80d1d979fd66ba745c8702927\"},\"headline\":\"D&#8217;Arist\u00f2til a Ulisses i d&#8217;altres referents universals\",\"datePublished\":\"2025-06-16T09:39:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/daristotil-a-ulisses-i-daltres-referents-universals\\\/\"},\"wordCount\":955,\"publisher\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/daristotil-a-ulisses-i-daltres-referents-universals\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/partenon-antigua-Grecia-licencia-pixabay.com-no-atrib.webp\",\"articleSection\":[\"Art\",\"Ci\u00e8ncies pol\u00edtiques\",\"Educaci\u00f3, \u00e8tica i valors\",\"Hist\u00f2ria\",\"Hist\u00f2ria de l'art i patrimoni cultural\",\"Literatura\"],\"inLanguage\":\"ca-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/daristotil-a-ulisses-i-daltres-referents-universals\\\/\",\"url\":\"https:\\\/\\\/raed.academy\\\/ca\\\/daristotil-a-ulisses-i-daltres-referents-universals\\\/\",\"name\":\"D'Arist\u00f2til a Ulisses i d'altres referents universals - Reial Acad\u00e8mia Europea de Doctors\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/daristotil-a-ulisses-i-daltres-referents-universals\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/daristotil-a-ulisses-i-daltres-referents-universals\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/partenon-antigua-Grecia-licencia-pixabay.com-no-atrib.webp\",\"datePublished\":\"2025-06-16T09:39:23+00:00\",\"description\":\"Joaqu\u00edn Callabed repr\u00e8n les seves reflexions sobre els autors de l'Antiga Gr\u00e8cia i l'actualitat de la cultura cl\u00e0ssica als seus \u00faltims articles\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/daristotil-a-ulisses-i-daltres-referents-universals\\\/#breadcrumb\"},\"inLanguage\":\"ca-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/raed.academy\\\/ca\\\/daristotil-a-ulisses-i-daltres-referents-universals\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/daristotil-a-ulisses-i-daltres-referents-universals\\\/#primaryimage\",\"url\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/partenon-antigua-Grecia-licencia-pixabay.com-no-atrib.webp\",\"contentUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/partenon-antigua-Grecia-licencia-pixabay.com-no-atrib.webp\",\"width\":600,\"height\":360,\"caption\":\"Parten\u00f3n de la antigua Grecia. Cedida por pixabay.com\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/daristotil-a-ulisses-i-daltres-referents-universals\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/raed.academy\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"D&#8217;Arist\u00f2til a Ulisses i d&#8217;altres referents universals\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/raed.academy\\\/ca\\\/\",\"name\":\"Reial Acad\u00e8mia Europea de Doctors\",\"description\":\"Corporaci\u00f3n de derecho p\u00fablico de car\u00e1cter cient\u00edfico, t\u00e9cnico y art\u00edstico, que tiene por objeto la investigaci\u00f3n, el estudio, el fomento y la extensi\u00f3n del conocimiento en su sentido m\u00e1s amplio\",\"publisher\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/raed.academy\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#organization\",\"name\":\"Real Academia Europea de Doctores\",\"url\":\"https:\\\/\\\/raed.academy\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/cropped-logo_raed.png\",\"contentUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/cropped-logo_raed.png\",\"width\":512,\"height\":512,\"caption\":\"Real Academia Europea de Doctores\"},\"image\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/fb.me\\\/raed.academy\",\"https:\\\/\\\/x.com\\\/raedacademy\",\"https:\\\/\\\/www.instagram.com\\\/raed.academy\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCUYQwW2KrdirNWihxMDObwg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/person\\\/5a755da80d1d979fd66ba745c8702927\",\"name\":\"RAED\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g\",\"caption\":\"RAED\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D'Arist\u00f2til a Ulisses i d'altres referents universals - Reial Acad\u00e8mia Europea de Doctors","description":"Joaqu\u00edn Callabed repr\u00e8n les seves reflexions sobre els autors de l'Antiga Gr\u00e8cia i l'actualitat de la cultura cl\u00e0ssica als seus \u00faltims articles","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/raed.academy\/ca\/daristotil-a-ulisses-i-daltres-referents-universals\/","og_locale":"ca_ES","og_type":"article","og_title":"D'Arist\u00f2til a Ulisses i d'altres referents universals - Reial Acad\u00e8mia Europea de Doctors","og_description":"Joaqu\u00edn Callabed repr\u00e8n les seves reflexions sobre els autors de l'Antiga Gr\u00e8cia i l'actualitat de la cultura cl\u00e0ssica als seus \u00faltims articles","og_url":"https:\/\/raed.academy\/ca\/daristotil-a-ulisses-i-daltres-referents-universals\/","og_site_name":"Reial Acad\u00e8mia Europea de Doctors","article_publisher":"http:\/\/fb.me\/raed.academy","article_published_time":"2025-06-16T09:39:23+00:00","og_image":[{"width":600,"height":360,"url":"https:\/\/raed.academy\/wp-content\/uploads\/2022\/10\/partenon-antigua-Grecia-licencia-pixabay.com-no-atrib.webp","type":"image\/webp"}],"author":"RAED","twitter_card":"summary_large_image","twitter_creator":"@raedacademy","twitter_site":"@raedacademy","twitter_misc":{"Written by":"RAED","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/raed.academy\/ca\/daristotil-a-ulisses-i-daltres-referents-universals\/#article","isPartOf":{"@id":"https:\/\/raed.academy\/ca\/daristotil-a-ulisses-i-daltres-referents-universals\/"},"author":{"name":"RAED","@id":"https:\/\/raed.academy\/ca\/#\/schema\/person\/5a755da80d1d979fd66ba745c8702927"},"headline":"D&#8217;Arist\u00f2til a Ulisses i d&#8217;altres referents universals","datePublished":"2025-06-16T09:39:23+00:00","mainEntityOfPage":{"@id":"https:\/\/raed.academy\/ca\/daristotil-a-ulisses-i-daltres-referents-universals\/"},"wordCount":955,"publisher":{"@id":"https:\/\/raed.academy\/ca\/#organization"},"image":{"@id":"https:\/\/raed.academy\/ca\/daristotil-a-ulisses-i-daltres-referents-universals\/#primaryimage"},"thumbnailUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2022\/10\/partenon-antigua-Grecia-licencia-pixabay.com-no-atrib.webp","articleSection":["Art","Ci\u00e8ncies pol\u00edtiques","Educaci\u00f3, \u00e8tica i valors","Hist\u00f2ria","Hist\u00f2ria de l'art i patrimoni cultural","Literatura"],"inLanguage":"ca-ES"},{"@type":"WebPage","@id":"https:\/\/raed.academy\/ca\/daristotil-a-ulisses-i-daltres-referents-universals\/","url":"https:\/\/raed.academy\/ca\/daristotil-a-ulisses-i-daltres-referents-universals\/","name":"D'Arist\u00f2til a Ulisses i d'altres referents universals - Reial Acad\u00e8mia Europea de Doctors","isPartOf":{"@id":"https:\/\/raed.academy\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/raed.academy\/ca\/daristotil-a-ulisses-i-daltres-referents-universals\/#primaryimage"},"image":{"@id":"https:\/\/raed.academy\/ca\/daristotil-a-ulisses-i-daltres-referents-universals\/#primaryimage"},"thumbnailUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2022\/10\/partenon-antigua-Grecia-licencia-pixabay.com-no-atrib.webp","datePublished":"2025-06-16T09:39:23+00:00","description":"Joaqu\u00edn Callabed repr\u00e8n les seves reflexions sobre els autors de l'Antiga Gr\u00e8cia i l'actualitat de la cultura cl\u00e0ssica als seus \u00faltims articles","breadcrumb":{"@id":"https:\/\/raed.academy\/ca\/daristotil-a-ulisses-i-daltres-referents-universals\/#breadcrumb"},"inLanguage":"ca-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/raed.academy\/ca\/daristotil-a-ulisses-i-daltres-referents-universals\/"]}]},{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/raed.academy\/ca\/daristotil-a-ulisses-i-daltres-referents-universals\/#primaryimage","url":"https:\/\/raed.academy\/wp-content\/uploads\/2022\/10\/partenon-antigua-Grecia-licencia-pixabay.com-no-atrib.webp","contentUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2022\/10\/partenon-antigua-Grecia-licencia-pixabay.com-no-atrib.webp","width":600,"height":360,"caption":"Parten\u00f3n de la antigua Grecia. Cedida por pixabay.com"},{"@type":"BreadcrumbList","@id":"https:\/\/raed.academy\/ca\/daristotil-a-ulisses-i-daltres-referents-universals\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/raed.academy\/ca\/"},{"@type":"ListItem","position":2,"name":"D&#8217;Arist\u00f2til a Ulisses i d&#8217;altres referents universals"}]},{"@type":"WebSite","@id":"https:\/\/raed.academy\/ca\/#website","url":"https:\/\/raed.academy\/ca\/","name":"Reial Acad\u00e8mia Europea de Doctors","description":"Corporaci\u00f3n de derecho p\u00fablico de car\u00e1cter cient\u00edfico, t\u00e9cnico y art\u00edstico, que tiene por objeto la investigaci\u00f3n, el estudio, el fomento y la extensi\u00f3n del conocimiento en su sentido m\u00e1s amplio","publisher":{"@id":"https:\/\/raed.academy\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/raed.academy\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca-ES"},{"@type":"Organization","@id":"https:\/\/raed.academy\/ca\/#organization","name":"Real Academia Europea de Doctores","url":"https:\/\/raed.academy\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/raed.academy\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/raed.academy\/wp-content\/uploads\/2017\/01\/cropped-logo_raed.png","contentUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2017\/01\/cropped-logo_raed.png","width":512,"height":512,"caption":"Real Academia Europea de Doctores"},"image":{"@id":"https:\/\/raed.academy\/ca\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/fb.me\/raed.academy","https:\/\/x.com\/raedacademy","https:\/\/www.instagram.com\/raed.academy\/","https:\/\/www.youtube.com\/channel\/UCUYQwW2KrdirNWihxMDObwg"]},{"@type":"Person","@id":"https:\/\/raed.academy\/ca\/#\/schema\/person\/5a755da80d1d979fd66ba745c8702927","name":"RAED","image":{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g","caption":"RAED"}}]}},"_links":{"self":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/posts\/165115","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/comments?post=165115"}],"version-history":[{"count":0,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/posts\/165115\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/media\/123507"}],"wp:attachment":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/media?parent=165115"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/categories?post=165115"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/tags?post=165115"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}