{"id":154172,"date":"2024-10-25T10:48:32","date_gmt":"2024-10-25T10:48:32","guid":{"rendered":"https:\/\/raed.academy\/?p=154172"},"modified":"2024-10-25T10:48:32","modified_gmt":"2024-10-25T10:48:32","slug":"la-historia-de-la-medicina-des-dels-seus-referents","status":"publish","type":"post","link":"https:\/\/raed.academy\/ca\/la-historia-de-la-medicina-des-dels-seus-referents\/","title":{"rendered":"La hist\u00f2ria de la medicina, des dels seus referents"},"content":{"rendered":"<div id=\"attachment_149375\" style=\"width: 627px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-149375\" class=\"wp-image-149375\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2024\/05\/Joaquin-Callabed-conferencia-abordaje-bio-psico-social-consulta-a-los-adolescentes.webp\" alt=\"Joaqu\u00edn Callabed\" width=\"617\" height=\"370\" srcset=\"https:\/\/raed.academy\/wp-content\/uploads\/2024\/05\/Joaquin-Callabed-conferencia-abordaje-bio-psico-social-consulta-a-los-adolescentes.webp 1200w, https:\/\/raed.academy\/wp-content\/uploads\/2024\/05\/Joaquin-Callabed-conferencia-abordaje-bio-psico-social-consulta-a-los-adolescentes-768x461.webp 768w, https:\/\/raed.academy\/wp-content\/uploads\/2024\/05\/Joaquin-Callabed-conferencia-abordaje-bio-psico-social-consulta-a-los-adolescentes-1080x648.webp 1080w, https:\/\/raed.academy\/wp-content\/uploads\/2024\/05\/Joaquin-Callabed-conferencia-abordaje-bio-psico-social-consulta-a-los-adolescentes-627x376.webp 627w, https:\/\/raed.academy\/wp-content\/uploads\/2024\/05\/Joaquin-Callabed-conferencia-abordaje-bio-psico-social-consulta-a-los-adolescentes-440x264.webp 440w\" sizes=\"(max-width: 617px) 100vw, 617px\" \/><p id=\"caption-attachment-149375\" class=\"wp-caption-text\">Dr. Joaqu\u00edn Callabed<\/p><\/div>\n<p><a href=\"https:\/\/raed.academy\/ca\/academics\/dr-joaquin-callabed-carracedo\/\" target=\"_blank\" rel=\"noopener\"><em><strong>Joaqu\u00edn Callabed<\/strong><\/em><\/a>, president del <strong>Club de Pediatria Social<\/strong>, acad\u00e8mic corresponent de la <strong>Reial Acad\u00e8mia de Medicina de Catalunya<\/strong> i de la <strong>Reial Acad\u00e8mia de Farm\u00e0cia de Catalunya<\/strong> i acad\u00e8mic de n\u00famero i vicepresident de la Secci\u00f3 de Ci\u00e8ncies de la Salut de la <strong>Reial Acad\u00e8mia Europea de Doctors -Barcelona 1914<\/strong> (RAED), aborda la hist\u00f2ria de la medicina a partir d&#8217;alguns dels seus grans referents als articles <strong>&#8220;<span class=\"TextRun SCXW41258458 BCX0\" lang=\"ES-ES\" xml:lang=\"ES-ES\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW41258458 BCX0\">Francisco Vall\u00e9s, el &#8216;divino Galeno espa\u00f1ol&#8217; creador de la anatom\u00eda patol\u00f3gica moderna&#8221;<\/span><\/span><\/strong><span class=\"TextRun SCXW41258458 BCX0\" lang=\"ES-ES\" xml:lang=\"ES-ES\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW41258458 BCX0\">,<\/span><\/span><strong><span class=\"TextRun SCXW41258458 BCX0\" lang=\"ES-ES\" xml:lang=\"ES-ES\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW41258458 BCX0\"> &#8220;G\u00f3mez Pereira, el fil\u00f3sofo m\u00e9dico humanista cr\u00edtico con Galeno y predecesor de Descartes&#8221;<\/span><\/span><\/strong><span class=\"TextRun SCXW41258458 BCX0\" lang=\"ES-ES\" xml:lang=\"ES-ES\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW41258458 BCX0\">, <\/span><\/span><strong><span class=\"TextRun SCXW41258458 BCX0\" lang=\"ES-ES\" xml:lang=\"ES-ES\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW41258458 BCX0\">&#8220;El &#8216;<\/span><span class=\"SpellingError SCXW41258458 BCX0\">annus<\/span> <span class=\"SpellingError SCXW41258458 BCX0\">horribilis<\/span><span class=\"NormalTextRun SCXW41258458 BCX0\">&#8216; de Ram\u00f3n y Cajal en Jaca&#8221; <\/span><\/span><\/strong><span class=\"TextRun SCXW41258458 BCX0\" lang=\"ES-ES\" xml:lang=\"ES-ES\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW41258458 BCX0\">i <\/span><\/span><strong><span class=\"TextRun SCXW41258458 BCX0\" lang=\"ES-ES\" xml:lang=\"ES-ES\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW41258458 BCX0\">&#8220;Tres preguntas sobre la medicina actual<\/span><\/span><\/strong><strong><span class=\"TextRun SCXW130459763 BCX0\" lang=\"ES-ES\" xml:lang=\"ES-ES\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW130459763 BCX0\">&#8220;<\/span><\/span><\/strong>, publicats entre el passat mes de juliol a la secci\u00f3<strong> &#8220;Lectores expertos&#8221;<\/strong> de l&#8217;edici\u00f3 digital del diari<strong> &#8220;La Vanguardia&#8221;<\/strong>, de la comunitat de lectors del qual forma part activa.<\/p>\n<p>A &#8220;Francisco Vall\u00e9s, el &#8216;divino Galeno espa\u00f1ol&#8217; creador de la anatom\u00eda patol\u00f3gica moderna&#8221;, el president del Club de Pediatria Social recupera la figura i el significat del creador de l&#8217;examen de l&#8217;anomenat Protomedicato per a tots els llicenciats en medicina al segle XVI. &#8220;Va estudiar a diverses ciutats europees, cosa que li va fer entrar en contacte amb <strong>Andrea Vesalio<\/strong>, al qual succeir\u00e0 el 1572 com a metge personal de <strong>Felip II<\/strong>, nomenant-li metge de cambra i protom\u00e8dic general dels regnes i senyorius de Castella, el c\u00e0rrec m\u00e8dic m\u00e9s elevat d&#8217;Espanya, assolit gran prestigi professional i reconeixement com a intel\u00b7lectual. Va ser aquest rei el que el va qualificar de &#8216;Div\u00ed&#8217;, en curar-lo d&#8217;una crisi de gota i el va nomenar protom\u00e8dic, t\u00edtol que no representava nom\u00e9s posse\u00efdor de coneixements m\u00e8dics, sin\u00f3 que requeria tamb\u00e9 molt seny, honestedat i just tracte&#8221;, resumeix.<\/p>\n<p>Per la seva banda, a &#8220;G\u00f3mez Pereira, el fil\u00f3sofo m\u00e9dico humanista cr\u00edtico con Galeno y predecesor de Descartes&#8221;, Callabed rememora la figura d&#8217;una altra figura de refer\u00e8ncia al segle XVI espanyol, un fil\u00f2sof, afamat m\u00e8dic, humanista i enginyer que al camp de la medicina va rebutjar els conceptes medievals proposant l&#8217;aplicaci\u00f3 dels emp\u00edrics. &#8220;G\u00f3mez Pereira ha passat a la hist\u00f2ria sobretot pels seus escrits, particularment per les seves obres<strong> &#8216;Antoniana Margarita&#8217;<\/strong> i <strong>&#8216;Novae veraeque Medicinae&#8217;<\/strong>, el contingut de la qual \u00e9s exclusivament m\u00e8dic. Se centra en l&#8217;estudi de les febres (les causes i els tipus) i en certes malalties concretes com la lepra o la verola, entre d&#8217;altres. En aquesta obra, que va dedicar a l&#8217;infant <strong>Carles<\/strong>, s&#8217;enfronta a les idees de <strong>Gal\u00e8<\/strong> i d&#8217;<strong>Arist\u00f2til<\/strong>, aix\u00ed com a la tradici\u00f3 medieval del &#8216;magister dixit'&#8221;, explica.<\/p>\n<div id=\"attachment_154199\" style=\"width: 538px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-154199\" class=\"wp-image-154199\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2024\/10\/Francisco-Valles.webp\" alt=\"\" width=\"528\" height=\"317\" srcset=\"https:\/\/raed.academy\/wp-content\/uploads\/2024\/10\/Francisco-Valles.webp 600w, https:\/\/raed.academy\/wp-content\/uploads\/2024\/10\/Francisco-Valles-440x264.webp 440w\" sizes=\"(max-width: 528px) 100vw, 528px\" \/><p id=\"caption-attachment-154199\" class=\"wp-caption-text\">Francisco Vall\u00e9s<\/p><\/div>\n<p>L&#8217;acad\u00e8mic incideix a la figura de <strong>Santiago Ram\u00f3n y Cajal<\/strong>, que ha estudiat en profunditat, a &#8220;El &#8216;annus horribilis&#8217; de Ram\u00f3n y Cajal en Jaca&#8221;, on explica els atzarosos estudis del futur <strong>Premi Nobel de Medicina<\/strong>. &#8220;Santiago Ram\u00f3n y Cajal defugia el tracte amb els seus companys de joc. Segurament recordava la seva colla d&#8217;Ayerbe i els seus jocs a l&#8217;aire lliure sense cap tutela. La tristesa l&#8217;acompanya sempre. Per sort trobava a l&#8217;art i a la contemplaci\u00f3 de la natura grans consols. Les muntanyes i paisatges que envolten la ciutat del riu Arag\u00f3 li feien oblidar les xafogors i tristeses escolars. Les seves passejades per la natura eren molt habituals&#8221;, explica l&#8217;expert recolzant-se a les mem\u00f2ries del reconegut metge.<\/p>\n<p>Finalment, a &#8220;Tres preguntas sobre la medicina actual&#8221; l&#8217;acad\u00e8mic tracta d&#8217;abordar de manera succinta la situaci\u00f3 de la medicina, els seus professionals i els pacients en aquest segle XXI amb l&#8217;ajuda de pensadors com <strong>Michel Foucault<\/strong>, <strong>Plat\u00f3<\/strong>, <strong>Pedro La\u00edn Entralgo<\/strong>, <strong>Juan Rof Carballo<\/strong>, <strong>Xavier Zubiri<\/strong> i els fil\u00f2sofs grecs, entre d&#8217;altres. &#8220;La professi\u00f3 passa un mal moment: \u00bfpotser la medicina ha de ser un conjunt de t\u00e8cniques de curaci\u00f3?, \u00bfel metge ha de ser \u00fanicament un t\u00e8cnic en salut?, \u00bfel pacient \u00e9s nom\u00e9s un malalt?&#8230;&#8221;, planteja amb q\u00fcestions per passar a oferir les respostes que aquestes i altres preguntes similars han ofert les figures del pensament i la ci\u00e8ncia que presenta, aix\u00ed com algunes altres.<\/p>\n<ul>\n<li>\n<h3><a href=\"https:\/\/www.lavanguardia.com\/participacion\/red-lectores\/20240703\/9774703\/francisco-valles-covarrubias-creador-anatomia-patologica-moderna.html\" target=\"_blank\" rel=\"noopener\"><strong>Llegiu &#8220;<span class=\"TextRun SCXW41258458 BCX0\" lang=\"ES-ES\" xml:lang=\"ES-ES\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW41258458 BCX0\">Francisco Vall\u00e9s, el \u2018divino Galeno espa\u00f1ol\u2019 creador de la anatom\u00eda patol\u00f3gica moderna&#8221;<\/span><\/span><\/strong><\/a><\/h3>\n<\/li>\n<li>\n<h3><a href=\"https:\/\/www.lavanguardia.com\/participacion\/red-lectores\/20240702\/9772602\/gomez-pereira-medico-humanista-predecesor-descartes.html\" target=\"_blank\" rel=\"noopener\"><strong><span class=\"TextRun SCXW41258458 BCX0\" lang=\"ES-ES\" xml:lang=\"ES-ES\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW41258458 BCX0\">Llegiu &#8220;G\u00f3mez Pereira, el fil\u00f3sofo m\u00e9dico humanista cr\u00edtico con Galeno y predecesor de Descartes&#8221;<\/span><\/span><\/strong><\/a><\/h3>\n<\/li>\n<li>\n<h3><a href=\"https:\/\/www.lavanguardia.com\/participacion\/red-lectores\/20240723\/9820800\/annus-horribilis-ramon-cajal-jaca.html\" target=\"_blank\" rel=\"noopener\"><strong><span class=\"TextRun SCXW41258458 BCX0\" lang=\"ES-ES\" xml:lang=\"ES-ES\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW41258458 BCX0\">Llegiu &#8220;El &#8216;<\/span><span class=\"SpellingError SCXW41258458 BCX0\">annus<\/span> <span class=\"SpellingError SCXW41258458 BCX0\">horribilis<\/span><span class=\"NormalTextRun SCXW41258458 BCX0\">&#8216; de Ram\u00f3n y Cajal en Jaca&#8221;<\/span><\/span><\/strong><\/a><\/h3>\n<\/li>\n<li>\n<h3><a href=\"https:\/\/www.lavanguardia.com\/participacion\/red-lectores\/20240724\/9823104\/tres-preguntas-sobre-medicina-actual.html\" target=\"_blank\" rel=\"noopener\"><strong><span class=\"TextRun SCXW41258458 BCX0\" lang=\"ES-ES\" xml:lang=\"ES-ES\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW41258458 BCX0\">Llegiu &#8220;Tres preguntas sobre la medicina actual<\/span><\/span><\/strong><strong><span class=\"TextRun SCXW130459763 BCX0\" lang=\"ES-ES\" xml:lang=\"ES-ES\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW130459763 BCX0\">&#8220;<\/span><\/span><\/strong><\/a><\/h3>\n<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Joaqu\u00edn Callabed, president del Club de Pediatria Social, acad\u00e8mic corresponent de la Reial Acad\u00e8mia de Medicina de Catalunya i de la Reial Acad\u00e8mia de Farm\u00e0cia de Catalunya i acad\u00e8mic de n\u00famero i vicepresident de la Secci\u00f3 de Ci\u00e8ncies de la Salut de la Reial Acad\u00e8mia Europea de Doctors -Barcelona 1914 (RAED), aborda la hist\u00f2ria de [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":154200,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[455,442,242,404,213],"tags":[],"class_list":["post-154172","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencies-de-la-salut","category-ciencies-farmaceutiques-ciencies-de-la-salut","category-categ-historia","category-historia-nacional-ca","category-medicina-i-cirurgia","et-has-post-format-content","et_post_format-et-post-format-standard"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La hist\u00f2ria de la medicina, des dels seus referents - Reial Acad\u00e8mia Europea de Doctors<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/raed.academy\/ca\/la-historia-de-la-medicina-des-dels-seus-referents\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La hist\u00f2ria de la medicina, des dels seus referents - Reial Acad\u00e8mia Europea de Doctors\" \/>\n<meta property=\"og:description\" content=\"Joaqu\u00edn Callabed, president del Club de Pediatria Social, acad\u00e8mic corresponent de la Reial Acad\u00e8mia de Medicina de Catalunya i de la Reial Acad\u00e8mia de Farm\u00e0cia de Catalunya i acad\u00e8mic de n\u00famero i vicepresident de la Secci\u00f3 de Ci\u00e8ncies de la Salut de la Reial Acad\u00e8mia Europea de Doctors -Barcelona 1914 (RAED), aborda la hist\u00f2ria de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/raed.academy\/ca\/la-historia-de-la-medicina-des-dels-seus-referents\/\" \/>\n<meta property=\"og:site_name\" content=\"Reial Acad\u00e8mia Europea de Doctors\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/fb.me\/raed.academy\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-25T10:48:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/raed.academy\/wp-content\/uploads\/2024\/10\/Francisco-Valles.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"RAED\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@raedacademy\" \/>\n<meta name=\"twitter:site\" content=\"@raedacademy\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"RAED\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/la-historia-de-la-medicina-des-dels-seus-referents\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/la-historia-de-la-medicina-des-dels-seus-referents\\\/\"},\"author\":{\"name\":\"RAED\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/person\\\/5a755da80d1d979fd66ba745c8702927\"},\"headline\":\"La hist\u00f2ria de la medicina, des dels seus referents\",\"datePublished\":\"2024-10-25T10:48:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/la-historia-de-la-medicina-des-dels-seus-referents\\\/\"},\"wordCount\":811,\"publisher\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/la-historia-de-la-medicina-des-dels-seus-referents\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Francisco-Valles.webp\",\"articleSection\":[\"Ci\u00e8ncies de la salut\",\"Ci\u00e8ncies Farmac\u00e8utiques\",\"Hist\u00f2ria\",\"Hist\u00f2ria nacional\",\"Medicina i cirurgia\"],\"inLanguage\":\"ca-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/la-historia-de-la-medicina-des-dels-seus-referents\\\/\",\"url\":\"https:\\\/\\\/raed.academy\\\/ca\\\/la-historia-de-la-medicina-des-dels-seus-referents\\\/\",\"name\":\"La hist\u00f2ria de la medicina, des dels seus referents - Reial Acad\u00e8mia Europea de Doctors\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/la-historia-de-la-medicina-des-dels-seus-referents\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/la-historia-de-la-medicina-des-dels-seus-referents\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Francisco-Valles.webp\",\"datePublished\":\"2024-10-25T10:48:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/la-historia-de-la-medicina-des-dels-seus-referents\\\/#breadcrumb\"},\"inLanguage\":\"ca-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/raed.academy\\\/ca\\\/la-historia-de-la-medicina-des-dels-seus-referents\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/la-historia-de-la-medicina-des-dels-seus-referents\\\/#primaryimage\",\"url\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Francisco-Valles.webp\",\"contentUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Francisco-Valles.webp\",\"width\":600,\"height\":360},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/la-historia-de-la-medicina-des-dels-seus-referents\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/raed.academy\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La hist\u00f2ria de la medicina, des dels seus referents\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/raed.academy\\\/ca\\\/\",\"name\":\"Reial Acad\u00e8mia Europea de Doctors\",\"description\":\"Corporaci\u00f3n de derecho p\u00fablico de car\u00e1cter cient\u00edfico, t\u00e9cnico y art\u00edstico, que tiene por objeto la investigaci\u00f3n, el estudio, el fomento y la extensi\u00f3n del conocimiento en su sentido m\u00e1s amplio\",\"publisher\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/raed.academy\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#organization\",\"name\":\"Real Academia Europea de Doctores\",\"url\":\"https:\\\/\\\/raed.academy\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/cropped-logo_raed.png\",\"contentUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/cropped-logo_raed.png\",\"width\":512,\"height\":512,\"caption\":\"Real Academia Europea de Doctores\"},\"image\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/fb.me\\\/raed.academy\",\"https:\\\/\\\/x.com\\\/raedacademy\",\"https:\\\/\\\/www.instagram.com\\\/raed.academy\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCUYQwW2KrdirNWihxMDObwg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/person\\\/5a755da80d1d979fd66ba745c8702927\",\"name\":\"RAED\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g\",\"caption\":\"RAED\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La hist\u00f2ria de la medicina, des dels seus referents - Reial Acad\u00e8mia Europea de Doctors","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/raed.academy\/ca\/la-historia-de-la-medicina-des-dels-seus-referents\/","og_locale":"ca_ES","og_type":"article","og_title":"La hist\u00f2ria de la medicina, des dels seus referents - Reial Acad\u00e8mia Europea de Doctors","og_description":"Joaqu\u00edn Callabed, president del Club de Pediatria Social, acad\u00e8mic corresponent de la Reial Acad\u00e8mia de Medicina de Catalunya i de la Reial Acad\u00e8mia de Farm\u00e0cia de Catalunya i acad\u00e8mic de n\u00famero i vicepresident de la Secci\u00f3 de Ci\u00e8ncies de la Salut de la Reial Acad\u00e8mia Europea de Doctors -Barcelona 1914 (RAED), aborda la hist\u00f2ria de [&hellip;]","og_url":"https:\/\/raed.academy\/ca\/la-historia-de-la-medicina-des-dels-seus-referents\/","og_site_name":"Reial Acad\u00e8mia Europea de Doctors","article_publisher":"http:\/\/fb.me\/raed.academy","article_published_time":"2024-10-25T10:48:32+00:00","og_image":[{"width":600,"height":360,"url":"https:\/\/raed.academy\/wp-content\/uploads\/2024\/10\/Francisco-Valles.webp","type":"image\/webp"}],"author":"RAED","twitter_card":"summary_large_image","twitter_creator":"@raedacademy","twitter_site":"@raedacademy","twitter_misc":{"Written by":"RAED","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/raed.academy\/ca\/la-historia-de-la-medicina-des-dels-seus-referents\/#article","isPartOf":{"@id":"https:\/\/raed.academy\/ca\/la-historia-de-la-medicina-des-dels-seus-referents\/"},"author":{"name":"RAED","@id":"https:\/\/raed.academy\/ca\/#\/schema\/person\/5a755da80d1d979fd66ba745c8702927"},"headline":"La hist\u00f2ria de la medicina, des dels seus referents","datePublished":"2024-10-25T10:48:32+00:00","mainEntityOfPage":{"@id":"https:\/\/raed.academy\/ca\/la-historia-de-la-medicina-des-dels-seus-referents\/"},"wordCount":811,"publisher":{"@id":"https:\/\/raed.academy\/ca\/#organization"},"image":{"@id":"https:\/\/raed.academy\/ca\/la-historia-de-la-medicina-des-dels-seus-referents\/#primaryimage"},"thumbnailUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2024\/10\/Francisco-Valles.webp","articleSection":["Ci\u00e8ncies de la salut","Ci\u00e8ncies Farmac\u00e8utiques","Hist\u00f2ria","Hist\u00f2ria nacional","Medicina i cirurgia"],"inLanguage":"ca-ES"},{"@type":"WebPage","@id":"https:\/\/raed.academy\/ca\/la-historia-de-la-medicina-des-dels-seus-referents\/","url":"https:\/\/raed.academy\/ca\/la-historia-de-la-medicina-des-dels-seus-referents\/","name":"La hist\u00f2ria de la medicina, des dels seus referents - Reial Acad\u00e8mia Europea de Doctors","isPartOf":{"@id":"https:\/\/raed.academy\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/raed.academy\/ca\/la-historia-de-la-medicina-des-dels-seus-referents\/#primaryimage"},"image":{"@id":"https:\/\/raed.academy\/ca\/la-historia-de-la-medicina-des-dels-seus-referents\/#primaryimage"},"thumbnailUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2024\/10\/Francisco-Valles.webp","datePublished":"2024-10-25T10:48:32+00:00","breadcrumb":{"@id":"https:\/\/raed.academy\/ca\/la-historia-de-la-medicina-des-dels-seus-referents\/#breadcrumb"},"inLanguage":"ca-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/raed.academy\/ca\/la-historia-de-la-medicina-des-dels-seus-referents\/"]}]},{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/raed.academy\/ca\/la-historia-de-la-medicina-des-dels-seus-referents\/#primaryimage","url":"https:\/\/raed.academy\/wp-content\/uploads\/2024\/10\/Francisco-Valles.webp","contentUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2024\/10\/Francisco-Valles.webp","width":600,"height":360},{"@type":"BreadcrumbList","@id":"https:\/\/raed.academy\/ca\/la-historia-de-la-medicina-des-dels-seus-referents\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/raed.academy\/ca\/"},{"@type":"ListItem","position":2,"name":"La hist\u00f2ria de la medicina, des dels seus referents"}]},{"@type":"WebSite","@id":"https:\/\/raed.academy\/ca\/#website","url":"https:\/\/raed.academy\/ca\/","name":"Reial Acad\u00e8mia Europea de Doctors","description":"Corporaci\u00f3n de derecho p\u00fablico de car\u00e1cter cient\u00edfico, t\u00e9cnico y art\u00edstico, que tiene por objeto la investigaci\u00f3n, el estudio, el fomento y la extensi\u00f3n del conocimiento en su sentido m\u00e1s amplio","publisher":{"@id":"https:\/\/raed.academy\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/raed.academy\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca-ES"},{"@type":"Organization","@id":"https:\/\/raed.academy\/ca\/#organization","name":"Real Academia Europea de Doctores","url":"https:\/\/raed.academy\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/raed.academy\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/raed.academy\/wp-content\/uploads\/2017\/01\/cropped-logo_raed.png","contentUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2017\/01\/cropped-logo_raed.png","width":512,"height":512,"caption":"Real Academia Europea de Doctores"},"image":{"@id":"https:\/\/raed.academy\/ca\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/fb.me\/raed.academy","https:\/\/x.com\/raedacademy","https:\/\/www.instagram.com\/raed.academy\/","https:\/\/www.youtube.com\/channel\/UCUYQwW2KrdirNWihxMDObwg"]},{"@type":"Person","@id":"https:\/\/raed.academy\/ca\/#\/schema\/person\/5a755da80d1d979fd66ba745c8702927","name":"RAED","image":{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g","caption":"RAED"}}]}},"_links":{"self":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/posts\/154172","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/comments?post=154172"}],"version-history":[{"count":0,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/posts\/154172\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/media\/154200"}],"wp:attachment":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/media?parent=154172"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/categories?post=154172"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/tags?post=154172"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}