{"id":142418,"date":"2023-12-14T10:54:40","date_gmt":"2023-12-14T10:54:40","guid":{"rendered":"https:\/\/raed.academy\/?p=142418"},"modified":"2023-12-15T11:12:44","modified_gmt":"2023-12-15T11:12:44","slug":"tabula-una-nova-base-de-dades-de-composicio-daliments-procesats","status":"publish","type":"post","link":"https:\/\/raed.academy\/ca\/tabula-una-nova-base-de-dades-de-composicio-daliments-procesats\/","title":{"rendered":"Tabula, una nova base de dades de composici\u00f3 d&#8217;aliments procesats"},"content":{"rendered":"<div id=\"attachment_100519\" style=\"width: 385px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-100519\" class=\"wp-image-100519 \" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2021\/03\/Gregorio-Varela-dstNtc.jpg\" alt=\"Gregorio Varela\" width=\"375\" height=\"225\" aria-describedby=\"caption-attachment-100519\" \/><p id=\"caption-attachment-100519\" class=\"wp-caption-text\">Dr. Gregorio Varela<\/p><\/div>\n<p><a href=\"https:\/\/raed.academy\/ca\/academics\/dr-gregorio-varela-moreiras\/\" target=\"_blank\" rel=\"noopener\"><em><strong>Gregorio Varela<\/strong><\/em><\/a>, catedr\u00e0tic de Nutrici\u00f3 i Bromatologia de la <strong>Universitat CEU-San Pablo<\/strong>, president de la<strong>\u00a0Fundaci\u00f3 Espanyola de la Nutrici\u00f3<\/strong> i de la <strong>Federaci\u00f3 Espanyola de Societats de Nutrici\u00f3, Alimentaci\u00f3 i Diet\u00e8tica<\/strong> i acad\u00e8mic de n\u00famero de la <strong>Reial Acad\u00e8mia Europea de Doctors-Barcelona 1914<\/strong> (RAED), lidera el projecte <strong>Tabula<\/strong> que impulsa l&#8217;<strong>Institut CEU Alimentaci\u00f3 i Societat<\/strong> de la Universitat CEU Sant Pau, que ell mateix dirigeix. Es tracta d&#8217;una nova base de dades de composici\u00f3 d&#8217;aliments processats que inclou m\u00e9s de 6.500 productes comercialitzats a Espanya, amb el comprom\u00eds de la seva actualitzaci\u00f3 peri\u00f2dica, i proporciona informaci\u00f3 de la composici\u00f3 nutricional i els ingredients dels productes processats m\u00e9s consumits al pa\u00eds, tant de marca de fabricant com de marca de distribuci\u00f3.<\/p>\n<p>Tabula permet obtenir, per a les diferents categories d&#8217;aliments i begudes, els productes per marca, denominaci\u00f3 legal i comercial, llistat d&#8217;ingredients i d&#8217;al\u00b7l\u00e8rgens, composici\u00f3 nutricional declarada a l&#8217;etiquetatge nutricional, i declaraci\u00f3 nutricional referent al contingut en nutrients cr\u00edtics (greix total, greixos saturats, sucres i sodi), segons el reglament europeu relatiu a les declaracions nutricionals i de propietats saludables als aliments. A m\u00e9s, permet buscar els aliments i les begudes comercialitzades a Espanya a trav\u00e9s de la categoritzaci\u00f3 <strong>EuroFIR<\/strong> i segons el model de perfil de nutrients de l&#8217;<strong>Organitzaci\u00f3 Mundial de la Salut<\/strong> per a Europa. Tabula tamb\u00e9 \u00e9s pionera en l&#8217;actualitzaci\u00f3 de la realitat del mercat alimentari espanyol despr\u00e9s de la finalitzaci\u00f3 del <strong>Pla de Col\u00b7laboraci\u00f3 per a la Millora de la Composici\u00f3 d&#8217;Aliments i Begudes i altres Mesures 2017-2020<\/strong>, dut a terme des de l&#8217;<strong>Ag\u00e8ncia Espanyola de Seguretat Aliment\u00e0ria i Nutrici\u00f3<\/strong>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-139909 alignleft\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2023\/11\/productos-alimentacion-dst.webp\" sizes=\"(max-width: 470px) 100vw, 470px\" srcset=\"https:\/\/raed.academy\/wp-content\/uploads\/2023\/11\/productos-alimentacion-dst.webp 600w, https:\/\/raed.academy\/wp-content\/uploads\/2023\/11\/productos-alimentacion-dst-440x264.webp 440w\" alt=\"\" width=\"470\" height=\"282\" \/>&#8220;El dia d&#8217;avui, no compt\u00e0vem amb taules de composici\u00f3 que s&#8217;adaptessin a la realitat actual, amb els aliments i begudes processats que estan disponibles al mercat espanyol, per la qual cosa calia tenir instruments validats que ens permetessin quantificar correctament la ingesta diet\u00e8tica. Despr\u00e9s del pla impulsat per l&#8217;Ag\u00e8ncia Espanyola de Seguretat Aliment\u00e0ria i Nutrici\u00f3, s\u00f3n molts els productes alimentaris que han canviat la seva composici\u00f3 des de l&#8217;any 2017, per la qual cosa fer servir bases de dades anteriors per avaluar la ingesta diet\u00e8tica actual mostraria una fotografia incorrecta i esbiaixada&#8221;, va explicar Varela durant la presentaci\u00f3 d&#8217;aquesta nova i completa base de dades, que es va celebrar el passat 11 de desembre a la seu de l&#8217;Institut CEU Alimentaci\u00f3 i Societat.<\/p>\n<p>Per a Varela, els resultats que s&#8217;extreguin en aquest ambici\u00f3s projecte permetran creuar dades amb altres estudis de rellev\u00e0ncia, com ara el mapa de l&#8217;obesitat recentment presentat per l&#8217;Ag\u00e8ncia, que indica com un ter\u00e7 de la poblaci\u00f3 infantil i adolescent t\u00e9 exc\u00e9s de pes i un de cada deu menors i joves presenta obesitat. &#8220;Aquesta enquesta aliment\u00e0ria, de la qual forma part Tabula, tamb\u00e9 ajudar\u00e0 a con\u00e8ixer com ha variat la ingesta d&#8217;aliments i begudes en aquesta \u00faltima d\u00e8cada en nens i adolescents i les noves necessitats de reformulaci\u00f3 que es puguin plantejar, encara que el mercat alimentari espanyol mostra un perfil millor pel que fa al contingut en greixos, sucres totals i sal en una bona part dels productes de consum freq\u00fcent&#8221;, va assenyalar l&#8217;expert.<\/p>\n<div data-mrf-recirculation=\"Enlaces p\u00e1rrafos\"><\/div>\n<div data-mrf-recirculation=\"Enlaces p\u00e1rrafos\">\n<p><iframe loading=\"lazy\" title=\"\u00bfQu\u00e9 es T\u00e1bula? Conoce la nueva base de datos de alimentaci\u00f3n\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/4D7_lp6cRgo?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Gregorio Varela lidera el projecte Tabula que impulsa a\u00a0Institut CEU Alimentaci\u00f3 i Societat de la\u00a0Universitat CEU San Pablo, que ell mateix dirigeix<\/p>\n","protected":false},"author":12,"featured_media":139910,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[237],"tags":[],"class_list":["post-142418","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alimentacio-i-nutricio","et-has-post-format-content","et_post_format-et-post-format-standard"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tabula, una nova base de dades de composici\u00f3 d&#039;aliments procesats - Reial Acad\u00e8mia Europea de Doctors<\/title>\n<meta name=\"description\" content=\"Gregorio Varela lidera el projecte Tabula que impulsa a\u00a0Institut CEU Alimentaci\u00f3 i Societat de la\u00a0Universitat CEU San Pablo, que ell mateix dirigeix\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/raed.academy\/ca\/tabula-una-nova-base-de-dades-de-composicio-daliments-procesats\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tabula, una nova base de dades de composici\u00f3 d&#039;aliments procesats - Reial Acad\u00e8mia Europea de Doctors\" \/>\n<meta property=\"og:description\" content=\"Gregorio Varela lidera el projecte Tabula que impulsa a\u00a0Institut CEU Alimentaci\u00f3 i Societat de la\u00a0Universitat CEU San Pablo, que ell mateix dirigeix\" \/>\n<meta property=\"og:url\" content=\"https:\/\/raed.academy\/ca\/tabula-una-nova-base-de-dades-de-composicio-daliments-procesats\/\" \/>\n<meta property=\"og:site_name\" content=\"Reial Acad\u00e8mia Europea de Doctors\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/fb.me\/raed.academy\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-14T10:54:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-15T11:12:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/raed.academy\/wp-content\/uploads\/2023\/11\/productos-alimentacion-dst.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"RAED\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@raedacademy\" \/>\n<meta name=\"twitter:site\" content=\"@raedacademy\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"RAED\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/tabula-una-nova-base-de-dades-de-composicio-daliments-procesats\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/tabula-una-nova-base-de-dades-de-composicio-daliments-procesats\\\/\"},\"author\":{\"name\":\"RAED\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/person\\\/5a755da80d1d979fd66ba745c8702927\"},\"headline\":\"Tabula, una nova base de dades de composici\u00f3 d&#8217;aliments procesats\",\"datePublished\":\"2023-12-14T10:54:40+00:00\",\"dateModified\":\"2023-12-15T11:12:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/tabula-una-nova-base-de-dades-de-composicio-daliments-procesats\\\/\"},\"wordCount\":596,\"publisher\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/tabula-una-nova-base-de-dades-de-composicio-daliments-procesats\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/productos-alimentacion-dst.webp\",\"articleSection\":[\"Alimentaci\u00f3 i nutrici\u00f3\"],\"inLanguage\":\"ca-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/tabula-una-nova-base-de-dades-de-composicio-daliments-procesats\\\/\",\"url\":\"https:\\\/\\\/raed.academy\\\/ca\\\/tabula-una-nova-base-de-dades-de-composicio-daliments-procesats\\\/\",\"name\":\"Tabula, una nova base de dades de composici\u00f3 d'aliments procesats - Reial Acad\u00e8mia Europea de Doctors\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/tabula-una-nova-base-de-dades-de-composicio-daliments-procesats\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/tabula-una-nova-base-de-dades-de-composicio-daliments-procesats\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/productos-alimentacion-dst.webp\",\"datePublished\":\"2023-12-14T10:54:40+00:00\",\"dateModified\":\"2023-12-15T11:12:44+00:00\",\"description\":\"Gregorio Varela lidera el projecte Tabula que impulsa a\u00a0Institut CEU Alimentaci\u00f3 i Societat de la\u00a0Universitat CEU San Pablo, que ell mateix dirigeix\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/tabula-una-nova-base-de-dades-de-composicio-daliments-procesats\\\/#breadcrumb\"},\"inLanguage\":\"ca-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/raed.academy\\\/ca\\\/tabula-una-nova-base-de-dades-de-composicio-daliments-procesats\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/tabula-una-nova-base-de-dades-de-composicio-daliments-procesats\\\/#primaryimage\",\"url\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/productos-alimentacion-dst.webp\",\"contentUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/productos-alimentacion-dst.webp\",\"width\":600,\"height\":360},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/tabula-una-nova-base-de-dades-de-composicio-daliments-procesats\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/raed.academy\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tabula, una nova base de dades de composici\u00f3 d&#8217;aliments procesats\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/raed.academy\\\/ca\\\/\",\"name\":\"Reial Acad\u00e8mia Europea de Doctors\",\"description\":\"Corporaci\u00f3n de derecho p\u00fablico de car\u00e1cter cient\u00edfico, t\u00e9cnico y art\u00edstico, que tiene por objeto la investigaci\u00f3n, el estudio, el fomento y la extensi\u00f3n del conocimiento en su sentido m\u00e1s amplio\",\"publisher\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/raed.academy\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#organization\",\"name\":\"Real Academia Europea de Doctores\",\"url\":\"https:\\\/\\\/raed.academy\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/cropped-logo_raed.png\",\"contentUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/cropped-logo_raed.png\",\"width\":512,\"height\":512,\"caption\":\"Real Academia Europea de Doctores\"},\"image\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/fb.me\\\/raed.academy\",\"https:\\\/\\\/x.com\\\/raedacademy\",\"https:\\\/\\\/www.instagram.com\\\/raed.academy\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCUYQwW2KrdirNWihxMDObwg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/person\\\/5a755da80d1d979fd66ba745c8702927\",\"name\":\"RAED\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g\",\"caption\":\"RAED\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tabula, una nova base de dades de composici\u00f3 d'aliments procesats - Reial Acad\u00e8mia Europea de Doctors","description":"Gregorio Varela lidera el projecte Tabula que impulsa a\u00a0Institut CEU Alimentaci\u00f3 i Societat de la\u00a0Universitat CEU San Pablo, que ell mateix dirigeix","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/raed.academy\/ca\/tabula-una-nova-base-de-dades-de-composicio-daliments-procesats\/","og_locale":"ca_ES","og_type":"article","og_title":"Tabula, una nova base de dades de composici\u00f3 d'aliments procesats - Reial Acad\u00e8mia Europea de Doctors","og_description":"Gregorio Varela lidera el projecte Tabula que impulsa a\u00a0Institut CEU Alimentaci\u00f3 i Societat de la\u00a0Universitat CEU San Pablo, que ell mateix dirigeix","og_url":"https:\/\/raed.academy\/ca\/tabula-una-nova-base-de-dades-de-composicio-daliments-procesats\/","og_site_name":"Reial Acad\u00e8mia Europea de Doctors","article_publisher":"http:\/\/fb.me\/raed.academy","article_published_time":"2023-12-14T10:54:40+00:00","article_modified_time":"2023-12-15T11:12:44+00:00","og_image":[{"width":600,"height":360,"url":"https:\/\/raed.academy\/wp-content\/uploads\/2023\/11\/productos-alimentacion-dst.webp","type":"image\/webp"}],"author":"RAED","twitter_card":"summary_large_image","twitter_creator":"@raedacademy","twitter_site":"@raedacademy","twitter_misc":{"Written by":"RAED","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/raed.academy\/ca\/tabula-una-nova-base-de-dades-de-composicio-daliments-procesats\/#article","isPartOf":{"@id":"https:\/\/raed.academy\/ca\/tabula-una-nova-base-de-dades-de-composicio-daliments-procesats\/"},"author":{"name":"RAED","@id":"https:\/\/raed.academy\/ca\/#\/schema\/person\/5a755da80d1d979fd66ba745c8702927"},"headline":"Tabula, una nova base de dades de composici\u00f3 d&#8217;aliments procesats","datePublished":"2023-12-14T10:54:40+00:00","dateModified":"2023-12-15T11:12:44+00:00","mainEntityOfPage":{"@id":"https:\/\/raed.academy\/ca\/tabula-una-nova-base-de-dades-de-composicio-daliments-procesats\/"},"wordCount":596,"publisher":{"@id":"https:\/\/raed.academy\/ca\/#organization"},"image":{"@id":"https:\/\/raed.academy\/ca\/tabula-una-nova-base-de-dades-de-composicio-daliments-procesats\/#primaryimage"},"thumbnailUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2023\/11\/productos-alimentacion-dst.webp","articleSection":["Alimentaci\u00f3 i nutrici\u00f3"],"inLanguage":"ca-ES"},{"@type":"WebPage","@id":"https:\/\/raed.academy\/ca\/tabula-una-nova-base-de-dades-de-composicio-daliments-procesats\/","url":"https:\/\/raed.academy\/ca\/tabula-una-nova-base-de-dades-de-composicio-daliments-procesats\/","name":"Tabula, una nova base de dades de composici\u00f3 d'aliments procesats - Reial Acad\u00e8mia Europea de Doctors","isPartOf":{"@id":"https:\/\/raed.academy\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/raed.academy\/ca\/tabula-una-nova-base-de-dades-de-composicio-daliments-procesats\/#primaryimage"},"image":{"@id":"https:\/\/raed.academy\/ca\/tabula-una-nova-base-de-dades-de-composicio-daliments-procesats\/#primaryimage"},"thumbnailUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2023\/11\/productos-alimentacion-dst.webp","datePublished":"2023-12-14T10:54:40+00:00","dateModified":"2023-12-15T11:12:44+00:00","description":"Gregorio Varela lidera el projecte Tabula que impulsa a\u00a0Institut CEU Alimentaci\u00f3 i Societat de la\u00a0Universitat CEU San Pablo, que ell mateix dirigeix","breadcrumb":{"@id":"https:\/\/raed.academy\/ca\/tabula-una-nova-base-de-dades-de-composicio-daliments-procesats\/#breadcrumb"},"inLanguage":"ca-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/raed.academy\/ca\/tabula-una-nova-base-de-dades-de-composicio-daliments-procesats\/"]}]},{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/raed.academy\/ca\/tabula-una-nova-base-de-dades-de-composicio-daliments-procesats\/#primaryimage","url":"https:\/\/raed.academy\/wp-content\/uploads\/2023\/11\/productos-alimentacion-dst.webp","contentUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2023\/11\/productos-alimentacion-dst.webp","width":600,"height":360},{"@type":"BreadcrumbList","@id":"https:\/\/raed.academy\/ca\/tabula-una-nova-base-de-dades-de-composicio-daliments-procesats\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/raed.academy\/ca\/"},{"@type":"ListItem","position":2,"name":"Tabula, una nova base de dades de composici\u00f3 d&#8217;aliments procesats"}]},{"@type":"WebSite","@id":"https:\/\/raed.academy\/ca\/#website","url":"https:\/\/raed.academy\/ca\/","name":"Reial Acad\u00e8mia Europea de Doctors","description":"Corporaci\u00f3n de derecho p\u00fablico de car\u00e1cter cient\u00edfico, t\u00e9cnico y art\u00edstico, que tiene por objeto la investigaci\u00f3n, el estudio, el fomento y la extensi\u00f3n del conocimiento en su sentido m\u00e1s amplio","publisher":{"@id":"https:\/\/raed.academy\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/raed.academy\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca-ES"},{"@type":"Organization","@id":"https:\/\/raed.academy\/ca\/#organization","name":"Real Academia Europea de Doctores","url":"https:\/\/raed.academy\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/raed.academy\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/raed.academy\/wp-content\/uploads\/2017\/01\/cropped-logo_raed.png","contentUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2017\/01\/cropped-logo_raed.png","width":512,"height":512,"caption":"Real Academia Europea de Doctores"},"image":{"@id":"https:\/\/raed.academy\/ca\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/fb.me\/raed.academy","https:\/\/x.com\/raedacademy","https:\/\/www.instagram.com\/raed.academy\/","https:\/\/www.youtube.com\/channel\/UCUYQwW2KrdirNWihxMDObwg"]},{"@type":"Person","@id":"https:\/\/raed.academy\/ca\/#\/schema\/person\/5a755da80d1d979fd66ba745c8702927","name":"RAED","image":{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g","caption":"RAED"}}]}},"_links":{"self":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/posts\/142418","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/comments?post=142418"}],"version-history":[{"count":0,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/posts\/142418\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/media\/139910"}],"wp:attachment":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/media?parent=142418"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/categories?post=142418"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/tags?post=142418"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}