{"id":140285,"date":"2023-11-10T10:59:22","date_gmt":"2023-11-10T10:59:22","guid":{"rendered":"https:\/\/raed.academy\/?p=140285"},"modified":"2023-11-10T10:59:22","modified_gmt":"2023-11-10T10:59:22","slug":"la-responsabilitat-serena-de-la-princesa-leonor","status":"publish","type":"post","link":"https:\/\/raed.academy\/ca\/la-responsabilitat-serena-de-la-princesa-leonor\/","title":{"rendered":"La responsabilitat serena de la Princesa Leonor"},"content":{"rendered":"<div id=\"attachment_118332\" style=\"width: 215px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-118332\" class=\"wp-image-118332\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2022\/05\/Ddaniel-Berzosa.jpg\" alt=\"\" width=\"205\" height=\"205\" srcset=\"https:\/\/raed.academy\/wp-content\/uploads\/2022\/05\/Ddaniel-Berzosa.jpg 270w, https:\/\/raed.academy\/wp-content\/uploads\/2022\/05\/Ddaniel-Berzosa-150x150.jpg 150w\" sizes=\"(max-width: 205px) 100vw, 205px\" \/><p id=\"caption-attachment-118332\" class=\"wp-caption-text\">Dr. Daniel Berzosa<\/p><\/div>\n<p><a href=\"https:\/\/raed.academy\/ca\/academics\/dr-daniel-berzosa-lopez\/\" target=\"_blank\" rel=\"noopener\"><em><strong>Daniel Berzosa<\/strong><\/em><\/a>, professor de Dret Constitucional i Drets Fonamentals de <strong>Cunef Universitat<\/strong>, de l&#8217;<strong>Institut d&#8217;Estudis Borsaris<\/strong> i de l&#8217;<strong>Institut d&#8217;Empresa-Law &amp; Business School<\/strong>, membre de l&#8217;<strong>Acad\u00e8mia Global<\/strong> i del <strong>Consell Cient\u00edfic<\/strong> del col\u00b7lectiu <strong>Citizens pro Europe<\/strong> i acad\u00e8mic de n\u00famero i membre de la <strong>Junta de Govern<\/strong> de la <strong>Reial Acad\u00e8mia Europea de Doctors-Barcelona 1914<\/strong> (RAED), va incidir en la seva an\u00e0lisi sobre la formaci\u00f3 militar de la princesa <b>Elionor <\/b>i la seva preparaci\u00f3 per assumir la responsabilitat de cap de l&#8217;Estat despr\u00e9s de jurar la <strong>Constituci\u00f3<\/strong> el 31 d&#8217;octubre passat amb la seva participaci\u00f3 al programa<strong> &#8220;24 horas&#8221;<\/strong> de <strong>R\u00e0dio Nacional d&#8217;Espanya<\/strong>, a l&#8217;espai <strong>&#8220;Los Reporteros&#8221;<\/strong> de <strong>Canal Sur Televisi\u00f3n<\/strong> i a <strong>&#8220;El Cascabel&#8221;<\/strong> de <strong>13TV<\/strong>. Al programa<strong> &#8220;Hoy d\u00eda&#8221;<\/strong> de Canal Sur, a m\u00e9s, va narrar el directe l&#8217;acte al costat de la periodista <strong>To\u00f1i Moreno<\/strong>.<\/p>\n<p>En totes les intervencions, l&#8217;expert va assenyalar que la jura de la Constituci\u00f3 per part de l&#8217;hereva \u00e9s molt m\u00e9s que un acte protocol\u00b7lari, ja que es tracta d&#8217;una obligaci\u00f3 constitucional \u00fanica al m\u00f3n. En haver arribat a la majoria d&#8217;edat, la princesa d&#8217;Ast\u00faries accediria al tron en cas d&#8217;inhabilitaci\u00f3 o mort del seu pare i, segons Berzosa, tamb\u00e9 s&#8217;incrementen \u00e8ticament i moralment l&#8217;obligaci\u00f3 i la consci\u00e8ncia. &#8220;Ha estat un dia extraordinari en la hist\u00f2ria d&#8217;Espanya, ja que les <strong>Corts<\/strong> i per extensi\u00f3 tota la societat espanyola reben aquest comprom\u00eds de la princesa d&#8217;Ast\u00faries, que ha destacat per la senzillesa, la serietat i la sobrietat. Representa no nom\u00e9s la seva princesa. generaci\u00f3, sin\u00f3 que recull els valors positius de la Monarquia. La solidesa de la Monarquia dep\u00e8n en bona mesura de la solidesa del Rei, que no ha tingut un moment de pau i que aix\u00f2 precisament l&#8217;ha refor\u00e7at&#8221;, va assenyalar a 13TV.<\/p>\n<p>A R\u00e0dio Nacional, l&#8217;acad\u00e8mic va assenyalar que, amb la majoria d&#8217;edat, la Princesa d&#8217;Ast\u00faries assumeix plena responsabilitat sobre el paper que li tocar\u00e0 representar. &#8220;Hist\u00f2ricament eren les Corts les que feien el jurament de lleialtat del rei o la reina, i des de la transici\u00f3 \u00e9s precisament al rev\u00e9s: \u00e9s l&#8217;hereu o l&#8217;hereva qui promet aquesta lleialtat a les Corts i a la societat espanyola. Ara, a Leonor li queda per davant una llarga formaci\u00f3. Al present, a les monarquies occidentals, aquesta figura s&#8217;identifica amb la garantia de la llibertat i la divisi\u00f3 de poders&#8221;, ha afegit a l&#8217;espai &#8220;24 horas&#8221;.<\/p>\n<p>Berzosa ja hi havia participat, coincidint amb l&#8217;inici de la formaci\u00f3 militar de la princesa d&#8217;Ast\u00faries, a diversos espais televisius. Al programa de <strong>Televisi\u00f3 Espanyola &#8220;Informe Semanal&#8221;<\/strong>, l&#8217;expert va ser un dels experts que van analitzar la situaci\u00f3 al reportatge <strong>&#8220;La misi\u00f3n de Leonor&#8221;<\/strong>. D&#8217;altra banda, al programa de <strong>RTVE Noticias &#8220;\u00bfC\u00f3mo ser\u00e1 la vida de la &#8216;Dama cadete Borb\u00f3n&#8217; en la Academia Militar?&#8221;<\/strong>, Berzosa va oferir les respostes a les preguntes m\u00e9s habituals sobre el dia a dia i la formaci\u00f3 castrense de la hereva, destacant-ne la transcend\u00e8ncia de cara a les seves futures responsabilitats constitucionals, l&#8217;exemple del seu pare, el rei <strong>Felip VI<\/strong>, i la formaci\u00f3 similar que reben els hereus de les principals cases reials europees. I a l&#8217;emissora <strong>Capital Radio<\/strong> va participar a l&#8217;espai <strong>&#8220;Hablemos de Defensa y Seguridad&#8221;<\/strong> despr\u00e9s que Elionor reb\u00e9s el sabre d&#8217;oficial de l&#8217;<strong>Ex\u00e8rcit de Terra<\/strong> a l&#8217;<strong>Acad\u00e8mia Militar General<\/strong> de Saragossa.<\/p>\n<p>Berzosa \u00e9s membre de la <strong>Societat de Diplom\u00e0cia i Ci\u00e8ncies Pol\u00edtiques dels Estats Units<\/strong>, coordinador de l&#8217;<strong>Observatori Internacional de la Regulaci\u00f3 de les Entitats del Sector P\u00fablic<\/strong> de la <strong>Universitat de Santiago de Compostela<\/strong>, membre dels comit\u00e8s organitzadors dels congressos del <strong>World Law Congress<\/strong> de Cartagena d&#8217;\u00cdndies 2021 i Madrid 2019 i autor de llibres i articles cient\u00edfics publicats en revistes de prestigi. \u00c9s aix\u00ed mateix un reconegut divulgador de temes legals i ci\u00e8ncies pol\u00edtiques als principals mitjans de comunicaci\u00f3 espanyols.<\/p>\n<p><iframe loading=\"lazy\" title=\"Sobre el juramento de la Constituci\u00f3n de la Princesa de Asturias\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/JyORdOqSmpE?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Daniel Berzosa va incidir en la seva an\u00e0lisi sobre la formaci\u00f3 militar de la princesa Leonor i la seva preparaci\u00f3 per assumir la Prefectura de l&#8217;Estat despr\u00e9s de jurar la Constituci\u00f3 el 31 d&#8217;octubre passat<\/p>\n","protected":false},"author":12,"featured_media":131472,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[350,487],"tags":[],"class_list":["post-140285","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencies-politiques","category-monarquia-ca","et-has-post-format-content","et_post_format-et-post-format-standard"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La responsabilitat serena de la Princesa Leonor - Reial Acad\u00e8mia Europea de Doctors<\/title>\n<meta name=\"description\" content=\"Daniel Berzosa va incidir en la seva an\u00e0lisi sobre la formaci\u00f3 militar de la princesa Elionor i la seva preparaci\u00f3 per assumir la Prefectura de l&#039;Estat\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/raed.academy\/ca\/la-responsabilitat-serena-de-la-princesa-leonor\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La responsabilitat serena de la Princesa Leonor - Reial Acad\u00e8mia Europea de Doctors\" \/>\n<meta property=\"og:description\" content=\"Daniel Berzosa va incidir en la seva an\u00e0lisi sobre la formaci\u00f3 militar de la princesa Elionor i la seva preparaci\u00f3 per assumir la Prefectura de l&#039;Estat\" \/>\n<meta property=\"og:url\" content=\"https:\/\/raed.academy\/ca\/la-responsabilitat-serena-de-la-princesa-leonor\/\" \/>\n<meta property=\"og:site_name\" content=\"Reial Acad\u00e8mia Europea de Doctors\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/fb.me\/raed.academy\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-10T10:59:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/raed.academy\/wp-content\/uploads\/2023\/04\/princesa-leonor.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"RAED\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@raedacademy\" \/>\n<meta name=\"twitter:site\" content=\"@raedacademy\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"RAED\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/la-responsabilitat-serena-de-la-princesa-leonor\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/la-responsabilitat-serena-de-la-princesa-leonor\\\/\"},\"author\":{\"name\":\"RAED\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/person\\\/5a755da80d1d979fd66ba745c8702927\"},\"headline\":\"La responsabilitat serena de la Princesa Leonor\",\"datePublished\":\"2023-11-10T10:59:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/la-responsabilitat-serena-de-la-princesa-leonor\\\/\"},\"wordCount\":732,\"publisher\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/la-responsabilitat-serena-de-la-princesa-leonor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/princesa-leonor.webp\",\"articleSection\":[\"Ci\u00e8ncies pol\u00edtiques\",\"Monarquia\"],\"inLanguage\":\"ca-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/la-responsabilitat-serena-de-la-princesa-leonor\\\/\",\"url\":\"https:\\\/\\\/raed.academy\\\/ca\\\/la-responsabilitat-serena-de-la-princesa-leonor\\\/\",\"name\":\"La responsabilitat serena de la Princesa Leonor - Reial Acad\u00e8mia Europea de Doctors\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/la-responsabilitat-serena-de-la-princesa-leonor\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/la-responsabilitat-serena-de-la-princesa-leonor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/princesa-leonor.webp\",\"datePublished\":\"2023-11-10T10:59:22+00:00\",\"description\":\"Daniel Berzosa va incidir en la seva an\u00e0lisi sobre la formaci\u00f3 militar de la princesa Elionor i la seva preparaci\u00f3 per assumir la Prefectura de l'Estat\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/la-responsabilitat-serena-de-la-princesa-leonor\\\/#breadcrumb\"},\"inLanguage\":\"ca-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/raed.academy\\\/ca\\\/la-responsabilitat-serena-de-la-princesa-leonor\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/la-responsabilitat-serena-de-la-princesa-leonor\\\/#primaryimage\",\"url\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/princesa-leonor.webp\",\"contentUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/princesa-leonor.webp\",\"width\":600,\"height\":360,\"caption\":\"Princesa Leonor\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/la-responsabilitat-serena-de-la-princesa-leonor\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/raed.academy\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La responsabilitat serena de la Princesa Leonor\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/raed.academy\\\/ca\\\/\",\"name\":\"Reial Acad\u00e8mia Europea de Doctors\",\"description\":\"Corporaci\u00f3n de derecho p\u00fablico de car\u00e1cter cient\u00edfico, t\u00e9cnico y art\u00edstico, que tiene por objeto la investigaci\u00f3n, el estudio, el fomento y la extensi\u00f3n del conocimiento en su sentido m\u00e1s amplio\",\"publisher\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/raed.academy\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#organization\",\"name\":\"Real Academia Europea de Doctores\",\"url\":\"https:\\\/\\\/raed.academy\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/cropped-logo_raed.png\",\"contentUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/cropped-logo_raed.png\",\"width\":512,\"height\":512,\"caption\":\"Real Academia Europea de Doctores\"},\"image\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/fb.me\\\/raed.academy\",\"https:\\\/\\\/x.com\\\/raedacademy\",\"https:\\\/\\\/www.instagram.com\\\/raed.academy\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCUYQwW2KrdirNWihxMDObwg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/person\\\/5a755da80d1d979fd66ba745c8702927\",\"name\":\"RAED\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g\",\"caption\":\"RAED\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La responsabilitat serena de la Princesa Leonor - Reial Acad\u00e8mia Europea de Doctors","description":"Daniel Berzosa va incidir en la seva an\u00e0lisi sobre la formaci\u00f3 militar de la princesa Elionor i la seva preparaci\u00f3 per assumir la Prefectura de l'Estat","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/raed.academy\/ca\/la-responsabilitat-serena-de-la-princesa-leonor\/","og_locale":"ca_ES","og_type":"article","og_title":"La responsabilitat serena de la Princesa Leonor - Reial Acad\u00e8mia Europea de Doctors","og_description":"Daniel Berzosa va incidir en la seva an\u00e0lisi sobre la formaci\u00f3 militar de la princesa Elionor i la seva preparaci\u00f3 per assumir la Prefectura de l'Estat","og_url":"https:\/\/raed.academy\/ca\/la-responsabilitat-serena-de-la-princesa-leonor\/","og_site_name":"Reial Acad\u00e8mia Europea de Doctors","article_publisher":"http:\/\/fb.me\/raed.academy","article_published_time":"2023-11-10T10:59:22+00:00","og_image":[{"width":600,"height":360,"url":"https:\/\/raed.academy\/wp-content\/uploads\/2023\/04\/princesa-leonor.webp","type":"image\/webp"}],"author":"RAED","twitter_card":"summary_large_image","twitter_creator":"@raedacademy","twitter_site":"@raedacademy","twitter_misc":{"Written by":"RAED","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/raed.academy\/ca\/la-responsabilitat-serena-de-la-princesa-leonor\/#article","isPartOf":{"@id":"https:\/\/raed.academy\/ca\/la-responsabilitat-serena-de-la-princesa-leonor\/"},"author":{"name":"RAED","@id":"https:\/\/raed.academy\/ca\/#\/schema\/person\/5a755da80d1d979fd66ba745c8702927"},"headline":"La responsabilitat serena de la Princesa Leonor","datePublished":"2023-11-10T10:59:22+00:00","mainEntityOfPage":{"@id":"https:\/\/raed.academy\/ca\/la-responsabilitat-serena-de-la-princesa-leonor\/"},"wordCount":732,"publisher":{"@id":"https:\/\/raed.academy\/ca\/#organization"},"image":{"@id":"https:\/\/raed.academy\/ca\/la-responsabilitat-serena-de-la-princesa-leonor\/#primaryimage"},"thumbnailUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2023\/04\/princesa-leonor.webp","articleSection":["Ci\u00e8ncies pol\u00edtiques","Monarquia"],"inLanguage":"ca-ES"},{"@type":"WebPage","@id":"https:\/\/raed.academy\/ca\/la-responsabilitat-serena-de-la-princesa-leonor\/","url":"https:\/\/raed.academy\/ca\/la-responsabilitat-serena-de-la-princesa-leonor\/","name":"La responsabilitat serena de la Princesa Leonor - Reial Acad\u00e8mia Europea de Doctors","isPartOf":{"@id":"https:\/\/raed.academy\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/raed.academy\/ca\/la-responsabilitat-serena-de-la-princesa-leonor\/#primaryimage"},"image":{"@id":"https:\/\/raed.academy\/ca\/la-responsabilitat-serena-de-la-princesa-leonor\/#primaryimage"},"thumbnailUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2023\/04\/princesa-leonor.webp","datePublished":"2023-11-10T10:59:22+00:00","description":"Daniel Berzosa va incidir en la seva an\u00e0lisi sobre la formaci\u00f3 militar de la princesa Elionor i la seva preparaci\u00f3 per assumir la Prefectura de l'Estat","breadcrumb":{"@id":"https:\/\/raed.academy\/ca\/la-responsabilitat-serena-de-la-princesa-leonor\/#breadcrumb"},"inLanguage":"ca-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/raed.academy\/ca\/la-responsabilitat-serena-de-la-princesa-leonor\/"]}]},{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/raed.academy\/ca\/la-responsabilitat-serena-de-la-princesa-leonor\/#primaryimage","url":"https:\/\/raed.academy\/wp-content\/uploads\/2023\/04\/princesa-leonor.webp","contentUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2023\/04\/princesa-leonor.webp","width":600,"height":360,"caption":"Princesa Leonor"},{"@type":"BreadcrumbList","@id":"https:\/\/raed.academy\/ca\/la-responsabilitat-serena-de-la-princesa-leonor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/raed.academy\/ca\/"},{"@type":"ListItem","position":2,"name":"La responsabilitat serena de la Princesa Leonor"}]},{"@type":"WebSite","@id":"https:\/\/raed.academy\/ca\/#website","url":"https:\/\/raed.academy\/ca\/","name":"Reial Acad\u00e8mia Europea de Doctors","description":"Corporaci\u00f3n de derecho p\u00fablico de car\u00e1cter cient\u00edfico, t\u00e9cnico y art\u00edstico, que tiene por objeto la investigaci\u00f3n, el estudio, el fomento y la extensi\u00f3n del conocimiento en su sentido m\u00e1s amplio","publisher":{"@id":"https:\/\/raed.academy\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/raed.academy\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca-ES"},{"@type":"Organization","@id":"https:\/\/raed.academy\/ca\/#organization","name":"Real Academia Europea de Doctores","url":"https:\/\/raed.academy\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/raed.academy\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/raed.academy\/wp-content\/uploads\/2017\/01\/cropped-logo_raed.png","contentUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2017\/01\/cropped-logo_raed.png","width":512,"height":512,"caption":"Real Academia Europea de Doctores"},"image":{"@id":"https:\/\/raed.academy\/ca\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/fb.me\/raed.academy","https:\/\/x.com\/raedacademy","https:\/\/www.instagram.com\/raed.academy\/","https:\/\/www.youtube.com\/channel\/UCUYQwW2KrdirNWihxMDObwg"]},{"@type":"Person","@id":"https:\/\/raed.academy\/ca\/#\/schema\/person\/5a755da80d1d979fd66ba745c8702927","name":"RAED","image":{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g","caption":"RAED"}}]}},"_links":{"self":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/posts\/140285","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/comments?post=140285"}],"version-history":[{"count":0,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/posts\/140285\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/media\/131472"}],"wp:attachment":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/media?parent=140285"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/categories?post=140285"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/tags?post=140285"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}