{"id":134141,"date":"2023-06-09T11:30:37","date_gmt":"2023-06-09T11:30:37","guid":{"rendered":"https:\/\/raed.academy\/?p=134141"},"modified":"2023-06-09T13:09:54","modified_gmt":"2023-06-09T13:09:54","slug":"la-ciencia-i-la-religio-als-estudis-de-robert-andrews-millikan","status":"publish","type":"post","link":"https:\/\/raed.academy\/ca\/la-ciencia-i-la-religio-als-estudis-de-robert-andrews-millikan\/","title":{"rendered":"La ci\u00e8ncia i la religi\u00f3 als estudis de Robert Andrews Millikan"},"content":{"rendered":"<div id=\"attachment_87810\" style=\"width: 222px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-87810\" class=\"wp-image-87810\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2020\/02\/Francisco-Gonzalez-de-Posada.jpg\" sizes=\"(max-width: 212px) 100vw, 212px\" srcset=\"https:\/\/raed.academy\/wp-content\/uploads\/2020\/02\/Francisco-Gonzalez-de-Posada.jpg 250w, https:\/\/raed.academy\/wp-content\/uploads\/2020\/02\/Francisco-Gonzalez-de-Posada-150x150.jpg 150w\" alt=\"Dr. Francisco Gonz\u00e1lez de Posada\" width=\"212\" height=\"212\" aria-describedby=\"caption-attachment-87810\" \/><p id=\"caption-attachment-87810\" class=\"wp-caption-text\">Dr. Francisco Gonz\u00e1lez de Posada<\/p><\/div>\n<p><a href=\"https:\/\/raed.academy\/ca\/academics\/dr-francisco-gonzalez-de-posada\/\" target=\"_blank\" rel=\"noopener\"><em><strong>Francisco Gonz\u00e1lez de Posada<\/strong><\/em><\/a>, catedr\u00e0tic de Fonaments F\u00edsics de la <strong>Universitat Polit\u00e8cnica de Madrid<\/strong> i acad\u00e8mic d&#8217;honor de la <strong>Reial Acad\u00e8mia Europea de Doctors-Barcelona 1914<\/strong> (RAED), va participar el passat 11 de maig a la jornada que el <strong>Comit\u00e8 de Defensa<\/strong> de l&#8217;<strong>Institut de l&#8217;Enginyeria d&#8217;Espanya<\/strong> va celebrar a la seva seu madrilenya amb motiu del <strong>Dia Mundial de la Metrologia<\/strong>, dedicat en aquesta edici\u00f3 a la figura i l&#8217;obra del cient\u00edfic nord-americ\u00e0 <strong>Robert Andrews Millikan<\/strong>, coincidint amb el centenari de la concessi\u00f3 per part de l&#8217;<strong>Acad\u00e8mia Sueca<\/strong> del Premi Nobel de F\u00edsica pels treballs que va dur a terme per determinar la c\u00e0rrega de l&#8217;electr\u00f3. L&#8217;acad\u00e8mic va tancar les sessions glossant la figura humana i religiosa d&#8217;aquest f\u00edsic experimental.<\/p>\n<p>El Dia Mundial de la Metrologia commemora la signatura, el 20 de maig de 1875, de la<strong> Convenci\u00f3 del Metre<\/strong>, que \u00e9s el conveni internacional m\u00e9s antic despr\u00e9s del de la <strong>Uni\u00f3 Internacional de Telecomunicacions<\/strong>, que es remunta a deu anys abans. La jornada organitzada per l&#8217;Institut d&#8217;Enginyeria d&#8217;Espanya, a proposta del <strong>Comit\u00e8 de Metrologia<\/strong>, va acollir el lliurament del <strong>M\u00e8rit a la Metrologia 2023<\/strong> per part de<strong> Jos\u00e9 Trigueros<\/strong>, president de l&#8217;Institut, i <strong>Antonio Moreno<\/strong>, president del Comit\u00e8 de Metrologia. El reconeixement va recaure en el capit\u00e0 de navili <strong>Juan Palacio Rodr\u00edguez<\/strong>. En l&#8217;homenatge a Millikan, per altra banda, va participar juntament amb <strong>Gonz\u00e1lez de Posada<\/strong> la investigadora del <strong>Centre Espanyol de Metrologia Yolanda \u00c1lvarez<\/strong>, que va exposar l&#8217;experiment per mesurar la c\u00e0rrega de l&#8217;electr\u00f3. La jornada es va tancar amb un animat col\u00b7loqui.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-134037 alignleft\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2023\/06\/Robert-Andrews-Millikan-Gonzalez-de-Posada-Dominio-Publico-DST.webp\" sizes=\"(max-width: 466px) 100vw, 466px\" srcset=\"https:\/\/raed.academy\/wp-content\/uploads\/2023\/06\/Robert-Andrews-Millikan-Gonzalez-de-Posada-Dominio-Publico-DST.webp 600w, https:\/\/raed.academy\/wp-content\/uploads\/2023\/06\/Robert-Andrews-Millikan-Gonzalez-de-Posada-Dominio-Publico-DST-440x264.webp 440w\" alt=\"\" width=\"466\" height=\"279\" \/>L&#8217;acad\u00e8mic va recordar l&#8217;origen presbiteri\u00e0 de <strong>Millikan<\/strong> i els moviments que es van produir entre les diverses esgl\u00e9sies presbiterianes als Estats Units a la d\u00e8cada dels anys 20 del segle passat i com el f\u00edsic va participar en la defensa de la hist\u00f2ria de la ci\u00e8ncia i en contra de les fortes campanyes contra la <strong>Teoria de l&#8217;Evoluci\u00f3<\/strong> de <strong>Charles Darwin<\/strong> que les esgl\u00e9sies protestants van impulsar a l&#8217;\u00e8poca. &#8220;<strong>Millikan<\/strong> va comen\u00e7ar a oferir confer\u00e8ncies de la relaci\u00f3 entre esgl\u00e9sia i religi\u00f3 per convertir-se en palad\u00ed de la concepci\u00f3 religiosa de l&#8217;univers, cosa que donaria lloc a la publicaci\u00f3 del llibre <strong>&#8216;Evolution in Science and Religion&#8217;<\/strong>&#8220;, va explicar <strong>Gonz\u00e1lez de Posada<\/strong> durant la seva intervenci\u00f3.<\/p>\n<p><strong>Gonz\u00e1lez de Posada<\/strong> \u00e9s enginyer i doctor de Camins, Canals i Ports per la Universitat Polit\u00e8cnica de Madrid, llicenciat en Filosofia i Lletres per la <strong>Universitat Pontif\u00edcia de Salamanca<\/strong> i llicenciat en Ci\u00e8ncies F\u00edsiques per la Universitat Complutense de Madrid. Posse\u00efdor de vuit doctorats, ha impulsat i dirigit nombrosos projectes i estudis de diverses branques del saber. Va ser reconegut amb la Medalla d&#8217;Honor al Foment de la Invenci\u00f3.<\/p>\n<p>\u00c9s acad\u00e8mic de n\u00famero de la<strong> Reial Acad\u00e8mia Nacional de Medicina d&#8217;Espanya<\/strong>, de la <strong>Reial Acad\u00e8mia de Doctors d&#8217;Espanya<\/strong> i membre de l&#8217;<strong>Acad\u00e8mia Mundial d&#8217;Arts i Ci\u00e8ncies<\/strong>, acad\u00e8mic corresponent de la<strong> Reial Acad\u00e8mia de Belles Arts de Cadis<\/strong>, de la <strong>Reial Acad\u00e8mia de Belles Arts de San Fernando<\/strong>\u00a0i la <strong>Reial Acad\u00e8mia de Ci\u00e8ncies, Belles Arts i Bones Lletres d&#8217;\u00c8cija<\/strong> i acad\u00e8mic d&#8217;honor de l&#8217;<strong>Acad\u00e8mia de Ci\u00e8ncies M\u00e8diques de Cant\u00e0bria<\/strong>, de la <strong>Reial Acad\u00e8mia de Cultura Valenciana<\/strong>, de la <strong>Reial Acad\u00e8mia de Medicina i Cirurgia de Cadis<\/strong> i de la <strong>Reial Acad\u00e8mia de Medicina de Can\u00e0ries<\/strong>. \u00c9s tamb\u00e9 acad\u00e8mic i presideix l&#8217;<strong>Acad\u00e8mia de Ci\u00e8ncies i Enginyeries de Lanzarote<\/strong>.<\/p>\n<p><iframe loading=\"lazy\" title=\"2023-05-11 D\u00eda Mundial de Metrolog\u00eda Centenario del Nobel Millikan medida de la carga del electr\u00f3n\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/yUz7yN4lgtY?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Francisco Gonz\u00e1lez de Posada participa en la jornada amb motiu del Dia Mundial de la Metrologia, dedicada a la figura i l&#8217;obra del cient\u00edfic nord-americ\u00e0 Robert Andrews Millikan<\/p>\n","protected":false},"author":12,"featured_media":134038,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[298,344,242,252,492],"tags":[],"class_list":["post-134141","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fisica-ca","category-fisica-de-particules","category-categ-historia","category-teologia-ca","category-trobades-cientifiques-i-congressos","et-has-post-format-content","et_post_format-et-post-format-standard"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La ci\u00e8ncia i la religi\u00f3 als estudis de Robert Andrews Millikan - Reial Acad\u00e8mia Europea de Doctors<\/title>\n<meta name=\"description\" content=\"Francisco Gonz\u00e1lez de Posada va participar en la jornada dedicada a la figura i l&#039;obra del cient\u00edfic nord-americ\u00e0 Robert Andrews Millikan\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/raed.academy\/ca\/la-ciencia-i-la-religio-als-estudis-de-robert-andrews-millikan\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La ci\u00e8ncia i la religi\u00f3 als estudis de Robert Andrews Millikan - Reial Acad\u00e8mia Europea de Doctors\" \/>\n<meta property=\"og:description\" content=\"Francisco Gonz\u00e1lez de Posada va participar en la jornada dedicada a la figura i l&#039;obra del cient\u00edfic nord-americ\u00e0 Robert Andrews Millikan\" \/>\n<meta property=\"og:url\" content=\"https:\/\/raed.academy\/ca\/la-ciencia-i-la-religio-als-estudis-de-robert-andrews-millikan\/\" \/>\n<meta property=\"og:site_name\" content=\"Reial Acad\u00e8mia Europea de Doctors\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/fb.me\/raed.academy\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-09T11:30:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-09T13:09:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/raed.academy\/wp-content\/uploads\/2023\/06\/Robert-Andrews-Millikan-Gonzalez-de-Posada-Dominio-Publico-DST.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"359\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"RAED\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@raedacademy\" \/>\n<meta name=\"twitter:site\" content=\"@raedacademy\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"RAED\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/la-ciencia-i-la-religio-als-estudis-de-robert-andrews-millikan\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/la-ciencia-i-la-religio-als-estudis-de-robert-andrews-millikan\\\/\"},\"author\":{\"name\":\"RAED\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/person\\\/5a755da80d1d979fd66ba745c8702927\"},\"headline\":\"La ci\u00e8ncia i la religi\u00f3 als estudis de Robert Andrews Millikan\",\"datePublished\":\"2023-06-09T11:30:37+00:00\",\"dateModified\":\"2023-06-09T13:09:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/la-ciencia-i-la-religio-als-estudis-de-robert-andrews-millikan\\\/\"},\"wordCount\":668,\"publisher\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/la-ciencia-i-la-religio-als-estudis-de-robert-andrews-millikan\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Robert-Andrews-Millikan-Gonzalez-de-Posada-Dominio-Publico-DST.webp\",\"articleSection\":[\"F\u00edsica\",\"F\u00edsica de part\u00edcules\",\"Hist\u00f2ria\",\"Teologia\",\"Trobades Cient\u00edfiques i Congressos\"],\"inLanguage\":\"ca-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/la-ciencia-i-la-religio-als-estudis-de-robert-andrews-millikan\\\/\",\"url\":\"https:\\\/\\\/raed.academy\\\/ca\\\/la-ciencia-i-la-religio-als-estudis-de-robert-andrews-millikan\\\/\",\"name\":\"La ci\u00e8ncia i la religi\u00f3 als estudis de Robert Andrews Millikan - Reial Acad\u00e8mia Europea de Doctors\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/la-ciencia-i-la-religio-als-estudis-de-robert-andrews-millikan\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/la-ciencia-i-la-religio-als-estudis-de-robert-andrews-millikan\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Robert-Andrews-Millikan-Gonzalez-de-Posada-Dominio-Publico-DST.webp\",\"datePublished\":\"2023-06-09T11:30:37+00:00\",\"dateModified\":\"2023-06-09T13:09:54+00:00\",\"description\":\"Francisco Gonz\u00e1lez de Posada va participar en la jornada dedicada a la figura i l'obra del cient\u00edfic nord-americ\u00e0 Robert Andrews Millikan\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/la-ciencia-i-la-religio-als-estudis-de-robert-andrews-millikan\\\/#breadcrumb\"},\"inLanguage\":\"ca-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/raed.academy\\\/ca\\\/la-ciencia-i-la-religio-als-estudis-de-robert-andrews-millikan\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/la-ciencia-i-la-religio-als-estudis-de-robert-andrews-millikan\\\/#primaryimage\",\"url\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Robert-Andrews-Millikan-Gonzalez-de-Posada-Dominio-Publico-DST.webp\",\"contentUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Robert-Andrews-Millikan-Gonzalez-de-Posada-Dominio-Publico-DST.webp\",\"width\":600,\"height\":359},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/la-ciencia-i-la-religio-als-estudis-de-robert-andrews-millikan\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/raed.academy\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La ci\u00e8ncia i la religi\u00f3 als estudis de Robert Andrews Millikan\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/raed.academy\\\/ca\\\/\",\"name\":\"Reial Acad\u00e8mia Europea de Doctors\",\"description\":\"Corporaci\u00f3n de derecho p\u00fablico de car\u00e1cter cient\u00edfico, t\u00e9cnico y art\u00edstico, que tiene por objeto la investigaci\u00f3n, el estudio, el fomento y la extensi\u00f3n del conocimiento en su sentido m\u00e1s amplio\",\"publisher\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/raed.academy\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#organization\",\"name\":\"Real Academia Europea de Doctores\",\"url\":\"https:\\\/\\\/raed.academy\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/cropped-logo_raed.png\",\"contentUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/cropped-logo_raed.png\",\"width\":512,\"height\":512,\"caption\":\"Real Academia Europea de Doctores\"},\"image\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/fb.me\\\/raed.academy\",\"https:\\\/\\\/x.com\\\/raedacademy\",\"https:\\\/\\\/www.instagram.com\\\/raed.academy\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCUYQwW2KrdirNWihxMDObwg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/person\\\/5a755da80d1d979fd66ba745c8702927\",\"name\":\"RAED\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g\",\"caption\":\"RAED\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La ci\u00e8ncia i la religi\u00f3 als estudis de Robert Andrews Millikan - Reial Acad\u00e8mia Europea de Doctors","description":"Francisco Gonz\u00e1lez de Posada va participar en la jornada dedicada a la figura i l'obra del cient\u00edfic nord-americ\u00e0 Robert Andrews Millikan","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/raed.academy\/ca\/la-ciencia-i-la-religio-als-estudis-de-robert-andrews-millikan\/","og_locale":"ca_ES","og_type":"article","og_title":"La ci\u00e8ncia i la religi\u00f3 als estudis de Robert Andrews Millikan - Reial Acad\u00e8mia Europea de Doctors","og_description":"Francisco Gonz\u00e1lez de Posada va participar en la jornada dedicada a la figura i l'obra del cient\u00edfic nord-americ\u00e0 Robert Andrews Millikan","og_url":"https:\/\/raed.academy\/ca\/la-ciencia-i-la-religio-als-estudis-de-robert-andrews-millikan\/","og_site_name":"Reial Acad\u00e8mia Europea de Doctors","article_publisher":"http:\/\/fb.me\/raed.academy","article_published_time":"2023-06-09T11:30:37+00:00","article_modified_time":"2023-06-09T13:09:54+00:00","og_image":[{"width":600,"height":359,"url":"https:\/\/raed.academy\/wp-content\/uploads\/2023\/06\/Robert-Andrews-Millikan-Gonzalez-de-Posada-Dominio-Publico-DST.webp","type":"image\/webp"}],"author":"RAED","twitter_card":"summary_large_image","twitter_creator":"@raedacademy","twitter_site":"@raedacademy","twitter_misc":{"Written by":"RAED","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/raed.academy\/ca\/la-ciencia-i-la-religio-als-estudis-de-robert-andrews-millikan\/#article","isPartOf":{"@id":"https:\/\/raed.academy\/ca\/la-ciencia-i-la-religio-als-estudis-de-robert-andrews-millikan\/"},"author":{"name":"RAED","@id":"https:\/\/raed.academy\/ca\/#\/schema\/person\/5a755da80d1d979fd66ba745c8702927"},"headline":"La ci\u00e8ncia i la religi\u00f3 als estudis de Robert Andrews Millikan","datePublished":"2023-06-09T11:30:37+00:00","dateModified":"2023-06-09T13:09:54+00:00","mainEntityOfPage":{"@id":"https:\/\/raed.academy\/ca\/la-ciencia-i-la-religio-als-estudis-de-robert-andrews-millikan\/"},"wordCount":668,"publisher":{"@id":"https:\/\/raed.academy\/ca\/#organization"},"image":{"@id":"https:\/\/raed.academy\/ca\/la-ciencia-i-la-religio-als-estudis-de-robert-andrews-millikan\/#primaryimage"},"thumbnailUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2023\/06\/Robert-Andrews-Millikan-Gonzalez-de-Posada-Dominio-Publico-DST.webp","articleSection":["F\u00edsica","F\u00edsica de part\u00edcules","Hist\u00f2ria","Teologia","Trobades Cient\u00edfiques i Congressos"],"inLanguage":"ca-ES"},{"@type":"WebPage","@id":"https:\/\/raed.academy\/ca\/la-ciencia-i-la-religio-als-estudis-de-robert-andrews-millikan\/","url":"https:\/\/raed.academy\/ca\/la-ciencia-i-la-religio-als-estudis-de-robert-andrews-millikan\/","name":"La ci\u00e8ncia i la religi\u00f3 als estudis de Robert Andrews Millikan - Reial Acad\u00e8mia Europea de Doctors","isPartOf":{"@id":"https:\/\/raed.academy\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/raed.academy\/ca\/la-ciencia-i-la-religio-als-estudis-de-robert-andrews-millikan\/#primaryimage"},"image":{"@id":"https:\/\/raed.academy\/ca\/la-ciencia-i-la-religio-als-estudis-de-robert-andrews-millikan\/#primaryimage"},"thumbnailUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2023\/06\/Robert-Andrews-Millikan-Gonzalez-de-Posada-Dominio-Publico-DST.webp","datePublished":"2023-06-09T11:30:37+00:00","dateModified":"2023-06-09T13:09:54+00:00","description":"Francisco Gonz\u00e1lez de Posada va participar en la jornada dedicada a la figura i l'obra del cient\u00edfic nord-americ\u00e0 Robert Andrews Millikan","breadcrumb":{"@id":"https:\/\/raed.academy\/ca\/la-ciencia-i-la-religio-als-estudis-de-robert-andrews-millikan\/#breadcrumb"},"inLanguage":"ca-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/raed.academy\/ca\/la-ciencia-i-la-religio-als-estudis-de-robert-andrews-millikan\/"]}]},{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/raed.academy\/ca\/la-ciencia-i-la-religio-als-estudis-de-robert-andrews-millikan\/#primaryimage","url":"https:\/\/raed.academy\/wp-content\/uploads\/2023\/06\/Robert-Andrews-Millikan-Gonzalez-de-Posada-Dominio-Publico-DST.webp","contentUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2023\/06\/Robert-Andrews-Millikan-Gonzalez-de-Posada-Dominio-Publico-DST.webp","width":600,"height":359},{"@type":"BreadcrumbList","@id":"https:\/\/raed.academy\/ca\/la-ciencia-i-la-religio-als-estudis-de-robert-andrews-millikan\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/raed.academy\/ca\/"},{"@type":"ListItem","position":2,"name":"La ci\u00e8ncia i la religi\u00f3 als estudis de Robert Andrews Millikan"}]},{"@type":"WebSite","@id":"https:\/\/raed.academy\/ca\/#website","url":"https:\/\/raed.academy\/ca\/","name":"Reial Acad\u00e8mia Europea de Doctors","description":"Corporaci\u00f3n de derecho p\u00fablico de car\u00e1cter cient\u00edfico, t\u00e9cnico y art\u00edstico, que tiene por objeto la investigaci\u00f3n, el estudio, el fomento y la extensi\u00f3n del conocimiento en su sentido m\u00e1s amplio","publisher":{"@id":"https:\/\/raed.academy\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/raed.academy\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca-ES"},{"@type":"Organization","@id":"https:\/\/raed.academy\/ca\/#organization","name":"Real Academia Europea de Doctores","url":"https:\/\/raed.academy\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/raed.academy\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/raed.academy\/wp-content\/uploads\/2017\/01\/cropped-logo_raed.png","contentUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2017\/01\/cropped-logo_raed.png","width":512,"height":512,"caption":"Real Academia Europea de Doctores"},"image":{"@id":"https:\/\/raed.academy\/ca\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/fb.me\/raed.academy","https:\/\/x.com\/raedacademy","https:\/\/www.instagram.com\/raed.academy\/","https:\/\/www.youtube.com\/channel\/UCUYQwW2KrdirNWihxMDObwg"]},{"@type":"Person","@id":"https:\/\/raed.academy\/ca\/#\/schema\/person\/5a755da80d1d979fd66ba745c8702927","name":"RAED","image":{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g","caption":"RAED"}}]}},"_links":{"self":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/posts\/134141","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/comments?post=134141"}],"version-history":[{"count":0,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/posts\/134141\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/media\/134038"}],"wp:attachment":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/media?parent=134141"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/categories?post=134141"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/tags?post=134141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}