{"id":131029,"date":"2023-03-22T16:55:58","date_gmt":"2023-03-22T16:55:58","guid":{"rendered":"https:\/\/raed.academy\/?p=131029"},"modified":"2023-04-09T11:09:31","modified_gmt":"2023-04-09T11:09:31","slug":"del-cotxe-actual-al-cotxe-del-futur","status":"publish","type":"post","link":"https:\/\/raed.academy\/ca\/del-cotxe-actual-al-cotxe-del-futur\/","title":{"rendered":"Del cotxe actual al cotxe del futur"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;section&#8221; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_row admin_label=&#8221;row&#8221; _builder_version=&#8221;4.16&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_video src=&#8221;https:\/\/youtu.be\/xTFnqXlqmHs&#8221; _builder_version=&#8221;4.20.4&#8243; _module_preset=&#8221;default&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_video][et_pb_text admin_label=&#8221;Text&#8221; _builder_version=&#8221;4.20.4&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p>La <strong>Reial Acad\u00e8mia Europea de Doctors-Barcelona 1914<\/strong> (RAED), va celebrar el passat 9 de mar\u00e7 a <strong>Foment del Treball Nacional<\/strong>, seu acad\u00e8mica, la sessi\u00f3 <strong>&#8220;Del cotxe actual al cotxe del futur&#8221;<\/strong>, que va tenir com a objecte analitzar des d&#8217;un punt de vista cient\u00edfic i pluridisciplinari la legislaci\u00f3 aprovada recentment pel <strong>Parlament Europeu<\/strong> que posa data de caducitat a la venda de vehicles nous a Europa amb motor de combusti\u00f3. Ser\u00e0 a partir del 2035, quan tots els turismes i furgonetes nous matriculats a Europa siguin d&#8217;emissi\u00f3 zero. Una legislaci\u00f3 que se suma a la provaci\u00f3 de la nova norma<strong> Euro 7<\/strong>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-131614 aligncenter size-full\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2023\/03\/debate-coches-combustion-y-coches-electricos-02.webp\" sizes=\"(max-width: 1400px) 100vw, 1400px\" srcset=\"https:\/\/raed.academy\/wp-content\/uploads\/2023\/03\/debate-coches-combustion-y-coches-electricos-02.webp 1400w, https:\/\/raed.academy\/wp-content\/uploads\/2023\/03\/debate-coches-combustion-y-coches-electricos-02-768x432.webp 768w, https:\/\/raed.academy\/wp-content\/uploads\/2023\/03\/debate-coches-combustion-y-coches-electricos-02-1080x608.webp 1080w\" alt=\"\" width=\"1400\" height=\"788\" \/><\/p>\n<p>A la jornada van participar <a href=\"https:\/\/raed.academy\/ca\/academics\/dr-jose-maria-baldasano-recio\/\" target=\"_blank\" rel=\"noopener\"><em><strong>Jos\u00e9 Mar\u00eda Baldasano<\/strong><\/em><\/a>, catedr\u00e0tic d&#8217;Enginyeria Ambiental de la<strong> Universitat Polit\u00e8cnica de Catalunya<\/strong> i acad\u00e8mic de n\u00famero de la RAED, que va intervenir amb el treball <strong>&#8220;Necessitat del canvi. Avantatges i limitacions del vehicle el\u00e8ctric i d&#8217;hidrogen&#8221;<\/strong>; <strong>Fernando de Miguel<\/strong>, director financer, IT i corporatiu de <strong>Toyota Espa\u00f1a<\/strong>, que va exposar la pon\u00e8ncia <strong>&#8220;Mobilitat sostenible&#8221;<\/strong>; <strong>Vicen\u00e7 Aguilera<\/strong>, expresident del <strong>Cl\u00faster de la Ind\u00fastria d&#8217;Automoci\u00f3 de Catalunya<\/strong> i del <strong>Circuit de Barcelona-Catalunya<\/strong>, que va participar amb &#8220;<strong>L&#8217;automoci\u00f3, cara a cara amb una complexa transici\u00f3&#8221;<\/strong>; <a href=\"https:\/\/raed.academy\/ca\/academics\/dr-pedro-nueno-iniesta\/\" target=\"_blank\" rel=\"noopener\"><em><strong>Pedro Nueno<\/strong><\/em><\/a>, professor de l&#8217;escola de negocis<strong> IESE-Universitat de Navarra<\/strong>, president de l&#8217;<strong>Escola de Negocis Internacional Xina-Europa<\/strong> (Ceibs) i acad\u00e8mic de n\u00famero i president de la Secci\u00f3 de Ci\u00e8ncies Socials de la RAED, que va dissertar sobre <strong>&#8220;L&#8217;autom\u00f2bil al m\u00f3n del futur&#8221;<\/strong>, i<strong> Carlos Adell<\/strong>, Solution Manager e-Mobility de <strong>Huawei Digital Power<\/strong>, que va abordar <strong>&#8220;Els reptes de la rec\u00e0rrega el\u00e8ctrica en la descarbonitzaci\u00f3 del sistema energ\u00e8tic&#8221;<\/strong>. Va intervenir com a moderador <a href=\"https:\/\/raed.academy\/ca\/academics\/dr-jose-ramon-calvo-fernandez\/\" target=\"_blank\" rel=\"noopener\"><em><strong>Jos\u00e9 Ram\u00f3n Calvo<\/strong><\/em><\/a>, assessor estrat\u00e8gic del<strong> Barcelona Supercomputing Center-Centre Nacional de Supercomputaci\u00f3<\/strong>, acad\u00e8mic corresponent de la<strong> Reial Acad\u00e8mia de Medicina del Pa\u00eds Basc<\/strong> i acad\u00e8mic de n\u00famero i president de l&#8217;<strong>Institut de Cooperaci\u00f3 Internacional<\/strong> de la Reial Acad\u00e8mia.<\/p>\n<p>&#8220;La ind\u00fastria de l&#8217;autom\u00f2bil est\u00e0 en un proc\u00e9s de transici\u00f3 cap a una nova mobilitat, per\u00f2 tamb\u00e9 s&#8217;enfronta a desafiaments globals com ara nous desenvolupaments tecnol\u00f2gics, tensions geopol\u00edtiques, disponibilitat de nous materials, augment dels preus de l&#8217;energia&#8230; La ra\u00f3 d&#8217;aquesta jornada \u00e9s debatre sobre l&#8217;evoluci\u00f3 del cotxe en l&#8217;actual context de transici\u00f3. Reflexionar sobre les diferents opcions de futur que estan obertes&#8221;, va assenyalar el moderador per iniciar la jornada.<\/p>\n<p><strong>Baldasano<\/strong> va comen\u00e7ar la seva presentaci\u00f3 amb les emissions de di\u00f2xid de carboni l&#8217;any 2022 degudes al sector de l&#8217;energia, que ha estat la quantitat de 36,8 Gt i que continuen augmentant cada any, a causa de l&#8217;\u00fas dels combustibles f\u00f2ssils, i es pot atribuir al transport el 27% del total. Els cotxes s\u00f3n els que m\u00e9s contribueixen a aquest percentatge seguit del transport per camions i a m\u00e9s dist\u00e0ncia el transport mar\u00edtim i aeri. L&#8217;acad\u00e8mic va presentar el cotxe el\u00e8ctric com a alternativa, amb una s\u00e8rie important d&#8217;avantatges, per\u00f2 tamb\u00e9 amb condicionants i limitacions significatives. Aix\u00ed mateix, <strong>Baldasano<\/strong> va analitzar els diferents nivells d&#8217;electrificaci\u00f3, des del simple h\u00edbrid, passant per l&#8217;h\u00edbrid endollable i el vehicle nom\u00e9s el\u00e8ctric, segons les necessitats de la capacitat de les bateries. &#8220;Crec que el cotxe d&#8217;hidrogen no representa una alternativa real, ja que l&#8217;hidrogen verd encara no est\u00e0 disponible, les expectatives se situen cap a l&#8217;any 2030, i a m\u00e9s \u00e9s molt m\u00e9s necessari la seva utilitzaci\u00f3 com a emmagatzematge energ\u00e8tic i m\u00e9s prioritari en altres usos. &#8220;De la mateixa manera, presenta un balan\u00e7 energ\u00e8tic, tant en la producci\u00f3 com en l&#8217;\u00fas, amb un baix rendiment&#8221;, va assenyalar.<\/p>\n<p><strong>De Miguel<\/strong> va presentar la visi\u00f3 mobilitat de Toyota, assenyalant que cada cop m\u00e9s els vehicles electrificats contribuiran a aquesta societat futura sense emissions i establint que necessitarem totes les tecnologies per assolir la neutralitat en carboni i responent alhora a les necessitats dels clients. Tamb\u00e9 va indicar que les emissions de NOx de la tecnologia HEV s\u00f3n molt inferiors a la normativa europea. Tamb\u00e9 va assenyalar que en el moment actual l&#8217;opci\u00f3 del vehicle h\u00edbrid ofereix una gran efici\u00e8ncia en recurs; i que Toyota recull m\u00e9s del 90% de les bateries h\u00edbrides al final de la vida \u00fatil dels vehicles. &#8220;Per a Toyota, l&#8217;hidrogen avui ja \u00e9s una realitat i ser\u00e0 clau per descarbonitzar la ciutat de dem\u00e0, per\u00f2 encara hi ha tres barreres per al desplegament de vehicles alimentats amb hidrogen: d&#8217;accessibilitat, \u00fas i reguladora&#8221;, va indicar.<\/p>\n<p><strong>Aguilera<\/strong>, per part seva, va reflexionar sobre la gran transformaci\u00f3 que representa per a la ind\u00fastria de l&#8217;autom\u00f2bil passar del vehicle amb motor de combusti\u00f3 al motor el\u00e8ctric. &#8220;Significa un canvi total del model actual de fabricaci\u00f3, en un marc fortament marcat per un conjunt d&#8217;escenaris que tenen una elevada c\u00e0rrega d&#8217;incertesa, cosa que dificulta profundament la presa de decisions&#8221;, va assenyalar. <strong>Nueno<\/strong> va fer una dissertaci\u00f3 sobre la complexitat de la ind\u00fastria dels fabricants d&#8217;autom\u00f2bils, del moment de canvi i incertesa en qu\u00e8 es troba i sobre la dificultat de l&#8217;usuari de definir opcions de compra clares. &#8220;\u00c9s sorprenent l&#8217;enorme volum de cotxes el\u00e8ctrics que els fabricants d&#8217;autom\u00f2bils diuen que fabricaran el 2030, alguns fins i tot s&#8217;atreveixen a dir el 2025. Tamb\u00e9 diuen en quines plantes els fabricaran i sembla que a Espanya ens en tocaran for\u00e7a. Per\u00f2 de moment es venen molt\u00edssims m\u00e9s cotxes de benzina que el\u00e8ctrics, tampoc sembla que tots els pa\u00efsos estiguin muntant punts de rec\u00e0rrega a totes les seves ciutats, pobles, carreteres, autopistes&#8230; Tot indica que les previsions no s\u00f3n realistes i el cotxe de combusti\u00f3 haur\u00e0 de conviure durant anys amb l&#8217;el\u00e8ctric, que per si mateix no \u00e9s la soluci\u00f3 a un model de mobilitat sostenible&#8221;, va assenyalar l&#8217;acad\u00e8mic.<\/p>\n<p>Finalment, <strong>Adell<\/strong> va definir el marc actual de l&#8217;\u00fas de les bateries al cotxe el\u00e8ctric i al sistema el\u00e8ctric en general, at\u00e8s el creixement exponencial de les energies renovables, la seva profunda evoluci\u00f3 tecnol\u00f2gica i el recorregut que t\u00e9 per millorar-lo i el que pot representar per emmagatzemar energia el\u00e8ctrica. Va presentar i analitzar l&#8217;anomenada &#8220;corba d&#8217;\u00e0nec&#8221;, que suposa el cicle diari de l&#8217;\u00fas d&#8217;electricitat i el repte que representa per a la infraestructura el\u00e8ctrica. La necessitat de transformaci\u00f3 de la xarxa el\u00e8ctrica, no nom\u00e9s en augment de pot\u00e8ncia, sin\u00f3 especialment en un canvi de model de grans generadors de pot\u00e8ncia amb molta in\u00e8rcia a multitud d&#8217;inversors i bateries, estabilitzant din\u00e0micament el sistema.<\/p>\n<p>Al col\u00b7loqui que va tenir lloc a continuaci\u00f3 es van destacar principalment tres temes. El primer es va centrar en l&#8217;horitz\u00f3 del sector de fabricaci\u00f3 d&#8217;autom\u00f2bils, amb la transformaci\u00f3 corresponent de la for\u00e7a laboral, tant pel que fa al nombre de treballadors com a la seva formaci\u00f3 espec\u00edfica. El segon, en el canvi d&#8217;acc\u00e9s al vehicle, des de l&#8217;opci\u00f3 de compra a l&#8217;opci\u00f3 de disposar-ne l&#8217;\u00fas en funci\u00f3 de la necessitat. El tercer va assenyalar la necessitat d&#8217;augmentar i millorar el transport p\u00fablic, clau per a una mobilitat futura sostenible.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-131611 aligncenter size-full\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2023\/03\/debate-coches-combustion-y-coches-electricos-01.webp\" sizes=\"(max-width: 1400px) 100vw, 1400px\" srcset=\"https:\/\/raed.academy\/wp-content\/uploads\/2023\/03\/debate-coches-combustion-y-coches-electricos-01.webp 1400w, https:\/\/raed.academy\/wp-content\/uploads\/2023\/03\/debate-coches-combustion-y-coches-electricos-01-768x432.webp 768w, https:\/\/raed.academy\/wp-content\/uploads\/2023\/03\/debate-coches-combustion-y-coches-electricos-01-1080x608.webp 1080w\" alt=\"\" width=\"1400\" height=\"788\" \/><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sessi\u00f3 &#8220;Del coche actual al coche del futuro&#8221;. Una an\u00e0lisi de la legislaci\u00f3 aprovada recentment pel Parlament Europeu que posa data de caducitat a la venda de vehicles nous a Europa amb motor de combusti\u00f3<\/p>\n","protected":false},"author":12,"featured_media":129793,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"La <strong>Reial Acad\u00e8mia Europea de Doctors-Barcelona 1914<\/strong> (RAED), va celebrar el passat 9 de mar\u00e7 a <strong>Foment del Treball Nacional<\/strong>, seu acad\u00e8mica, la sessi\u00f3 <strong>\"Del cotxe actual al cotxe del futur\"<\/strong>, que va tenir com a objecte analitzar des d'un punt de vista cient\u00edfic i pluridisciplinari la legislaci\u00f3 aprovada recentment pel <strong>Parlament Europeu<\/strong> que posa data de caducitat a la venda de vehicles nous a Europa amb motor de combusti\u00f3. Ser\u00e0 a partir del 2035, quan tots els turismes i furgonetes nous matriculats a Europa siguin d'emissi\u00f3 zero. Una legislaci\u00f3 que se suma a la provaci\u00f3 de la nova norma<strong> Euro 7<\/strong>.\r\n\r\nA la jornada van participar <a href=\"https:\/\/raed.academy\/ca\/academics\/dr-jose-maria-baldasano-recio\/\" target=\"_blank\" rel=\"noopener\"><em><strong>Jos\u00e9 Mar\u00eda Baldasano<\/strong><\/em><\/a>, catedr\u00e0tic d'Enginyeria Ambiental de la<strong> Universitat Polit\u00e8cnica de Catalunya<\/strong> i acad\u00e8mic de n\u00famero de la RAED, que va intervenir amb el treball <strong>\"Necessitat del canvi. Avantatges i limitacions del vehicle el\u00e8ctric i d'hidrogen\"<\/strong>; <strong>Fernando de Miguel<\/strong>, director financer, IT i corporatiu de <strong>Toyota Espa\u00f1a<\/strong>, que va exposar la pon\u00e8ncia <strong>\"Mobilitat sostenible\"<\/strong>; <strong>Vicen\u00e7 Aguilera<\/strong>, expresident del <strong>Cl\u00faster de la Ind\u00fastria d'Automoci\u00f3 de Catalunya<\/strong> i del <strong>Circuit de Barcelona-Catalunya<\/strong>, que va participar amb \"<strong>L'automoci\u00f3, cara a cara amb una complexa transici\u00f3\"<\/strong>; <a href=\"https:\/\/raed.academy\/ca\/academics\/dr-pedro-nueno-iniesta\/\" target=\"_blank\" rel=\"noopener\"><em><strong>Pedro Nueno<\/strong><\/em><\/a>, professor de l'escola de negocis<strong> IESE-Universitat de Navarra<\/strong>, president de l'<strong>Escola de Negocis Internacional Xina-Europa<\/strong> (Ceibs) i acad\u00e8mic de n\u00famero i president de la Secci\u00f3 de Ci\u00e8ncies Socials de la RAED, que va dissertar sobre <strong>\"L'autom\u00f2bil al m\u00f3n del futur\"<\/strong>, i<strong> Carlos Adell<\/strong>, Solution Manager e-Mobility de <strong>Huawei Digital Power<\/strong>, que va abordar <strong>\"Els reptes de la rec\u00e0rrega el\u00e8ctrica en la descarbonitzaci\u00f3 del sistema energ\u00e8tic\"<\/strong>. Va intervenir com a moderador <a href=\"https:\/\/raed.academy\/ca\/academics\/dr-jose-ramon-calvo-fernandez\/\" target=\"_blank\" rel=\"noopener\"><em><strong>Jos\u00e9 Ram\u00f3n Calvo<\/strong><\/em><\/a>, assessor estrat\u00e8gic del<strong> Barcelona Supercomputing Center-Centre Nacional de Supercomputaci\u00f3<\/strong>, acad\u00e8mic corresponent de la<strong> Reial Acad\u00e8mia de Medicina del Pa\u00eds Basc<\/strong> i acad\u00e8mic de n\u00famero i president de l'<strong>Institut de Cooperaci\u00f3 Internacional<\/strong> de la Reial Acad\u00e8mia.\r\n\r\n\"La ind\u00fastria de l'autom\u00f2bil est\u00e0 en un proc\u00e9s de transici\u00f3 cap a una nova mobilitat, per\u00f2 tamb\u00e9 s'enfronta a desafiaments globals com ara nous desenvolupaments tecnol\u00f2gics, tensions geopol\u00edtiques, disponibilitat de nous materials, augment dels preus de l'energia... La ra\u00f3 d'aquesta jornada \u00e9s debatre sobre l'evoluci\u00f3 del cotxe en l'actual context de transici\u00f3. Reflexionar sobre les diferents opcions de futur que estan obertes\", va assenyalar el moderador per iniciar la jornada.\r\n\r\nBaldasano va comen\u00e7ar la seva presentaci\u00f3 amb les emissions de di\u00f2xid de carboni l'any 2022 degudes al sector de l'energia, que ha estat la quantitat de 36,8 Gt i que continuen augmentant cada any, a causa de l'\u00fas dels combustibles f\u00f2ssils, i es pot atribuir al transport el 27% del total. Els cotxes s\u00f3n els que m\u00e9s contribueixen a aquest percentatge seguit del transport per camions i a m\u00e9s dist\u00e0ncia el transport mar\u00edtim i aeri. L'acad\u00e8mic va presentar el cotxe el\u00e8ctric com a alternativa, amb una s\u00e8rie important d'avantatges, per\u00f2 tamb\u00e9 amb condicionants i limitacions significatives. Aix\u00ed mateix, Baldasano va analitzar els diferents nivells d'electrificaci\u00f3, des del simple h\u00edbrid, passant per l'h\u00edbrid endollable i el vehicle nom\u00e9s el\u00e8ctric, segons les necessitats de la capacitat de les bateries. \"Crec que el cotxe d'hidrogen no representa una alternativa real, ja que l'hidrogen verd encara no est\u00e0 disponible, les expectatives se situen cap a l'any 2030, i a m\u00e9s \u00e9s molt m\u00e9s necessari la seva utilitzaci\u00f3 com a emmagatzematge energ\u00e8tic i m\u00e9s prioritari en altres usos. \"De la mateixa manera, presenta un balan\u00e7 energ\u00e8tic, tant en la producci\u00f3 com en l'\u00fas, amb un baix rendiment\", va assenyalar.\r\n\r\nDe Miguel va presentar la visi\u00f3 mobilitat de Toyota, assenyalant que cada cop m\u00e9s els vehicles electrificats contribuiran a aquesta societat futura sense emissions i establint que necessitarem totes les tecnologies per assolir la neutralitat en carboni i responent alhora a les necessitats dels clients. Tamb\u00e9 va indicar que les emissions de NOx de la tecnologia HEV s\u00f3n molt inferiors a la normativa europea. Tamb\u00e9 va assenyalar que en el moment actual l'opci\u00f3 del vehicle h\u00edbrid ofereix una gran efici\u00e8ncia en recurs; i que Toyota recull m\u00e9s del 90% de les bateries h\u00edbrides al final de la vida \u00fatil dels vehicles. \"Per a Toyota, l'hidrogen avui ja \u00e9s una realitat i ser\u00e0 clau per descarbonitzar la ciutat de dem\u00e0, per\u00f2 encara hi ha tres barreres per al desplegament de vehicles alimentats amb hidrogen: d'accessibilitat, \u00fas i reguladora\", va indicar.\r\n\r\nAguilera, per part seva, va reflexionar sobre la gran transformaci\u00f3 que representa per a la ind\u00fastria de l'autom\u00f2bil passar del vehicle amb motor de combusti\u00f3 al motor el\u00e8ctric. \"Significa un canvi total del model actual de fabricaci\u00f3, en un marc fortament marcat per un conjunt d'escenaris que tenen una elevada c\u00e0rrega d'incertesa, cosa que dificulta profundament la presa de decisions\", va assenyalar. Nueno va fer una dissertaci\u00f3 sobre la complexitat de la ind\u00fastria dels fabricants d'autom\u00f2bils, del moment de canvi i incertesa en qu\u00e8 es troba i sobre la dificultat de l'usuari de definir opcions de compra clares. \"\u00c9s sorprenent l'enorme volum de cotxes el\u00e8ctrics que els fabricants d'autom\u00f2bils diuen que fabricaran el 2030, alguns fins i tot s'atreveixen a dir el 2025. Tamb\u00e9 diuen en quines plantes els fabricaran i sembla que a Espanya ens en tocaran for\u00e7a. Per\u00f2 de moment es venen molt\u00edssims m\u00e9s cotxes de benzina que el\u00e8ctrics, tampoc sembla que tots els pa\u00efsos estiguin muntant punts de rec\u00e0rrega a totes les seves ciutats, pobles, carreteres, autopistes... Tot indica que les previsions no s\u00f3n realistes i el cotxe de combusti\u00f3 haur\u00e0 de conviure durant anys amb l'el\u00e8ctric, que per si mateix no \u00e9s la soluci\u00f3 a un model de mobilitat sostenible\", va assenyalar l'acad\u00e8mic.\r\n\r\nFinalment, Adell va definir el marc actual de l'\u00fas de les bateries al cotxe el\u00e8ctric i al sistema el\u00e8ctric en general, at\u00e8s el creixement exponencial de les energies renovables, la seva profunda evoluci\u00f3 tecnol\u00f2gica i el recorregut que t\u00e9 per millorar-lo i el que pot representar per emmagatzemar energia el\u00e8ctrica. Va presentar i analitzar l'anomenada \"corba d'\u00e0nec\", que suposa el cicle diari de l'\u00fas d'electricitat i el repte que representa per a la infraestructura el\u00e8ctrica. La necessitat de transformaci\u00f3 de la xarxa el\u00e8ctrica, no nom\u00e9s en augment de pot\u00e8ncia, sin\u00f3 especialment en un canvi de model de grans generadors de pot\u00e8ncia amb molta in\u00e8rcia a multitud d'inversors i bateries, estabilitzant din\u00e0micament el sistema.\r\n\r\nAl col\u00b7loqui que va tenir lloc a continuaci\u00f3 es van destacar principalment tres temes. El primer es va centrar en l'horitz\u00f3 del sector de fabricaci\u00f3 d'autom\u00f2bils, amb la transformaci\u00f3 corresponent de la for\u00e7a laboral, tant pel que fa al nombre de treballadors com a la seva formaci\u00f3 espec\u00edfica. El segon, en el canvi d'acc\u00e9s al vehicle, des de l'opci\u00f3 de compra a l'opci\u00f3 de disposar-ne l'\u00fas en funci\u00f3 de la necessitat. El tercer va assenyalar la necessitat d'augmentar i millorar el transport p\u00fablic, clau per a una mobilitat futura sostenible.","_et_gb_content_width":"","footnotes":""},"categories":[416,304,310,413],"tags":[],"class_list":["post-131029","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-canvi-climatic","category-economia-i-politica-ca","category-medi-ambient","category-transicio-energetica-i-energies-renovables","et-has-post-format-content","et_post_format-et-post-format-standard"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Del cotxe actual al cotxe del futur - Reial Acad\u00e8mia Europea de Doctors<\/title>\n<meta name=\"description\" content=\"Sessi\u00f3 \u201cDel cotxe actual al cotxe del futur\u201d. Una an\u00e0lisi de la legislaci\u00f3 que posa data de caducitat a la venda de vehicles amb motor de combusti\u00f3\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/raed.academy\/ca\/del-cotxe-actual-al-cotxe-del-futur\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Del cotxe actual al cotxe del futur - Reial Acad\u00e8mia Europea de Doctors\" \/>\n<meta property=\"og:description\" content=\"Sessi\u00f3 \u201cDel cotxe actual al cotxe del futur\u201d. Una an\u00e0lisi de la legislaci\u00f3 que posa data de caducitat a la venda de vehicles amb motor de combusti\u00f3\" \/>\n<meta property=\"og:url\" content=\"https:\/\/raed.academy\/ca\/del-cotxe-actual-al-cotxe-del-futur\/\" \/>\n<meta property=\"og:site_name\" content=\"Reial Acad\u00e8mia Europea de Doctors\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/fb.me\/raed.academy\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-22T16:55:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-09T11:09:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/raed.academy\/wp-content\/uploads\/2023\/02\/coches-electricos-no-atrib-licencia-Pixabay-carrusel.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"550\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"RAED\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@raedacademy\" \/>\n<meta name=\"twitter:site\" content=\"@raedacademy\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"RAED\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/del-cotxe-actual-al-cotxe-del-futur\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/del-cotxe-actual-al-cotxe-del-futur\\\/\"},\"author\":{\"name\":\"RAED\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/person\\\/5a755da80d1d979fd66ba745c8702927\"},\"headline\":\"Del cotxe actual al cotxe del futur\",\"datePublished\":\"2023-03-22T16:55:58+00:00\",\"dateModified\":\"2023-04-09T11:09:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/del-cotxe-actual-al-cotxe-del-futur\\\/\"},\"wordCount\":1362,\"publisher\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/del-cotxe-actual-al-cotxe-del-futur\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/coches-electricos-no-atrib-licencia-Pixabay-carrusel.webp\",\"articleSection\":[\"Canvi clim\u00e0tic\",\"Economia i pol\u00edtica\",\"Medi ambient\",\"Transici\u00f3 energ\u00e8tica i energies renovables\"],\"inLanguage\":\"ca-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/del-cotxe-actual-al-cotxe-del-futur\\\/\",\"url\":\"https:\\\/\\\/raed.academy\\\/ca\\\/del-cotxe-actual-al-cotxe-del-futur\\\/\",\"name\":\"Del cotxe actual al cotxe del futur - Reial Acad\u00e8mia Europea de Doctors\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/del-cotxe-actual-al-cotxe-del-futur\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/del-cotxe-actual-al-cotxe-del-futur\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/coches-electricos-no-atrib-licencia-Pixabay-carrusel.webp\",\"datePublished\":\"2023-03-22T16:55:58+00:00\",\"dateModified\":\"2023-04-09T11:09:31+00:00\",\"description\":\"Sessi\u00f3 \u201cDel cotxe actual al cotxe del futur\u201d. Una an\u00e0lisi de la legislaci\u00f3 que posa data de caducitat a la venda de vehicles amb motor de combusti\u00f3\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/del-cotxe-actual-al-cotxe-del-futur\\\/#breadcrumb\"},\"inLanguage\":\"ca-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/raed.academy\\\/ca\\\/del-cotxe-actual-al-cotxe-del-futur\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/del-cotxe-actual-al-cotxe-del-futur\\\/#primaryimage\",\"url\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/coches-electricos-no-atrib-licencia-Pixabay-carrusel.webp\",\"contentUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/coches-electricos-no-atrib-licencia-Pixabay-carrusel.webp\",\"width\":1600,\"height\":550},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/del-cotxe-actual-al-cotxe-del-futur\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/raed.academy\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Del cotxe actual al cotxe del futur\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/raed.academy\\\/ca\\\/\",\"name\":\"Reial Acad\u00e8mia Europea de Doctors\",\"description\":\"Corporaci\u00f3n de derecho p\u00fablico de car\u00e1cter cient\u00edfico, t\u00e9cnico y art\u00edstico, que tiene por objeto la investigaci\u00f3n, el estudio, el fomento y la extensi\u00f3n del conocimiento en su sentido m\u00e1s amplio\",\"publisher\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/raed.academy\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#organization\",\"name\":\"Real Academia Europea de Doctores\",\"url\":\"https:\\\/\\\/raed.academy\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/cropped-logo_raed.png\",\"contentUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/cropped-logo_raed.png\",\"width\":512,\"height\":512,\"caption\":\"Real Academia Europea de Doctores\"},\"image\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/fb.me\\\/raed.academy\",\"https:\\\/\\\/x.com\\\/raedacademy\",\"https:\\\/\\\/www.instagram.com\\\/raed.academy\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCUYQwW2KrdirNWihxMDObwg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/person\\\/5a755da80d1d979fd66ba745c8702927\",\"name\":\"RAED\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g\",\"caption\":\"RAED\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Del cotxe actual al cotxe del futur - Reial Acad\u00e8mia Europea de Doctors","description":"Sessi\u00f3 \u201cDel cotxe actual al cotxe del futur\u201d. Una an\u00e0lisi de la legislaci\u00f3 que posa data de caducitat a la venda de vehicles amb motor de combusti\u00f3","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/raed.academy\/ca\/del-cotxe-actual-al-cotxe-del-futur\/","og_locale":"ca_ES","og_type":"article","og_title":"Del cotxe actual al cotxe del futur - Reial Acad\u00e8mia Europea de Doctors","og_description":"Sessi\u00f3 \u201cDel cotxe actual al cotxe del futur\u201d. Una an\u00e0lisi de la legislaci\u00f3 que posa data de caducitat a la venda de vehicles amb motor de combusti\u00f3","og_url":"https:\/\/raed.academy\/ca\/del-cotxe-actual-al-cotxe-del-futur\/","og_site_name":"Reial Acad\u00e8mia Europea de Doctors","article_publisher":"http:\/\/fb.me\/raed.academy","article_published_time":"2023-03-22T16:55:58+00:00","article_modified_time":"2023-04-09T11:09:31+00:00","og_image":[{"width":1600,"height":550,"url":"https:\/\/raed.academy\/wp-content\/uploads\/2023\/02\/coches-electricos-no-atrib-licencia-Pixabay-carrusel.webp","type":"image\/webp"}],"author":"RAED","twitter_card":"summary_large_image","twitter_creator":"@raedacademy","twitter_site":"@raedacademy","twitter_misc":{"Written by":"RAED","Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/raed.academy\/ca\/del-cotxe-actual-al-cotxe-del-futur\/#article","isPartOf":{"@id":"https:\/\/raed.academy\/ca\/del-cotxe-actual-al-cotxe-del-futur\/"},"author":{"name":"RAED","@id":"https:\/\/raed.academy\/ca\/#\/schema\/person\/5a755da80d1d979fd66ba745c8702927"},"headline":"Del cotxe actual al cotxe del futur","datePublished":"2023-03-22T16:55:58+00:00","dateModified":"2023-04-09T11:09:31+00:00","mainEntityOfPage":{"@id":"https:\/\/raed.academy\/ca\/del-cotxe-actual-al-cotxe-del-futur\/"},"wordCount":1362,"publisher":{"@id":"https:\/\/raed.academy\/ca\/#organization"},"image":{"@id":"https:\/\/raed.academy\/ca\/del-cotxe-actual-al-cotxe-del-futur\/#primaryimage"},"thumbnailUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2023\/02\/coches-electricos-no-atrib-licencia-Pixabay-carrusel.webp","articleSection":["Canvi clim\u00e0tic","Economia i pol\u00edtica","Medi ambient","Transici\u00f3 energ\u00e8tica i energies renovables"],"inLanguage":"ca-ES"},{"@type":"WebPage","@id":"https:\/\/raed.academy\/ca\/del-cotxe-actual-al-cotxe-del-futur\/","url":"https:\/\/raed.academy\/ca\/del-cotxe-actual-al-cotxe-del-futur\/","name":"Del cotxe actual al cotxe del futur - Reial Acad\u00e8mia Europea de Doctors","isPartOf":{"@id":"https:\/\/raed.academy\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/raed.academy\/ca\/del-cotxe-actual-al-cotxe-del-futur\/#primaryimage"},"image":{"@id":"https:\/\/raed.academy\/ca\/del-cotxe-actual-al-cotxe-del-futur\/#primaryimage"},"thumbnailUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2023\/02\/coches-electricos-no-atrib-licencia-Pixabay-carrusel.webp","datePublished":"2023-03-22T16:55:58+00:00","dateModified":"2023-04-09T11:09:31+00:00","description":"Sessi\u00f3 \u201cDel cotxe actual al cotxe del futur\u201d. Una an\u00e0lisi de la legislaci\u00f3 que posa data de caducitat a la venda de vehicles amb motor de combusti\u00f3","breadcrumb":{"@id":"https:\/\/raed.academy\/ca\/del-cotxe-actual-al-cotxe-del-futur\/#breadcrumb"},"inLanguage":"ca-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/raed.academy\/ca\/del-cotxe-actual-al-cotxe-del-futur\/"]}]},{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/raed.academy\/ca\/del-cotxe-actual-al-cotxe-del-futur\/#primaryimage","url":"https:\/\/raed.academy\/wp-content\/uploads\/2023\/02\/coches-electricos-no-atrib-licencia-Pixabay-carrusel.webp","contentUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2023\/02\/coches-electricos-no-atrib-licencia-Pixabay-carrusel.webp","width":1600,"height":550},{"@type":"BreadcrumbList","@id":"https:\/\/raed.academy\/ca\/del-cotxe-actual-al-cotxe-del-futur\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/raed.academy\/ca\/"},{"@type":"ListItem","position":2,"name":"Del cotxe actual al cotxe del futur"}]},{"@type":"WebSite","@id":"https:\/\/raed.academy\/ca\/#website","url":"https:\/\/raed.academy\/ca\/","name":"Reial Acad\u00e8mia Europea de Doctors","description":"Corporaci\u00f3n de derecho p\u00fablico de car\u00e1cter cient\u00edfico, t\u00e9cnico y art\u00edstico, que tiene por objeto la investigaci\u00f3n, el estudio, el fomento y la extensi\u00f3n del conocimiento en su sentido m\u00e1s amplio","publisher":{"@id":"https:\/\/raed.academy\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/raed.academy\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca-ES"},{"@type":"Organization","@id":"https:\/\/raed.academy\/ca\/#organization","name":"Real Academia Europea de Doctores","url":"https:\/\/raed.academy\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/raed.academy\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/raed.academy\/wp-content\/uploads\/2017\/01\/cropped-logo_raed.png","contentUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2017\/01\/cropped-logo_raed.png","width":512,"height":512,"caption":"Real Academia Europea de Doctores"},"image":{"@id":"https:\/\/raed.academy\/ca\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/fb.me\/raed.academy","https:\/\/x.com\/raedacademy","https:\/\/www.instagram.com\/raed.academy\/","https:\/\/www.youtube.com\/channel\/UCUYQwW2KrdirNWihxMDObwg"]},{"@type":"Person","@id":"https:\/\/raed.academy\/ca\/#\/schema\/person\/5a755da80d1d979fd66ba745c8702927","name":"RAED","image":{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g","caption":"RAED"}}]}},"_links":{"self":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/posts\/131029","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/comments?post=131029"}],"version-history":[{"count":0,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/posts\/131029\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/media\/129793"}],"wp:attachment":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/media?parent=131029"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/categories?post=131029"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/tags?post=131029"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}