{"id":126520,"date":"2022-12-23T12:12:48","date_gmt":"2022-12-23T12:12:48","guid":{"rendered":"https:\/\/raed.academy\/?p=126520"},"modified":"2022-12-28T12:54:31","modified_gmt":"2022-12-28T12:54:31","slug":"auditoria-i-salut","status":"publish","type":"post","link":"https:\/\/raed.academy\/ca\/auditoria-i-salut\/","title":{"rendered":"Auditoria i salut"},"content":{"rendered":"<p>La <strong>Reial Acad\u00e8mia Europea de Doctors-Barcelona 1914<\/strong> (RAED) i el <strong>Col\u00b7legi de Censors Jurats de Comptes de Catalunya<\/strong> van organitzar el passat 19 de desembre a la seu d&#8217;aquesta instituci\u00f3 i en format h\u00edbrid la jornada <strong>&#8220;L&#8217;auditor i la salut m\u00e9s enll\u00e0 de la verificaci\u00f3 financera&#8221;<\/strong>, que va estar liderada pel president del Col\u00b7legi i col\u00b7laborador habitual de la Reial Acad\u00e8mia<strong> Antoni G\u00f3mez<\/strong>, i per l&#8217;acad\u00e8mic de n\u00famero i president de la <strong>Junta de Govern<\/strong> de la RAED, <a href=\"https:\/\/raed.academy\/ca\/academics\/dr-alfredo-rocafort-nicolau\/\" target=\"_blank\" rel=\"noopener\"><em><strong>Alfredo Rocafort<\/strong><\/em><\/a>. Tots dos van ser els encarregats d&#8217;inaugurar i clausurar l&#8217;activitat.<\/p>\n<p>A les sessions van participar <a href=\"https:\/\/raed.academy\/ca\/academics\/dra-maria-dels-angels-calvo-torras\/\" target=\"_blank\" rel=\"noopener\"><em><strong>Maria \u00c0ngels Calvo<\/strong><\/em><\/a>, catedr\u00e0tica de la Facultat de Veterin\u00e0ria de la <strong>Universitat Aut\u00f2noma de Barcelona<\/strong>, acad\u00e8mica de n\u00famero de la <strong>Reial Acad\u00e8mia de Medicina de Catalunya<\/strong>, de la <strong>Reial Acad\u00e8mia de Farm\u00e0cia de Catalunya<\/strong>, acad\u00e8mica i secret\u00e0ria general de l&#8217;<strong>Acad\u00e8mia de Ci\u00e8ncies Veterin\u00e0ries de Catalunya<\/strong> i acad\u00e8mica de n\u00famero i vicepresidenta de la RAED, que va ser la responsable de pronunciar la confer\u00e8ncia inaugural: <strong>&#8220;L&#8217;auditor i la salut global&#8221;<\/strong>, en qu\u00e8 va unir \u00e0mbits aparentment tan diferents per\u00f2 realment estretament vinculats com a salut i economia, per introduir-hi aix\u00ed l&#8217;objecte de debat.<\/p>\n<p>La seva pon\u00e8ncia va donar pas a la primera taula rodona, que va portar per t\u00edtol <strong>&#8220;Els reptes de la salut i les empreses&#8221;<\/strong>, en qu\u00e8 van participar<a href=\"https:\/\/raed.academy\/ca\/academics\/dr-joan-massons-rabassa\/\" target=\"_blank\" rel=\"noopener\"><em><strong> Joan Massons<\/strong><\/em><\/a>, professor de Finances d&#8217;<strong>Esade Business School<\/strong>, expert en an\u00e0lisi i estrat\u00e8gia financera i acad\u00e8mic numerari de la RAED; <a href=\"https:\/\/raed.academy\/ca\/academics\/dra-mireia-las-heras-maestro\/\" target=\"_blank\" rel=\"noopener\"><em><strong>Mireia Las Heras<\/strong><\/em><\/a>, professora de l&#8217;escola de negocis <strong>IESE-Universitat de Navarra<\/strong> i tamb\u00e9 acad\u00e8mica de n\u00famero de la RAED, i<strong> Xavier Carbonell<\/strong>, membre de la <strong>Comissi\u00f3 de Responsabilitat Social Empresarial<\/strong> del Col\u00b7legi de Censors Jurats de Comptes de Catalunya i director de la <strong>C\u00e0tedra Mango de Responsabilitat Social<\/strong> de l&#8217;<strong>Escola Superior de Comer\u00e7 Internacional<\/strong> de la <strong>Universitat Pompeu Fabra<\/strong>. Va moderar la sessi\u00f3 <strong>Joan Vall<\/strong>, primer vicepresident del Col\u00b7legi<\/p>\n<p>Les jornades van continuar amb la segona taula rodona, dedicada a <strong>&#8220;La gesti\u00f3 de la salut i auditoria&#8221;<\/strong>, que va comptar amb la participaci\u00f3 de <a href=\"https:\/\/raed.academy\/ca\/academics\/dr-joaquim-gironella-coll\/\" target=\"_blank\" rel=\"noopener\"><em><strong>Joaquim Gironella<\/strong><\/em><\/a>, codirector m\u00e8dic del centre <strong>Laser Medical Rent<\/strong>, acad\u00e8mic corresponent de la Reial Acad\u00e8mia de Medicina de Catalunya i acad\u00e8mic de n\u00famero de la RAED, i <strong>Pere Ruiz<\/strong>, membre del <strong>Consell Directiu<\/strong> del Col\u00b7legi. En aquest cas, el moderador va ser <a href=\"https:\/\/raed.academy\/ca\/academics\/dr-frederic-borras-pamies\/\" target=\"_blank\" rel=\"noopener\"><em><strong>Frederic Borr\u00e0s<\/strong><\/em><\/a>, president d&#8217;honor del Col\u00b7legi d&#8217;Auditors i Censors Jurats de Comptes de Catalunya i acad\u00e8mic de n\u00famero de la RAED.<\/p>\n<p>La confer\u00e8ncia de cloenda va anar a c\u00e0rrec de <a href=\"https:\/\/raed.academy\/ca\/academics\/dr-jose-ramon-calvo-fernandez\/\" target=\"_blank\" rel=\"noopener\"><em><strong>Jos\u00e9 Ram\u00f3n Calvo<\/strong><\/em><\/a>, assessor estrat\u00e8gic del <strong>Barcelona Supercomputing Center-Centre Nacional de Supercomputaci\u00f3<\/strong>, acad\u00e8mic corresponent de la <strong>Reial Acad\u00e8mia de Medicina del Pa\u00eds Basc<\/strong> i acad\u00e8mic de n\u00famero i president de l&#8217;<strong>Institut de Cooperaci\u00f3 Internacional<\/strong> de la RAED, qui va dissertar sobre <strong>&#8220;Un caso para reflexionar: las empresas tabaqueras&#8221;<\/strong>. La presentaci\u00f3 va anar a c\u00e0rrec de <strong>Jos\u00e9 Antonio Gonz\u00e1lez<\/strong>, vicepresident segon del Col\u00b7legi de Censors Jurats de Comptes.<\/p>\n<p>El Col\u00b7legi i l&#8217;Acad\u00e8mia han revalidat el conveni de col\u00b7laboraci\u00f3 signat per ambdues institucions l&#8217;any 2019, que comprometen les dues parts a celebrar actes cient\u00edfics conjunts i a un intercanvi d&#8217;informaci\u00f3, tant interna com externa, i de difusi\u00f3 de les activitats i publicacions d&#8217;inter\u00e8s com\u00fa. L&#8217;acord contempla, aix\u00ed mateix, que tots els acad\u00e8mics de la RAED siguin alhora membres del Col\u00b7legi de Censors Jurats, amb tots els drets que aix\u00f2 comporta. En el marc d&#8217;aquest acord, les dues institucions ja havien celebrat de manera conjunta la<strong> Jornada sobre Informaci\u00f3 no Financera<\/strong>, que tamb\u00e9 va comptar amb la participaci\u00f3 de destacats acad\u00e8mics.<\/p>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 50%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-126520 gallery-columns-2 gallery-size-full'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1100\" height=\"825\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2022\/12\/19-12-2022-jornada-El-auditor-y-la-salud.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/raed.academy\/wp-content\/uploads\/2022\/12\/19-12-2022-jornada-El-auditor-y-la-salud.webp 1100w, https:\/\/raed.academy\/wp-content\/uploads\/2022\/12\/19-12-2022-jornada-El-auditor-y-la-salud-768x576.webp 768w, https:\/\/raed.academy\/wp-content\/uploads\/2022\/12\/19-12-2022-jornada-El-auditor-y-la-salud-1080x810.webp 1080w, https:\/\/raed.academy\/wp-content\/uploads\/2022\/12\/19-12-2022-jornada-El-auditor-y-la-salud-400x300.webp 400w\" sizes=\"(max-width: 1100px) 100vw, 1100px\" \/>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1100\" height=\"825\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2022\/12\/19-12-2022-jornada-El-auditor-y-la-salud-2.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/raed.academy\/wp-content\/uploads\/2022\/12\/19-12-2022-jornada-El-auditor-y-la-salud-2.webp 1100w, https:\/\/raed.academy\/wp-content\/uploads\/2022\/12\/19-12-2022-jornada-El-auditor-y-la-salud-2-768x576.webp 768w, https:\/\/raed.academy\/wp-content\/uploads\/2022\/12\/19-12-2022-jornada-El-auditor-y-la-salud-2-1080x810.webp 1080w, https:\/\/raed.academy\/wp-content\/uploads\/2022\/12\/19-12-2022-jornada-El-auditor-y-la-salud-2-400x300.webp 400w\" sizes=\"(max-width: 1100px) 100vw, 1100px\" \/>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>La RAED i el Col\u00b7legi de Censors Jurats de Comptes de Catalunya organitzen la jornada &#8220;El auditor y la salud m\u00e1s all\u00e1 de la verificaci\u00f3n financiera&#8221;<\/p>\n","protected":false},"author":12,"featured_media":126624,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[455,233],"tags":[],"class_list":["post-126520","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencies-de-la-salut","category-economiques-i-empresarials","et-has-post-format-content","et_post_format-et-post-format-standard"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Auditoria i salut - Reial Acad\u00e8mia Europea de Doctors<\/title>\n<meta name=\"description\" content=\"La RAED i el Col\u00b7legi de Censors Jurats de Comptes de Catalunya organitzen la jornada &quot;El auditor y la salud m\u00e1s all\u00e1 de la verificaci\u00f3n financiera&quot;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/raed.academy\/ca\/auditoria-i-salut\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Auditoria i salut - Reial Acad\u00e8mia Europea de Doctors\" \/>\n<meta property=\"og:description\" content=\"La RAED i el Col\u00b7legi de Censors Jurats de Comptes de Catalunya organitzen la jornada &quot;El auditor y la salud m\u00e1s all\u00e1 de la verificaci\u00f3n financiera&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/raed.academy\/ca\/auditoria-i-salut\/\" \/>\n<meta property=\"og:site_name\" content=\"Reial Acad\u00e8mia Europea de Doctors\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/fb.me\/raed.academy\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-23T12:12:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-28T12:54:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/raed.academy\/wp-content\/uploads\/2022\/12\/Col-legi-de-Censors-Jurats-de-Comptes-de-Catalunya-dst.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"RAED\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@raedacademy\" \/>\n<meta name=\"twitter:site\" content=\"@raedacademy\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"RAED\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/auditoria-i-salut\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/auditoria-i-salut\\\/\"},\"author\":{\"name\":\"RAED\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/person\\\/5a755da80d1d979fd66ba745c8702927\"},\"headline\":\"Auditoria i salut\",\"datePublished\":\"2022-12-23T12:12:48+00:00\",\"dateModified\":\"2022-12-28T12:54:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/auditoria-i-salut\\\/\"},\"wordCount\":662,\"publisher\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/auditoria-i-salut\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Col-legi-de-Censors-Jurats-de-Comptes-de-Catalunya-dst.webp\",\"articleSection\":[\"Ci\u00e8ncies de la salut\",\"Econ\u00f2miques i Empresarials\"],\"inLanguage\":\"ca-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/auditoria-i-salut\\\/\",\"url\":\"https:\\\/\\\/raed.academy\\\/ca\\\/auditoria-i-salut\\\/\",\"name\":\"Auditoria i salut - Reial Acad\u00e8mia Europea de Doctors\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/auditoria-i-salut\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/auditoria-i-salut\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Col-legi-de-Censors-Jurats-de-Comptes-de-Catalunya-dst.webp\",\"datePublished\":\"2022-12-23T12:12:48+00:00\",\"dateModified\":\"2022-12-28T12:54:31+00:00\",\"description\":\"La RAED i el Col\u00b7legi de Censors Jurats de Comptes de Catalunya organitzen la jornada \\\"El auditor y la salud m\u00e1s all\u00e1 de la verificaci\u00f3n financiera\\\"\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/auditoria-i-salut\\\/#breadcrumb\"},\"inLanguage\":\"ca-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/raed.academy\\\/ca\\\/auditoria-i-salut\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/auditoria-i-salut\\\/#primaryimage\",\"url\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Col-legi-de-Censors-Jurats-de-Comptes-de-Catalunya-dst.webp\",\"contentUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Col-legi-de-Censors-Jurats-de-Comptes-de-Catalunya-dst.webp\",\"width\":600,\"height\":360},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/auditoria-i-salut\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/raed.academy\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Auditoria i salut\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/raed.academy\\\/ca\\\/\",\"name\":\"Reial Acad\u00e8mia Europea de Doctors\",\"description\":\"Corporaci\u00f3n de derecho p\u00fablico de car\u00e1cter cient\u00edfico, t\u00e9cnico y art\u00edstico, que tiene por objeto la investigaci\u00f3n, el estudio, el fomento y la extensi\u00f3n del conocimiento en su sentido m\u00e1s amplio\",\"publisher\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/raed.academy\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#organization\",\"name\":\"Real Academia Europea de Doctores\",\"url\":\"https:\\\/\\\/raed.academy\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/cropped-logo_raed.png\",\"contentUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/cropped-logo_raed.png\",\"width\":512,\"height\":512,\"caption\":\"Real Academia Europea de Doctores\"},\"image\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/fb.me\\\/raed.academy\",\"https:\\\/\\\/x.com\\\/raedacademy\",\"https:\\\/\\\/www.instagram.com\\\/raed.academy\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCUYQwW2KrdirNWihxMDObwg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/person\\\/5a755da80d1d979fd66ba745c8702927\",\"name\":\"RAED\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g\",\"caption\":\"RAED\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Auditoria i salut - Reial Acad\u00e8mia Europea de Doctors","description":"La RAED i el Col\u00b7legi de Censors Jurats de Comptes de Catalunya organitzen la jornada \"El auditor y la salud m\u00e1s all\u00e1 de la verificaci\u00f3n financiera\"","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/raed.academy\/ca\/auditoria-i-salut\/","og_locale":"ca_ES","og_type":"article","og_title":"Auditoria i salut - Reial Acad\u00e8mia Europea de Doctors","og_description":"La RAED i el Col\u00b7legi de Censors Jurats de Comptes de Catalunya organitzen la jornada \"El auditor y la salud m\u00e1s all\u00e1 de la verificaci\u00f3n financiera\"","og_url":"https:\/\/raed.academy\/ca\/auditoria-i-salut\/","og_site_name":"Reial Acad\u00e8mia Europea de Doctors","article_publisher":"http:\/\/fb.me\/raed.academy","article_published_time":"2022-12-23T12:12:48+00:00","article_modified_time":"2022-12-28T12:54:31+00:00","og_image":[{"width":600,"height":360,"url":"https:\/\/raed.academy\/wp-content\/uploads\/2022\/12\/Col-legi-de-Censors-Jurats-de-Comptes-de-Catalunya-dst.webp","type":"image\/webp"}],"author":"RAED","twitter_card":"summary_large_image","twitter_creator":"@raedacademy","twitter_site":"@raedacademy","twitter_misc":{"Written by":"RAED","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/raed.academy\/ca\/auditoria-i-salut\/#article","isPartOf":{"@id":"https:\/\/raed.academy\/ca\/auditoria-i-salut\/"},"author":{"name":"RAED","@id":"https:\/\/raed.academy\/ca\/#\/schema\/person\/5a755da80d1d979fd66ba745c8702927"},"headline":"Auditoria i salut","datePublished":"2022-12-23T12:12:48+00:00","dateModified":"2022-12-28T12:54:31+00:00","mainEntityOfPage":{"@id":"https:\/\/raed.academy\/ca\/auditoria-i-salut\/"},"wordCount":662,"publisher":{"@id":"https:\/\/raed.academy\/ca\/#organization"},"image":{"@id":"https:\/\/raed.academy\/ca\/auditoria-i-salut\/#primaryimage"},"thumbnailUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2022\/12\/Col-legi-de-Censors-Jurats-de-Comptes-de-Catalunya-dst.webp","articleSection":["Ci\u00e8ncies de la salut","Econ\u00f2miques i Empresarials"],"inLanguage":"ca-ES"},{"@type":"WebPage","@id":"https:\/\/raed.academy\/ca\/auditoria-i-salut\/","url":"https:\/\/raed.academy\/ca\/auditoria-i-salut\/","name":"Auditoria i salut - Reial Acad\u00e8mia Europea de Doctors","isPartOf":{"@id":"https:\/\/raed.academy\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/raed.academy\/ca\/auditoria-i-salut\/#primaryimage"},"image":{"@id":"https:\/\/raed.academy\/ca\/auditoria-i-salut\/#primaryimage"},"thumbnailUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2022\/12\/Col-legi-de-Censors-Jurats-de-Comptes-de-Catalunya-dst.webp","datePublished":"2022-12-23T12:12:48+00:00","dateModified":"2022-12-28T12:54:31+00:00","description":"La RAED i el Col\u00b7legi de Censors Jurats de Comptes de Catalunya organitzen la jornada \"El auditor y la salud m\u00e1s all\u00e1 de la verificaci\u00f3n financiera\"","breadcrumb":{"@id":"https:\/\/raed.academy\/ca\/auditoria-i-salut\/#breadcrumb"},"inLanguage":"ca-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/raed.academy\/ca\/auditoria-i-salut\/"]}]},{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/raed.academy\/ca\/auditoria-i-salut\/#primaryimage","url":"https:\/\/raed.academy\/wp-content\/uploads\/2022\/12\/Col-legi-de-Censors-Jurats-de-Comptes-de-Catalunya-dst.webp","contentUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2022\/12\/Col-legi-de-Censors-Jurats-de-Comptes-de-Catalunya-dst.webp","width":600,"height":360},{"@type":"BreadcrumbList","@id":"https:\/\/raed.academy\/ca\/auditoria-i-salut\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/raed.academy\/ca\/"},{"@type":"ListItem","position":2,"name":"Auditoria i salut"}]},{"@type":"WebSite","@id":"https:\/\/raed.academy\/ca\/#website","url":"https:\/\/raed.academy\/ca\/","name":"Reial Acad\u00e8mia Europea de Doctors","description":"Corporaci\u00f3n de derecho p\u00fablico de car\u00e1cter cient\u00edfico, t\u00e9cnico y art\u00edstico, que tiene por objeto la investigaci\u00f3n, el estudio, el fomento y la extensi\u00f3n del conocimiento en su sentido m\u00e1s amplio","publisher":{"@id":"https:\/\/raed.academy\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/raed.academy\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca-ES"},{"@type":"Organization","@id":"https:\/\/raed.academy\/ca\/#organization","name":"Real Academia Europea de Doctores","url":"https:\/\/raed.academy\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/raed.academy\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/raed.academy\/wp-content\/uploads\/2017\/01\/cropped-logo_raed.png","contentUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2017\/01\/cropped-logo_raed.png","width":512,"height":512,"caption":"Real Academia Europea de Doctores"},"image":{"@id":"https:\/\/raed.academy\/ca\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/fb.me\/raed.academy","https:\/\/x.com\/raedacademy","https:\/\/www.instagram.com\/raed.academy\/","https:\/\/www.youtube.com\/channel\/UCUYQwW2KrdirNWihxMDObwg"]},{"@type":"Person","@id":"https:\/\/raed.academy\/ca\/#\/schema\/person\/5a755da80d1d979fd66ba745c8702927","name":"RAED","image":{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g","caption":"RAED"}}]}},"_links":{"self":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/posts\/126520","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/comments?post=126520"}],"version-history":[{"count":0,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/posts\/126520\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/media\/126624"}],"wp:attachment":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/media?parent=126520"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/categories?post=126520"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/tags?post=126520"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}