{"id":124200,"date":"2022-11-04T06:35:27","date_gmt":"2022-11-04T06:35:27","guid":{"rendered":"https:\/\/raed.academy\/?p=124200"},"modified":"2022-11-07T12:58:18","modified_gmt":"2022-11-07T12:58:18","slug":"la-psiquiatria-al-llarg-de-la-historia-i-la-cultura","status":"publish","type":"post","link":"https:\/\/raed.academy\/ca\/la-psiquiatria-al-llarg-de-la-historia-i-la-cultura\/","title":{"rendered":"La Psiquiatria al llarg de la hist\u00f2ria i la cultura"},"content":{"rendered":"<p><a href=\"https:\/\/raed.academy\/ca\/academics\/dr-leopoldo-ortega-monasterio-gaston\/\" target=\"_blank\" rel=\"noopener\"><strong>Leopoldo Ortega-Monasterio<\/strong><\/a>, doctor en Medicina, va ingressar com a acad\u00e8mic corresponent de la <strong>Reial Acad\u00e8mia Europea de Doctors-Barcelona 1914<\/strong> (RAED), durant una solemne sessi\u00f3 que es va celebrar a la seu de la Reial Corporaci\u00f3 dijous passat, 3 de novembre. L&#8217;acte es va poder seguir tant de forma presencial com en streaming des de la <a href=\"https:\/\/raed.academy\/events\/acto-de-ingreso-como-academico-correspondiente-leopoldo-ortega-monasterio\/\"><strong>web de la RAED<\/strong><\/a>, on es pot visionar. El recipiendari va llegir el discurs d&#8217;ingr\u00e9s <a href=\"https:\/\/raed.academy\/wp-content\/uploads\/2022\/11\/libro-ingreso-Leopoldo-Ortega-Monasterio-La-psiquiatri-ante-la-historia-de-la-cultura_cmpr.pdf\" target=\"_blank\" rel=\"noopener\"><strong>&#8220;La psiquiatr\u00eda ante la historia de la cultura&#8221;<\/strong><\/a>. Li va respondre, en nom de la Reial Acad\u00e8mia, l&#8217;acad\u00e8mica numer\u00e0ria i vicepresidenta de la corporaci\u00f3, <a href=\"https:\/\/raed.academy\/ca\/academics\/dra-maria-dels-angels-calvo-torras\/\" target=\"_blank\" rel=\"noopener\"><em><strong>Maria \u00c0ngels Calvo<\/strong><\/em><\/a>.<\/p>\n<p>Especialista en Psiquiatria i en Medicina Legal i Forense, doctor per la <strong>Universitat de Barcelona<\/strong> i la <strong>Universitat de Lausana<\/strong>\u00a0i professor de la <strong>Universitat Internacional de Catalunya<\/strong>, on dirigeix \u200b\u200bel <strong>M\u00e0ster Oficial de Psicopatologia Legal, Forense i Criminol\u00f2gica<\/strong>, el recipiendari va realitzar durant la seva intervenci\u00f3 un complet rep\u00e0s a la hist\u00f2ria de la Psiquiatria des de l&#8217;Antiguitat Cl\u00e0ssica, l&#8217;Edat Mitjana i els inicis de l&#8217;Edat Moderna fins al Renaixement i la Il\u00b7lustraci\u00f3, destacant la figura de <strong>Ren\u00e9 Descartes<\/strong> i el dualisme cos i \u00e0nima.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-124142\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2022\/11\/Philippe_Pinel_Asilo-de-Paris-para-mujeres-locas-psiquiatria-dmn-publico-dst.webp\" alt=\"\" width=\"600\" height=\"360\" srcset=\"https:\/\/raed.academy\/wp-content\/uploads\/2022\/11\/Philippe_Pinel_Asilo-de-Paris-para-mujeres-locas-psiquiatria-dmn-publico-dst.webp 600w, https:\/\/raed.academy\/wp-content\/uploads\/2022\/11\/Philippe_Pinel_Asilo-de-Paris-para-mujeres-locas-psiquiatria-dmn-publico-dst-440x264.webp 440w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>Endinsant-se a l&#8217;era contempor\u00e0nia, <strong>Ortega-Monasterio<\/strong> va evocar les fites d&#8217;aquesta especialitat durant el Romanticisme i el positivisme del segle XIX, va analitzar la figura de <strong>Karl Jaspers<\/strong> i la fenomenologia a l&#8217;hist\u00f2ric escenari de l&#8217;<strong>Escola de Heidelberg<\/strong>, els deliris i l&#8217;angoixa des de la perspectiva fenomenol\u00f2gica i es va endinsar en l&#8217;an\u00e0lisi existencial, avantsala de la revoluci\u00f3 que va suposar la psicoan\u00e0lisi, que va emparentar culturalment amb el surrealisme, i l&#8217;ap\u00e8ndix del conductisme, que va tenir el seu correlat cultural al realisme. Immers ja al segle XX i la postmodernitat, el nou acad\u00e8mic va analitzar l&#8217;antipsiquiatria a l&#8217;escenari del maig parisenc de 1968, la relaci\u00f3 entre cinema i Psiquiatria, la literatura i la psicopatologia, amb nombrosos i reveladors exemples cl\u00e0ssics i contemporanis, i l&#8217;eclecticisme des de la <strong>Teoria General dels Sistemes<\/strong>, per acabar amb un reconeixement de la Psiquiatria espanyola m\u00e9s recent.<\/p>\n<p>&#8220;Una visi\u00f3 global de la Psiquiatria al llarg de la seva hist\u00f2ria ens porta a considerar que probablement ha estat fins avui l&#8217;especialitat m\u00e8dica m\u00e9s influenciada per la cultura en el sentit m\u00e9s ampli del terme, ja que la Dermatologia, la Nefrologia, o la Pneumologia, o tantes altres disciplines m\u00e8diques, se circumscriuen a un \u00e0mbit som\u00e0tic ben delimitat. Tot i aix\u00f2, en l&#8217;especificitat de la Psiquiatria i la Psicologia Cl\u00ednica, els factors socioculturals graviten d&#8217;una forma m\u00e9s not\u00f2ria que en la resta de mat\u00e8ries m\u00e8diques&#8221;, va assenyalar el recipiendari a les seves conclusions. Aix\u00ed mateix, va considerar, en aquesta relaci\u00f3 en doble sentit, que la Psiquiatria tamb\u00e9 s&#8217;ha interessat per disciplines com l&#8217;evolucionisme per explicar la pres\u00e8ncia d&#8217;alguns trastorns.<\/p>\n<p>Membre de la <strong>Reial Acad\u00e8mia de Medicina de Salamanca<\/strong> i president de la <strong>Societat Espanyola de Psiquiatria Forense<\/strong>, <strong>Ortega-Monasterio<\/strong> va concloure la seva intervenci\u00f3 destacant el valor emp\u00e0tic del psiquiatre i el psic\u00f2leg amb els seus pacients i l&#8217;avan\u00e7ada que aquestes especialitats suposen per a la medicina humanista que ha de marcar el futur m\u00e9s enll\u00e0 dels diagn\u00f2stics i els tractaments a la carta.<\/p>\n<h2><a href=\"https:\/\/raed.academy\/wp-content\/uploads\/2022\/11\/libro-ingreso-Leopoldo-Ortega-Monasterio-La-psiquiatri-ante-la-historia-de-la-cultura_cmpr.pdf\" target=\"_blank\" rel=\"noopener\">Discurs d&#8217;ingr\u00e9s<\/a><\/h2>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-124200 gallery-columns-3 gallery-size-full'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2022\/11\/ingreso-RAED-Dr-Leopoldo-Ortega-Monasterio-05.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/raed.academy\/wp-content\/uploads\/2022\/11\/ingreso-RAED-Dr-Leopoldo-Ortega-Monasterio-05.webp 1200w, https:\/\/raed.academy\/wp-content\/uploads\/2022\/11\/ingreso-RAED-Dr-Leopoldo-Ortega-Monasterio-05-768x512.webp 768w, https:\/\/raed.academy\/wp-content\/uploads\/2022\/11\/ingreso-RAED-Dr-Leopoldo-Ortega-Monasterio-05-1080x720.webp 1080w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"600\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2022\/11\/ingreso-RAED-Dr-Leopoldo-Ortega-Monasterio-01.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/raed.academy\/wp-content\/uploads\/2022\/11\/ingreso-RAED-Dr-Leopoldo-Ortega-Monasterio-01.webp 900w, https:\/\/raed.academy\/wp-content\/uploads\/2022\/11\/ingreso-RAED-Dr-Leopoldo-Ortega-Monasterio-01-768x512.webp 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2022\/11\/ingreso-RAED-Dr-Leopoldo-Ortega-Monasterio-02.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/raed.academy\/wp-content\/uploads\/2022\/11\/ingreso-RAED-Dr-Leopoldo-Ortega-Monasterio-02.webp 800w, https:\/\/raed.academy\/wp-content\/uploads\/2022\/11\/ingreso-RAED-Dr-Leopoldo-Ortega-Monasterio-02-768x512.webp 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2022\/11\/ingreso-RAED-Dr-Leopoldo-Ortega-Monasterio-03-M-Angels-Calvo.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/raed.academy\/wp-content\/uploads\/2022\/11\/ingreso-RAED-Dr-Leopoldo-Ortega-Monasterio-03-M-Angels-Calvo.webp 800w, https:\/\/raed.academy\/wp-content\/uploads\/2022\/11\/ingreso-RAED-Dr-Leopoldo-Ortega-Monasterio-03-M-Angels-Calvo-768x512.webp 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2022\/11\/ingreso-RAED-Dr-Leopoldo-Ortega-Monasterio-04.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/raed.academy\/wp-content\/uploads\/2022\/11\/ingreso-RAED-Dr-Leopoldo-Ortega-Monasterio-04.webp 800w, https:\/\/raed.academy\/wp-content\/uploads\/2022\/11\/ingreso-RAED-Dr-Leopoldo-Ortega-Monasterio-04-768x512.webp 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"970\" height=\"647\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2022\/11\/ingreso-RAED-Dr-Leopoldo-Ortega-Monasterio-06.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/raed.academy\/wp-content\/uploads\/2022\/11\/ingreso-RAED-Dr-Leopoldo-Ortega-Monasterio-06.webp 970w, https:\/\/raed.academy\/wp-content\/uploads\/2022\/11\/ingreso-RAED-Dr-Leopoldo-Ortega-Monasterio-06-768x512.webp 768w\" sizes=\"(max-width: 970px) 100vw, 970px\" \/>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2022\/11\/ingreso-RAED-Dr-Leopoldo-Ortega-Monasterio-07.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/raed.academy\/wp-content\/uploads\/2022\/11\/ingreso-RAED-Dr-Leopoldo-Ortega-Monasterio-07.webp 1024w, https:\/\/raed.academy\/wp-content\/uploads\/2022\/11\/ingreso-RAED-Dr-Leopoldo-Ortega-Monasterio-07-768x512.webp 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2022\/11\/ingreso-RAED-Dr-Leopoldo-Ortega-Monasterio-08.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/raed.academy\/wp-content\/uploads\/2022\/11\/ingreso-RAED-Dr-Leopoldo-Ortega-Monasterio-08.webp 1024w, https:\/\/raed.academy\/wp-content\/uploads\/2022\/11\/ingreso-RAED-Dr-Leopoldo-Ortega-Monasterio-08-768x512.webp 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2022\/11\/ingreso-RAED-Dr-Leopoldo-Ortega-Monasterio-09.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/raed.academy\/wp-content\/uploads\/2022\/11\/ingreso-RAED-Dr-Leopoldo-Ortega-Monasterio-09.webp 1024w, https:\/\/raed.academy\/wp-content\/uploads\/2022\/11\/ingreso-RAED-Dr-Leopoldo-Ortega-Monasterio-09-768x512.webp 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"600\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2022\/11\/ingreso-RAED-Dr-Leopoldo-Ortega-Monasterio-10.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/raed.academy\/wp-content\/uploads\/2022\/11\/ingreso-RAED-Dr-Leopoldo-Ortega-Monasterio-10.webp 900w, https:\/\/raed.academy\/wp-content\/uploads\/2022\/11\/ingreso-RAED-Dr-Leopoldo-Ortega-Monasterio-10-768x512.webp 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2022\/11\/ingreso-RAED-Dr-Leopoldo-Ortega-Monasterio-11.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/raed.academy\/wp-content\/uploads\/2022\/11\/ingreso-RAED-Dr-Leopoldo-Ortega-Monasterio-11.webp 800w, https:\/\/raed.academy\/wp-content\/uploads\/2022\/11\/ingreso-RAED-Dr-Leopoldo-Ortega-Monasterio-11-768x512.webp 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2022\/11\/ingreso-RAED-Dr-Leopoldo-Ortega-Monasterio-13.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/raed.academy\/wp-content\/uploads\/2022\/11\/ingreso-RAED-Dr-Leopoldo-Ortega-Monasterio-13.webp 1200w, https:\/\/raed.academy\/wp-content\/uploads\/2022\/11\/ingreso-RAED-Dr-Leopoldo-Ortega-Monasterio-13-768x512.webp 768w, https:\/\/raed.academy\/wp-content\/uploads\/2022\/11\/ingreso-RAED-Dr-Leopoldo-Ortega-Monasterio-13-1080x720.webp 1080w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n<p><iframe loading=\"lazy\" title=\"Acto de ingreso como Acad\u00e9mico Correspondiente del Dr. Leopoldo Ortega-Monasterio y Gast\u00f3n.\" src=\"https:\/\/www.youtube.com\/embed\/3IGc0tc4r1I\" width=\"1201\" height=\"595\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Leopoldo Ortega-Monasterio repassa, en el seu ingr\u00e9s com a Acad\u00e8mic de la RAED, la hist\u00f2ria de la Psiquiatria des de l&#8217;Antiguitat Cl\u00e0ssica, l&#8217;Edat Mitjana i els inicis de l&#8217;Edat Moderna fins al Renaixement i la Il\u00b7lustraci\u00f3, destacant la figura de Ren\u00e9 Descartes i el dualisme cos i \u00e0nima<\/p>\n","protected":false},"author":12,"featured_media":124242,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[229,455,242,439,213,451],"tags":[475],"class_list":["post-124200","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-art","category-ciencies-de-la-salut","category-categ-historia","category-literatura-ca","category-medicina-i-cirurgia","category-psicologia-ca","tag-ingressos-academics","et-has-post-format-content","et_post_format-et-post-format-standard"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Psiquiatria al llarg de la hist\u00f2ria i la cultura - Reial Acad\u00e8mia Europea de Doctors<\/title>\n<meta name=\"description\" content=\"Leopoldo Ortega-Monasterio repassa, en el seu ingr\u00e9s a la RAED, la hist\u00f2ria de la Psiquiatria des de l&#039;Antiguitat Cl\u00e0ssica\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/raed.academy\/ca\/la-psiquiatria-al-llarg-de-la-historia-i-la-cultura\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Psiquiatria al llarg de la hist\u00f2ria i la cultura - Reial Acad\u00e8mia Europea de Doctors\" \/>\n<meta property=\"og:description\" content=\"Leopoldo Ortega-Monasterio repassa, en el seu ingr\u00e9s a la RAED, la hist\u00f2ria de la Psiquiatria des de l&#039;Antiguitat Cl\u00e0ssica\" \/>\n<meta property=\"og:url\" content=\"https:\/\/raed.academy\/ca\/la-psiquiatria-al-llarg-de-la-historia-i-la-cultura\/\" \/>\n<meta property=\"og:site_name\" content=\"Reial Acad\u00e8mia Europea de Doctors\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/fb.me\/raed.academy\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-04T06:35:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-07T12:58:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/raed.academy\/wp-content\/uploads\/2022\/11\/ingreso-RAED-Dr-Leopoldo-Ortega-Monasterio-05.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"RAED\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@raedacademy\" \/>\n<meta name=\"twitter:site\" content=\"@raedacademy\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"RAED\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/la-psiquiatria-al-llarg-de-la-historia-i-la-cultura\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/la-psiquiatria-al-llarg-de-la-historia-i-la-cultura\\\/\"},\"author\":{\"name\":\"RAED\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/person\\\/5a755da80d1d979fd66ba745c8702927\"},\"headline\":\"La Psiquiatria al llarg de la hist\u00f2ria i la cultura\",\"datePublished\":\"2022-11-04T06:35:27+00:00\",\"dateModified\":\"2022-11-07T12:58:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/la-psiquiatria-al-llarg-de-la-historia-i-la-cultura\\\/\"},\"wordCount\":589,\"publisher\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/la-psiquiatria-al-llarg-de-la-historia-i-la-cultura\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/ingreso-RAED-Dr-Leopoldo-Ortega-Monasterio-05.webp\",\"keywords\":[\"Ingressos acad\u00e8mics\"],\"articleSection\":[\"Art\",\"Ci\u00e8ncies de la salut\",\"Hist\u00f2ria\",\"Literatura\",\"Medicina i cirurgia\",\"Psicologia\"],\"inLanguage\":\"ca-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/la-psiquiatria-al-llarg-de-la-historia-i-la-cultura\\\/\",\"url\":\"https:\\\/\\\/raed.academy\\\/ca\\\/la-psiquiatria-al-llarg-de-la-historia-i-la-cultura\\\/\",\"name\":\"La Psiquiatria al llarg de la hist\u00f2ria i la cultura - Reial Acad\u00e8mia Europea de Doctors\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/la-psiquiatria-al-llarg-de-la-historia-i-la-cultura\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/la-psiquiatria-al-llarg-de-la-historia-i-la-cultura\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/ingreso-RAED-Dr-Leopoldo-Ortega-Monasterio-05.webp\",\"datePublished\":\"2022-11-04T06:35:27+00:00\",\"dateModified\":\"2022-11-07T12:58:18+00:00\",\"description\":\"Leopoldo Ortega-Monasterio repassa, en el seu ingr\u00e9s a la RAED, la hist\u00f2ria de la Psiquiatria des de l'Antiguitat Cl\u00e0ssica\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/la-psiquiatria-al-llarg-de-la-historia-i-la-cultura\\\/#breadcrumb\"},\"inLanguage\":\"ca-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/raed.academy\\\/ca\\\/la-psiquiatria-al-llarg-de-la-historia-i-la-cultura\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/la-psiquiatria-al-llarg-de-la-historia-i-la-cultura\\\/#primaryimage\",\"url\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/ingreso-RAED-Dr-Leopoldo-Ortega-Monasterio-05.webp\",\"contentUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/ingreso-RAED-Dr-Leopoldo-Ortega-Monasterio-05.webp\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/la-psiquiatria-al-llarg-de-la-historia-i-la-cultura\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/raed.academy\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Psiquiatria al llarg de la hist\u00f2ria i la cultura\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/raed.academy\\\/ca\\\/\",\"name\":\"Reial Acad\u00e8mia Europea de Doctors\",\"description\":\"Corporaci\u00f3n de derecho p\u00fablico de car\u00e1cter cient\u00edfico, t\u00e9cnico y art\u00edstico, que tiene por objeto la investigaci\u00f3n, el estudio, el fomento y la extensi\u00f3n del conocimiento en su sentido m\u00e1s amplio\",\"publisher\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/raed.academy\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#organization\",\"name\":\"Real Academia Europea de Doctores\",\"url\":\"https:\\\/\\\/raed.academy\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/cropped-logo_raed.png\",\"contentUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/cropped-logo_raed.png\",\"width\":512,\"height\":512,\"caption\":\"Real Academia Europea de Doctores\"},\"image\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/fb.me\\\/raed.academy\",\"https:\\\/\\\/x.com\\\/raedacademy\",\"https:\\\/\\\/www.instagram.com\\\/raed.academy\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCUYQwW2KrdirNWihxMDObwg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/person\\\/5a755da80d1d979fd66ba745c8702927\",\"name\":\"RAED\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g\",\"caption\":\"RAED\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Psiquiatria al llarg de la hist\u00f2ria i la cultura - Reial Acad\u00e8mia Europea de Doctors","description":"Leopoldo Ortega-Monasterio repassa, en el seu ingr\u00e9s a la RAED, la hist\u00f2ria de la Psiquiatria des de l'Antiguitat Cl\u00e0ssica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/raed.academy\/ca\/la-psiquiatria-al-llarg-de-la-historia-i-la-cultura\/","og_locale":"ca_ES","og_type":"article","og_title":"La Psiquiatria al llarg de la hist\u00f2ria i la cultura - Reial Acad\u00e8mia Europea de Doctors","og_description":"Leopoldo Ortega-Monasterio repassa, en el seu ingr\u00e9s a la RAED, la hist\u00f2ria de la Psiquiatria des de l'Antiguitat Cl\u00e0ssica","og_url":"https:\/\/raed.academy\/ca\/la-psiquiatria-al-llarg-de-la-historia-i-la-cultura\/","og_site_name":"Reial Acad\u00e8mia Europea de Doctors","article_publisher":"http:\/\/fb.me\/raed.academy","article_published_time":"2022-11-04T06:35:27+00:00","article_modified_time":"2022-11-07T12:58:18+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/raed.academy\/wp-content\/uploads\/2022\/11\/ingreso-RAED-Dr-Leopoldo-Ortega-Monasterio-05.webp","type":"image\/webp"}],"author":"RAED","twitter_card":"summary_large_image","twitter_creator":"@raedacademy","twitter_site":"@raedacademy","twitter_misc":{"Written by":"RAED","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/raed.academy\/ca\/la-psiquiatria-al-llarg-de-la-historia-i-la-cultura\/#article","isPartOf":{"@id":"https:\/\/raed.academy\/ca\/la-psiquiatria-al-llarg-de-la-historia-i-la-cultura\/"},"author":{"name":"RAED","@id":"https:\/\/raed.academy\/ca\/#\/schema\/person\/5a755da80d1d979fd66ba745c8702927"},"headline":"La Psiquiatria al llarg de la hist\u00f2ria i la cultura","datePublished":"2022-11-04T06:35:27+00:00","dateModified":"2022-11-07T12:58:18+00:00","mainEntityOfPage":{"@id":"https:\/\/raed.academy\/ca\/la-psiquiatria-al-llarg-de-la-historia-i-la-cultura\/"},"wordCount":589,"publisher":{"@id":"https:\/\/raed.academy\/ca\/#organization"},"image":{"@id":"https:\/\/raed.academy\/ca\/la-psiquiatria-al-llarg-de-la-historia-i-la-cultura\/#primaryimage"},"thumbnailUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2022\/11\/ingreso-RAED-Dr-Leopoldo-Ortega-Monasterio-05.webp","keywords":["Ingressos acad\u00e8mics"],"articleSection":["Art","Ci\u00e8ncies de la salut","Hist\u00f2ria","Literatura","Medicina i cirurgia","Psicologia"],"inLanguage":"ca-ES"},{"@type":"WebPage","@id":"https:\/\/raed.academy\/ca\/la-psiquiatria-al-llarg-de-la-historia-i-la-cultura\/","url":"https:\/\/raed.academy\/ca\/la-psiquiatria-al-llarg-de-la-historia-i-la-cultura\/","name":"La Psiquiatria al llarg de la hist\u00f2ria i la cultura - Reial Acad\u00e8mia Europea de Doctors","isPartOf":{"@id":"https:\/\/raed.academy\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/raed.academy\/ca\/la-psiquiatria-al-llarg-de-la-historia-i-la-cultura\/#primaryimage"},"image":{"@id":"https:\/\/raed.academy\/ca\/la-psiquiatria-al-llarg-de-la-historia-i-la-cultura\/#primaryimage"},"thumbnailUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2022\/11\/ingreso-RAED-Dr-Leopoldo-Ortega-Monasterio-05.webp","datePublished":"2022-11-04T06:35:27+00:00","dateModified":"2022-11-07T12:58:18+00:00","description":"Leopoldo Ortega-Monasterio repassa, en el seu ingr\u00e9s a la RAED, la hist\u00f2ria de la Psiquiatria des de l'Antiguitat Cl\u00e0ssica","breadcrumb":{"@id":"https:\/\/raed.academy\/ca\/la-psiquiatria-al-llarg-de-la-historia-i-la-cultura\/#breadcrumb"},"inLanguage":"ca-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/raed.academy\/ca\/la-psiquiatria-al-llarg-de-la-historia-i-la-cultura\/"]}]},{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/raed.academy\/ca\/la-psiquiatria-al-llarg-de-la-historia-i-la-cultura\/#primaryimage","url":"https:\/\/raed.academy\/wp-content\/uploads\/2022\/11\/ingreso-RAED-Dr-Leopoldo-Ortega-Monasterio-05.webp","contentUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2022\/11\/ingreso-RAED-Dr-Leopoldo-Ortega-Monasterio-05.webp","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/raed.academy\/ca\/la-psiquiatria-al-llarg-de-la-historia-i-la-cultura\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/raed.academy\/ca\/"},{"@type":"ListItem","position":2,"name":"La Psiquiatria al llarg de la hist\u00f2ria i la cultura"}]},{"@type":"WebSite","@id":"https:\/\/raed.academy\/ca\/#website","url":"https:\/\/raed.academy\/ca\/","name":"Reial Acad\u00e8mia Europea de Doctors","description":"Corporaci\u00f3n de derecho p\u00fablico de car\u00e1cter cient\u00edfico, t\u00e9cnico y art\u00edstico, que tiene por objeto la investigaci\u00f3n, el estudio, el fomento y la extensi\u00f3n del conocimiento en su sentido m\u00e1s amplio","publisher":{"@id":"https:\/\/raed.academy\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/raed.academy\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca-ES"},{"@type":"Organization","@id":"https:\/\/raed.academy\/ca\/#organization","name":"Real Academia Europea de Doctores","url":"https:\/\/raed.academy\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/raed.academy\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/raed.academy\/wp-content\/uploads\/2017\/01\/cropped-logo_raed.png","contentUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2017\/01\/cropped-logo_raed.png","width":512,"height":512,"caption":"Real Academia Europea de Doctores"},"image":{"@id":"https:\/\/raed.academy\/ca\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/fb.me\/raed.academy","https:\/\/x.com\/raedacademy","https:\/\/www.instagram.com\/raed.academy\/","https:\/\/www.youtube.com\/channel\/UCUYQwW2KrdirNWihxMDObwg"]},{"@type":"Person","@id":"https:\/\/raed.academy\/ca\/#\/schema\/person\/5a755da80d1d979fd66ba745c8702927","name":"RAED","image":{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g","caption":"RAED"}}]}},"_links":{"self":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/posts\/124200","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/comments?post=124200"}],"version-history":[{"count":0,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/posts\/124200\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/media\/124242"}],"wp:attachment":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/media?parent=124200"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/categories?post=124200"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/tags?post=124200"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}