{"id":122198,"date":"2022-09-18T23:54:32","date_gmt":"2022-09-18T23:54:32","guid":{"rendered":"https:\/\/raed.academy\/?p=122198"},"modified":"2022-09-22T16:06:01","modified_gmt":"2022-09-22T16:06:01","slug":"dona-i-salut-mental","status":"publish","type":"post","link":"https:\/\/raed.academy\/ca\/dona-i-salut-mental\/","title":{"rendered":"Dona i salut mental"},"content":{"rendered":"<div id=\"attachment_122462\" style=\"width: 240px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-122462\" class=\"wp-image-122462\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2022\/09\/Paula-Plaza-Moreno.webp\" alt=\"Paula Plaza Moreno\" width=\"230\" height=\"410\" aria-describedby=\"caption-attachment-122462\" \/><p id=\"caption-attachment-122462\" class=\"wp-caption-text\">Dra. Paula Plaza<\/p><\/div>\n<p><strong>Paula Plaza<\/strong>, il\u00b7lustradora cient\u00edfica i acad\u00e8mica de n\u00famero electa de la <strong>Reial Acad\u00e8mia Europea de Doctors-Barcelona 1914<\/strong> (RAED), participar\u00e0 els propers 6 i 7 d&#8217;octubre al cicle <strong>&#8220;Mujeres, sufrimiento ps\u00edquico y suicidio, una mirada feminista&#8221;<\/strong>, que celebrar\u00e0 l&#8217;<strong>Institut Canari d&#8217;Igualtat<\/strong> a l&#8217;<strong>Hotel Cristina by Tigotan<\/strong> de Las Palmas de Gran Can\u00e0ria amb la participaci\u00f3 de professionals i activistes de la salut emocional i psicol\u00f2gica. Les jornades s&#8217;obriran amb un acte d&#8217;inauguraci\u00f3 on participaran <strong>Noem\u00ed Santana<\/strong>, consellera de Drets Socials, Igualtat, Diversitat i Joventut del <strong>Govern de les Can\u00e0ries<\/strong>; <strong>Mar\u00eda del R\u00edo<\/strong>, presidenta de la <strong>Comissi\u00f3 de Drets Socials, Igualtat, Diversitat i Joventut<\/strong> del <strong>Parlament de les Can\u00e0ries<\/strong>, i <strong>Kika Fumero<\/strong>, directora de l&#8217;Institut.<\/p>\n<p>&#8220;Amb aquestes jornades, el que pretenem \u00e9s generar un espai de debat, de reflexi\u00f3 i d&#8217;aprenentatge. Un espai on les principals protagonistes seran les activistes, les entitats, les artistes, les investigadores i aquells col\u00b7lectius socials que busquen i lluiten per un canvi de paradigma en la salut mental. Amb aquesta trobada, des de l&#8217;Institut Canari d&#8217;Igualtat volem abordar i apropar-nos a un concepte integral de la salut mental que tingui en compte i que valori tots aquells factors que intervenen en el desenvolupament, el manteniment i la precaritzaci\u00f3 de la vida, que posi el focus a les cures i en el suport a la col\u00b7lectivitat sense exclusions&#8221;, va assenyalar <strong>Fumero<\/strong> a la presentaci\u00f3 de l&#8217;esdeveniment.<\/p>\n<p>El cicle en si s&#8217;obrir\u00e0 amb la intervenci\u00f3 de <strong>Mar\u00eda Asunci\u00f3n Gonz\u00e1lez de Ch\u00e1vez<\/strong>, que presentar\u00e0 el treball <strong>&#8220;Modelos de feminidad e ideal maternal: sus consecuencias en la salud f\u00edsico-ps\u00edquica de las mujeres&#8221;<\/strong>, i el debat <strong>&#8220;Asociaciones y colectivos en la salud mental&#8221;<\/strong>, que comptar\u00e0 amb la participaci\u00f3 d&#8217;<strong>Eva Roncero<\/strong>, de l&#8217;<strong>Associaci\u00f3 Mejorana<\/strong>; <strong>Carmen Agrafojo Betancor<\/strong>, de l&#8217;<strong>Associaci\u00f3 Bipolar de Las Palmas<\/strong>; <strong>F\u00e1tima Masoud Salazar<\/strong>, d&#8217;<strong>Orgullo Loco<\/strong>, i <strong>Viviana Carmona<\/strong>, de l&#8217;<strong>Associaci\u00f3 ActivaMent<\/strong>. El seguir\u00e0 la presentaci\u00f3 del monogr\u00e0fic <strong>&#8220;Locura&#8221;<\/strong>, a c\u00e0rrec d&#8217;<strong>Andrea Momoito<\/strong>, i de la taula rodona <strong>&#8220;\u00bfD\u00f3nde acudir?&#8221;<\/strong>, amb <strong>Pilar Aparicio Azc\u00e1rraga<\/strong>, del <strong>Tel\u00e8fon a l&#8217;Atenci\u00f3 a la Conducta Su\u00efcida 024<\/strong>; <strong>Pilar \u00c1lamo<\/strong>, d&#8217;<strong>Atelsam<\/strong>; <strong>Natalia Gonz\u00e1lez Brito<\/strong>, coordinadora de Salut Mental de Can\u00e0ries, i<strong> Calixto Herrera<\/strong>, del <strong>Projecte Erugues i Papallones de Colors<\/strong> de la <strong>Conselleria d&#8217;Educaci\u00f3<\/strong> del Govern canari.<\/p>\n<p><strong>Dolors L\u00f3pez Aliaga<\/strong> presentar\u00e0 l&#8217;estudi <strong>&#8220;La igualdad como factor de protecci\u00f3n en salud mental&#8221;<\/strong> i<strong> Itxaso Gardoki<\/strong>, el treball <strong>&#8220;Gesti\u00f3n colectiva del malestar&#8221;<\/strong>. El debat <strong>&#8220;Activistas en primera persona y cuidados&#8221;<\/strong> estar\u00e0 protagonitzat per <strong>Beatriz Gimeno<\/strong>, <strong>Patricia Rey<\/strong> i <strong>Cristina Mart\u00edn<\/strong>, i <strong>Mar\u00eda Castrej\u00f3n<\/strong> presentar\u00e0 l&#8217;acte po\u00e8tic <strong>&#8220;Cuando todos los d\u00edas son mi\u00e9rcoles&#8221;<\/strong>. Les jornades conclouran amb la representaci\u00f3 de l&#8217;obra teatral<strong> &#8220;Sacudida&#8221;<\/strong>, a c\u00e0rrec de la companyia <strong>La Rueda Teatro Social<\/strong>. La producci\u00f3 compta amb l&#8217;impuls de la <strong>Confederaci\u00f3 de Salut Mental d&#8217;Espanya<\/strong>.<\/p>\n<h2><a href=\"https:\/\/tribunaevents.com\/inscripciones\/eventos\/jornadas-sobre-mujeres-sufrimiento-psiquico-y-suicidio\/\" target=\"_blank\" rel=\"noopener\">Inscripci\u00f3<\/a><\/h2>\n","protected":false},"excerpt":{"rendered":"<p>Cicle &#8220;Dones, patiment ps\u00edquic i su\u00efcidi, una mirada feminista&#8221;, propers 6 i 7 d&#8217;octubre a Las Palmas de Gran Can\u00e0ria, amb la participaci\u00f3 de professionals i activistes de la salut emocional i psicol\u00f2gica<\/p>\n","protected":false},"author":12,"featured_media":122469,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[455,213,451],"tags":[],"class_list":["post-122198","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencies-de-la-salut","category-medicina-i-cirurgia","category-psicologia-ca","et-has-post-format-content","et_post_format-et-post-format-standard"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dona i salut mental - Reial Acad\u00e8mia Europea de Doctors<\/title>\n<meta name=\"description\" content=\"Cicle &quot;Dones, patiment ps\u00edquic i su\u00efcidi, una mirada feminista&quot;, propers 6 i 7 d&#039;octubre a Las Palmas de Gran Can\u00e0ria, amb la participaci\u00f3 de professionals i activistes de la salut emocional i psicol\u00f2gica\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/raed.academy\/ca\/dona-i-salut-mental\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dona i salut mental - Reial Acad\u00e8mia Europea de Doctors\" \/>\n<meta property=\"og:description\" content=\"Cicle &quot;Dones, patiment ps\u00edquic i su\u00efcidi, una mirada feminista&quot;, propers 6 i 7 d&#039;octubre a Las Palmas de Gran Can\u00e0ria, amb la participaci\u00f3 de professionals i activistes de la salut emocional i psicol\u00f2gica\" \/>\n<meta property=\"og:url\" content=\"https:\/\/raed.academy\/ca\/dona-i-salut-mental\/\" \/>\n<meta property=\"og:site_name\" content=\"Reial Acad\u00e8mia Europea de Doctors\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/fb.me\/raed.academy\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-18T23:54:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-22T16:06:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/raed.academy\/wp-content\/uploads\/2022\/09\/sesion-Mujeres-sufrimiento-psiquico-y-suicidio-una-mirada-feminista.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"RAED\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@raedacademy\" \/>\n<meta name=\"twitter:site\" content=\"@raedacademy\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"RAED\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/dona-i-salut-mental\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/dona-i-salut-mental\\\/\"},\"author\":{\"name\":\"RAED\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/person\\\/5a755da80d1d979fd66ba745c8702927\"},\"headline\":\"Dona i salut mental\",\"datePublished\":\"2022-09-18T23:54:32+00:00\",\"dateModified\":\"2022-09-22T16:06:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/dona-i-salut-mental\\\/\"},\"wordCount\":521,\"publisher\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/dona-i-salut-mental\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/sesion-Mujeres-sufrimiento-psiquico-y-suicidio-una-mirada-feminista.webp\",\"articleSection\":[\"Ci\u00e8ncies de la salut\",\"Medicina i cirurgia\",\"Psicologia\"],\"inLanguage\":\"ca-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/dona-i-salut-mental\\\/\",\"url\":\"https:\\\/\\\/raed.academy\\\/ca\\\/dona-i-salut-mental\\\/\",\"name\":\"Dona i salut mental - Reial Acad\u00e8mia Europea de Doctors\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/dona-i-salut-mental\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/dona-i-salut-mental\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/sesion-Mujeres-sufrimiento-psiquico-y-suicidio-una-mirada-feminista.webp\",\"datePublished\":\"2022-09-18T23:54:32+00:00\",\"dateModified\":\"2022-09-22T16:06:01+00:00\",\"description\":\"Cicle \\\"Dones, patiment ps\u00edquic i su\u00efcidi, una mirada feminista\\\", propers 6 i 7 d'octubre a Las Palmas de Gran Can\u00e0ria, amb la participaci\u00f3 de professionals i activistes de la salut emocional i psicol\u00f2gica\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/dona-i-salut-mental\\\/#breadcrumb\"},\"inLanguage\":\"ca-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/raed.academy\\\/ca\\\/dona-i-salut-mental\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/dona-i-salut-mental\\\/#primaryimage\",\"url\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/sesion-Mujeres-sufrimiento-psiquico-y-suicidio-una-mirada-feminista.webp\",\"contentUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/sesion-Mujeres-sufrimiento-psiquico-y-suicidio-una-mirada-feminista.webp\",\"width\":500,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/dona-i-salut-mental\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/raed.academy\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dona i salut mental\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/raed.academy\\\/ca\\\/\",\"name\":\"Reial Acad\u00e8mia Europea de Doctors\",\"description\":\"Corporaci\u00f3n de derecho p\u00fablico de car\u00e1cter cient\u00edfico, t\u00e9cnico y art\u00edstico, que tiene por objeto la investigaci\u00f3n, el estudio, el fomento y la extensi\u00f3n del conocimiento en su sentido m\u00e1s amplio\",\"publisher\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/raed.academy\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#organization\",\"name\":\"Real Academia Europea de Doctores\",\"url\":\"https:\\\/\\\/raed.academy\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/cropped-logo_raed.png\",\"contentUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/cropped-logo_raed.png\",\"width\":512,\"height\":512,\"caption\":\"Real Academia Europea de Doctores\"},\"image\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/fb.me\\\/raed.academy\",\"https:\\\/\\\/x.com\\\/raedacademy\",\"https:\\\/\\\/www.instagram.com\\\/raed.academy\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCUYQwW2KrdirNWihxMDObwg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/person\\\/5a755da80d1d979fd66ba745c8702927\",\"name\":\"RAED\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g\",\"caption\":\"RAED\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dona i salut mental - Reial Acad\u00e8mia Europea de Doctors","description":"Cicle \"Dones, patiment ps\u00edquic i su\u00efcidi, una mirada feminista\", propers 6 i 7 d'octubre a Las Palmas de Gran Can\u00e0ria, amb la participaci\u00f3 de professionals i activistes de la salut emocional i psicol\u00f2gica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/raed.academy\/ca\/dona-i-salut-mental\/","og_locale":"ca_ES","og_type":"article","og_title":"Dona i salut mental - Reial Acad\u00e8mia Europea de Doctors","og_description":"Cicle \"Dones, patiment ps\u00edquic i su\u00efcidi, una mirada feminista\", propers 6 i 7 d'octubre a Las Palmas de Gran Can\u00e0ria, amb la participaci\u00f3 de professionals i activistes de la salut emocional i psicol\u00f2gica","og_url":"https:\/\/raed.academy\/ca\/dona-i-salut-mental\/","og_site_name":"Reial Acad\u00e8mia Europea de Doctors","article_publisher":"http:\/\/fb.me\/raed.academy","article_published_time":"2022-09-18T23:54:32+00:00","article_modified_time":"2022-09-22T16:06:01+00:00","og_image":[{"width":500,"height":300,"url":"https:\/\/raed.academy\/wp-content\/uploads\/2022\/09\/sesion-Mujeres-sufrimiento-psiquico-y-suicidio-una-mirada-feminista.webp","type":"image\/webp"}],"author":"RAED","twitter_card":"summary_large_image","twitter_creator":"@raedacademy","twitter_site":"@raedacademy","twitter_misc":{"Written by":"RAED","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/raed.academy\/ca\/dona-i-salut-mental\/#article","isPartOf":{"@id":"https:\/\/raed.academy\/ca\/dona-i-salut-mental\/"},"author":{"name":"RAED","@id":"https:\/\/raed.academy\/ca\/#\/schema\/person\/5a755da80d1d979fd66ba745c8702927"},"headline":"Dona i salut mental","datePublished":"2022-09-18T23:54:32+00:00","dateModified":"2022-09-22T16:06:01+00:00","mainEntityOfPage":{"@id":"https:\/\/raed.academy\/ca\/dona-i-salut-mental\/"},"wordCount":521,"publisher":{"@id":"https:\/\/raed.academy\/ca\/#organization"},"image":{"@id":"https:\/\/raed.academy\/ca\/dona-i-salut-mental\/#primaryimage"},"thumbnailUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2022\/09\/sesion-Mujeres-sufrimiento-psiquico-y-suicidio-una-mirada-feminista.webp","articleSection":["Ci\u00e8ncies de la salut","Medicina i cirurgia","Psicologia"],"inLanguage":"ca-ES"},{"@type":"WebPage","@id":"https:\/\/raed.academy\/ca\/dona-i-salut-mental\/","url":"https:\/\/raed.academy\/ca\/dona-i-salut-mental\/","name":"Dona i salut mental - Reial Acad\u00e8mia Europea de Doctors","isPartOf":{"@id":"https:\/\/raed.academy\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/raed.academy\/ca\/dona-i-salut-mental\/#primaryimage"},"image":{"@id":"https:\/\/raed.academy\/ca\/dona-i-salut-mental\/#primaryimage"},"thumbnailUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2022\/09\/sesion-Mujeres-sufrimiento-psiquico-y-suicidio-una-mirada-feminista.webp","datePublished":"2022-09-18T23:54:32+00:00","dateModified":"2022-09-22T16:06:01+00:00","description":"Cicle \"Dones, patiment ps\u00edquic i su\u00efcidi, una mirada feminista\", propers 6 i 7 d'octubre a Las Palmas de Gran Can\u00e0ria, amb la participaci\u00f3 de professionals i activistes de la salut emocional i psicol\u00f2gica","breadcrumb":{"@id":"https:\/\/raed.academy\/ca\/dona-i-salut-mental\/#breadcrumb"},"inLanguage":"ca-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/raed.academy\/ca\/dona-i-salut-mental\/"]}]},{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/raed.academy\/ca\/dona-i-salut-mental\/#primaryimage","url":"https:\/\/raed.academy\/wp-content\/uploads\/2022\/09\/sesion-Mujeres-sufrimiento-psiquico-y-suicidio-una-mirada-feminista.webp","contentUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2022\/09\/sesion-Mujeres-sufrimiento-psiquico-y-suicidio-una-mirada-feminista.webp","width":500,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/raed.academy\/ca\/dona-i-salut-mental\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/raed.academy\/ca\/"},{"@type":"ListItem","position":2,"name":"Dona i salut mental"}]},{"@type":"WebSite","@id":"https:\/\/raed.academy\/ca\/#website","url":"https:\/\/raed.academy\/ca\/","name":"Reial Acad\u00e8mia Europea de Doctors","description":"Corporaci\u00f3n de derecho p\u00fablico de car\u00e1cter cient\u00edfico, t\u00e9cnico y art\u00edstico, que tiene por objeto la investigaci\u00f3n, el estudio, el fomento y la extensi\u00f3n del conocimiento en su sentido m\u00e1s amplio","publisher":{"@id":"https:\/\/raed.academy\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/raed.academy\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca-ES"},{"@type":"Organization","@id":"https:\/\/raed.academy\/ca\/#organization","name":"Real Academia Europea de Doctores","url":"https:\/\/raed.academy\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/raed.academy\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/raed.academy\/wp-content\/uploads\/2017\/01\/cropped-logo_raed.png","contentUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2017\/01\/cropped-logo_raed.png","width":512,"height":512,"caption":"Real Academia Europea de Doctores"},"image":{"@id":"https:\/\/raed.academy\/ca\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/fb.me\/raed.academy","https:\/\/x.com\/raedacademy","https:\/\/www.instagram.com\/raed.academy\/","https:\/\/www.youtube.com\/channel\/UCUYQwW2KrdirNWihxMDObwg"]},{"@type":"Person","@id":"https:\/\/raed.academy\/ca\/#\/schema\/person\/5a755da80d1d979fd66ba745c8702927","name":"RAED","image":{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g","caption":"RAED"}}]}},"_links":{"self":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/posts\/122198","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/comments?post=122198"}],"version-history":[{"count":0,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/posts\/122198\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/media\/122469"}],"wp:attachment":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/media?parent=122198"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/categories?post=122198"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/tags?post=122198"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}