{"id":120217,"date":"2022-06-30T06:30:24","date_gmt":"2022-06-30T06:30:24","guid":{"rendered":"https:\/\/raed.academy\/?p=120217"},"modified":"2022-07-05T09:02:54","modified_gmt":"2022-07-05T09:02:54","slug":"bon-veinatge","status":"publish","type":"post","link":"https:\/\/raed.academy\/ca\/bon-veinatge\/","title":{"rendered":"El nou marc de relacions bilaterals entre Espanya i el Marroc"},"content":{"rendered":"<div id=\"attachment_119603\" style=\"width: 410px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-119603\" class=\"wp-image-119603\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2022\/06\/08-06-2022-Presentacion-del-proyecto-2022-Retos-Vitales-para-una-nueva-era-16.webp\" sizes=\"(max-width: 400px) 100vw, 400px\" srcset=\"https:\/\/raed.academy\/wp-content\/uploads\/2022\/06\/08-06-2022-Presentacion-del-proyecto-2022-Retos-Vitales-para-una-nueva-era-16.webp 700w, https:\/\/raed.academy\/wp-content\/uploads\/2022\/06\/08-06-2022-Presentacion-del-proyecto-2022-Retos-Vitales-para-una-nueva-era-16-627x376.webp 627w, https:\/\/raed.academy\/wp-content\/uploads\/2022\/06\/08-06-2022-Presentacion-del-proyecto-2022-Retos-Vitales-para-una-nueva-era-16-440x264.webp 440w\" alt=\"Dr. Aldo Olcese\" width=\"400\" height=\"240\" aria-describedby=\"caption-attachment-119603\" \/><p id=\"caption-attachment-119603\" class=\"wp-caption-text\">Dr. Aldo Olcese<\/p><\/div>\n<p><a href=\"https:\/\/raed.academy\/ca\/academics\/dr-aldo-olcese-santonja\/\" target=\"_blank\" rel=\"noopener\"><em><strong>Aldo Olcese<\/strong><\/em><\/a>, president de la\u00a0<strong>Fundaci\u00f3n Independente<\/strong> i de l&#8217;<strong>Associaci\u00f3n Nacional Sociedad Civil Ahora<\/strong>, acad\u00e8mic de n\u00famero de la <strong>Reial Acad\u00e8mia de Ci\u00e8ncies Econ\u00f2miques i Financeres<\/strong> i acad\u00e8mic de n\u00famero i vicepresident de la <strong>Reial Acad\u00e8mia Europea de Doctors-Barcelona 1914<\/strong> (RAED), reflexiona en una entrevista concedida al diari <strong>&#8220;El Independiente&#8221;<\/strong> publicada el passat 20 de juny, sobre el nou marc de relacions bilaterals entre Espanya i el Marroc, que segons ell respon en bona part al nou ordre que ha obert la invasi\u00f3 russa d&#8217;Ucra\u00efna i a les obligades relacions de bon ve\u00efnatge que exigeix \u200b\u200bla comunitat internacional.<\/p>\n<p>&#8220;La situaci\u00f3 creada per la guerra d&#8217;Ucra\u00efna ha obligat tots els actors internacionals d&#8217;una certa consist\u00e8ncia, com pot ser Espanya, a definir b\u00e9 els seus posicionaments en relaci\u00f3 amb les aliances dels pa\u00efsos implicats i aix\u00f2 tamb\u00e9 inclou el Marroc i Alg\u00e8ria. Tamb\u00e9 ha ajudat que els Estats Units hagin demanat als seus aliats que aclareixin les seves posicions creuades, i aix\u00f2 tamb\u00e9 explica que Espanya hagi hagut de privilegiar les relacions amb el Marroc a les relacions amb Alg\u00e8ria. Molts pa\u00efsos jugaven fins ara un doble joc, per\u00f2 la guerra ha obligat tothom a tenir clares quines s\u00f3n les cartes amb qu\u00e8 jugar\u00e0&#8221;, argumenta Olcese, de qui la publicaci\u00f3 recorda que \u00e9s el ciutad\u00e0 espanyol m\u00e9s condecorat pel Marroc.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-120513\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2022\/06\/Espana-y-Marruecos-dst.webp\" sizes=\"(max-width: 500px) 100vw, 500px\" srcset=\"https:\/\/raed.academy\/wp-content\/uploads\/2022\/06\/Espana-y-Marruecos-dst.webp 500w, https:\/\/raed.academy\/wp-content\/uploads\/2022\/06\/Espana-y-Marruecos-dst-440x264.webp 440w\" alt=\"\" width=\"500\" height=\"300\" \/>Per a l&#8217;acad\u00e8mic, l&#8217;elecci\u00f3 del Marroc com a aliat al Magrib en detriment de R\u00fassia suposa un encert de la diplom\u00e0cia espanyola, ja que considera Alg\u00e8ria com un aliat de R\u00fassia. Sobre el subministrament de gas, assenyala que no he d&#8217;estar en perill, tot i que el m\u00e9s desitjable seria que no exist\u00eds cap depend\u00e8ncia d&#8217;Alger. En aquest sentit, assenyala que cada cop \u00e9s menor, xifrant la seva depend\u00e8ncia del 80% que havia assolit el 20% actual i albira un nou marc de relacions energ\u00e8tiques entre el Marroc i Espanya enriquidores per a les dues parts. &#8220;Al gas americ\u00e0 regasificat a Espanya i exportat a Europa se li afegir\u00e0 l&#8217;electricitat nuclear produ\u00efda al Marroc i distribu\u00efda a Europa pel cable d&#8217;interconnexi\u00f3 marroquina a la pen\u00ednsula. El binomi energia nuclear i gas de regasificaci\u00f3 per a Europa a trav\u00e9s d&#8217;Espanya ser\u00e0 el principi d&#8217;una independ\u00e8ncia energ\u00e8tica europea fiable sense depend\u00e8ncies de R\u00fassia ni d&#8217;Alg\u00e8ria&#8221;, afirma.<\/p>\n<p>Sobre el conflicte del S\u00e0hara Occidental, Olcese assenyala que la postura que ha mantingut al llarg dels anys d&#8217;Espanya en relaci\u00f3 amb el <strong>Front Polisario<\/strong> no ha condu\u00eft a cap resoluci\u00f3 del conflicte i que el canvi de posicionament empr\u00e8s pel Govern no nom\u00e9s s&#8217;alinea al dels seus principals socis europeus i al dels Estats Units, sin\u00f3 que se situa en el context de soluci\u00f3 pac\u00edfica i negociada que propugna l&#8217;<strong>ONU<\/strong>. &#8220;No puc comprendre b\u00e9, per exemple, com un partit pol\u00edtic com el <strong>Partit Popular<\/strong> pot estar defensant el Front Polisario davant del Marroc en aquests moments. Una organitzaci\u00f3 que encara ha de retre comptes de 315 ciutadans espanyols que van morir a mans dels seus atemptats&#8221;, opina.<\/p>\n<h2><a href=\"https:\/\/www.elindependiente.com\/internacional\/2022\/06\/20\/habla-el-espanol-mas-condecorado-por-marruecos-argelia-no-es-un-ejemplo-para-occidente\/\" target=\"_blank\" rel=\"noopener\">Llegiu l&#8217;entrevista<\/a><\/h2>\n","protected":false},"excerpt":{"rendered":"<p>Aldo Olcese reflexiona sobre el nou marc de relacions bilaterals entre Espanya i el Marroc, que segons ell respon en bona part al nou ordre que ha obert la invasi\u00f3 russa d&#8217;Ucra\u00efna i a les obligades relacions de bon ve\u00efnatge que exigeix la comunitat internacional<\/p>\n","protected":false},"author":12,"featured_media":120514,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[380,225],"tags":[],"class_list":["post-120217","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-conflictes-bellics","category-dret","et-has-post-format-content","et_post_format-et-post-format-standard"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El nou marc de relacions bilaterals entre Espanya i el Marroc - Reial Acad\u00e8mia Europea de Doctors<\/title>\n<meta name=\"description\" content=\"Aldo Olcese, sobre el nou marc de relacions bilaterals entre Espanya i el Marroc, &quot; &quot;respon en bona part al nou ordre que ha obert la invasi\u00f3 russa d&#039;Ucra\u00efna...&quot;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/raed.academy\/ca\/bon-veinatge\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El nou marc de relacions bilaterals entre Espanya i el Marroc - Reial Acad\u00e8mia Europea de Doctors\" \/>\n<meta property=\"og:description\" content=\"Aldo Olcese, sobre el nou marc de relacions bilaterals entre Espanya i el Marroc, &quot; &quot;respon en bona part al nou ordre que ha obert la invasi\u00f3 russa d&#039;Ucra\u00efna...&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/raed.academy\/ca\/bon-veinatge\/\" \/>\n<meta property=\"og:site_name\" content=\"Reial Acad\u00e8mia Europea de Doctors\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/fb.me\/raed.academy\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-30T06:30:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-05T09:02:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/raed.academy\/wp-content\/uploads\/2022\/06\/Espana-y-Marruecos-dst.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"RAED\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@raedacademy\" \/>\n<meta name=\"twitter:site\" content=\"@raedacademy\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"RAED\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/bon-veinatge\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/bon-veinatge\\\/\"},\"author\":{\"name\":\"RAED\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/person\\\/5a755da80d1d979fd66ba745c8702927\"},\"headline\":\"El nou marc de relacions bilaterals entre Espanya i el Marroc\",\"datePublished\":\"2022-06-30T06:30:24+00:00\",\"dateModified\":\"2022-07-05T09:02:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/bon-veinatge\\\/\"},\"wordCount\":570,\"publisher\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/bon-veinatge\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Espana-y-Marruecos-dst.webp\",\"articleSection\":[\"Conflictes b\u00e8l\u00b7lics\",\"Dret\"],\"inLanguage\":\"ca-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/bon-veinatge\\\/\",\"url\":\"https:\\\/\\\/raed.academy\\\/ca\\\/bon-veinatge\\\/\",\"name\":\"El nou marc de relacions bilaterals entre Espanya i el Marroc - Reial Acad\u00e8mia Europea de Doctors\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/bon-veinatge\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/bon-veinatge\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Espana-y-Marruecos-dst.webp\",\"datePublished\":\"2022-06-30T06:30:24+00:00\",\"dateModified\":\"2022-07-05T09:02:54+00:00\",\"description\":\"Aldo Olcese, sobre el nou marc de relacions bilaterals entre Espanya i el Marroc, \\\" \\\"respon en bona part al nou ordre que ha obert la invasi\u00f3 russa d'Ucra\u00efna...\\\"\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/bon-veinatge\\\/#breadcrumb\"},\"inLanguage\":\"ca-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/raed.academy\\\/ca\\\/bon-veinatge\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/bon-veinatge\\\/#primaryimage\",\"url\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Espana-y-Marruecos-dst.webp\",\"contentUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Espana-y-Marruecos-dst.webp\",\"width\":500,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/bon-veinatge\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/raed.academy\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El nou marc de relacions bilaterals entre Espanya i el Marroc\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/raed.academy\\\/ca\\\/\",\"name\":\"Reial Acad\u00e8mia Europea de Doctors\",\"description\":\"Corporaci\u00f3n de derecho p\u00fablico de car\u00e1cter cient\u00edfico, t\u00e9cnico y art\u00edstico, que tiene por objeto la investigaci\u00f3n, el estudio, el fomento y la extensi\u00f3n del conocimiento en su sentido m\u00e1s amplio\",\"publisher\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/raed.academy\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#organization\",\"name\":\"Real Academia Europea de Doctores\",\"url\":\"https:\\\/\\\/raed.academy\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/cropped-logo_raed.png\",\"contentUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/cropped-logo_raed.png\",\"width\":512,\"height\":512,\"caption\":\"Real Academia Europea de Doctores\"},\"image\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/fb.me\\\/raed.academy\",\"https:\\\/\\\/x.com\\\/raedacademy\",\"https:\\\/\\\/www.instagram.com\\\/raed.academy\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCUYQwW2KrdirNWihxMDObwg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/person\\\/5a755da80d1d979fd66ba745c8702927\",\"name\":\"RAED\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g\",\"caption\":\"RAED\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El nou marc de relacions bilaterals entre Espanya i el Marroc - Reial Acad\u00e8mia Europea de Doctors","description":"Aldo Olcese, sobre el nou marc de relacions bilaterals entre Espanya i el Marroc, \" \"respon en bona part al nou ordre que ha obert la invasi\u00f3 russa d'Ucra\u00efna...\"","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/raed.academy\/ca\/bon-veinatge\/","og_locale":"ca_ES","og_type":"article","og_title":"El nou marc de relacions bilaterals entre Espanya i el Marroc - Reial Acad\u00e8mia Europea de Doctors","og_description":"Aldo Olcese, sobre el nou marc de relacions bilaterals entre Espanya i el Marroc, \" \"respon en bona part al nou ordre que ha obert la invasi\u00f3 russa d'Ucra\u00efna...\"","og_url":"https:\/\/raed.academy\/ca\/bon-veinatge\/","og_site_name":"Reial Acad\u00e8mia Europea de Doctors","article_publisher":"http:\/\/fb.me\/raed.academy","article_published_time":"2022-06-30T06:30:24+00:00","article_modified_time":"2022-07-05T09:02:54+00:00","og_image":[{"width":500,"height":300,"url":"https:\/\/raed.academy\/wp-content\/uploads\/2022\/06\/Espana-y-Marruecos-dst.webp","type":"image\/webp"}],"author":"RAED","twitter_card":"summary_large_image","twitter_creator":"@raedacademy","twitter_site":"@raedacademy","twitter_misc":{"Written by":"RAED","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/raed.academy\/ca\/bon-veinatge\/#article","isPartOf":{"@id":"https:\/\/raed.academy\/ca\/bon-veinatge\/"},"author":{"name":"RAED","@id":"https:\/\/raed.academy\/ca\/#\/schema\/person\/5a755da80d1d979fd66ba745c8702927"},"headline":"El nou marc de relacions bilaterals entre Espanya i el Marroc","datePublished":"2022-06-30T06:30:24+00:00","dateModified":"2022-07-05T09:02:54+00:00","mainEntityOfPage":{"@id":"https:\/\/raed.academy\/ca\/bon-veinatge\/"},"wordCount":570,"publisher":{"@id":"https:\/\/raed.academy\/ca\/#organization"},"image":{"@id":"https:\/\/raed.academy\/ca\/bon-veinatge\/#primaryimage"},"thumbnailUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2022\/06\/Espana-y-Marruecos-dst.webp","articleSection":["Conflictes b\u00e8l\u00b7lics","Dret"],"inLanguage":"ca-ES"},{"@type":"WebPage","@id":"https:\/\/raed.academy\/ca\/bon-veinatge\/","url":"https:\/\/raed.academy\/ca\/bon-veinatge\/","name":"El nou marc de relacions bilaterals entre Espanya i el Marroc - Reial Acad\u00e8mia Europea de Doctors","isPartOf":{"@id":"https:\/\/raed.academy\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/raed.academy\/ca\/bon-veinatge\/#primaryimage"},"image":{"@id":"https:\/\/raed.academy\/ca\/bon-veinatge\/#primaryimage"},"thumbnailUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2022\/06\/Espana-y-Marruecos-dst.webp","datePublished":"2022-06-30T06:30:24+00:00","dateModified":"2022-07-05T09:02:54+00:00","description":"Aldo Olcese, sobre el nou marc de relacions bilaterals entre Espanya i el Marroc, \" \"respon en bona part al nou ordre que ha obert la invasi\u00f3 russa d'Ucra\u00efna...\"","breadcrumb":{"@id":"https:\/\/raed.academy\/ca\/bon-veinatge\/#breadcrumb"},"inLanguage":"ca-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/raed.academy\/ca\/bon-veinatge\/"]}]},{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/raed.academy\/ca\/bon-veinatge\/#primaryimage","url":"https:\/\/raed.academy\/wp-content\/uploads\/2022\/06\/Espana-y-Marruecos-dst.webp","contentUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2022\/06\/Espana-y-Marruecos-dst.webp","width":500,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/raed.academy\/ca\/bon-veinatge\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/raed.academy\/ca\/"},{"@type":"ListItem","position":2,"name":"El nou marc de relacions bilaterals entre Espanya i el Marroc"}]},{"@type":"WebSite","@id":"https:\/\/raed.academy\/ca\/#website","url":"https:\/\/raed.academy\/ca\/","name":"Reial Acad\u00e8mia Europea de Doctors","description":"Corporaci\u00f3n de derecho p\u00fablico de car\u00e1cter cient\u00edfico, t\u00e9cnico y art\u00edstico, que tiene por objeto la investigaci\u00f3n, el estudio, el fomento y la extensi\u00f3n del conocimiento en su sentido m\u00e1s amplio","publisher":{"@id":"https:\/\/raed.academy\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/raed.academy\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca-ES"},{"@type":"Organization","@id":"https:\/\/raed.academy\/ca\/#organization","name":"Real Academia Europea de Doctores","url":"https:\/\/raed.academy\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/raed.academy\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/raed.academy\/wp-content\/uploads\/2017\/01\/cropped-logo_raed.png","contentUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2017\/01\/cropped-logo_raed.png","width":512,"height":512,"caption":"Real Academia Europea de Doctores"},"image":{"@id":"https:\/\/raed.academy\/ca\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/fb.me\/raed.academy","https:\/\/x.com\/raedacademy","https:\/\/www.instagram.com\/raed.academy\/","https:\/\/www.youtube.com\/channel\/UCUYQwW2KrdirNWihxMDObwg"]},{"@type":"Person","@id":"https:\/\/raed.academy\/ca\/#\/schema\/person\/5a755da80d1d979fd66ba745c8702927","name":"RAED","image":{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g","caption":"RAED"}}]}},"_links":{"self":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/posts\/120217","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/comments?post=120217"}],"version-history":[{"count":0,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/posts\/120217\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/media\/120514"}],"wp:attachment":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/media?parent=120217"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/categories?post=120217"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/tags?post=120217"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}