{"id":118257,"date":"2022-05-25T10:38:22","date_gmt":"2022-05-25T10:38:22","guid":{"rendered":"https:\/\/raed.academy\/?p=118257"},"modified":"2022-05-26T17:27:25","modified_gmt":"2022-05-26T17:27:25","slug":"el-patrimoni-com-a-valor-compartit","status":"publish","type":"post","link":"https:\/\/raed.academy\/ca\/el-patrimoni-com-a-valor-compartit\/","title":{"rendered":"El patrimoni com a valor compartit"},"content":{"rendered":"<div id=\"attachment_118273\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-118273\" class=\"wp-image-118273 size-full\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2022\/05\/2022-05-12.Reedicion-libro-El-patrimonio-mundial-Ignacio-Buqueras-02.webp\" sizes=\"(max-width: 700px) 100vw, 700px\" srcset=\"https:\/\/raed.academy\/wp-content\/uploads\/2022\/05\/2022-05-12.Reedicion-libro-El-patrimonio-mundial-Ignacio-Buqueras-02.webp 700w, https:\/\/raed.academy\/wp-content\/uploads\/2022\/05\/2022-05-12.Reedicion-libro-El-patrimonio-mundial-Ignacio-Buqueras-02-627x376.webp 627w, https:\/\/raed.academy\/wp-content\/uploads\/2022\/05\/2022-05-12.Reedicion-libro-El-patrimonio-mundial-Ignacio-Buqueras-02-440x264.webp 440w\" alt=\"Reedici\u00f3n del libro El patrimonio mundial de Ignacio Buqueras\" width=\"700\" height=\"420\" aria-describedby=\"caption-attachment-118273\" \/><p id=\"caption-attachment-118273\" class=\"wp-caption-text\">D&#8217;esquerra a dreta: Dr. Xabier A\u00f1overos, Dr. Ignacio Buqueras, Dr. Alfredo Rocafort y Dra. Judith Urbano<\/p><\/div>\n<p><a href=\"https:\/\/raed.academy\/ca\/academics\/dr-ignacio-buqueras-bach\/\" target=\"_blank\" rel=\"noopener\"><em><strong>Ignacio Buqueras<\/strong><\/em><\/a>, president de l&#8217;<strong>Associaci\u00f3 per a la Difusi\u00f3 i Promoci\u00f3 del Patrimoni Espanyol<\/strong>\u00a0i acad\u00e8mic de n\u00famero de la <strong>Reial Acad\u00e8mia Europea de Doctors-Barcelona 1914<\/strong> (RAED), va presentar el passat 12 de maig a la seu de la Reial Acad\u00e8mia la reedici\u00f3 del llibre <strong>&#8220;El Patrimonio Mundial e Inmaterial de Espa\u00f1a&#8221;<\/strong>, impulsat per l&#8217;associaci\u00f3 que presideix. L&#8217;obra \u00e9s fruit de la dedicaci\u00f3 intensa d&#8217;aquesta entitat en anys de treball en defensa i difusi\u00f3 del patrimoni espanyol reconegut per la <strong>Unesco<\/strong>. Publicada per la prestigiosa editorial <strong>McGraw Hill<\/strong>, es tracta de la tercera reedici\u00f3 d&#8217;aquesta obra de refer\u00e8ncia, ampliada i millorada, que l\u00f2gicament inclou el darrer reconeixement, del 2022: el passeig del Prado i el Buen Retiro, paisatge de les arts i les ci\u00e8ncies.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-116130\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2022\/04\/libro-El-patrimonio-mundial-cultural-natural-e-inmaterial-de-Espana-reedicion-2022.webp\" alt=\"\" width=\"370\" height=\"482\" \/>A l&#8217;acte van participar l&#8217;acad\u00e8mic de n\u00famero i president de la <strong>Junta de Govern<\/strong> de la Reial Acad\u00e8mia, <a href=\"https:\/\/raed.academy\/ca\/academics\/dr-alfredo-rocafort-nicolau\/\" target=\"_blank\" rel=\"noopener\"><em><strong>Alfredo Rocafort<\/strong><\/em><\/a>, que va agrair a <strong>Buqueras<\/strong> tant la seva tasca a la instituci\u00f3 com la presentaci\u00f3 del llibre a la seva seu; el tamb\u00e9 acad\u00e8mic numerari i vicepresident <a href=\"https:\/\/raed.academy\/ca\/academics\/dr-xabier-anoveros-trias-de-bes\/\" target=\"_blank\" rel=\"noopener\"><em><strong>Xabier A\u00f1overos<\/strong><\/em><\/a>, i la degana de la Facultat d&#8217;Humanitats de la <strong>Universitat Internacional de Catalunya<\/strong>, <strong>Judith Urbano<\/strong>, a m\u00e9s del mateix <strong>Buqueras<\/strong>, que va efectuar una \u00e0mplia exposici\u00f3 sobre la import\u00e0ncia del Patrimoni Mundial d&#8217;Espanya, el tercer amb m\u00e9s declaracions per part de la Unesco.<\/p>\n<p>Al llibre es recullen els 49 b\u00e9ns culturals i naturals i els 19 immaterials, cosa que en fa un total de 68. Aprofitant la seva pres\u00e8ncia a Barcelona, <strong>\u200b\u200bBuqueras<\/strong> va destacar els b\u00e9ns declarats a Catalunya: a Barcelona, \u200b\u200bles obres d&#8217;<strong>Antoni Gaud\u00ed<\/strong>, el Palau de la M\u00fasica i l&#8217;Hospital de la Santa Creu i Sant Pau; a Lleida, les esgl\u00e9sies rom\u00e0niques de Vall de Bo\u00ed; a Tarragona, el conjunt arqueol\u00f2gic de Tarraco i el monestir de Poblet. D&#8217;altra banda, l&#8217;art rupestre de l&#8217;Arc Mediterrani \u00e9s un b\u00e9 compartit. Els Immaterials s\u00f3n la Patum de Berga, els Castells de Tarragona i Barcelona \u200b\u200bi les festes del foc del solstici d&#8217;estiu als Pirineus com a ben compartit.<\/p>\n<p>Amb aquests 49 b\u00e9ns declarats patrimoni de la humanitat, Espanya se situa com el tercer pa\u00eds amb m\u00e9s b\u00e9ns declarats al m\u00f3n, per darrere d&#8217;It\u00e0lia i la Xina. D&#8217;aquests, 43 s\u00f3n b\u00e9ns culturals, quatre s\u00f3n b\u00e9ns naturals, dos s\u00f3n b\u00e9ns mixtos i quatre s\u00f3n b\u00e9ns compartits amb altres pa\u00efsos: un amb Fran\u00e7a, un altre amb Portugal, un tercer amb Eslov\u00e8nia i un quart compartit amb onze pa\u00efsos europeus m\u00e9s. Per la seva banda, els 19 b\u00e9ns immaterials fan d&#8217;Espanya el pa\u00eds d&#8217;Europa amb m\u00e9s b\u00e9ns declarats Patrimoni Cultural Immaterial, seguit de Cro\u00e0cia. A m\u00e9s, Espanya tamb\u00e9 compta amb 11 documents distingits com a <strong>Mem\u00f2ria del M\u00f3n<\/strong> per la mateixa Unesco. Tot plegat es pot trobar perfectament documentat a una obra de m\u00e9s de 400 p\u00e0gines il\u00b7lustrada amb m\u00e9s de 300 fotografies.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ignacio Buqueras presenta la reedici\u00f3 del llibre &#8220;El Patrimoni Mundial i Immaterial d&#8217;Espanya&#8221;, impulsat per l&#8217;Associaci\u00f3 per a la Difusi\u00f3 i Promoci\u00f3 del Patrimoni Espanyol (ADIPROPE)<\/p>\n","protected":false},"author":12,"featured_media":118274,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[401],"tags":[],"class_list":["post-118257","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-historia-de-lart-i-patrimoni-cultural","et-has-post-format-content","et_post_format-et-post-format-standard"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El patrimoni com a valor compartit - Reial Acad\u00e8mia Europea de Doctors<\/title>\n<meta name=\"description\" content=\"Ignacio Buqueras presenta la reedici\u00f3 del llibre &quot;El Patrimoni Mundial i Immaterial d&#039;Espanya&quot;, impulsat per ADIPROPE\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/raed.academy\/ca\/el-patrimoni-com-a-valor-compartit\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El patrimoni com a valor compartit - Reial Acad\u00e8mia Europea de Doctors\" \/>\n<meta property=\"og:description\" content=\"Ignacio Buqueras presenta la reedici\u00f3 del llibre &quot;El Patrimoni Mundial i Immaterial d&#039;Espanya&quot;, impulsat per ADIPROPE\" \/>\n<meta property=\"og:url\" content=\"https:\/\/raed.academy\/ca\/el-patrimoni-com-a-valor-compartit\/\" \/>\n<meta property=\"og:site_name\" content=\"Reial Acad\u00e8mia Europea de Doctors\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/fb.me\/raed.academy\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-25T10:38:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-26T17:27:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/raed.academy\/wp-content\/uploads\/2022\/05\/2022-05-12.Reedicion-libro-El-patrimonio-mundial-Ignacio-Buqueras-02.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"420\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"RAED\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@raedacademy\" \/>\n<meta name=\"twitter:site\" content=\"@raedacademy\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"RAED\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/el-patrimoni-com-a-valor-compartit\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/el-patrimoni-com-a-valor-compartit\\\/\"},\"author\":{\"name\":\"RAED\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/person\\\/5a755da80d1d979fd66ba745c8702927\"},\"headline\":\"El patrimoni com a valor compartit\",\"datePublished\":\"2022-05-25T10:38:22+00:00\",\"dateModified\":\"2022-05-26T17:27:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/el-patrimoni-com-a-valor-compartit\\\/\"},\"wordCount\":555,\"publisher\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/el-patrimoni-com-a-valor-compartit\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/2022-05-12.Reedicion-libro-El-patrimonio-mundial-Ignacio-Buqueras-02.webp\",\"articleSection\":[\"Hist\u00f2ria de l'art i patrimoni cultural\"],\"inLanguage\":\"ca-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/el-patrimoni-com-a-valor-compartit\\\/\",\"url\":\"https:\\\/\\\/raed.academy\\\/ca\\\/el-patrimoni-com-a-valor-compartit\\\/\",\"name\":\"El patrimoni com a valor compartit - Reial Acad\u00e8mia Europea de Doctors\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/el-patrimoni-com-a-valor-compartit\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/el-patrimoni-com-a-valor-compartit\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/2022-05-12.Reedicion-libro-El-patrimonio-mundial-Ignacio-Buqueras-02.webp\",\"datePublished\":\"2022-05-25T10:38:22+00:00\",\"dateModified\":\"2022-05-26T17:27:25+00:00\",\"description\":\"Ignacio Buqueras presenta la reedici\u00f3 del llibre \\\"El Patrimoni Mundial i Immaterial d'Espanya\\\", impulsat per ADIPROPE\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/el-patrimoni-com-a-valor-compartit\\\/#breadcrumb\"},\"inLanguage\":\"ca-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/raed.academy\\\/ca\\\/el-patrimoni-com-a-valor-compartit\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/el-patrimoni-com-a-valor-compartit\\\/#primaryimage\",\"url\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/2022-05-12.Reedicion-libro-El-patrimonio-mundial-Ignacio-Buqueras-02.webp\",\"contentUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/2022-05-12.Reedicion-libro-El-patrimonio-mundial-Ignacio-Buqueras-02.webp\",\"width\":700,\"height\":420,\"caption\":\"Reedicion del libro El patrimonio mundial de Ignacio Buqueras\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/el-patrimoni-com-a-valor-compartit\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/raed.academy\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El patrimoni com a valor compartit\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/raed.academy\\\/ca\\\/\",\"name\":\"Reial Acad\u00e8mia Europea de Doctors\",\"description\":\"Corporaci\u00f3n de derecho p\u00fablico de car\u00e1cter cient\u00edfico, t\u00e9cnico y art\u00edstico, que tiene por objeto la investigaci\u00f3n, el estudio, el fomento y la extensi\u00f3n del conocimiento en su sentido m\u00e1s amplio\",\"publisher\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/raed.academy\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#organization\",\"name\":\"Real Academia Europea de Doctores\",\"url\":\"https:\\\/\\\/raed.academy\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/cropped-logo_raed.png\",\"contentUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/cropped-logo_raed.png\",\"width\":512,\"height\":512,\"caption\":\"Real Academia Europea de Doctores\"},\"image\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/fb.me\\\/raed.academy\",\"https:\\\/\\\/x.com\\\/raedacademy\",\"https:\\\/\\\/www.instagram.com\\\/raed.academy\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCUYQwW2KrdirNWihxMDObwg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/person\\\/5a755da80d1d979fd66ba745c8702927\",\"name\":\"RAED\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g\",\"caption\":\"RAED\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El patrimoni com a valor compartit - Reial Acad\u00e8mia Europea de Doctors","description":"Ignacio Buqueras presenta la reedici\u00f3 del llibre \"El Patrimoni Mundial i Immaterial d'Espanya\", impulsat per ADIPROPE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/raed.academy\/ca\/el-patrimoni-com-a-valor-compartit\/","og_locale":"ca_ES","og_type":"article","og_title":"El patrimoni com a valor compartit - Reial Acad\u00e8mia Europea de Doctors","og_description":"Ignacio Buqueras presenta la reedici\u00f3 del llibre \"El Patrimoni Mundial i Immaterial d'Espanya\", impulsat per ADIPROPE","og_url":"https:\/\/raed.academy\/ca\/el-patrimoni-com-a-valor-compartit\/","og_site_name":"Reial Acad\u00e8mia Europea de Doctors","article_publisher":"http:\/\/fb.me\/raed.academy","article_published_time":"2022-05-25T10:38:22+00:00","article_modified_time":"2022-05-26T17:27:25+00:00","og_image":[{"width":700,"height":420,"url":"https:\/\/raed.academy\/wp-content\/uploads\/2022\/05\/2022-05-12.Reedicion-libro-El-patrimonio-mundial-Ignacio-Buqueras-02.webp","type":"image\/webp"}],"author":"RAED","twitter_card":"summary_large_image","twitter_creator":"@raedacademy","twitter_site":"@raedacademy","twitter_misc":{"Written by":"RAED","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/raed.academy\/ca\/el-patrimoni-com-a-valor-compartit\/#article","isPartOf":{"@id":"https:\/\/raed.academy\/ca\/el-patrimoni-com-a-valor-compartit\/"},"author":{"name":"RAED","@id":"https:\/\/raed.academy\/ca\/#\/schema\/person\/5a755da80d1d979fd66ba745c8702927"},"headline":"El patrimoni com a valor compartit","datePublished":"2022-05-25T10:38:22+00:00","dateModified":"2022-05-26T17:27:25+00:00","mainEntityOfPage":{"@id":"https:\/\/raed.academy\/ca\/el-patrimoni-com-a-valor-compartit\/"},"wordCount":555,"publisher":{"@id":"https:\/\/raed.academy\/ca\/#organization"},"image":{"@id":"https:\/\/raed.academy\/ca\/el-patrimoni-com-a-valor-compartit\/#primaryimage"},"thumbnailUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2022\/05\/2022-05-12.Reedicion-libro-El-patrimonio-mundial-Ignacio-Buqueras-02.webp","articleSection":["Hist\u00f2ria de l'art i patrimoni cultural"],"inLanguage":"ca-ES"},{"@type":"WebPage","@id":"https:\/\/raed.academy\/ca\/el-patrimoni-com-a-valor-compartit\/","url":"https:\/\/raed.academy\/ca\/el-patrimoni-com-a-valor-compartit\/","name":"El patrimoni com a valor compartit - Reial Acad\u00e8mia Europea de Doctors","isPartOf":{"@id":"https:\/\/raed.academy\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/raed.academy\/ca\/el-patrimoni-com-a-valor-compartit\/#primaryimage"},"image":{"@id":"https:\/\/raed.academy\/ca\/el-patrimoni-com-a-valor-compartit\/#primaryimage"},"thumbnailUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2022\/05\/2022-05-12.Reedicion-libro-El-patrimonio-mundial-Ignacio-Buqueras-02.webp","datePublished":"2022-05-25T10:38:22+00:00","dateModified":"2022-05-26T17:27:25+00:00","description":"Ignacio Buqueras presenta la reedici\u00f3 del llibre \"El Patrimoni Mundial i Immaterial d'Espanya\", impulsat per ADIPROPE","breadcrumb":{"@id":"https:\/\/raed.academy\/ca\/el-patrimoni-com-a-valor-compartit\/#breadcrumb"},"inLanguage":"ca-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/raed.academy\/ca\/el-patrimoni-com-a-valor-compartit\/"]}]},{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/raed.academy\/ca\/el-patrimoni-com-a-valor-compartit\/#primaryimage","url":"https:\/\/raed.academy\/wp-content\/uploads\/2022\/05\/2022-05-12.Reedicion-libro-El-patrimonio-mundial-Ignacio-Buqueras-02.webp","contentUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2022\/05\/2022-05-12.Reedicion-libro-El-patrimonio-mundial-Ignacio-Buqueras-02.webp","width":700,"height":420,"caption":"Reedicion del libro El patrimonio mundial de Ignacio Buqueras"},{"@type":"BreadcrumbList","@id":"https:\/\/raed.academy\/ca\/el-patrimoni-com-a-valor-compartit\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/raed.academy\/ca\/"},{"@type":"ListItem","position":2,"name":"El patrimoni com a valor compartit"}]},{"@type":"WebSite","@id":"https:\/\/raed.academy\/ca\/#website","url":"https:\/\/raed.academy\/ca\/","name":"Reial Acad\u00e8mia Europea de Doctors","description":"Corporaci\u00f3n de derecho p\u00fablico de car\u00e1cter cient\u00edfico, t\u00e9cnico y art\u00edstico, que tiene por objeto la investigaci\u00f3n, el estudio, el fomento y la extensi\u00f3n del conocimiento en su sentido m\u00e1s amplio","publisher":{"@id":"https:\/\/raed.academy\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/raed.academy\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca-ES"},{"@type":"Organization","@id":"https:\/\/raed.academy\/ca\/#organization","name":"Real Academia Europea de Doctores","url":"https:\/\/raed.academy\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/raed.academy\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/raed.academy\/wp-content\/uploads\/2017\/01\/cropped-logo_raed.png","contentUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2017\/01\/cropped-logo_raed.png","width":512,"height":512,"caption":"Real Academia Europea de Doctores"},"image":{"@id":"https:\/\/raed.academy\/ca\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/fb.me\/raed.academy","https:\/\/x.com\/raedacademy","https:\/\/www.instagram.com\/raed.academy\/","https:\/\/www.youtube.com\/channel\/UCUYQwW2KrdirNWihxMDObwg"]},{"@type":"Person","@id":"https:\/\/raed.academy\/ca\/#\/schema\/person\/5a755da80d1d979fd66ba745c8702927","name":"RAED","image":{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g","caption":"RAED"}}]}},"_links":{"self":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/posts\/118257","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/comments?post=118257"}],"version-history":[{"count":0,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/posts\/118257\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/media\/118274"}],"wp:attachment":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/media?parent=118257"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/categories?post=118257"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/tags?post=118257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}