{"id":117883,"date":"2022-05-19T15:10:38","date_gmt":"2022-05-19T15:10:38","guid":{"rendered":"https:\/\/raed.academy\/?p=117883"},"modified":"2022-05-21T19:36:57","modified_gmt":"2022-05-21T19:36:57","slug":"amb-una-tassa-o-dues-nhi-ha-prou","status":"publish","type":"post","link":"https:\/\/raed.academy\/ca\/amb-una-tassa-o-dues-nhi-ha-prou\/","title":{"rendered":"Les qualitats del caf\u00e8 i els riscos de l&#8217;exc\u00e9s de consum"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-117870\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2022\/05\/granos-cafe-dmn-publico-pxhere.com-dst.webp\" sizes=\"(max-width: 450px) 100vw, 450px\" srcset=\"https:\/\/raed.academy\/wp-content\/uploads\/2022\/05\/granos-cafe-dmn-publico-pxhere.com-dst.webp 600w, https:\/\/raed.academy\/wp-content\/uploads\/2022\/05\/granos-cafe-dmn-publico-pxhere.com-dst-440x264.webp 440w\" alt=\"\" width=\"450\" height=\"270\" \/><a href=\"https:\/\/raed.academy\/ca\/academics\/dr-javier-aranceta-bartrina\/\" target=\"_blank\" rel=\"noopener\"><em><strong>Javier Aranceta<\/strong><\/em><\/a>, president del<strong> Comit\u00e8 Cient\u00edfic<\/strong> de la <strong>Societat Espanyola de Nutrici\u00f3 Comunit\u00e0ria<\/strong> i de la <strong>Reial Acad\u00e8mia de Medicina del Pa\u00eds Basc<\/strong> i acad\u00e8mic de n\u00famero i membre de la <strong>Junta de Govern<\/strong> de la <strong>Reial Acad\u00e8mia Europea de Doctors-Barcelona 1914<\/strong> (RAED), destaca les qualitats del caf\u00e8, aix\u00ed com els riscos del seu consum en exc\u00e9s, a l&#8217;article <strong>&#8220;Las consecuencias de una taza de caf\u00e9 para la salud&#8221;<\/strong>, publicat al diari <strong>&#8220;El Correo&#8221;<\/strong> el passat 11 de maig. L&#8217;acad\u00e8mic incideix, especialment, en les conseq\u00fc\u00e8ncies que pot arribar a tenir per a la salut un exc\u00e9s de cafe\u00efna perllongat al llarg del temps.<\/p>\n<p>&#8220;El contingut de cafe\u00efna al caf\u00e8 dep\u00e8n de la varietat, sistema de torrat i preparaci\u00f3 de la infusi\u00f3. La varietat robusta aporta m\u00e9s contingut en cafe\u00efna que l&#8217;ar\u00e0biga, tot i que tamb\u00e9 dep\u00e8n de l&#8217;altitud dels cultius. L&#8217;alcaloide ajuda a millorar la concentraci\u00f3 i l&#8217;estat d&#8217;alerta amb sensacions positives fins a una ingesta de 250 mg de cafe\u00efna (gaireb\u00e9 3 tasses de caf\u00e8 filtrat al dia), encara que la reacci\u00f3 dep\u00e8n de l&#8217;estat de salut, pes corporal, consum de medicaments i potencial hep\u00e0tic de metabolitzaci\u00f3 de les xantines a partir de la xantina oxidasa&#8221;, inicia Aranceta la seva reflexi\u00f3.<\/p>\n<div id=\"attachment_93379\" style=\"width: 380px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-93379\" class=\"wp-image-93379\" src=\"https:\/\/raed.academy\/wp-content\/uploads\/2020\/09\/Javier-Aranceta-Bartrina-prp-RAED.jpg\" alt=\"Dr. Javier Aranceta Bartrina\" width=\"370\" height=\"259\" aria-describedby=\"caption-attachment-93379\" \/><p id=\"caption-attachment-93379\" class=\"wp-caption-text\">Dr. Javier Aranceta<\/p><\/div>\n<p>Per a l&#8217;expert, un consum excessius continuat tant del caf\u00e8 com d&#8217;altres begudes que contenen cafe\u00efna (te, cacau, mat, guaran\u00e0, les anomenades begudes energ\u00e8tiques&#8230;) pot induir a una toler\u00e0ncia a la cafe\u00efna i posteriorment una depend\u00e8ncia que arribaria a manifestar-se en cas de supressi\u00f3 de la ingesta de caf\u00e8. Tamb\u00e9 s&#8217;han descrit possibles efectes desfavorables sobre els nivells de colesterol total i colesterol LDL a la sang i una reducci\u00f3 dels nivells de sucre a la sang en pacients amb diabetis, cosa que pot ser una de les causes de la menor prevalen\u00e7a d&#8217;aquesta malaltia tipus II en adults consumidors de caf\u00e8. La durada de l&#8217;efecte estimulant \u00e9s de sis hores, per\u00f2 la seva acci\u00f3 funcional dep\u00e8n de cada persona i les seves caracter\u00edstiques, entre les quals sens dubte hi hauria el potencial hep\u00e0tic de la xantina oxidasa.<\/p>\n<p>&#8220;La dosi compatible amb un efecte m\u00e9s benefici\u00f3s sobre la salut cardiovascular, els nivells de gluc\u00e8mia i les capacitats cognitives seria entre 3 i 4 tasses de caf\u00e8 sol, filtrat, al dia. Podr\u00edem plantejar com a recomanaci\u00f3 general el consum moderat de la varietat ar\u00e0biga de torrat natural, filtrat i sense sucre ni edulcorants. En cas d&#8217;hipertensi\u00f3 arterial o consum de medicaments relacionats amb el sistema nervi\u00f3s, especialment antidepressius o altres f\u00e0rmacs que incorporin xantines, \u00e9s aconsellable consumir formes descafe\u00efnades. Aquesta infusi\u00f3 no seria recomanable, per\u00f2, en per\u00edodes d&#8217;embar\u00e0s, lact\u00e0ncia i en dones postmenop\u00e0usiques amb osteoporosi&#8221;, conclou l&#8217;acad\u00e8mic.<\/p>\n<h2><a href=\"https:\/\/www.elcorreo.com\/jantour\/nutricion\/cafe-consecuencias-para-la-salud-20220506090804-nt.html?ref=https%3A%2F%2Fwww.elcorreo.com%2Fjantour%2Fnutricion%2Fcafe-consecuencias-para-la-salud-20220506090804-nt.html\" target=\"_blank\" rel=\"noopener\">Llegiu l&#8217;article<\/a><\/h2>\n","protected":false},"excerpt":{"rendered":"<p>Javier Aranceta destaca les qualitats del caf\u00e8, aix\u00ed com els riscos del seu consum en exc\u00e9s, a l&#8217;article &#8220;Las consecuencias de una taza de caf\u00e9 para la salud&#8221;<\/p>\n","protected":false},"author":12,"featured_media":117871,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[237],"tags":[],"class_list":["post-117883","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alimentacio-i-nutricio","et-has-post-format-content","et_post_format-et-post-format-standard"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les qualitats del caf\u00e8 i els riscos de l&#039;exc\u00e9s de consum - Reial Acad\u00e8mia Europea de Doctors<\/title>\n<meta name=\"description\" content=\"Javier Aranceta destaca les qualitats del caf\u00e8, aix\u00ed com els riscos del seu consum en exc\u00e9s, a l&#039;article &quot;Las consecuencias de una taza de caf\u00e9 para la salud&quot;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/raed.academy\/ca\/amb-una-tassa-o-dues-nhi-ha-prou\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les qualitats del caf\u00e8 i els riscos de l&#039;exc\u00e9s de consum - Reial Acad\u00e8mia Europea de Doctors\" \/>\n<meta property=\"og:description\" content=\"Javier Aranceta destaca les qualitats del caf\u00e8, aix\u00ed com els riscos del seu consum en exc\u00e9s, a l&#039;article &quot;Las consecuencias de una taza de caf\u00e9 para la salud&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/raed.academy\/ca\/amb-una-tassa-o-dues-nhi-ha-prou\/\" \/>\n<meta property=\"og:site_name\" content=\"Reial Acad\u00e8mia Europea de Doctors\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/fb.me\/raed.academy\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-19T15:10:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-21T19:36:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/raed.academy\/wp-content\/uploads\/2022\/05\/granos-cafe-dmn-publico-pxhere.com-dst.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"RAED\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@raedacademy\" \/>\n<meta name=\"twitter:site\" content=\"@raedacademy\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"RAED\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/amb-una-tassa-o-dues-nhi-ha-prou\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/amb-una-tassa-o-dues-nhi-ha-prou\\\/\"},\"author\":{\"name\":\"RAED\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/person\\\/5a755da80d1d979fd66ba745c8702927\"},\"headline\":\"Les qualitats del caf\u00e8 i els riscos de l&#8217;exc\u00e9s de consum\",\"datePublished\":\"2022-05-19T15:10:38+00:00\",\"dateModified\":\"2022-05-21T19:36:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/amb-una-tassa-o-dues-nhi-ha-prou\\\/\"},\"wordCount\":517,\"publisher\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/amb-una-tassa-o-dues-nhi-ha-prou\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/granos-cafe-dmn-publico-pxhere.com-dst.webp\",\"articleSection\":[\"Alimentaci\u00f3 i nutrici\u00f3\"],\"inLanguage\":\"ca-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/amb-una-tassa-o-dues-nhi-ha-prou\\\/\",\"url\":\"https:\\\/\\\/raed.academy\\\/ca\\\/amb-una-tassa-o-dues-nhi-ha-prou\\\/\",\"name\":\"Les qualitats del caf\u00e8 i els riscos de l'exc\u00e9s de consum - Reial Acad\u00e8mia Europea de Doctors\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/amb-una-tassa-o-dues-nhi-ha-prou\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/amb-una-tassa-o-dues-nhi-ha-prou\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/granos-cafe-dmn-publico-pxhere.com-dst.webp\",\"datePublished\":\"2022-05-19T15:10:38+00:00\",\"dateModified\":\"2022-05-21T19:36:57+00:00\",\"description\":\"Javier Aranceta destaca les qualitats del caf\u00e8, aix\u00ed com els riscos del seu consum en exc\u00e9s, a l'article \\\"Las consecuencias de una taza de caf\u00e9 para la salud\\\"\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/amb-una-tassa-o-dues-nhi-ha-prou\\\/#breadcrumb\"},\"inLanguage\":\"ca-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/raed.academy\\\/ca\\\/amb-una-tassa-o-dues-nhi-ha-prou\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/amb-una-tassa-o-dues-nhi-ha-prou\\\/#primaryimage\",\"url\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/granos-cafe-dmn-publico-pxhere.com-dst.webp\",\"contentUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/granos-cafe-dmn-publico-pxhere.com-dst.webp\",\"width\":600,\"height\":360},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/amb-una-tassa-o-dues-nhi-ha-prou\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/raed.academy\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les qualitats del caf\u00e8 i els riscos de l&#8217;exc\u00e9s de consum\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/raed.academy\\\/ca\\\/\",\"name\":\"Reial Acad\u00e8mia Europea de Doctors\",\"description\":\"Corporaci\u00f3n de derecho p\u00fablico de car\u00e1cter cient\u00edfico, t\u00e9cnico y art\u00edstico, que tiene por objeto la investigaci\u00f3n, el estudio, el fomento y la extensi\u00f3n del conocimiento en su sentido m\u00e1s amplio\",\"publisher\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/raed.academy\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#organization\",\"name\":\"Real Academia Europea de Doctores\",\"url\":\"https:\\\/\\\/raed.academy\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/cropped-logo_raed.png\",\"contentUrl\":\"https:\\\/\\\/raed.academy\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/cropped-logo_raed.png\",\"width\":512,\"height\":512,\"caption\":\"Real Academia Europea de Doctores\"},\"image\":{\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/fb.me\\\/raed.academy\",\"https:\\\/\\\/x.com\\\/raedacademy\",\"https:\\\/\\\/www.instagram.com\\\/raed.academy\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCUYQwW2KrdirNWihxMDObwg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/raed.academy\\\/ca\\\/#\\\/schema\\\/person\\\/5a755da80d1d979fd66ba745c8702927\",\"name\":\"RAED\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g\",\"caption\":\"RAED\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les qualitats del caf\u00e8 i els riscos de l'exc\u00e9s de consum - Reial Acad\u00e8mia Europea de Doctors","description":"Javier Aranceta destaca les qualitats del caf\u00e8, aix\u00ed com els riscos del seu consum en exc\u00e9s, a l'article \"Las consecuencias de una taza de caf\u00e9 para la salud\"","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/raed.academy\/ca\/amb-una-tassa-o-dues-nhi-ha-prou\/","og_locale":"ca_ES","og_type":"article","og_title":"Les qualitats del caf\u00e8 i els riscos de l'exc\u00e9s de consum - Reial Acad\u00e8mia Europea de Doctors","og_description":"Javier Aranceta destaca les qualitats del caf\u00e8, aix\u00ed com els riscos del seu consum en exc\u00e9s, a l'article \"Las consecuencias de una taza de caf\u00e9 para la salud\"","og_url":"https:\/\/raed.academy\/ca\/amb-una-tassa-o-dues-nhi-ha-prou\/","og_site_name":"Reial Acad\u00e8mia Europea de Doctors","article_publisher":"http:\/\/fb.me\/raed.academy","article_published_time":"2022-05-19T15:10:38+00:00","article_modified_time":"2022-05-21T19:36:57+00:00","og_image":[{"width":600,"height":360,"url":"https:\/\/raed.academy\/wp-content\/uploads\/2022\/05\/granos-cafe-dmn-publico-pxhere.com-dst.webp","type":"image\/webp"}],"author":"RAED","twitter_card":"summary_large_image","twitter_creator":"@raedacademy","twitter_site":"@raedacademy","twitter_misc":{"Written by":"RAED","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/raed.academy\/ca\/amb-una-tassa-o-dues-nhi-ha-prou\/#article","isPartOf":{"@id":"https:\/\/raed.academy\/ca\/amb-una-tassa-o-dues-nhi-ha-prou\/"},"author":{"name":"RAED","@id":"https:\/\/raed.academy\/ca\/#\/schema\/person\/5a755da80d1d979fd66ba745c8702927"},"headline":"Les qualitats del caf\u00e8 i els riscos de l&#8217;exc\u00e9s de consum","datePublished":"2022-05-19T15:10:38+00:00","dateModified":"2022-05-21T19:36:57+00:00","mainEntityOfPage":{"@id":"https:\/\/raed.academy\/ca\/amb-una-tassa-o-dues-nhi-ha-prou\/"},"wordCount":517,"publisher":{"@id":"https:\/\/raed.academy\/ca\/#organization"},"image":{"@id":"https:\/\/raed.academy\/ca\/amb-una-tassa-o-dues-nhi-ha-prou\/#primaryimage"},"thumbnailUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2022\/05\/granos-cafe-dmn-publico-pxhere.com-dst.webp","articleSection":["Alimentaci\u00f3 i nutrici\u00f3"],"inLanguage":"ca-ES"},{"@type":"WebPage","@id":"https:\/\/raed.academy\/ca\/amb-una-tassa-o-dues-nhi-ha-prou\/","url":"https:\/\/raed.academy\/ca\/amb-una-tassa-o-dues-nhi-ha-prou\/","name":"Les qualitats del caf\u00e8 i els riscos de l'exc\u00e9s de consum - Reial Acad\u00e8mia Europea de Doctors","isPartOf":{"@id":"https:\/\/raed.academy\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/raed.academy\/ca\/amb-una-tassa-o-dues-nhi-ha-prou\/#primaryimage"},"image":{"@id":"https:\/\/raed.academy\/ca\/amb-una-tassa-o-dues-nhi-ha-prou\/#primaryimage"},"thumbnailUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2022\/05\/granos-cafe-dmn-publico-pxhere.com-dst.webp","datePublished":"2022-05-19T15:10:38+00:00","dateModified":"2022-05-21T19:36:57+00:00","description":"Javier Aranceta destaca les qualitats del caf\u00e8, aix\u00ed com els riscos del seu consum en exc\u00e9s, a l'article \"Las consecuencias de una taza de caf\u00e9 para la salud\"","breadcrumb":{"@id":"https:\/\/raed.academy\/ca\/amb-una-tassa-o-dues-nhi-ha-prou\/#breadcrumb"},"inLanguage":"ca-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/raed.academy\/ca\/amb-una-tassa-o-dues-nhi-ha-prou\/"]}]},{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/raed.academy\/ca\/amb-una-tassa-o-dues-nhi-ha-prou\/#primaryimage","url":"https:\/\/raed.academy\/wp-content\/uploads\/2022\/05\/granos-cafe-dmn-publico-pxhere.com-dst.webp","contentUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2022\/05\/granos-cafe-dmn-publico-pxhere.com-dst.webp","width":600,"height":360},{"@type":"BreadcrumbList","@id":"https:\/\/raed.academy\/ca\/amb-una-tassa-o-dues-nhi-ha-prou\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/raed.academy\/ca\/"},{"@type":"ListItem","position":2,"name":"Les qualitats del caf\u00e8 i els riscos de l&#8217;exc\u00e9s de consum"}]},{"@type":"WebSite","@id":"https:\/\/raed.academy\/ca\/#website","url":"https:\/\/raed.academy\/ca\/","name":"Reial Acad\u00e8mia Europea de Doctors","description":"Corporaci\u00f3n de derecho p\u00fablico de car\u00e1cter cient\u00edfico, t\u00e9cnico y art\u00edstico, que tiene por objeto la investigaci\u00f3n, el estudio, el fomento y la extensi\u00f3n del conocimiento en su sentido m\u00e1s amplio","publisher":{"@id":"https:\/\/raed.academy\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/raed.academy\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca-ES"},{"@type":"Organization","@id":"https:\/\/raed.academy\/ca\/#organization","name":"Real Academia Europea de Doctores","url":"https:\/\/raed.academy\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/raed.academy\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/raed.academy\/wp-content\/uploads\/2017\/01\/cropped-logo_raed.png","contentUrl":"https:\/\/raed.academy\/wp-content\/uploads\/2017\/01\/cropped-logo_raed.png","width":512,"height":512,"caption":"Real Academia Europea de Doctores"},"image":{"@id":"https:\/\/raed.academy\/ca\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/fb.me\/raed.academy","https:\/\/x.com\/raedacademy","https:\/\/www.instagram.com\/raed.academy\/","https:\/\/www.youtube.com\/channel\/UCUYQwW2KrdirNWihxMDObwg"]},{"@type":"Person","@id":"https:\/\/raed.academy\/ca\/#\/schema\/person\/5a755da80d1d979fd66ba745c8702927","name":"RAED","image":{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/19fdfdc0d67fb9c45714b703a2ac82251c4fcea3637f002ac3c9b74c0183583c?s=96&d=mm&r=g","caption":"RAED"}}]}},"_links":{"self":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/posts\/117883","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/comments?post=117883"}],"version-history":[{"count":0,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/posts\/117883\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/media\/117871"}],"wp:attachment":[{"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/media?parent=117883"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/categories?post=117883"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/raed.academy\/ca\/wp-json\/wp\/v2\/tags?post=117883"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}